{"id":65983,"date":"2004-05-27T00:00:00","date_gmt":"2004-05-27T00:00:00","guid":{"rendered":"https:\/\/new.dedefensa.org\/index.php\/2004\/05\/27\/ladministration-gw-de-plus-en-plus-isolee-sur-kyoto\/"},"modified":"2004-05-27T00:00:00","modified_gmt":"2004-05-27T00:00:00","slug":"ladministration-gw-de-plus-en-plus-isolee-sur-kyoto","status":"publish","type":"post","link":"https:\/\/new.dedefensa.org\/index.php\/2004\/05\/27\/ladministration-gw-de-plus-en-plus-isolee-sur-kyoto\/","title":{"rendered":"<strong><em>L&rsquo;administration GW de plus en plus isol\u00e9e sur Kyoto<\/em><\/strong>"},"content":{"rendered":"<p><h2 class=\"common-article\">L&rsquo;administration GW de plus en plus isol\u00e9e sur Kyoto<\/h2>\n<\/p>\n<p><\/p>\n<p><p>\t27 mai 2004  L&rsquo;\u00e9volution de Moscou sur la question du Protocole de Kyoto, annonc\u00e9e la semaine derni\u00e8re (le 22 mai), est per\u00e7ue <a href=\"http:\/\/news.independent.co.uk\/world\/environment\/story.jsp?story=523978\" class=\"gen\">de source britannique comme d\u00e9cisive<\/a>. <\/p>\n<\/p>\n<p><\/p>\n<p><p>\t\u00ab <em>Russia&rsquo;s President Vladimir Putin  who will effectively decide whether the Kyoto Protocol stands or falls  announced on Friday that his country would rapidly move towards ratification in the wake of a complex deal with the European Union.<\/em><\/p>\n<\/p>\n<p><p>\t\u00bb <em>One British source close to negotiating the deal said yesterday that the announcement was more than I had dared to hope. Another said he thought it increased the likelihood of the treaty coming into effect from less that 50 per cent to about 90 per cent.<\/em> \u00bb<\/p>\n<\/p>\n<p><\/p>\n<p><p>\tLe m\u00eame article signale qu&rsquo;aux \u00c9tats-Unis m\u00eames les structures de pouvoir hors du gouvernement f\u00e9d\u00e9ral \u00e9voluent dans un sens favorable au Protocole de Kyoto (y compris dans certaines entreprises p\u00e9troli\u00e8res). <a href=\"http:\/\/www.dedefensa.org\/article.php?art_id=832\" class=\"gen\">Divers \u00c9tats de l&rsquo;Union sont favorables<\/a> aux dispositions de Kyoto, et certains les appliquent d\u00e9j\u00e0.<\/p>\n<\/p>\n<p><\/p>\n<p><p>\t\u00ab <em>Surprisingly, Mr Bush is under pressure from the industry responsible for much of the pollution: electric power companies owning nearly two-fifths of US generating capacity have endorsed legislation that would compulsorily limit their emissions of carbon dioxide, the main global-warming gas. There are even indications that ExxonMobil, the main industry cheerleader for the President&rsquo;s position, is beginning to change its stance.<\/em><\/p>\n<\/p>\n<p><p>\t\u00bb <em>Three key Republican-governed states &#8211; California, New York and Massachusetts &#8211; have parted company with the President and moved to take aggressive measures to reduce emissions. Both houses of Congress have called on the Bush administration to return to the negotiating table.<\/em> \u00bb<\/p>\n<\/p>\n<p><\/p>\n<p><p>\tCet ensemble d&rsquo;informationssemble montrer que la question de la ratification du Protocole de Kyoto pourrait \u00e9voluer favorablement. Ce dont on s&rsquo;aper\u00e7oit d&rsquo;autre part, mais c&rsquo;est l&rsquo;information principale sans aucun doute, c&rsquo;est combien l&rsquo;administration GW Bush se trouve isol\u00e9e dans ce contexte, m\u00eame vis-\u00e0-vis de ses soutiens habituels et normalement les adversaires les plus acharn\u00e9s de Kyoto (les compagnies p\u00e9troli\u00e8res). Le paradoxe serait alors que l&rsquo;administration GW continuerait \u00e0 d\u00e9fendre une position que ceux qui l&rsquo;ont encourag\u00e9e \u00e0 cette opposition d\u00e9savoueraient <em>facto<\/em>.<\/p>\n<\/p>\n<p><p>\tL&rsquo;explication ne se trouve ni dans les d\u00e9cisions ni dans la politique. Elle se trouve dans les structures m\u00eames du gouvernement US, et on rencontre d&rsquo;autres exemples de cette situation dans d&rsquo;autres domaines aujourd&rsquo;hui. Le pouvoir US est devenu si faible, il s&rsquo;est si compl\u00e8tement morcel\u00e9 en divers centres d&rsquo;influence et de pouvoirs partiels, qu&rsquo;une fois qu&rsquo;une politique est dans les structures de ce pouvoir, il est impossible de revenir sur elle avant un temps tr\u00e8s long et des batailles bureaucratiques \u00e9puisantes. On peut avancer l&rsquo;id\u00e9e que cette situation s&rsquo;est consid\u00e9rablement aggrav\u00e9e avec l&rsquo;administration GW Bush, dans la mesure o\u00f9 cette administration est structurellement d&rsquo;une extraordinaire faiblesse puisque son centre (le Pr\u00e9sident) est politiquement totalement inexistant.<\/p>\n<\/p>\n<p><p>\tUn \u00e9l\u00e9ment suppl\u00e9mentaire de paralysie est la tr\u00e8s forte id\u00e9ologisation de l&rsquo;administration (avec des \u00e9l\u00e9ments d&rsquo;une droite radicale ultra-dure). Cela rend encore plus difficile des r\u00e9visions politiques dans la mesure o\u00f9 l&rsquo;id\u00e9ologie radicale fige les uns et les autres dans leurs positions, \u00e0 cause essentiellement de la crainte de sortir de la ligne avec des cons\u00e9quences professionnelles graves. Effectivement, l&rsquo;administration GW pr\u00e9sente un sch\u00e9ma tr\u00e8s proche de celui du gouvernement sovi\u00e9tique, sur la fin (\u00e9poque Brejnev) : un m\u00e9lange de d\u00e9lusion du pouvoir central donnant d&rsquo;autant plus de puissance \u00e0 divers composants partiels, de bureaucratie omnipr\u00e9sente, de normes id\u00e9ologiques fig\u00e9es et contraignantes.  <\/p>\n<\/p>\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>L&rsquo;administration GW de plus en plus isol\u00e9e sur Kyoto 27 mai 2004 L&rsquo;\u00e9volution de Moscou sur la question du Protocole de Kyoto, annonc\u00e9e la semaine derni\u00e8re (le 22 mai), est per\u00e7ue de source britannique comme d\u00e9cisive. \u00ab Russia&rsquo;s President Vladimir Putin who will effectively decide whether the Kyoto Protocol stands or falls announced on Friday&hellip;&nbsp;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[916],"class_list":["post-65983","post","type-post","status-publish","format-standard","hentry","category-faits-et-commentaires","tag-poutine"],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/65983","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/comments?post=65983"}],"version-history":[{"count":0,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/65983\/revisions"}],"wp:attachment":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/media?parent=65983"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/categories?post=65983"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/tags?post=65983"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}