{"id":65987,"date":"2004-05-31T00:00:00","date_gmt":"2004-05-31T00:00:00","guid":{"rendered":"https:\/\/new.dedefensa.org\/index.php\/2004\/05\/31\/notre-samizdat-globalise-suite\/"},"modified":"2004-05-31T00:00:00","modified_gmt":"2004-05-31T00:00:00","slug":"notre-samizdat-globalise-suite","status":"publish","type":"post","link":"https:\/\/new.dedefensa.org\/index.php\/2004\/05\/31\/notre-samizdat-globalise-suite\/","title":{"rendered":"Notre samizdat globalis\u00e9 (suite)"},"content":{"rendered":"<p><h2 class=\"titleset_c.deepblue\" style=\"color:#0f3955; font-size:1.25em\">Pr\u00e9cision<\/h2>\n<\/p>\n<p><p>Ci-dessous, nous publions le texte de la rubrique <em>Contexte<\/em> de <em>de defensa<\/em> du 10 mai 2004. Nous pensons que ce texte \u00e9clairera un aspect de <a class=\"gen\" href=\"http:\/\/www.dedefensa.org\/article.php?art_id=1125\">nos commentaires sur le mea culpa du glorieux New York Times<\/a>, \u00e0 propos de sa couverture tr\u00e8s professionnelle des \u00e9v\u00e9nements menant \u00e0 la guerre en Irak.<\/p>\n<\/p>\n<p><p>______________________________<\/p>\n<\/p>\n<\/p>\n<p><h2 class=\"titleset_a.deepblue\" style=\"color:#0f3955; font-size:2em\">Notre samizdat globalis\u00e9 (suite)<\/h2>\n<\/p>\n<p><p><strong>Il y a presque cinq ans, le 10 juillet 1999, nous publiions, dans cette m\u00eame rubrique, une analyse pour saluer la naissance de &laquo; notre samizdat globalis\u00e9 &raquo;, &mdash; surnom que nous donnions \u00e0 l&rsquo;information \u00ab\u00a0dissidente\u00a0\u00bb v\u00e9hicul\u00e9e par Internet. Nous revenons sur le th\u00e8me, pour constater une \u00e9volution d\u00e9cisive.<\/strong><\/p>\n<\/p>\n<p><p>&#8230;Donc, le 10 juillet 1999, dans notre Volume 14 n&deg;20, nous nous attachions \u00e0 tracer les grandes lignes de ce ph\u00e9nom\u00e8ne qu&rsquo;\u00e9tait la naissance d&rsquo;une v\u00e9ritable information alternative, une \u00ab\u00a0dissidence\u00a0\u00bb sur les r\u00e9seaux d&rsquo;Internet. C&rsquo;\u00e9tait &laquo;<em>Notre samizdat globalis\u00e9<\/em>&raquo;. (Le mot russe <em>samizdat<\/em> d\u00e9signe les \u00e9crits clandestins, diffus\u00e9s par la dissidence, dans l&rsquo;URSS de l&rsquo;apr\u00e8s- guerre post-stalinienne jusqu&rsquo;\u00e0 la chute finale.) Aujourd&rsquo;hui, nous nous attachons \u00e0 la suite, \u00e0 l&rsquo;\u00e9volution du ph\u00e9nom\u00e8ne.<\/p>\n<\/p>\n<p><p>Pour autant, ce n&rsquo;est pas simplement par go&ucirc;t des comm\u00e9morations, ou des rapports automatiques d\u00e9pendant de la seule chronologie, que nous \u00e9crivons ce texte. De nombreux incidents sont survenus ces derniers mois, en marge de la guerre irakienne, qui montrent l&rsquo;extension du ph\u00e9nom\u00e8ne \u00ab\u00a0samizdat globalis\u00e9\u00a0\u00bb. Notre appr\u00e9ciation est qu&rsquo;il s&rsquo;est m\u00eame produit une rupture de substance \u00e0 cet \u00e9gard.<\/p>\n<\/p>\n<p><p>Nous rappelons deux \u00e9v\u00e9nements, dont nous traitons par ailleurs dans ce num\u00e9ro (voir nos rubriques <em>de defensa<\/em> et <em>Journal<\/em>). Ils ont eu lieu le m\u00eame jour, le 22 avril.<\/p>\n<\/p>\n<p><p>&bull; Le premier, c&rsquo;est la diffusion de photos du transport et du d\u00e9barquement de cercueils de soldats am\u00e9ricains tu\u00e9s en Irak. C&rsquo;est le site <em>www.memoryhole.org<\/em> qui a diffus\u00e9 ces photographies. (La diffusion de photos de tortures US, le 28 avril, a suivi un autre canal.)<\/p>\n<\/p>\n<p><p>&bull; Un rapport du groupe Center for Investigative Reporting (CIR) sur les dimen- sions de la corruption en Irak, suscit\u00e9e par les \u00ab\u00a0r\u00e9formes\u00a0\u00bb am\u00e9ricaines, et, souvent, par les Am\u00e9ricains eux-m\u00eames. Le rapport est publi\u00e9 sur le site du CIR (site <em>www.muckraker.org<\/em>).<\/p>\n<\/p>\n<p><p>[&bull; Nous rappellerons que d&rsquo;autres \u00e9v\u00e9nements de cette sorte se sont d\u00e9j\u00e0 produits, comme celui que nous \u00e9voquions indirectement dans notre rubrique <em>Contexte<\/em> du 25 f\u00e9vrier 2003, Vol18, n&deg;11 : la diffusion sur Internet, par le groupe CASI, de la mise en \u00e9vidence de la tromperie, \u00e0 partir du \u00ab\u00a0repiquage\u00a0\u00bb d&rsquo;articles ou de documents d\u00e9pass\u00e9s, que constituait le rapport \u00ab\u00a0secret\u00a0\u00bb divulgu\u00e9 le 30 janvier 2003 par l&rsquo;\u00e9quipe d&rsquo;Alastair Campbell (proche de Tony Blair) sur les turpitudes de Saddam Hussein.]<\/p>\n<\/p>\n<p><p>Les deux \u00e9v\u00e9nements signal\u00e9s ici (les photos et la corruption) constituent un apport d&rsquo;information et d&rsquo;analyse important, voire d\u00e9cisif, dans le travail de mise en \u00e9vidence des r\u00e9alit\u00e9s de la situation irakienne.<\/p>\n<\/p>\n<p><h2 class=\"titleset_b.deepblue\" style=\"color:#0f3955; font-size:1.65em; font-variant:small-caps\">Internet arrive \u00e0 maturit\u00e9<\/h2>\n<\/p>\n<p><p>Des deux cas techniquement similaires, c&rsquo;est celui des photos qui est le plus significatif. La diffusion de ces photos par <em>memoryhole.org<\/em> fit grand bruit. Les grands journaux firent des articles, o&ugrave; l&rsquo;on cita cette source. Certains, sans trop insister sur le fait qu&rsquo;ils se mettaient eux-m\u00eames en cause, s&rsquo;interrog\u00e8rent sur le fait de savoir pourquoi les grands organes de presse n&rsquo;avaient pas, eux- m\u00eames, r\u00e9alis\u00e9 cette op\u00e9ration. (En effet, les photos ont \u00e9t\u00e9 obtenues par simple demande faite \u00e0 la direction d&rsquo;une base de l&rsquo;USAF, o&ugrave; arrivent les cercueils, au nom du Freedom of Information Act [FOIA]. Apr\u00e8s avoir essuy\u00e9 un premier refus et avoir fait appel, <em>memoryhole.org<\/em> obtint les documents. Tout le monde pouvait faire de m\u00eame.)<\/p>\n<\/p>\n<p><p>Le New York <em>Times<\/em> publia un article o&ugrave; cette question \u00e9tait abord\u00e9e, et pos\u00e9e \u00e0 certains dirigeants de grands organes de presse. On y lit les r\u00e9ponses de deux d&rsquo;entre eux, Bill Keller, un des r\u00e9dacteurs en chef du New York Times, et John Banner, producteur de l&rsquo;\u00e9mission World News Tonight de ABC. Leur r\u00e9ponse est similaire : \u00ab\u00a0nous ne savions pas\u00a0\u00bb. (John Banner : &laquo; <em>We did not file a FOIA request ourselves, because this was the first we had known that the military was shooting these pictures.<\/em> &raquo;)<\/p>\n<\/p>\n<p><p>L&rsquo;argument est sans la moindre valeur. Nul n&rsquo;ignore, surtout pas le directeur d&rsquo;une grande organisation d&rsquo;information am\u00e9ricaine, d&rsquo;une part le formalisme institutionnel am\u00e9ricain (donc l&rsquo;existence, m\u00eame de mani\u00e8re non-publique, du c\u00e9r\u00e9monial classique pour le rapatriement des cercueils) ; d&rsquo;autre part, l&rsquo;obsession fondamentale des forces arm\u00e9es am\u00e9ricaines et du Pentagone pour le t\u00e9moignage photographique de tous les \u00e9v\u00e9nements, et, par cons\u00e9quent bien s&ucirc;r, ce rapatriement des corps.<\/p>\n<\/p>\n<p><p>L&rsquo;attitude des grands m\u00e9dias am\u00e9ricains est beaucoup mieux expliqu\u00e9e par leur volont\u00e9 de ne pas trop d\u00e9roger de la ligne officielle, et, dans ce cas, de ne pas interf\u00e9rer dans la politique officielle du Pentagone (de l&rsquo;administration) de dissimuler \u00e0 tout prix la visualisation des pertes. (Ce qui est en jeu, en effet, n&rsquo;est pas la connaissance des pertes mais la visualisation : il ne s&rsquo;agit ici que d&rsquo;\u00e9motion, et ce que veut le Pentagone, c&rsquo;est \u00e9viter la r\u00e9action \u00e9motionnelle primaire devant le spectacle des cercueils.)<\/p>\n<\/p>\n<p><p>Cette attitude n&rsquo;est pas nouvelle. Les grands m\u00e9dias am\u00e9ricains ont d\u00e9j\u00e0 \u00e9cart\u00e9 des informations importantes pour suivre la ligne officielle de l&rsquo;administration, de fa\u00e7on voyante, presque tapageuse, depuis le 11 septembre 2001. Par exemple, ils n&rsquo;ont accord\u00e9 qu&rsquo;une couverture mineure, voire ridicule au mouvement anti-guerre avant la guerre. Ils n&rsquo;ont absolument pas relay\u00e9 vers le public am\u00e9ricain l&rsquo;affaire Katharine Gun, en f\u00e9vrier 2003. (Cette affaire d&rsquo;une employ\u00e9e du GCHQ britannique, divulguant des consignes de la NSA au GCHQ pour effectuer des \u00e9coutes clandestines de certaines d\u00e9l\u00e9gations \u00e0 l&rsquo;ONU au moment des d\u00e9bats sur la guerre. L&rsquo;implication massive de la NSA am\u00e9ricaine rendait imp\u00e9rative la diffusion de cette information. S&rsquo;il n&rsquo;y avait pas eu les sites ind\u00e9pendants sur Internet, le public am\u00e9ricain n&rsquo;aurait eu aucune connaissance de cette affaire.)<\/p>\n<\/p>\n<p><p>Dans l&rsquo;affaire de l&rsquo;analyse g\u00e9n\u00e9rale de la corruption en Irak, r\u00e9alis\u00e9e par le CIR (et diffus\u00e9e sur un des relais radio du CIR, MarketPlace, apr\u00e8s la diffusion sur site), on rel\u00e8ve l&rsquo;absence des grands m\u00e9dias (sauf l&rsquo;un de ses commentateurs, Krugman, mais dont on sait bien s&ucirc;r qu&rsquo;il est certainement l&rsquo;un des plus hostiles \u00e0 la ligne officielle).<\/p>\n<\/p>\n<p><p>Dans ces quelques cas \u00e9voqu\u00e9s ici, on peut commencer \u00e0 voir autre chose que des circonstances accidentelles ou \u00e9pisodiques. On peut commencer \u00e0 avancer l&rsquo;id\u00e9e que les r\u00e9seaux Internet, avec leurs sites ind\u00e9pendants et dissidents, poss\u00e8dent d\u00e9sormais des modalit\u00e9s d&rsquo;action et des moyens de diffusion compl\u00e8tement sp\u00e9cifiques. On peut envisager l&rsquo;hypoth\u00e8se qu&rsquo;on peut les consid\u00e9rer comme bien autre chose qu&rsquo;une force de r\u00e9action \u00e0 l&rsquo;information officielle.<\/p>\n<\/p>\n<p><h2 class=\"titleset_b.deepblue\" style=\"color:#0f3955; font-size:1.65em; font-variant:small-caps\">Une \u00e9volution g\u00e9n\u00e9rale et r\u00e9volutionnaire<\/h2>\n<\/p>\n<p><p>Si nous d\u00e9crivons ici des circonstances am\u00e9ricaines, ou anglo-saxonnes plus pr\u00e9cis\u00e9ment, c&rsquo;est parce que c&rsquo;est dans cet univers que les choses \u00e9voluent de la fa\u00e7on la plus significative.<\/p>\n<\/p>\n<p><p>En Europe, les choses sont moins marquantes dans le sens qu&rsquo;on d\u00e9crit ici, mais tout aussi significatives. Il y a un foss\u00e9 consid\u00e9rable entre le r\u00e9seau de l&rsquo;information dite \u00ab\u00a0grand public\u00a0\u00bb, dans les m\u00e9dias classiques, et le r\u00e9seau de la nouvelle information alternative.<\/p>\n<\/p>\n<p><p>Dans le premier, les affaires irakiennes, les soubresauts de la politique am\u00e9ricaine, sont suivis de loin en loin et de fa\u00e7on tr\u00e8s superficielle, en s&rsquo;en tenant aux aspects spectaculaires. Certains jours, les contenus des journaux t\u00e9l\u00e9vis\u00e9s et des bulletins radios par rapport aux documents disponibles sur Internet pr\u00e9sentent une distorsion consid\u00e9rable. Il est remarquable que les grands m\u00e9dias, surtout en Europe, s&rsquo;attachent de plus en plus aux informations nationales vues dans un sens r\u00e9gional et local, avec la seule exception des nouvelles europ\u00e9ennes qui ne concernent que l&rsquo;apparence institutionnelle et quasiment jamais la r\u00e9alit\u00e9. Cela laisse le champ libre \u00e0 Internet comme dispensateur des informations internationales, consid\u00e9r\u00e9es d&rsquo;un point de vue tr\u00e8s ind\u00e9pendant, tr\u00e8s exigeant, parfois tr\u00e8s pol\u00e9mique.<\/p>\n<\/p>\n<p><p>Ce qui appara&icirc;t aujourd&rsquo;hui, qui fait une diff\u00e9rence de substance, c&rsquo;est une certaine disparition de la concurrence entre Internet et l&rsquo;information \u00ab\u00a0officielle\u00a0\u00bb, comme il y avait nettement du temps de la guerre du Kosovo. Les grands m\u00e9dias classiques, prisonniers des int\u00e9r\u00eats \u00e9conomiques puis ayant justifi\u00e9 cet emprisonnement par une id\u00e9ologie conformiste (disons la \u00ab\u00a0pens\u00e9e unique\u00a0\u00bb, \u00e0 la fois hyper-lib\u00e9rale, pro-am\u00e9ricaine, moralisante, etc), tendent aujourd&rsquo;hui \u00e0 d\u00e9politiser leur information devant l&rsquo;impossibilit\u00e9 d&rsquo;\u00e9carter les informations n&rsquo;entrant pas dans leur sch\u00e9ma d&rsquo;intervention (l&rsquo;Irak).<\/p>\n<\/p>\n<p><p>Bien s&ucirc;r, nous tra\u00e7ons l\u00e0 une tendance g\u00e9n\u00e9rale. Il n&rsquo;y a pas de fronti\u00e8re brutale et les exceptions sont multiples mais elles confirment n\u00e9anmoins la r\u00e8gle nouvelle. Il y a d\u00e9sormais deux univers de l&rsquo;information, ou, dans tous les cas, deux cadres form\u00e9s qui vont tendre \u00e0 se d\u00e9velopper jusqu&rsquo;\u00e0 former effectivement deux univers de l&rsquo;information. Les diverses affaires signal\u00e9es ici montrent que les r\u00e9seaux ind\u00e9pendants sur Internet sont devenus des partenaires majeurs, avec des capacit\u00e9s et des initiatives journalistiques d&rsquo;investigation qui d\u00e9passent souvent celles des grands r\u00e9seaux.<\/p>\n<\/p>\n<p><p>Cette situation des \u00ab\u00a0deux univers\u00a0\u00bb fait liti\u00e8re de toute esp\u00e9rance d&rsquo;une \u00ab\u00a0information objective\u00a0\u00bb. Cela peut \u00eatre per\u00e7u comme un grave revers par ceux qui s&rsquo;en tiennent aux th\u00e9ories ou qui moralisent \u00e0 ce propos. Ce n&rsquo;est pas du tout notre cas. Dans la situation actuelle, l&rsquo;existence d&rsquo;une \u00ab\u00a0information objective\u00a0\u00bb signifierait simplement que l&rsquo;information \u00ab\u00a0officielle\u00a0\u00bb (celle des autorit\u00e9s en place) est devenue l&rsquo;information tout court, c&rsquo;est-\u00e0-dire l'\u00a0\u00bbinformation objective\u00a0\u00bb en question. Nous serions totalement prisonniers d&rsquo;un univers compl\u00e8tement \u00e0 la disposition des autorit\u00e9s en place. On a vu cette situation se mettre en place aux USA aussit\u00f4t apr\u00e8s le 11 septembre, lorsque les grands m\u00e9dias furent simplement les relais de l&rsquo;information officielle. Cette situation n&rsquo;a pas compl\u00e8tement chang\u00e9, elle s&rsquo;est simplement nuanc\u00e9e, notamment sous la pression des r\u00e9alit\u00e9s (il est difficile de continuer, aujourd&rsquo;hui, \u00e0 saluer l&rsquo;affaire irakienne comme justifi\u00e9e, honn\u00eate, bien faite, utile, etc). Mais les grands m\u00e9dias am\u00e9ricains ne sont pas vraiment revenus sur la suj\u00e9tion aux autorit\u00e9s qu&rsquo;ils ont compl\u00e8tement accept\u00e9es juste apr\u00e8s le 11 septembre. S&rsquo;il n&rsquo;y avait pas Internet et son \u00ab\u00a0deuxi\u00e8me univers\u00a0\u00bb, ce serait cela, l'\u00a0\u00bbinformation objective\u00a0\u00bb.<\/p>\n<\/p>\n<p><p>Il y a une \u00e9volution de substance qui met d\u00e9sormais ce qui \u00e9tait le ph\u00e9nom\u00e8ne de l&rsquo;information sur Internet dans une cat\u00e9gorie qui n&rsquo;est plus celle du &laquo; <em>fait extraordinaire<\/em> &raquo; (d\u00e9finition de \u00ab\u00a0ph\u00e9nom\u00e8ne\u00a0\u00bb). L&rsquo;information sur Internet est en train de s&rsquo;institutionnaliser, dans le bon sens du mot certes, parce qu&rsquo;Internet \u00e9chappe par d\u00e9finition aux cha&icirc;nes habituelles de l&rsquo;institution (les exigences id\u00e9ologiques des contraintes \u00e9conomiques). Cet \u00e9v\u00e9nement ne va plus cesser de prendre de l&rsquo;ampleur et va bouleverser les perspectives de notre situation.<\/p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Pr\u00e9cision Ci-dessous, nous publions le texte de la rubrique Contexte de de defensa du 10 mai 2004. Nous pensons que ce texte \u00e9clairera un aspect de nos commentaires sur le mea culpa du glorieux New York Times, \u00e0 propos de sa couverture tr\u00e8s professionnelle des \u00e9v\u00e9nements menant \u00e0 la guerre en Irak. ______________________________ Notre samizdat&hellip;&nbsp;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","footnotes":"","jetpack_post_was_ever_published":false},"categories":[3],"tags":[3015,2631,60,2622,4298,2984,4299,3014],"class_list":["post-65987","post","type-post","status-publish","format-standard","hentry","category-analyse","tag-communication","tag-de","tag-internet","tag-la","tag-maturite","tag-samizdat","tag-sources","tag-systeme"],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/65987","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/comments?post=65987"}],"version-history":[{"count":0,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/65987\/revisions"}],"wp:attachment":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/media?parent=65987"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/categories?post=65987"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/tags?post=65987"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}