{"id":65989,"date":"2004-06-01T00:00:00","date_gmt":"2004-06-01T00:00:00","guid":{"rendered":"https:\/\/new.dedefensa.org\/index.php\/2004\/06\/01\/la-peur-du-terrorisme-est-en-train-de-gagner-la-guerre-du-terrorisme-une-drole-devolution-pour-une-drole-de-guerre\/"},"modified":"2004-06-01T00:00:00","modified_gmt":"2004-06-01T00:00:00","slug":"la-peur-du-terrorisme-est-en-train-de-gagner-la-guerre-du-terrorisme-une-drole-devolution-pour-une-drole-de-guerre","status":"publish","type":"post","link":"https:\/\/new.dedefensa.org\/index.php\/2004\/06\/01\/la-peur-du-terrorisme-est-en-train-de-gagner-la-guerre-du-terrorisme-une-drole-devolution-pour-une-drole-de-guerre\/","title":{"rendered":"<strong><em>La peur du terrorisme est en train de \u201cgagner la guerre\u201d du terrorisme, \u2014 une dr\u00f4le d&rsquo;\u00e9volution pour une \u201cdr\u00f4le de guerre\u201d<\/em><\/strong>"},"content":{"rendered":"<p><h2 class=\"common-article\">La peur du terrorisme est en train de gagner la guerre du terrorisme,  une dr\u00f4le d&rsquo;\u00e9volution pour une dr\u00f4le de guerre <\/h2>\n<\/p>\n<p><\/p>\n<p><p>\tDe fa\u00e7on assez brutale et peut-\u00eatre significative, la perspective d&rsquo;une attaque terroriste (aux USA essentiellement), voire de ce que certains s&rsquo;avancent \u00e0 nommer une victoire d&rsquo;Al Qa\u00efda, est en train de devenir un \u00e9l\u00e9ment de la situation internationale. Il s&rsquo;agit l\u00e0 d&rsquo;une cons\u00e9quence de la dramatique situation, pour les Am\u00e9ricains, en Irak ; c&rsquo;est un signe que cette d\u00e9route d&rsquo;une guerre qui n&rsquo;avait au d\u00e9part aucun lien avec le terrorisme malgr\u00e9 les constructions virtualistes de l&rsquo;\u00e9quipe GW Bush, finit par s&rsquo;inscrire dans le sch\u00e9ma de la crise g\u00e9n\u00e9rale dont on nous dit qu&rsquo;elle a tout \u00e0 voir avec le terrorisme (virtualisme au second, ou au ni\u00e8me degr\u00e9) ; c&rsquo;est un signe, \u00e9galement, que la d\u00e9route irakienne des USA n&rsquo;en restera pas l\u00e0,  au simple \u00e9chec dans ce pays,  et qu&rsquo;elle aura des r\u00e9percussions internationales et, surtout, nationales aux USA. C&rsquo;est, enfin, un signe que la campagne \u00e9lectorale aux USA est plus que jamais plac\u00e9e devant une perspective inconnue et sans pr\u00e9c\u00e9dent.<\/p>\n<\/p>\n<p><p>\tLorsque des experts asiatiques annoncent que <a href=\"http:\/\/www.theage.com.au\/articles\/2004\/05\/31\/1085855500880.html#\" class=\"gen\">Al Qa\u00efda est en train de gagner la guerre contre la terreur,<\/a> ils veulent signifier surtout que les USA sont en train de la perdre. C&rsquo;est plus significatif et plus facile \u00e0 comprendre, et \u00e0 expliquer d&rsquo;ailleurs, parce que les USA existent bel et bien, tandis que la forme de l&rsquo;existence d&rsquo;Al Qa\u00efda, son \u00e9ventuel \u00e9tat pr\u00e9sent, etc, sont des facteurs extr\u00eamement incertains. D&rsquo;ailleurs, ces experts insistent plus sur les fautes des Am\u00e9ricains que sur une pr\u00e9tendue strat\u00e9gie et\/ou tactique des terroristes d&rsquo;Al Qa\u00efda, qu&rsquo;il serait bien malais\u00e9 de d\u00e9finir. (Les experts \u00ab <em>were speaking at a three-day Asia-Pacific Roundtable on security organised by Malaysia&rsquo;s Institute of Strategic and International Studies (ISIS)<\/em> \u00bb)<\/p>\n<\/p>\n<p><\/p>\n<p><p>\t\u00ab <em>The director of Singapore&rsquo;s Institute of Defence and Strategic Studies, Barry Desker, said al-Qaeda remained resilient and the use of force could not eliminate terror threats.<\/em><\/p>\n<\/p>\n<p><p>\t\u00bb <em>The response cannot be a military one. This is fundamentally a US error, he said, adding that the US-led war on Iraq and subsequent occupation had driven Islamic militants to wage jihad, or holy war, against Washington.<\/em><\/p>\n<\/p>\n<p><p>\t\u00bb <em>Iraq is seen as the epicentre of jihad, he said, adding that al-Qaeda was propagating the view that the US occupation was the manifestation of an evil scheme to dissolve Islamic identity.<\/em><\/p>\n<\/p>\n<p><p>\t\u00bb <em>Noordin Sopiee, Malaysia&rsquo;s ISIS chairman, said the world was losing the war on terror because we have expanded the sea of hatred and expanded the reservoir of deep-seated rage (in the Muslim world).<\/em> \u00bb<\/p>\n<\/p>\n<p><\/p>\n<p><p>\tCette impression g\u00e9n\u00e9rale d&rsquo;une d\u00e9faite am\u00e9ricaine li\u00e9e \u00e0 une campagne irakienne qui n&rsquo;avait au d\u00e9part aucun lien concret avec le terrorisme, comme l&rsquo;ont r\u00e9p\u00e9t\u00e9 sans cesse les adversaires de la guerre, montre la volatilit\u00e9 de l&rsquo;appr\u00e9ciation de ce conflit contre le terrorisme, sa d\u00e9pendance de facteurs compl\u00e8tement irrationnels par rapport \u00e0 (ou par absence de rapports avec) la r\u00e9alit\u00e9, tels notamment les courants d&rsquo;interpr\u00e9tation virtualistes et m\u00e9diatiques. La cons\u00e9quence de cette situation est \u00e9videmment une tr\u00e8s grande incertitude psychologique et une variabilit\u00e9 consid\u00e9rable du jugement qui n&rsquo;est appuy\u00e9 sur aucune certitude concr\u00e8te. D&rsquo;o\u00f9, encore, la vuln\u00e9rabilit\u00e9 de ce jugement \u00e0 des courants g\u00e9n\u00e9raux d&rsquo;appr\u00e9ciation qui ne refl\u00e8tent pas n\u00e9cessairement la soi-disant r\u00e9alit\u00e9 observable. D&rsquo;o\u00f9, d&rsquo;ailleurs, cette question : qu&rsquo;est-ce que la r\u00e9alit\u00e9 observable ? Et la r\u00e9alit\u00e9, d&rsquo;ailleurs ?<\/p>\n<\/p>\n<p><\/p>\n<h3>Une guerre qui est prioritairement, peut-\u00eatre exclusivement psychologique,  comme nous l&rsquo;avons voulue, en fait<\/h3>\n<\/p>\n<p><p>\tChaque jour montre que cette guerre est psychologique en substance, c&rsquo;est-\u00e0-dire que les faits n&rsquo;ont plus aucune valeur d\u00e9cisive ni aucune r\u00e9alit\u00e9 historique, sinon du point de vue de l&rsquo;effet sur la psychologie. La r\u00e9alit\u00e9 le c\u00e8de compl\u00e8tement \u00e0 la perception, avec toutes les manipulations qui vont avec. L&rsquo;historien britannique John Keegan a beau s&rsquo;\u00e9poumoner <a href=\"http:\/\/www.telegraph.co.uk\/opinion\/main.jhtml?xml=\/opinion\/2004\/06\/01\/do0101.xml&#038;sSheet=\/portal\/2004\/06\/01\/ixportal.html\" class=\"gen\">pour rappeler que tout apr\u00e8s-guerre est chaotique<\/a>,  alors, s&rsquo;inqui\u00e8te-t-il avec une fi\u00e8vre significative, pourquoi \u00e9mettre un jugement catastrophique sur l&rsquo;Irak ? Parce que la guerre irakienne n&rsquo;est devenue une vraie guerre que dans l&rsquo;apr\u00e8s-guerre et que les Am\u00e9ricains avaient fait les choses en sorte que la guerre ne pouvait \u00eatre que triomphale et rapidement exp\u00e9di\u00e9e pour \u00eatre la victoire annonc\u00e9e,  sans quoi c&rsquo;est une d\u00e9faite, et pire que le Viet-n\u00e2m, n&rsquo;en d\u00e9plaise \u00e0 l&rsquo;historien Keegan.<\/p>\n<\/p>\n<p><p>\tIl faut \u00e9videmment rappeler, pour bien saisir le sens de la situation, que les Am\u00e9ricains ont voulu, plus encore que les myst\u00e9rieux r\u00e9seaux d&rsquo;Al Qa\u00efda dont on ne sait ni la couleur ni la r\u00e9alit\u00e9, la dimension psychologique de cette guerre. C&rsquo;est eux qui ont install\u00e9 la dimension psychologique du conflit qui va jusqu&rsquo;\u00e0 l&rsquo;ivresse, qui va effectivement jusqu&rsquo;\u00e0 conduire \u00e0 penser que cette guerre n&rsquo;a plus aucune r\u00e9alit\u00e9 d\u00e9cisive que psychologique. Ainsi sont-ils en train de perdre la guerre qu&rsquo;ils ont voulue eux-m\u00eames, qui est la guerre psychologique et la guerre de la repr\u00e9sentation virtualiste. Dans cette guerre-l\u00e0, le conflit irakien devait \u00eatre un triomphe et ce triomphe devait porter un coup fatal au terrorisme, tout cela en aussi peu de temps qu&rsquo;il faut pour lire un article de Richard Perle. Le contraire se produit, et m\u00eame si ce n&rsquo;est pas inattendu ni dramatique au regard de l&rsquo;Histoire ce l&rsquo;est au regard des r\u00e9f\u00e9rences virtualistes qui nous ont \u00e9t\u00e9 impos\u00e9es. Les Am\u00e9ricains ont la guerre qu&rsquo;ils ont voulue et celle-l\u00e0, ils sont en train de la perdre.<\/p>\n<\/p>\n<p><p>\tLes r\u00e9percussions au niveau interne am\u00e9ricain sont consid\u00e9rables. L&rsquo;hypoth\u00e8se d&rsquo;une attaque terroriste (contre les USA) est maintenant un facteur objectif de la campagne \u00e9lectorale, ou, disons, une perception psychologique avec nombre d&rsquo;arri\u00e8re-pens\u00e9es politiques et id\u00e9ologiques qui a \u00e9t\u00e9  objectiv\u00e9e par l&rsquo;abondance du commentaire et du d\u00e9bat.<\/p>\n<\/p>\n<p><\/p>\n<h3>On calcule les cibles et les armes de l&rsquo;attaque : pourquoi pas Houston, Texas, avec une bombe sale ?<\/h3>\n<\/p>\n<p><p>\tD\u00e9sormais, les analystes strat\u00e9giques discutent, non plus de cette possibilit\u00e9 d&rsquo;attaque mais \u00e0 propos de la cible probable de cette attaque. Ainsi, l&rsquo;institut d&rsquo;analyse Stratfor, bas\u00e9 au Texas, pr\u00e9voit <a href=\"http:\/\/www.informationclearinghouse.info\/article6264.htm\" class=\"gen\">la probabilit\u00e9 la plus grande pour une attaque contre Houston, Texas<\/a>. Stratfor estime que cette attaque a la plus grande chance de se faire \u00e0 l&rsquo;aide d&rsquo;une bombe sale. Stratfor s&rsquo;explique en un langage impressionnant de rationalit\u00e9.<\/p>\n<\/p>\n<p><\/p>\n<p><p>\t\u00ab <em>The timing for an attack within the United States is nearly perfect: while Americans are engrossed with Iraq, presidential politics and the rising price of oil. Logic dictates that cells are in place and awaiting a signal to act; as in the recent attack in the Saudi city of Yanbu, operatives could have had time to infiltrate the potential target, observing the lay of the land and the routines of security forces.<\/em> <\/p>\n<\/p>\n<p><p>\t\u00bb <em>Although Stratfor believes that strikes could be carried out against multiple targets of opportunity, certain factors  including time and al Qaeda&rsquo;s targeting criteria  lead us to conclude that Houston, Texas, is near the top of the list. Not only is it home to much of the nation&rsquo;s oil infrastructure, which carries significant economic implications, but it also is a city of 5 million people  and the home of former President George H.W. Bush. A strike here would lend a personal nature to the attack that would send a clear message across the desk of President George W. Bush.<\/em> <\/p>\n<\/p>\n<p><p>\t\u00bb <em>In our view, the strike would be sophisticated and spectacular. It likely would involve either a dirty bomb deployed within the city, or a conventional attack against oil infrastructure, carried out on the scale of Sept. 11.<\/em> <\/p>\n<\/p>\n<p><p>\t\u00bb <em>In this case, we believe a truck bomb is the most likely delivery mechanism  perhaps a stolen delivery van, helping to mask the driver&rsquo;s intentions. This scenario was discussed by a sleeper cell in New York City before the first World Trade Center attack in 1993, and al Qaeda has shown a tendency to return to previous attack plans. The assailants might use a ramming car to break through perimeter fences while either shooting or running over security guards. However, it also is feasible that they could use legitimate company identification cards in order to slip past the guards. Once near the target, the explosive would be detonated, killing the attack team.<\/em> \u00bb<\/p>\n<\/p>\n<p><\/p>\n<h3>Quelles cons\u00e9quences une attaque aurait-elle sur les pr\u00e9sidentielles? C&rsquo;est de plus en plus compliqu\u00e9<\/h3>\n<\/p>\n<p><p>\tD\u00e9sormais, une sorte de science conjoncturelle s&rsquo;impose, qui est <a href=\"http:\/\/www.newsday.com\/news\/politics\/ny-usterr0531,0,2064973.story\" class=\"gen\">celle de l&rsquo;analyse des effets d&rsquo;une attaque terroriste contre les USA sur l&rsquo;issue de la campagne \u00e9lectorale<\/a>.<\/p>\n<\/p>\n<p><p>\tDu coup, la perspective se complique. Jusqu&rsquo;alors, il n&rsquo;\u00e9tait question que d&rsquo;effets d\u00e9cisifs d&rsquo;une possible attaque dans le sens d&rsquo;une victoire de GW ; la chose \u00e9tait si compl\u00e8tement acquise qu&rsquo;on envisageait \u00e9videmment que cette attaque pourrait bien \u00eatre le r\u00e9sultat d&rsquo;un montage provocateur de l&rsquo;administration elle-m\u00eame. Aujourd&rsquo;hui, cette perspective est elle-m\u00eame largement disput\u00e9e, ce qui implique que d&rsquo;\u00e9ventuels provocateurs ne sauraient m\u00eame plus s&rsquo;il est avantageux de monter une fausse attaque, ou de susciter une vraie, etc La sp\u00e9culation virtualiste finirait donc par paralyser m\u00eame l&rsquo;art \u00e9trange de la manipulation et de la provocation.<\/p>\n<\/p>\n<p><\/p>\n<p><p>\t\u00ab <em>Most analysts believe a new terrorist attack on U.S. soil also would increase support for Bush, at least in the short run, as Americans follow the time-honored instinct of rallying around the president in a crisis.<\/em><\/p>\n<\/p>\n<p><p>\t\u00bb <em>But much that has already happened in this year&rsquo;s campaign has confounded the conventional wisdom  and the terrorism issue may prove equally unpredictable.<\/em><\/p>\n<\/p>\n<p><p>\t()<\/p>\n<\/p>\n<p><p>\t\u00bb <em>Baker, the Rutgers scholar, said the likely reaction of U.S. voters would be quite different than in Spain. Rather than seeming to accede to what the terrorists want, I think we would show much greater defiance, he said. Our response would be, find somebody to bomb.<\/em><\/p>\n<\/p>\n<p><p>\t\u00bb <em>Most analysts and pollsters said a terrorist attack shortly before the election would probably increase support for Bush. But one occurring earlier might not, they said, because the initial rally-&#8217;round-the-president reaction would have time to fade  and be supplanted by controversy about whether the administration had done an effective job of guarding against an attack.<\/em><\/p>\n<\/p>\n<p><p>\t\u00bb <em>Zogby, who is something of a maverick in his field, said he thought this conventional wisdom was wrong. The closer an attack occurs to Election Day, he said, the less support Bush would gain from it.<\/em><\/p>\n<\/p>\n<p><p>\t\u00bb <em>If it happens in the next couple of months, it is to the benefit of the president, Zogby said. If it happens after the Democratic convention, after Kerry successfully defines himself as a credible candidate &#8230; it could actually backfire on the president.<\/em> \u00bb<\/p>\n<\/p>\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>La peur du terrorisme est en train de gagner la guerre du terrorisme, une dr\u00f4le d&rsquo;\u00e9volution pour une dr\u00f4le de guerre De fa\u00e7on assez brutale et peut-\u00eatre significative, la perspective d&rsquo;une attaque terroriste (aux USA essentiellement), voire de ce que certains s&rsquo;avancent \u00e0 nommer une victoire d&rsquo;Al Qa\u00efda, est en train de devenir un \u00e9l\u00e9ment&hellip;&nbsp;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","footnotes":"","jetpack_post_was_ever_published":false},"categories":[3],"tags":[],"class_list":["post-65989","post","type-post","status-publish","format-standard","hentry","category-analyse"],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/65989","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/comments?post=65989"}],"version-history":[{"count":0,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/65989\/revisions"}],"wp:attachment":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/media?parent=65989"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/categories?post=65989"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/tags?post=65989"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}