{"id":65990,"date":"2004-06-01T00:00:00","date_gmt":"2004-06-01T00:00:00","guid":{"rendered":"https:\/\/new.dedefensa.org\/index.php\/2004\/06\/01\/seize-mois-plus-tard-le-mois-quils-voudraient-decisif\/"},"modified":"2004-06-01T00:00:00","modified_gmt":"2004-06-01T00:00:00","slug":"seize-mois-plus-tard-le-mois-quils-voudraient-decisif","status":"publish","type":"post","link":"https:\/\/new.dedefensa.org\/index.php\/2004\/06\/01\/seize-mois-plus-tard-le-mois-quils-voudraient-decisif\/","title":{"rendered":"<strong><em>Seize mois plus tard, le mois qu&rsquo;ils voudraient d\u00e9cisif<\/em><\/strong>"},"content":{"rendered":"<p><h2 class=\"common-article\">Seize mois plus tard, le mois qu&rsquo;ils voudraient d\u00e9cisif<\/h2>\n<\/p>\n<p><\/p>\n<p><p>\t1er juin 2004  Juin 2004 est le mois d\u00e9cisif, disent-ils, \u00e9voquant le date du 30 et le transfert de souverainet\u00e9. Il y a seize mois, l&rsquo;attaque contre et la prise de Bagdad \u00e9taient \u00e9galement d\u00e9crites comme d\u00e9cisives. Dont acte. (En clair : pour le 30 juin, on verra.)<\/p>\n<\/p>\n<p><p>\tIl y a seize mois, \u00e9galement, on nous disait que la France, notamment et plus particuli\u00e8rement elle, et surtout elle, ne perdait rien pour attendre. Il \u00e9tait temps, disaient les commentateurs, jusqu&rsquo;aux plus hupp\u00e9s, et particuli\u00e8rement en France, que la France rentre dans le rang et se mette sur les rangs pour passer \u00e0 la soupe,  comprendre : demander humblement et esp\u00e9rer quelques reliefs du festin que promettait d&rsquo;\u00eatre la reconstruction de l&rsquo;Irak.<\/p>\n<\/p>\n<p><p>\tCes temps sont donc impr\u00e9visibles.<\/p>\n<\/p>\n<p><p>\tQu&rsquo;on mesure le dilemme du <em>Monde<\/em> du 28 mai. Il avait, en page int\u00e9rieure (2), <a href=\"http:\/\/www.lemonde.fr\/web\/article\/0,1-0@2-3210,36-366589,0.html\" class=\"gen\">un article de synth\u00e8se sur la situation diplomatique autour de l&rsquo;Irak<\/a>, avec notamment les USA demandant l&rsquo;aide de l&rsquo;ONU. Le titre indiquait clairement vers o\u00f9 penchait la balance du rapport des forces : \u00ab <em>La communaut\u00e9 internationale pose ses conditions \u00e0 George Bush.<\/em> \u00bb Vu l&rsquo;importance du propos, on d\u00e9cida de reprendre l&rsquo;article et l&rsquo;id\u00e9e, et le titre, en manchette \u00e0 la une. Mais faire deux lignes avec un tel titre est impossible, notamment avec cette expression longuette de communaut\u00e9 internationale (il faudra songer \u00e0 lui trouver un acronyme parlant pour aider les r\u00e9dacteurs des titres de manchette). On choisit donc l&rsquo;audace de la r\u00e9alit\u00e9 : \u00ab <em>Chirac pose ses conditions \u00e0 George Bush.<\/em> \u00bb Curieuse ironie, on rejoignait effectivement la r\u00e9alit\u00e9 car nul ne devrait ignorer que, dans ces batailles diplomatiques sur ce sujet aujourd&rsquo;hui, la France est, contre les USA, ma\u00eetresse du jeu.<\/p>\n<\/p>\n<p><p>\tNous y revoici donc : seize mois plus tard, la France est plus que jamais ma\u00eetresse du jeu. Remercions la confusion du d\u00e9bat politique en France, qui n&rsquo;a pas permis de d\u00e9gager une pression assez forte pour que le gouvernement c\u00e8de et aille \u00e0 Canossa en avril-mai 2003. Le propos en eut \u00e9t\u00e9 moins net.<\/p>\n<\/p>\n<p><p>\tEntre-temps, certes, il s&rsquo;est pass\u00e9 ce qui s&rsquo;est pass\u00e9, comme dirait de Gaulle parlant de l&rsquo;Irak. Cela permet \u00e0 Chirac de montrer une certaine assurance indulgente et presque compatissante, mais s\u00e9rieuse, et aux Am\u00e9ricains d&rsquo;enrager plus que jamais. Voici comment cela s&rsquo;\u00e9crit (<em>Le Monde<\/em> toujours) :<\/p>\n<\/p>\n<p><\/p>\n<p><p>\t\u00ab <em>Nous avons, avec le projet pr\u00e9sent\u00e9 par les Etats-Unis, une base s\u00e9rieuse, mais une base qu&rsquo;il faut maintenant s\u00e9rieusement am\u00e9liorer, a d\u00e9clar\u00e9 Jacques Chirac, jeudi 27 mai, lors de sa visite au Guatemala \u00e0 propos du projet de r\u00e9solution am\u00e9ricano-britannique sur l&rsquo;Irak.  Et cela, a-t-il ajout\u00e9, afin de permettre au futur gouvernement irakien d&rsquo;avoir une capacit\u00e9 de d\u00e9cision sur l&rsquo;engagement de ses propres forces et sur les op\u00e9rations majeures de la force multinationale. M. Chirac a \u00e9galement pr\u00e9cis\u00e9 que le mandat de la force internationale dirig\u00e9e par les Etats-Unis doit \u00eatre limit\u00e9 dans le temps, \u00e9tant entendu que le gouvernement irakien issu des \u00e9lections pr\u00e9vues en janvier 2005 doit \u00e0 tout moment pouvoir d\u00e9cider d&rsquo;y mettre fin ou d&rsquo;en demander la r\u00e9vision. M. Chirac a insist\u00e9 pour que le futur gouvernement irakien ait une souverainet\u00e9 enti\u00e8re dans tous les domaines, politique, \u00e9conomique, s\u00e9curitaire, judiciaire, diplomatique et qu&rsquo;il aura notamment le contr\u00f4le des ressources naturelles de l&rsquo;Irak, \u00e0 partir du transfert du pouvoir pr\u00e9vu le 30 juin. Il a pr\u00e9venu que sans cela, la situation ne pourra que se d\u00e9t\u00e9riorer davantage.<\/em> \u00bb<\/p>\n<\/p>\n<p><\/p>\n<p><p>\tNon seulement la France est ma\u00eetresse du jeu \u00e0 l&rsquo;ONU, comme en janvier-mars 2003  (car le but de la France, contrairement aux arguments des simplistes r\u00e9alistes, n&rsquo;\u00e9tait pas d&#8217;emp\u00eacher la guerre, chose impossible devant le bulldozer US, mais d&#8217;emp\u00eacher que cette guerre f\u00fbt internationalement sanctifi\u00e9e,  elle \u00e9tait donc bien ma\u00eetresse du jeu) ; mais, plus encore, les d\u00e9bats du mois qui vient \u00e0 l&rsquo;ONU pourraient s&rsquo;av\u00e9rer extr\u00eamement int\u00e9ressants, autant qu&rsquo;en janvier-mars 2003. En bref, ce ne sera pas une simple formalit\u00e9.<\/p>\n<\/p>\n<p><p>\tAlors que les Am\u00e9ricains, comme d&rsquo;habitude, ont des analyses marqu\u00e9es par la suffisance (sur l&rsquo;in\u00e9luctabilit\u00e9 de l&rsquo;acquiescement fran\u00e7ais\/onusien \u00e0 leur demande) et continuent \u00e0 intriguer \u00e0 propos du futur ex\u00e9cutif, les Fran\u00e7ais sont, comme en janvier-mars 2003, bien d\u00e9cid\u00e9s \u00e0 ne pas c\u00e9der sur des exigences essentielles. Cette fois, ils sont mieux soutenus, notamment par les Chinois, qui sugg\u00e8rent des exigences de contr\u00f4le humanitaire des forces US qui les vengeraient des exigences humanitaires am\u00e9ricaines apr\u00e8s Tien An-men. Selon le mot d&rsquo;un diplomate fran\u00e7ais : \u00ab <em>On ne mesure pas combien le d\u00e9bat \u00e0 l&rsquo;ONU pour une r\u00e9solution sanctifiant la nouvelle situation en Irak pourrait tr\u00e8s rapidement se transformer en un affrontement entre les USA et le reste, aussi violent qu&rsquo;au d\u00e9but 2003.<\/em> \u00bb<\/p>\n<\/p>\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Seize mois plus tard, le mois qu&rsquo;ils voudraient d\u00e9cisif 1er juin 2004 Juin 2004 est le mois d\u00e9cisif, disent-ils, \u00e9voquant le date du 30 et le transfert de souverainet\u00e9. Il y a seize mois, l&rsquo;attaque contre et la prise de Bagdad \u00e9taient \u00e9galement d\u00e9crites comme d\u00e9cisives. Dont acte. (En clair : pour le 30 juin,&hellip;&nbsp;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[779,3478],"class_list":["post-65990","post","type-post","status-publish","format-standard","hentry","category-faits-et-commentaires","tag-chirac","tag-onu"],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/65990","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/comments?post=65990"}],"version-history":[{"count":0,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/65990\/revisions"}],"wp:attachment":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/media?parent=65990"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/categories?post=65990"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/tags?post=65990"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}