{"id":66001,"date":"2004-06-11T00:00:00","date_gmt":"2004-06-11T00:00:00","guid":{"rendered":"https:\/\/new.dedefensa.org\/index.php\/2004\/06\/11\/portrait-in-extremis-de-saint-rr-imaginaire-et-commentaires-sur-le-destin-de-lancien-president-des-etats-unis\/"},"modified":"2004-06-11T00:00:00","modified_gmt":"2004-06-11T00:00:00","slug":"portrait-in-extremis-de-saint-rr-imaginaire-et-commentaires-sur-le-destin-de-lancien-president-des-etats-unis","status":"publish","type":"post","link":"https:\/\/new.dedefensa.org\/index.php\/2004\/06\/11\/portrait-in-extremis-de-saint-rr-imaginaire-et-commentaires-sur-le-destin-de-lancien-president-des-etats-unis\/","title":{"rendered":"<strong><em>Portrait in extremis de Saint-RR (Imaginaire et commentaires sur le destin de l&rsquo;ancien pr\u00e9sident des Etats-Unis)<\/em><\/strong>"},"content":{"rendered":"<p><h2 class=\"common-article\">Portrait in extremis de Saint-RR (Imaginaire et commentaires sur le destin de l&rsquo;ancien pr\u00e9sident des Etats-Unis)<\/h2>\n<\/p>\n<p><\/p>\n<p><p>\tD&rsquo;apr\u00e8s nos sources (pas vraiment recoup\u00e9es, certes, contrairement \u00e0 celles du New York <em>Times<\/em>), RR (Ronald Reagan) serait arriv\u00e9 devant Dieu, souriant, triomphant, heureux de continuer \u00e0 vivre en Am\u00e9rique (RR n&rsquo;aurait pas encore compris qu&rsquo;il est mort), b\u00e9at en un mot, et Celui-Ci (Dieu), l\u00e9g\u00e8rement agac\u00e9 il faut dire, lui aurait dit : \u00ab <em>Mais vous, vous? Qui \u00eates-vous, au fond? Regardez-moi dans les yeux, enfin! Cessez de rigoler aux anges! Vous n&rsquo;allez pas \u00eatre un ange-Teflon, j&rsquo;esp\u00e8re?<\/em> \u00bb <\/p>\n<\/p>\n<p><p>\t(Explication : du temps de la premi\u00e8re pr\u00e9sidence, RR \u00e9tait surnomm\u00e9 pr\u00e9sident-Teflon, r\u00e9f\u00e9rence \u00e0 la po\u00eale qui n&rsquo;attache pas, fameuse \u00e0 l&rsquo;\u00e9poque, parce que rien, aucune erreur, aucun scandale de son administration ne semblait devoir s&rsquo;attacher \u00e0 sa personne ni faire baisser son apparent indice de popularit\u00e9 au sommet. <a href=\"http:\/\/www.dedefensa.org\/article.php?art_id=1139\" class=\"gen\">C&rsquo;est faux d&rsquo;ailleurs, RR n&rsquo;\u00e9tait pas si populaire que cela<\/a>, et m\u00eame encore moins. Mais RR, c&rsquo;est-\u00e0-dire l&rsquo;image qu&rsquo;on fabriqua de lui, s&rsquo;arrangea toujours pour laisser faire croire \u00e0 ce propos et dans ce sens. Les m\u00e9dias, avec la libert\u00e9 d&rsquo;expression en sautoir, continuent \u00e0 clamer cette v\u00e9rit\u00e9 d&rsquo;une pr\u00e9tendue popularit\u00e9 \u00e0 partir de chiffres qu&rsquo;on \u00e9voque mais qu&rsquo;on ne cite pas parce qu&rsquo;ils n&rsquo;existent pas. RR \u00e9tait la po\u00eale-Teflon d&rsquo;une fausse r\u00e9alit\u00e9 \u00e0 la place de la vraie. Cela vous rappelle quelque chose, qu&rsquo;on verra plus loin.)<\/p>\n<\/p>\n<p><p>\tPoursuivons cette visite \u00e0 Dieu. Selon nos sources, toujours aussi peu recoup\u00e9es, RR aurait r\u00e9pondu \u00e0 Dieu, le sourire quasiment extatique : \u00ab <em>America is back! God Bless America!<\/em> \u00bb Dieu, vraiment agac\u00e9 il faut avouer, aurait marmonn\u00e9 : \u00ab <em>Mais Bon Dieu, s&rsquo;il y a quelqu&rsquo;un, ici, qui sait qui Dieu b\u00e9nit, c&rsquo;est Moi, Bon Dieu<\/em> \u00bb Mais RR n&rsquo;\u00e9tait plus l\u00e0 pour L&rsquo;entendre, parti voir un film-western avec John Wayne, au cin\u00e9ma <em>Paradisio<\/em>, priant <em>the Lord<\/em> d&rsquo;accorder longue vie \u00e0 Nancy.<\/p>\n<\/p>\n<p><p>\tAinsi en va-t-il de RR, le pr\u00e9sident le plus insaisissable des Temps Modernes, l&rsquo;homme qui oscille, dans les appr\u00e9ciations qu&rsquo;on en a, entre celle du plus grand h\u00e9ros de l&rsquo;histoire am\u00e9ricaine (avec Lincoln, Washington et John Wayne) et celle d&rsquo;un constat abrupt et un peu d\u00e9go\u00fbt\u00e9 de la nullit\u00e9 \u00e0 perte de vue, comme une sorte de d\u00e9sert des Tartares climatis\u00e9.  (Entendez donc ce que Norman Mailer en dit dans un entretien t\u00e9l\u00e9vis\u00e9 : Mailer, qui, au cours d&rsquo;un repas, ne r\u00e9ussit jamais \u00e0 accrocher le regard de RR, ni m\u00eame, en v\u00e9rit\u00e9, \u00e0 lui poser une question, tant il avait l&rsquo;impression d&rsquo;un vide insaisissable en face de lui.) Devinez o\u00f9 se situe notre appr\u00e9ciation, entre ces deux options extr\u00eames Non, non, vous n&rsquo;avez pas devin\u00e9 : notre appr\u00e9ciation est que RR est une blague, qu&rsquo;il n&rsquo;a jamais vraiment exist\u00e9. D&rsquo;o\u00f9 l&#8217;embarras de Dieu (sources recoup\u00e9es, cette fois).<\/p>\n<\/p>\n<p><p>\tEn attendant, voici un floril\u00e8ge de liens, quelques appr\u00e9ciations sur RR aussi diverses que les faces cach\u00e9es et\/ou visibles du pr\u00e9sident-Teflon. Elles montrent que l&rsquo;Am\u00e9rique n&rsquo;a gu\u00e8re chang\u00e9,  on veut dire, que la crise am\u00e9ricaine ne s&rsquo;est gu\u00e8re r\u00e9solue depuis RR qui pr\u00e9tendit la r\u00e9soudre, et que c&rsquo;est m\u00eame plut\u00f4t le contraire. Et que GW, apr\u00e8s tout, a bien m\u00e9rit\u00e9 de RR ; et qu&rsquo;il est, peut-\u00eatre, RR r\u00e9incarn\u00e9, Dieu s&rsquo;\u00e9tant laiss\u00e9 convaincre par faiblesse et go\u00fbt de la tranquillit\u00e9, assortie d&rsquo;une tentative de corruption, \u00e0-la-Enron.<\/p>\n<\/p>\n<p><\/p>\n<h3>Comment RR a, sous nos yeux \u00e9blouis et \u00e9bahis, litt\u00e9ralement chang\u00e9 le monde<\/h3>\n<\/p>\n<p><p>\tD&rsquo;abord il y a le classique des classiques, le Cantique des Cantiques si vous voulez : RR avait l&rsquo;air d&rsquo;un abruti complet mais c&rsquo;est vous, Europ\u00e9ens, snobs, qui n&rsquo;y comprenez rien. <a href=\" http:\/\/www.guardian.co.uk\/usa\/story\/0,12271,1233808,00.html\" class=\"gen\">RR a chang\u00e9 le monde, point final<\/a>.<\/p>\n<\/p>\n<p><p>\tCela n&rsquo;est peut-\u00eatre pas si faux,  simplement il faut voir pourquoi, comment et \u00e0 quoi \u00e7a sert. Martin Kettle : \u00ab <em>Reagan&rsquo;s presidency marked a series of decisive tipping points in American life. The country he left behind in 1989 was very different from the one he inherited in 1981<\/em> \u00bb<\/p>\n<\/p>\n<p><\/p>\n<p><p>\t() America \u00ab <em>became, quite simply, a nation which grew away from Europe. It grew away from us economically, militarily, culturally and, above all, emotionally. It left us in a different place, not always conscious of the decisiveness of the change that Reagan had wrought, and in many cases underestimating the continuing dynamic of what he had bequeathed, particularly under Bush since 9\/11. It left Europeans, including the British, needing to rethink our own place in the world, to answer a new set of harsher Who are we? questions. Reagan changed America forever, but in doing so he changed us forever too.<\/em> \u00bb<\/p>\n<\/p>\n<p><\/p>\n<h3>RR est un super-dur, un cador, l&rsquo;homme qui nous a install\u00e9s un capitalisme-Terminator apr\u00e8s nous avoir sauv\u00e9s de l&rsquo;Ogre communiste<\/h3>\n<\/p>\n<p><p>\tIl y a ensuite le super-dur, le guerrier de la Guerre froide et du capitalisme triomphant, l&rsquo;homme de l&rsquo;apocalypse hyperlib\u00e9rale. Derri\u00e8re son sourire niais et st\u00e9r\u00e9otyp\u00e9, RR cachait une volont\u00e9 de Marine, une \u00e2me de <em>Special Force<\/em> du capitalisme, une sorte de Stallone cous-main multipli\u00e9 par Schwarzenegger. C&rsquo;est le chroniqueur Spengler de <em>atimes.com<\/em>, c\u00e9l\u00e8bre pour ses professions de foi social-darwinistes et imp\u00e9rialistes, qui trace un portrait tr\u00e8s convainquant dans ce sens de RR, <a href=\"http:\/\/atimes.com\/atimes\/Front_Page\/FF08Aa01.html\" class=\"gen\">dans un texte sur atimes.com, le 8 juin<\/a>.<\/p>\n<\/p>\n<p><p>\tSpengler attribue \u00e0 RR la vertu supr\u00eame, du point de vue d&rsquo;un capitaliste pur et dur, de la <em>destructive creation<\/em>. A cet \u00e9gard, le portrait que fait Spengler n&rsquo;est pas faux, lorsqu&rsquo;il d\u00e9crit l&rsquo;administration RR comme une administration aventuri\u00e8re, qui a chang\u00e9 les structures m\u00eame de l&rsquo;Am\u00e9rique. Lorsque Spengler nous rapporte son d\u00e9go\u00fbt pour le \u00ab <em>oily<\/em> \u00bb George Tenet, par opposition \u00e0 son admiration pour son pr\u00e9d\u00e9cesseur de l&rsquo;\u00e8re RR, Bill Casey, capable de poser un microphone dans le bureau d&rsquo;une personnalit\u00e9 qu&rsquo;il venait officiellement visiter, on comprend ce qu&rsquo;il veut dire.<\/p>\n<\/p>\n<p><\/p>\n<p><p>\t\u00ab <em>Reagan possessed the strategic vision to brush aside the objections and plunge ahead. His economic policies embodied \u00a0\u00bbcreative destruction\u00a0\u00bb, the chaotic emergence of new firms and methods to challenge the old. Conventional economics thinking restricted its attention to large corporations that depend on the debt markets. Under Reagan, employment at the 500 largest US corporations shrank, but the explosion of small businesses more than made up for it. After the first round of Reagan tax cuts, which nearly halved the top tax rate, the value of the American stock market doubled in 1984. Creative destruction transformed the landscape of the American economy. The microchip transformed domestic life as well as warfare, and America regained a dominant position in the global economy. Reagan&rsquo;s strategic policy stemmed from a similar kind of creative destruction. Under the old containment doctrine, the United States sought to maintain stability while the Soviets stirred the pot. As I wrote some years ago, The elder Bush and advisers such as James Baker and Brent Scowcroft, schooled in the Cold War, flinched at the thought of instability. Any regime, no matter how corrupt and oppressive, merited American backing, as long it was our bastard&rsquo;, as Franklin Roosevelt qualified Nicaragua&rsquo;s strongman of the 1930s. It is a stretch to accuse such men of having a philosophy. Their strategic reflex came from the simple fact that the Soviet Union stood to gain from any instability outside its immediate sphere of influence. The more chaos, the more options open to the Kremlin. A coup in Western Asia, a civil war somewhere in the Pacific Rim, a war between India and Pakistan, an insurgency in Latin America gave Russia a chance to get involved. Russia had unlimited upside and little downside (Geopolitics in the light of Option Theory, Jan 26, 2002).<\/em><\/p>\n<\/p>\n<p><p>\t\u00bb <em>Reagan and his band of wild-eyed radicals put the burden of uncertainty onto the Russians. The sclerotic Soviet Union, they believed, could not match America&rsquo;s pace of technological innovation in armaments. Not only the Star Wars anti-missile project, but avionics, smart weapons, and a host of other improvements convinced the Russian military that it could not win a war against the United States.<\/em> \u00bb<\/p>\n<\/p>\n<p><\/p>\n<p><p>\tEn fait, ce que Spengler n&rsquo;\u00e9nonce pas de cette fa\u00e7on, parce que, sans doute, pour lui, cette \u00e9volution ne m\u00e9rite pas fondamentalement une analyse critique, c&rsquo;est que la r\u00e9volution reaganienne fut bien d&rsquo;entreprendre une privatisation fondamentale de l&rsquo;Am\u00e9rique, et notamment de ses structures gouvernementales et de s\u00e9curit\u00e9. A Partir de Reagan, le gouvernement ne fut pas moins gros (il y avait plus de fonctionnaires quand il partir que lorsqu&rsquo;il arriva), mais il eut beaucoup moins de pouvoirs et encore moins d&rsquo;autorit\u00e9, tout cela \u00e0 l&rsquo;avantage de l&rsquo;argent priv\u00e9, des grands groupes capitalistes et des groupes de pression vendant l&rsquo;id\u00e9ologie gr\u00e2ce aux relations publiques (type n\u00e9o-conservateurs).<\/p>\n<\/p>\n<p><p>\tRR est le p\u00e8re direct de l&rsquo;actuelle administration GW et de son orientation hyper-privatis\u00e9e, jusque dans les moindres d\u00e9tails op\u00e9rationnels (pr\u00e9sence de soldats-mercenaires en tr\u00e8s grand nombre en Irak, par exemple). Il est juste de dire que RR n&rsquo;a pas eu peur de se saisir du chaos et de s&rsquo;en servir ; il serait n\u00e9cessaire de compl\u00e9ter l&rsquo;id\u00e9e en observant que RR a, ce faisant, install\u00e9 le chaos au cur de la puissance am\u00e9ricaine, tant pour sa d\u00e9finition propre que pour son action. Clinton a largement accentu\u00e9 cette tendance, jusqu&rsquo;\u00e0 GW.<\/p>\n<\/p>\n<p><p>\tPour le reste de ce que nous dit Spengler, on est oblig\u00e9 de constater qu&rsquo;il y a beaucoup \u00e0 boire et pas mal \u00e0 manger. Notamment, son appr\u00e9ciation sur l&rsquo;action de RR vis-\u00e0-vis de l&rsquo;URSS est plus que contestable et renvoie \u00e0 des clich\u00e9s de l&rsquo;\u00e9poque sans correction. Placer le discours sur l&rsquo;<em>Evil Empire<\/em> en 1982 est faux (il eut lieu le 9 mars 1983) et affirmer que Reagan fut plus impopulaire que GW, et par cons\u00e9quent les relations USA-Europe plus mauvaises qu&rsquo;elles ne sont aujourd&rsquo;hui l&rsquo;est \u00e9galement . (\u00ab <em>When Reagan made clear his intention to bury the \u00a0\u00bbevil empire\u00a0\u00bb (as he characterized it before the Commons in 1982), a wave of shock and indignation spread among the Atlantic elite unimaginable to those who where not there at the time. Europe&rsquo;s disgust at George W Bush is a gentle June shower compared to the tempests of 1982.<\/em> \u00bb)<\/p>\n<\/p>\n<p><p>\tAffirmer \u00e9galement que les Sovi\u00e9tiques \u00e9taient en 1979-80 partout en position de domination (pour constater que RR changea cela, bien entendu) revient \u00e9galement \u00e0 s&rsquo;en tenir aux clich\u00e9s de l&rsquo;\u00e9poque. Depuis, la r\u00e9alit\u00e9 s&rsquo;est faite jour pour nous dire que <a href=\"http:\/\/www.dedefensa.org\/article.php?art_id=877\" class=\"gen\">les Sovi\u00e9tiques \u00e9taient morts de peur<\/a>. Comme position de domination, on fait mieux. N\u00e9anmoins, cette l\u00e9gende de RR sauvant l&rsquo;Occident en 1981-85, notamment par un gargantuesque programme de r\u00e9armement dont on continue aujourd&rsquo;hui \u00e0 go\u00fbter les fruits amers avec le gaspillage universel du Pentagone, la l\u00e9gende a la peau dure et survit comme un des dogmes de l&rsquo;histoire officielle US.<\/p>\n<\/p>\n<p><p>\tLa croisade contre l&rsquo;Empire de RR ressort moins d&rsquo;une vision strat\u00e9gique que d&rsquo;une logique d&rsquo;entreprise, due \u00e0 cette privatisation de la puissance am\u00e9ricaine, et elle s&rsquo;appuie sur les actions d&rsquo;hommes qui agirent plus comme des <em>businessmen<\/em> agressifs (Bill Casey, patron de la CIA, comme on l&rsquo;a vu) que comme des fonctionnaires et des agents du service public. Dans ses rapports avec l&rsquo;URSS, au contraire, RR eut une attitude extraordinairement ambigu\u00eb et chaotique. Son r\u00f4le dans l&rsquo;effondrement de l&rsquo;URSS est, <a href=\"http:\/\/www.dedefensa.org\/article.php?art_id=1136\" class=\"gen\">comme on l&rsquo;a vu par ailleurs<\/a>, extr\u00eamement contest\u00e9 et effectivement contestable, et bien plus encore.<\/p>\n<\/p>\n<p><\/p>\n<h3>RR a invent\u00e9 le virtualisme pour le plus grand plaisir de l&rsquo;Am\u00e9rique enfin retrouv\u00e9e : fabrication garantie authentique en faux-pl\u00e2tre, en faux-marbre, en fausses-dents et en faux-semblants<\/h3>\n<\/p>\n<p><p>\tMaintenant soyons s\u00e9rieux, voici certainement l&rsquo;aspect essentiel qu&rsquo;il faut retenir de RR : il est un peu, beaucoup, passionn\u00e9ment l&rsquo;inventeur du virtualisme. Venant de Hollywood, amateur de bandes dessin\u00e9es (c&rsquo;est ce qui le convainquit de lancer la SDI\/<em>Star War<\/em>), il n&rsquo;y a rien l\u00e0 pour nous \u00e9tonner. L&rsquo;homme est fabriqu\u00e9 de A \u00e0 Z, sa politique aussi, et \u00e9galement l&rsquo;Am\u00e9rique qu&rsquo;il installa. <a href=\"http:\/\/www.guardian.co.uk\/usa\/story\/0,12271,1232950,00.html\" class=\"gen\">L&rsquo;\u00e9ditorial du Guardian<\/a> du 7 juin nous le dit bien : \u00ab <em>Mr Reagan had a rose-tinted view of America&rsquo;s past and America&rsquo;s future alike. He elided things he saw in the movies with reality. At times he could seem oblivious to the facts; when he gave evidence on Iran-Contra in 1990 he used the phrases \u00a0\u00bbI don&rsquo;t recall\u00a0\u00bb or \u00a0\u00bbI don&rsquo;t remember\u00a0\u00bb a total of 130 times. He was the bane of biographers, one of whom, Edmund Morris, actually felt himself driven to produce a part-fictionalised account in order to make the former president more understandable.<\/em> \u00bb<\/p>\n<\/p>\n<p><p>\tBien. RR a invent\u00e9 l&rsquo;optimisme au temps o\u00f9 l&rsquo;Am\u00e9rique en avait besoin, para\u00eet-il. Pauvre Am\u00e9rique, nous \u00e9tions si triste pour elle qui broyait du noir. RR vint et plus rien ne fut plus pareil. RR inventa une nouvelle Am\u00e9rique, une nouvelle Histoire, une nouvelle pr\u00e9sidence et ainsi de suite. Il inventa aussi, si l&rsquo;on veut, une autre sorte de g\u00e9nie, une autre fa\u00e7on d&rsquo;\u00eatre un grand homme d&rsquo;\u00c9tat. Il y en a pas mal qui sont satisfaits avec tout cela, qui trouvent m\u00eame que c&rsquo;est grandiose, historique, etc. A ce compte, on comprend <a href=\"http:\/\/www.dedefensa.org\/article.php?art_id=1139\" class=\"gen\">l&rsquo;extraordinaire v\u00e9n\u00e9ration et la vague de conformisme b\u00e9at qui a parcouru les m\u00e9dias am\u00e9ricains et la population<\/a>.<\/p>\n<\/p>\n<p><p>\tEn bref, on ne peut finalement discuter avec s\u00e9rieux d&rsquo;un homme, d&rsquo;une \u00e9poque et d&rsquo;un pays, et du syst\u00e8me qui englobe le tout, qui se sont si manifestement plac\u00e9s en-dehors des r\u00e9f\u00e9rences de l&rsquo;histoire du monde et des habituelles normes de la r\u00e9alit\u00e9. A chacun son choix. Comme on disait du temps du marxisme, RR ce fut un choix de soci\u00e9t\u00e9 ; mais plus d&rsquo;ailleurs, ce fut un choix d&rsquo;une humanit\u00e9, d&rsquo;une psychologie diff\u00e9rentes. C&rsquo;est tellement vrai que <a href=\"http:\/\/www.guardian.co.uk\/usa\/story\/0,12271,1232950,00.html\" class=\"gen\">m\u00eame le souvenir de Reagan est fabriqu\u00e9 de A \u00e0 Z<\/a> et ne laisse place qu&rsquo;\u00e0 une moiti\u00e9, un quart de Reagan, et encore, une moiti\u00e9 ou un quart compl\u00e8tement re-format\u00e9, fabriqu\u00e9 en son et en paille. Cet homme a invent\u00e9 l&rsquo;alphabet complet du virtualisme. <\/p>\n<\/p>\n<p><\/p>\n<p><p>\t\u00ab <em> Visitors to the Ronald Reagan Presidential Library in Simi Valley, California, in the grounds of which the 40th president of the United States will be laid to rest later this month, frequently depart somewhat baffled. The Reagan museum and library are magnificently set out on a matchlessly beautiful hilltop setting north of Los Angeles. The optimistic feel of the visitor experience, with its prominent displays about Mr Reagan&rsquo;s movies and Mrs Reagan&rsquo;s gowns, is undeniably attractive. But there is also something missing. The nitty-gritty documentary political records of the president&rsquo;s toughest moments, the sort of sweaty detail that makes a visit to John Kennedy&rsquo;s or Richard Nixon&rsquo;s presidential libraries so compellingly interesting, is largely absent here. The visitor to Simi Valley emerges feeling extremely benevolent towards Mr Reagan, but without quite knowing what he really did. It is as though he presided over his years in office rather than leaving a conventional political imprint upon them.<\/em> \u00bb<\/p>\n<\/p>\n<p><\/p>\n<h3>T\u00e9moignage particulier d&rsquo;un dur de dur au pr\u00e9sident-Teflon qui sut nous appara\u00eetre comme un dur de dur<\/h3>\n<\/p>\n<p><p>\tCe qui nous ennuie avec Richard Perle, que l&rsquo;on pouvait juger sympathique dans les ann\u00e9es 1980, lorsqu&rsquo;il avait son franc-parler avec ses coll\u00e8gues bureaucrates et pas sa langue dans sa poche avec les journalistes, c&rsquo;est qu&rsquo;arriv\u00e9 au pinacle de sa puissance avant de nous rejouer la balade de la roche tarp\u00e9ienne, il ne cesse de nous faire d\u00e9couvrir de lui des c\u00f4t\u00e9s d\u00e9testables. On conna\u00eet depuis quelques temps le strat\u00e8ge expert vivant dans l&rsquo;opulence des d\u00e9lices des bonnes affaires militaro-industrielles. Nous d\u00e9couvrons d\u00e9sormais l&rsquo;expert strat\u00e8ge rompu aux viles flatteries de Cour, et encore, une Cour d\u00e9mocratique et washingtonienne.<\/p>\n<\/p>\n<p><p>\tNul ne doit ignorer que Perle avait un franc (quoique peut-\u00eatre chaleureux) m\u00e9pris pour RR, dont il connaissait les limites extr\u00eamement chiches. Cela ne l&#8217;emp\u00eache pas d&rsquo;\u00e9crire ceci, qui montre que les n\u00e9o-conservateurs, finalement, n&rsquo;oseront jamais \u00eatre eux-m\u00eames (des lib\u00e9raux-trotskistes, le missile entre les dents), qu&rsquo;il leur faudra toujours s&rsquo;abriter derri\u00e8re une ic\u00f4ne conservatrice, si possible la plus b\u00eate possible pour ne pas avoir trop d&rsquo;ombre et ne tromper personne.<\/p>\n<\/p>\n<p><p>\tVoici donc <a href=\"http:\/\/www.telegraph.co.uk\/opinion\/main.jhtml?xml=\/opinion\/2004\/06\/06\/do0601.xml&#038;sSheet=\/portal\/2004\/06\/06\/ixportal.html\" class=\"gen\">l&rsquo;apologie de RR-Socrate<\/a>, par Perle-Platon.<\/p>\n<\/p>\n<p><\/p>\n<p><p>\t\u00ab <em>Much has been written about the source of Ronald Reagan&rsquo;s policy of re-igniting the political dimension of the Cold War, of challenging the legitimacy of the Soviet leadership, of pushing them until they fell. Theories abound about the influence of this adviser or that, about the authorship of one inflammatory phrase or another. Who was it who wanted to stop the Soviet oil pipeline into Germany? Was Edward Teller behind the SDI? Who penned the phrase evil empire? From inside the administration, the identity of the architect who erected the last grand strategy of the Cold War was clear: it was Reagan himself. And much as those of us who were privileged to advise him might wish to share the recognition of success that will clearly come with the passage of time  liberals are too confused or self-serving to credit the Reagan strategy with the Western victory in the Cold War any time soon  the truth is that Ronald Reagan was singular in understanding, and acting to exploit, the depth of Soviet vulnerability.<\/em> \u00bb<\/p>\n<\/p>\n<p><\/p>\n<h3>Visite aux terres immenses et b\u00e9nies de Dieu de Saint-Ronnie, qui pleurent bruyamment la disparition de RR<\/h3>\n<\/p>\n<p><p>\tNous terminerons par la cerise sur le g\u00e2teau, une r\u00e9flexion de P\u00e9p\u00e9 Escobar, excellent reporteur de <em>atimes.com<\/em>, qui se trouve en reportage aux USA et qui n&rsquo;a pas manqu\u00e9 de nous rapporter <a href=\"http:\/\/atimes.com\/atimes\/Front_Page\/FF08Aa02.html\" class=\"gen\">ses impressions sur Saint Ronnie, le Bien-Nomm\u00e9<\/a>. C&rsquo;est une partie de plus qui irait bien dans le <em>Chronique de l&rsquo;idiotie triomphante<\/em> de Regis Debray.<\/p>\n<\/p>\n<p><p>\tEscobar nous d\u00e9crit ce pays compl\u00e8tement fabriqu\u00e9, absolument artificiel, qui s&rsquo;\u00e9panche en pleurs tr\u00e8s visibles (il faut g\u00e9mir pour \u00eatre bien vu) et en appr\u00e9ciations grotesques de pompe surfaite et de gloire frelat\u00e9e sur le h\u00e9ros en cellulo\u00efd qui nous a quitt\u00e9s. Nous devrions \u00eatre d\u00e9sol\u00e9s de nous laisser aller \u00e0 une telle description caricaturale, sauf qu&rsquo;elle nous est impos\u00e9e par le pays en question et ses manifestations diverses.<\/p>\n<\/p>\n<p><\/p>\n<p><p>\t\u00ab <em>It&rsquo;s a long way from Tampico, Illinois to sainthood. Ronald Wilson Reagan, dead at 93, made it  at least by the standards of the hagiographic, wall-to-wall, mega-festival in his honor, an ongoing psalm until at least the funeral next Friday. For hardcore conservative corporate media, and for conservative-tinted mainstream corporate media, he is now Saint Ronnie, with Nancy playing the part of a stern Virgin Mary. History has not afforded young America enough time to nurture her own St Francis, St Paul or St Matthew. So sainthood is bestowed on dead pop stars and presidents (Richard \u00a0\u00bbI&rsquo;m not a crook\u00a0\u00bb Nixon excluded).<\/em> <\/p>\n<\/p>\n<p><p>\t\u00bb <em>\u00a0\u00bbView the world\u00a0\u00bb is the official slogan of the Sears Tower skydeck in Chicago. Assuming efforts by Osama bin Laden and a few misguided Arab evildoers to bring it down were thwarted by the resolution of true Reagan heir George W Bush and his team, the skyline in the most all-American city of them all may not be such a bad place to, indeed, \u00a0\u00bbview the world\u00a0\u00bb post-Reaganism.<\/em> <\/p>\n<\/p>\n<p><p>\t\u00bb <em>For scriptwriter Peggy Noonan he was a giant. For Senator John McCain he won the Cold War. For NBC&rsquo;s Tom Brokaw he was larger than life. For the Chicago Tribune, he was a revolutionary.<\/em> <\/p>\n<\/p>\n<p><p>\t\u00bb <em>The weekend overlapping of the copy  George W Bush  in Normandy and the original &#8211; Ronald Reagan &#8211; dying at home in California, as observed from Chicago, was enormously engaging, especially considering the Bush neo-conservatives&rsquo; irrational hate of all things French. The first white men to pass through the Chicago River were Frenchmen Louis Jolliet and Father Jacques Marquette. The fabulous collection of the Art Institute of Chicago is a feast of Chagall, Kandinsky, Matisse, Gauguin, Cezanne, Degas and Monet: but Grant Wood&rsquo;s 1930 \u00a0\u00bbAmerican Gothic\u00a0\u00bb would be more to the neo-cons&rsquo; liking. The crowning tower of the magnificent, 1925 Chicago Tribune building borrows its design from the Rouen cathedral in Normandy.<\/em> <\/p>\n<\/p>\n<p><p>\t\u00bb <em>The city of big shoulders could not but give us the skyscraper and the atomic bomb. Reagan himself had big shoulders. Reading the Chicago Tribune at Lou Mitchell&rsquo;s, one of the great American breakfast joints, very close to the official beginning of Route 66, America&rsquo;s Mother Road, one could not but be reminded of the timeless French dictum: \u00a0\u00bbplus ca change &#8230;\u00a0\u00bb<\/em> <\/p>\n<\/p>\n<p><p>\t\u00bb <em>Who said the Reagan era was over? Bush, the candid cowboy, is not really daddy&rsquo;s son &#8230; he is the ideological son of Saint Ronnie. Just like Saint Ronnie, he sold the promise of a simple man, full of good sense, a man who \u00a0\u00bbsays what he does and does what he says\u00a0\u00bb. Just like Saint Ronnie with Santa Barbara, whenever he can he escapes town to cultivate a love affair with his Texas ranch (33 visits to Crawford, all or part of 233 days). Just like Saint Ronnie fought the \u00a0\u00bbevil empire\u00a0\u00bb, Bush fights the \u00a0\u00bbaxis of evil\u00a0\u00bb. And just like Saint Ronnie swore to end communism, he swears he will destroy terrorism.<\/em> \u00bb <\/p>\n<\/p>\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Portrait in extremis de Saint-RR (Imaginaire et commentaires sur le destin de l&rsquo;ancien pr\u00e9sident des Etats-Unis) D&rsquo;apr\u00e8s nos sources (pas vraiment recoup\u00e9es, certes, contrairement \u00e0 celles du New York Times), RR (Ronald Reagan) serait arriv\u00e9 devant Dieu, souriant, triomphant, heureux de continuer \u00e0 vivre en Am\u00e9rique (RR n&rsquo;aurait pas encore compris qu&rsquo;il est mort), b\u00e9at&hellip;&nbsp;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","footnotes":"","jetpack_post_was_ever_published":false},"categories":[3],"tags":[],"class_list":["post-66001","post","type-post","status-publish","format-standard","hentry","category-analyse"],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/66001","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/comments?post=66001"}],"version-history":[{"count":0,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/66001\/revisions"}],"wp:attachment":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/media?parent=66001"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/categories?post=66001"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/tags?post=66001"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}