{"id":66002,"date":"2004-06-14T00:00:00","date_gmt":"2004-06-14T00:00:00","guid":{"rendered":"https:\/\/new.dedefensa.org\/index.php\/2004\/06\/14\/les-tyrannies-de-lideal-le-mal-americain-1\/"},"modified":"2004-06-14T00:00:00","modified_gmt":"2004-06-14T00:00:00","slug":"les-tyrannies-de-lideal-le-mal-americain-1","status":"publish","type":"post","link":"https:\/\/new.dedefensa.org\/index.php\/2004\/06\/14\/les-tyrannies-de-lideal-le-mal-americain-1\/","title":{"rendered":"Les tyrannies de l&rsquo;id\u00e9al : le mal am\u00e9ricain&#8230;"},"content":{"rendered":"<p><h2 class=\"titleset_b.deepgreen\" style=\"color:#75714d; font-size:1.65em; font-variant:small-caps\">Tyrannie de l&rsquo;id\u00e9al : le \u00ab\u00a0mal am\u00e9ricain\u00a0\u00bb<\/h2>\n<\/p>\n<p><p>Nous pr\u00e9sentons ci-apr\u00e8s le texte d&rsquo;une communication extraite du livre \u00e9dit\u00e9 par Jacques Portes, <em>L&rsquo;Am\u00e9rique comme mod\u00e8le, l&rsquo;Am\u00e9rique sans mod\u00e8le<\/em> (Diffusion Presses Universitaires de Lille, 4eme trimestre 1993). <em>Les tyrannies de l&rsquo;id\u00e9al : le mal am\u00e9ricain et ses rem\u00e8des (1880-1918)<\/em>, de Patrick Di Mascio, de l&rsquo;Universit\u00e9 de Rouen, repr\u00e9sente une approche syst\u00e9matique de la question du d\u00e9s\u00e9quilibre de la psychologie am\u00e9ricaine. (On trouve dans cette communication, notamment, un \u00e9pisode freudien qui nous permet de nous rem\u00e9morer la vigueur du jugement de Freud \u00e0 l&rsquo;encontre de l&rsquo;Am\u00e9rique.)<\/p>\n<\/p>\n<p><p>Ce texte doit \u00eatre lu \u00e0 la lumi\u00e8re de certaines appr\u00e9ciations qu&rsquo;on peut faire, aujourd&rsquo;hui, sur l&rsquo;\u00e9volution de la psychologie am\u00e9ricaine, ainsi que sur la perception de la psychologie am\u00e9ricaine comme une sp\u00e9cificit\u00e9. (On pourra se reporter notamment, comme \u00e0 une r\u00e9f\u00e9rence tr\u00e8s proche, <a class=\"gen\" href=\"http:\/\/www.dedefensa.org\/article.php?art_id=1132\">au texte de John Chuckman<\/a> sur ce sujet.)<\/p>\n<\/p>\n<p><p>Le titre complet de cette communication, que nous avons raccourci,  est bien &laquo; <em>Les tyrannies de l&rsquo;id\u00e9al: le mal am\u00e9ricain et ses rem\u00e8des (1880-1918)<\/em> &raquo;, par Patrick Du Mascio, de l&rsquo;Universit\u00e9 de Rouen<\/p>\n<\/p>\n<p><h4><em>dde.org<\/em><\/h4>\n<\/p>\n<p><p>_________________________<\/p>\n<\/p>\n<\/p>\n<p><h2 class=\"titleset_a.deepgreen\" style=\"color:#75714d; font-size:2em\">Les tyrannies de l&rsquo;id\u00e9al: le mal am\u00e9ricain <\/h2>\n<\/p>\n<p><h3 class=\"subtitleset_b.deepgreen\" style=\"color:#75714d; font-size:1.65em; font-variant:small-caps\">La marche des \u00e9v\u00e9nements<\/h3>\n<\/p>\n<p><p>Au d\u00e9tour d&rsquo;une recension des d\u00e9finitions existantes du subconscient, Morton Prince, \u00e9minent psychiatre, rendu c\u00e9l\u00e8bre pour son \u00e9tude des personnalit\u00e9s multiples, en d\u00e9signe une, particuli\u00e8rement lourde d&rsquo;imaginaire culturel :<\/p>\n<\/p>\n<p><p><em>&#8230;toutes ces exp\u00e9riences pass\u00e9es conscientes, qui sont oubli\u00e9es et ne peuvent \u00eatre rappel\u00e9s d la m\u00e9moire, ou qui n\u00e9 peuvent l&rsquo;\u00eatre que comme souvenirs, mais qui, pour l&rsquo;instant, ne sont pas pr\u00e9sentes d l&rsquo;esprit parce que, dans la marche des \u00e9v\u00e9nements, nos pens\u00e9es les ont d\u00e9pass\u00e9es&hellip;<\/em> (1)<\/p>\n<\/p>\n<p><p>&laquo; La marche des \u00e9v\u00e9nements &raquo; : telle est bien la r\u00e9alit\u00e9 historique avec laquelle l&rsquo;Am\u00e9rique doit composer dans cette p\u00e9riode ou s&rsquo;effectue l&rsquo;entr\u00e9e dans un si\u00e8cle de modernit\u00e9. D\u00e8s la fin de la Guerre de S\u00e9cession et le retour \u00e0 la paix en 1865, l&rsquo;Am\u00e9rique entre dans son \u00e9poque h\u00e9ro\u00efque : les chemins de fer, la banque, l&rsquo;industrie, rendent imaginables &laquo; un \u00e9vangile de la richesse &raquo;. Cet \u00e9vangile a ses saints, ou ses h\u00e9ros : les Andrew Carneige et autres Rockefeller. Ces <em>self-made men<\/em> m\u00e8nent la marche qui doit conduire l&rsquo;Am\u00e9rique vers son destin.<\/p>\n<\/p>\n<p><p>Cependant, les \u00e9pop\u00e9es les plus fameuses ont laiss\u00e9 derri\u00e8re elles leurs victimes ou engendr\u00e9 leurs rebelles, parfois m\u00eame, elles ont cr\u00e9\u00e9 des nostalgies. Par ailleurs, le mod\u00e8le le plus \u00e9difiant peut, si la r\u00e9alit\u00e9 lui r\u00e9siste, laisser place \u00e0 la plus grande et \u00e0 la plus tyrannique des solitudes celle qui confronte \u00e0 un id\u00e9al inaccessible. Freud nous l&rsquo;a enseign\u00e9 : le progr\u00e8s, ou ce qui en tient lieu, engendre le malaise d\u00e8s lors qu&rsquo;il est impos\u00e9 par quelque surmoi culturel qui impose \u00e0 l&rsquo;individu de vivre au dessus de ses moyens psychiques. Que faire quand le malaise est l\u00e0?<\/p>\n<\/p>\n<p><h3 class=\"subtitleset_b.deepgreen\" style=\"color:#75714d; font-size:1.65em; font-variant:small-caps\">Le moment Beard: la nervosit\u00e9 am\u00e9ricaine<\/h3>\n<\/p>\n<p><p>Au beau milieu de ce moment d\u00e9cisif de l&rsquo;histoire, alors que les forces de la nation r\u00e9unifi\u00e9e sont sollicit\u00e9es par une croissance acc\u00e9l\u00e9r\u00e9e, que l&rsquo;ombre des nouveaux h\u00e9ros culturels se projette sur l&rsquo;Am\u00e9rique, le diagnostic tombe. Il est brutal: l&rsquo;Am\u00e9rique est malade.<\/p>\n<\/p>\n<p><p>Un m\u00e9decin du nom de Beard isole un syndrome qui va lui valoir une place bien \u00e9tablie dans l&rsquo;histoire de la psychiatrie : la neurasth\u00e9nie. Il publie en 1880 un premier livre, <em>A Practical Treatise on Nervous Exhaustion (Neurasthenia)<\/em> dans lequel il dresse un tableau clinique \u00e9loquent long de 80 pages, d\u00e9crivant 53 sympt\u00f4mes &laquo;<em>caract\u00e9ristiques<\/em>&raquo;; on y trouve \u00e0 peu pr\u00e8s tout ce qu&rsquo;il est possible d&rsquo;imaginer, de la sensibilit\u00e9 du cuir chevelu aux crampes, des b\u00e2illements aux pieds froids, de la sensibilit\u00e9 au chaud comme au froid, sans oublier la peur, y compris la plus terrible de toutes : &laquo;<em>la peur de tout<\/em>&raquo;.<\/p>\n<\/p>\n<p><p>Cette \u00e9vocation \u00e0 la Borg\u00e8s, tir\u00e9e d&rsquo;une encyclop\u00e9die bien am\u00e9ricaine, rel\u00e8ve d&rsquo;une po\u00e9tique sur laquelle nous ne pouvons nous attarder : elle \u00e9voque un envers de l&rsquo;histoire, une traduction en n\u00e9gatif des vertus du <em>go getter<\/em>, l&rsquo;aventurier du progr\u00e8s, h\u00e9ros du folklore historique. (2) Beard d\u00e9signe sans tarder la cause \u00e9tiologique unique du mal : il s&rsquo;agit d&rsquo;un &laquo;<em>manque de force nerveuse<\/em>&raquo; (Beard, 1880, 8). Cause unique, effets multiples. D\u00e8s ce premier livre, il s&rsquo;avise qu&rsquo;il existe une corr\u00e9lation entre ce type de troubles fonctionnels et la civilisation (Beard, 1880, passim).<\/p>\n<\/p>\n<p><p>Beard, \u00e0 sa mani\u00e8re, anticipe l&rsquo;article de 1908 de Freud, &laquo;<em>La morale sexuelle \u00ab\u00a0civilis\u00e9e\u00a0\u00bb et la maladie nerveuse des temps modernes<\/em>&raquo;. (3) La civilisation, constamment entendue comme la marche progressiste de l&rsquo;histoire, et non comme l&rsquo;&oelig;uvre d&rsquo;Eros, sollicite les ressources nerveuses jusqu&rsquo;\u00e0 l&rsquo;\u00e9puisement. Dans un second temps, Beard radicalise une id\u00e9e qui \u00e9tait d\u00e9j\u00e0 tr\u00e8s pr\u00e9sente dans son premier livre : la neurasth\u00e9nie est une sorte de sp\u00e9cialit\u00e9 am\u00e9ricaine. Bien s&ucirc;r, on la rencontre ailleurs, et les am\u00e9ricains peuvent souffrir d&rsquo;autre chose que de neurasth\u00e9nie. Mais l&rsquo;Am\u00e9rique permet une rencontre d\u00e9tonnante entre tous les ingr\u00e9dients de l&rsquo;affection :<\/p>\n<\/p>\n<p><p>&laquo;<em>La nervosit\u00e9 am\u00e9ricaine est le produit de la civilisation am\u00e9ricaine &#8230; La logique de son d\u00e9veloppement &#8230;peut \u00eatre exprim\u00e9e par la formule alg\u00e9brique suivante: civilisation en g\u00e9n\u00e9ral + civilisation am\u00e9ricaine en particulier + (nation jeune au d\u00e9veloppement rapide, b\u00e9n\u00e9ficiant des libert\u00e9s civiles, religieuses et sociales) + climat harassant (extr\u00eames de temp\u00e9rature et s\u00e9cheresse de l&rsquo;air) + diath\u00e8se nerveuse (qui est elle-m\u00eame un r\u00e9sultat du facteur pr\u00e9c\u00e9dent) + indulgence g\u00e9n\u00e9rale ou excessive dans les app\u00e9tits ou les passions = attaque de neurasth\u00e9nie ou \u00e9puisement nerveux<\/em>&raquo; (Beard, 1881, 164).<\/p>\n<\/p>\n<p><p>Si la civilisation est la cause d\u00e9clenchante, l&rsquo;am\u00e9ricanit\u00e9 est une cause aggravante. Beard tire la morale de l&rsquo;histoire. La Fronti\u00e8re de la nervosit\u00e9 requiert les \u00e9nergies :<\/p>\n<\/p>\n<p><p>&laquo;<em>Notre immunit\u00e9 contre la nervosit\u00e9 et les maladies nerveuses, nous l&rsquo;avons sacrifi\u00e9e \u00e0 la civilisation. En effet, nous ne pouvons pas avoir la civilisation et tout le reste ; dans notre marche en avant, nous perdons de vue, et perdons en effet, la r\u00e9gion que nous avons travers\u00e9e<\/em>&raquo; (Beard, 1881, 191).<\/p>\n<\/p>\n<p><p>La t\u00e2che que s&rsquo;est donn\u00e9 Beard tient de l&rsquo;entreprise de salut public. La mission de l&rsquo;Am\u00e9rique est consommatrice de force nerveuse et requiert toutes les forces d&rsquo;un peuple menac\u00e9 de panne d&rsquo;\u00e9nergie. L&rsquo;\u00e9tat d&rsquo;urgence n&rsquo;\u00e9chappera pas, quelques ann\u00e9es plus tard, \u00e0 William James qui \u00e9voque un &laquo;<em>probl\u00e8me tr\u00e8s pratique d&rsquo;\u00e9conomie nationale autant que d&rsquo;\u00e9thique personnelle &#8230; un homme dont le niveau \u00e9nerg\u00e9tique est inf\u00e9rieur \u00e0 son maximum diminue d&rsquo;autant sa capacit\u00e9 \u00e0 saisir sa chance dans la vie &#8230; et une nation pleine de tels individus est inf\u00e9rieure \u00e0 une nation soumise \u00e0 une pression plus forte. Le probl\u00e8me est donc de savoir comment \u00e9lever des individus jusqu&rsquo;\u00e0 leur niveau \u00e9nerg\u00e9tique le plus haut <\/em>&raquo; (James [1907], 1947, 42).<\/p>\n<\/p>\n<p><p>De la d\u00e9couverte de la neurasth\u00e9nie aux ann\u00e9es qui pr\u00e9c\u00e8dent imm\u00e9diatement l&rsquo;arriv\u00e9e de Freud en Am\u00e9rique, le diagnostic sur l&rsquo;\u00e9tat de l&rsquo;Union ne s&rsquo;affine gu\u00e8re, et la th\u00e9orie de Beard fait autorit\u00e9. Freud, devant ses \u00e9tudiants viennois, &laquo;<em>commente Beard<\/em>&raquo; (Lettre \u00e0 Fliess, 5.11.97).<\/p>\n<\/p>\n<p><p>La m\u00e9decine officielle \u00e9tant d\u00e9bord\u00e9e, les psychologies populaires se saisissent du probl\u00e8me. Mary Baker Eddy et ses \u00e9pigones se chargent d&rsquo;apporter une r\u00e9ponse \u00e0 cette pathologie diffuse du malaise nerveux de la culture am\u00e9ricaine en exhortant \u00e0 la volont\u00e9. (4) De la neurasth\u00e9nie restreinte, que Beard voyait confin\u00e9e \u00e0 des cercles privil\u00e9gi\u00e9s, particuli\u00e8rement concern\u00e9s par le progr\u00e8s, nous passons \u00e0 une neurasth\u00e9nie g\u00e9n\u00e9ralis\u00e9e telle que James en \u00e9value les cons\u00e9quences possibles. Tentant une synth\u00e8se du diagnostic et du pronostic, Beard esquisse le portrait de l&rsquo;am\u00e9ricain du futur : &laquo;<em>Il sera sensible et impressionnable<\/em> [&#8230;] <em>mais form\u00e9 et soutenu par une volont\u00e9 d&rsquo;acier<\/em> [&#8230;] <em>Il saura quoi savoir et ce qu&rsquo;il faut ignorer<\/em>&raquo; (Beard, 1881, 345). Moiti\u00e9 Adam, moiti\u00e9 Prom\u00e9th\u00e9e, l&rsquo;am\u00e9ricain de Beard avance vers son destin, lest\u00e9 du poids de son pass\u00e9, mais pouss\u00e9 par une volont\u00e9 dont Beard certifie au passage qu&rsquo;elle est tremp\u00e9e dans la mati\u00e8re m\u00eame du progr\u00e8s.<\/p>\n<\/p>\n<p><p>Ce qui retient l&rsquo;attention dans les travaux de Beard, c&rsquo;est de voir \u00e0 quel point la th\u00e9orie est satur\u00e9e d&rsquo;imaginaire culturel. Entre th\u00e9orie et culture, un dialogue particulier s&rsquo;installe : les th\u00e9ories sont ventriloques. Leurs v\u00e9rit\u00e9s sont le murmure des soci\u00e9t\u00e9s. Le neurasth\u00e9nique est un v\u00e9ritable monument \u00e0 l&rsquo;\u00e9poque jeffersonnienne de l&rsquo;Am\u00e9rique qui prend valeur de pass\u00e9 \u00e9d\u00e9nique et mythique. (5) En termes freudiens, sa pathologie est le r\u00e9sultat d&rsquo;une fixation, non pas \u00e0 un pass\u00e9 personnel, mais \u00e0 un pass\u00e9 collectif qui refuse de passer tout \u00e0 fait. Le neurasth\u00e9nique de Beard est un sujet cliv\u00e9 : pratiquant de la modernit\u00e9, il n&rsquo;en continue pas moins de v\u00e9n\u00e9rer en cachette les vieilles valeurs d&rsquo;une Am\u00e9rique pr\u00e9-industrielle. L&rsquo;heure n&rsquo;est pourtant pas \u00e0 la nostalgie : &laquo;<em>Il est hautement d\u00e9sirable de remettre ces patients en \u00e9tat de marche<\/em>&raquo; (Beard, 1881, 163), rappelle Beard, s&rsquo;arrachant \u00e0 sa r\u00eaverie. L&rsquo;histoire attend.<\/p>\n<\/p>\n<p><h3 class=\"subtitleset_b.deepgreen\" style=\"color:#75714d; font-size:1.65em; font-variant:small-caps\">Le moment Freud : le malaise culturel<\/h3>\n<\/p>\n<p><p>Dans le contexte d&rsquo;un malaise dans la civilisation am\u00e9ricaine, doubl\u00e9 d&rsquo;une carence des ripostes th\u00e9rapeutiques, la visite de Freud \u00e0 l&rsquo;Universit\u00e9 de Clark en 1909 ressemble \u00e0 la visite d&rsquo;un m\u00e9decin au chevet d&rsquo;un malade. On conna&icirc;t l&rsquo;histoire mille fois r\u00e9p\u00e9t\u00e9e de cet \u00e9v\u00e9nement qui marque de fa\u00e7on commode le d\u00e9but de la psychanalyse en Am\u00e9rique. (6) Nous ne retiendrons que quelques \u00e9l\u00e9ments de nature \u00e0 illustrer notre propos : les traces, dans la r\u00e9ponse de Freud, de la demande que lui fait l&rsquo;Am\u00e9rique.<\/p>\n<\/p>\n<p><p>Tout particuli\u00e8rement pertinent ici est le commentaire inquiet d&rsquo;un lames qui, cinq ans apr\u00e8s son constat de faillite \u00e9nerg\u00e9tique de l&rsquo;Am\u00e9rique, se prendra \u00e0 esp\u00e9rer que la psychanalyse renouvelle la psychologie. James esquisse ce qui va devenir le fantasme sous-tendant un usage am\u00e9ricain de la psychanalyse : qu&rsquo;elle accompagne l&rsquo;Am\u00e9rique sur le chemin de la r\u00e9alisation de ses id\u00e9aux. Le malentendu est de taille, comme le montre la correspondance entre Freud et Putnam, longue tentative de dialogue les id\u00e9aux de l&rsquo;analyse et ceux de sa culture d&rsquo;accueil.<\/p>\n<\/p>\n<p><p>Freud ne se pr\u00eatera jamais \u00e0 ce jeu pour une double raison. Dans le registre individuel auquel la cure permet d&rsquo;acc\u00e9der, le psychanalyste n&rsquo;a pas le &laquo;<em>droit d&rsquo;\u00eatre pr\u00eatre<\/em>&raquo; (1963a, 183) et ne doit pas donner \u00e0 la cure de buts qui lui soient \u00e9trangers. L&rsquo;autre raison est m\u00e9thodologique : rien, dans la psychanalyse, ne permet de pr\u00e9tendre traiter la pathologie suppos\u00e9e de soci\u00e9t\u00e9s<\/p>\n<\/p>\n<p><p>&laquo;<em>Quant \u00e0 l&rsquo;application th\u00e9rapeutique de nos connaissances &#8230; \u00e0 quoi servirait donc l&rsquo;analyse la plus p\u00e9n\u00e9trante de la n\u00e9vrose sociale, puisque personne n&rsquo;aurait l&rsquo;autorit\u00e9 n\u00e9cessaire pour imposer \u00e0 la collectivit\u00e9 la th\u00e9rapeutique voulue? En d\u00e9pit de toutes ces difficult\u00e9s, on peut s&rsquo;attendre \u00e0 ce qu&rsquo;un jour, quelqu&rsquo;un s&rsquo;enhardisse \u00e0 entreprendre dans ce sens la pathologie des soci\u00e9t\u00e9s civilis\u00e9es<\/em>&raquo; (1930a, 106).<\/p>\n<\/p>\n<p><p>Vaste programme, en effet. Ce jugement \u00e9nonc\u00e9 dans <em>Malaise dans la civilisation<\/em>, vingt ans apr\u00e8s la visite \u00e0 Clark laisse entendre combien est grand le malentendu entre Freud et les tenants \u00e9ventuels d&rsquo;une th\u00e9rapeutique sociale. Dans le m\u00eame texte, il avoue devoir r\u00e9sister \u00e0 la tentation de se lancer &laquo;<em>dans la critique de la civilisation am\u00e9ricaine<\/em>&raquo; (1930a, 70) qui offre un parfait exemple selon Freud de &laquo;<em>mis\u00e8re psychologique de la masse<\/em>&raquo; \u00e0 cause de la m\u00e9diocrit\u00e9 de ses leaders.<\/p>\n<\/p>\n<p><p>Il n&rsquo;en demeure pas moins que Freud arrive en Am\u00e9rique fermement convaincu des buts &laquo;<em>pratiques<\/em>&raquo; de l&rsquo;auditoire de Clark (1910a, 72), d&rsquo;o&ugrave; son choix de l&rsquo;hyst\u00e9rie pour illustrer la nature de la psychanalyse. Fid\u00e8le \u00e0 son go&ucirc;t de la m\u00e9taphore, Freud se lance dans une vaste all\u00e9gorie \u00e9clairant au passage la notion de fixation. Il situe sa fable p\u00e9dagogique \u00e0 Londres, entre Charing Cross et le Monument, et met en sc\u00e8ne quelques promeneurs solitaires :<\/p>\n<\/p>\n<p><p>&laquo;<em>que diriez-vous d&rsquo;un londonien qui, aujourd&rsquo;hui encore, resterait tristement en arr\u00eat devant le monument qui rappelle le cort\u00e8ge fun\u00e9raire de la reine El\u00e9onore au lieu de vaquer \u00e0 ses affaires, avec la diligence que r\u00e9clament les conditions de travail modernes, ou au jeu de songer avec joie \u00e0 la jeune et fra&icirc;che reine de son coeur? Ou que diriez-vous de cet autre Londonnien qui, devant le \u00ab\u00a0Monument\u00a0\u00bb, pleurerait sur sa ch\u00e8re ville natale r\u00e9duite en cendres, alors que, depuis ce temps, elle est ren\u00e9e bien plus brillante qu&rsquo;autrefois? Et bien, les hyst\u00e9riques et les n\u00e9vros\u00e9s se conduisent comme ses deux Londonniens d\u00e9nu\u00e9s de sens pratique; non seulement parce qu&rsquo;ils se souviennent des exp\u00e9riences douloureuses qu&rsquo;ils ont faites longtemps auparavant, mais parce qu&rsquo;ils restent attach\u00e9s \u00e0 elles par leurs affects; ils n&rsquo;arrivent pas \u00e0 se lib\u00e9rer du pass\u00e9 et n\u00e9gligent pour lui la r\u00e9alit\u00e9 et le pr\u00e9sent<\/em>&raquo; (1910a, 43).<\/p>\n<\/p>\n<p><p>Freud peint ici une fresque inattendue. Si le sch\u00e9ma th\u00e9orique est conforme \u00e0 celui que l&rsquo;on peut retrouver dans bon nombre de ses \u00e9crits sur l&rsquo;hyst\u00e9rie, le choix des images est tout \u00e0 fait in\u00e9dit. Freud reprend \u00e0 son compte l&rsquo;imp\u00e9ratif de la marche en avant. Il met en sc\u00e8ne deux anglais qui, comme les neurasth\u00e9niques de Beard, sont des \u00eatres du pass\u00e9. Au lieu de r\u00e9pondre \u00e0 l&rsquo;appel de leur vocation, ils s&rsquo;attardent devant des monuments aux mortes. Cette conf\u00e9rence de Freud, la premi\u00e8re des cinq, est le premier texte de psychanalyse am\u00e9ricaine. Ses r\u00e9f\u00e9rences aux conditions de vie modernes, \u00e0 la r\u00e9alit\u00e9 et au pr\u00e9sent, sont des traits distinctifs &mdash; ou tenus pour tels &mdash; de la psychanalyse \u00e0 l&rsquo;am\u00e9ricaine . (7)<\/p>\n<\/p>\n<p><p>Si Beard recommandait aux neurasth\u00e9niques, notamment, de rester dans une chambre close, Freud n&rsquo;h\u00e9site pas \u00e0 comparer la n\u00e9vrose \u00e0 un couvent, lieu dont chacun sait qu&rsquo;il n&rsquo;est pas pr\u00e9cis\u00e9ment un lieu d&rsquo;\u00e9panouissement sexuel : &laquo;<em>En notre temps, la n\u00e9vrose tient la place du couvent o&ugrave; se retiraient tous les individus que la vie avait d\u00e9\u00e7us, ou qui se sentaient trop faibles pour la vie<\/em>&raquo; (1910a, 108). Image tr\u00e8s parlante, bien que pittoresque de la part d&rsquo;un juif qui s&rsquo;adresse \u00e0 des protestants et qui met au centre de sa comparaison un lieu de culture catholique, confession ici d\u00e9sign\u00e9e comme le lieu de tous les renoncements. Pour un puritain, le couvent est l&rsquo;anti-monde : il fait obstacle \u00e0 la vocation et \u00e0 l&rsquo;oeuvre men\u00e9e pour la plus grande gloire de Dieu. Qu&rsquo;il s&rsquo;en rende pleinement compte ou non, Freud parle un langage tout \u00e0 fait adapt\u00e9 \u00e0 la situation : il rappelle que le n\u00e9vros\u00e9 est menac\u00e9 de chute hors du monde moderne. Sa comparaison \u00e0 venir entre le n\u00e9vros\u00e9 et le primitif, dans <em>Totem et tabou<\/em>, est ici en somme amorc\u00e9e. Le n\u00e9vros\u00e9 de Freud est un reclus et tourne le dos \u00e0 l&rsquo;histoire en tentant de s&rsquo;inventer un monde a-temporel dans lequel il ne manquera pas de croiser le neurasth\u00e9nique de Beard. Ce ne sont pas des oubli\u00e9s de l&rsquo;histoire : ce sont eux qui oublient l&rsquo;histoire. Cet oubli peut leur co&ucirc;ter leur salut : cette imbrication de la cure d&rsquo;\u00e2me et des mentalit\u00e9s religieuses est fondamentale pour comprendre la r\u00e9ception de la psychanalyse aux Etats-Unis et la r\u00e9action sp\u00e9cifique de Putnam \u00e9tudi\u00e9e plus loin. (8)<\/p>\n<\/p>\n<p><p>Sans doute ces diff\u00e9rentes m\u00e9taphores constituent-elles autant de d\u00e9tours du discours et ne peuvent tenir lieu de prescription du Dr Freud \u00e0 une Am\u00e9rique malade, Chemin faisant d&rsquo;ailleurs, on a perdu de vue la nervosit\u00e9 am\u00e9ricaine. Un coup de boutoir, un parmi de nombreux autres, contre la pr\u00e9tention de Beard \u00e0 en faire une pathologie am\u00e9ricaine est rapport\u00e9 dans l&rsquo;article de Freud, &laquo;<em>La morale sexuelle \u00a0\u00bb civilis\u00e9e \u00a0\u00bb et la maladie nerveuse de notre temps<\/em>&raquo;. Freud cite 0. Binswanger, qui \u00e9crivait dans son livre, <em>La pathologie et la th\u00e9rapie de la neurasth\u00e9nie<\/em> (1896) :<\/p>\n<\/p>\n<p><p>&laquo;<em>On a caract\u00e9ris\u00e9 la neurasth\u00e9nie sp\u00e9cialement comme une maladie tout \u00e0 fait moderne et Beard \u00e0 qui nous en devons la premi\u00e8re description distincte croyait avoir d\u00e9couvert l\u00e0 une nouvelle maladie nerveuse qui s&rsquo;\u00e9tait sp\u00e9cialement d\u00e9velopp\u00e9e sur le sol am\u00e9ricain. Naturellement cette hypoth\u00e8se \u00e9tait erron\u00e9e; cependant le fait que ce soit un m\u00e9decin am\u00e9ricain qui ait pu saisir et retenir le premier les traits caract\u00e9ristiques de cette maladie indique sans aucun doute le tien serr\u00e9 entre cette maladie et la vie moderne, la chasse effr\u00e9n\u00e9e \u00e0 l&rsquo;argent et aux possessions, les progr\u00e8s formidables du domaine technique qui ont rendu illusoires tous les obstacles temporels et spacieux \u00e0 la circulation<\/em>&raquo; (1908d, 31).<\/p>\n<\/p>\n<p><p>Un soup\u00e7on continue de peser : et si, au fond, \u00e0 pousser la civilisation jusqu&rsquo;\u00e0 la caricature, (9) l&rsquo;Am\u00e9rique \u00e9tait pathog\u00e8ne ? Plus tard, Freud, sans aller aussi loin dans une mise en accusation de l&rsquo;Am\u00e9rique, remarquera que le &laquo;<em>comportement de l&rsquo;individu \u00e0 l&rsquo;\u00e9gard de l&rsquo;argent devrait \u00eatre particuli\u00e8rement r\u00e9v\u00e9lateur en Am\u00e9rique o&ugrave; l&rsquo;\u00e9rotisme anal a fait l&rsquo;objet de transformations tr\u00e8s int\u00e9ressantes<\/em>&raquo; (Lettre \u00e0 Putnam du 05.12.1909) (Hale, 1968, 115). Freud est en train de travailler \u00e0 son analyse de l&rsquo;Homme aux rats&#8230; Si pour Freud, quelque chose comme un mal am\u00e9ricain existe, c&rsquo;est sans doute une forme commune de n\u00e9vrose obsessionnelle, avec ses manifestations quant \u00e0 l&rsquo;attitude face \u00e0 l&rsquo;argent et aux pratiques religieuses, toutes deux si lourdes de cons\u00e9quences au niveau culturel.<\/p>\n<\/p>\n<p><p>Le voyage de Freud ne laissera pas indiff\u00e9rents ceux qui ont assist\u00e9 \u00e0 ses conf\u00e9rences. Le m\u00eame William James qui faisait un constat d&rsquo;urgence nationale trois ans auparavant sur la paup\u00e9risation nerveuse, confiera \u00e0 Jones : &laquo;<em>L&rsquo;avenir de la psychologie appartient \u00e0 votre travail<\/em>&raquo; (Jones, 1955, 57). Il dira autre chose, \u00e0 une proche : &laquo;<em>j&rsquo;ai la tr\u00e8s nette impression que ce Freud, avec sa th\u00e9orie du r\u00eave, est un v\u00e9ritable hallucin\u00e9. J&rsquo;esp\u00e8re n\u00e9anmoins que lui et ces disciples iront jusqu&rsquo;au bout car la th\u00e9orie rend s&ucirc;rement compte de certains faits<\/em>&raquo; (Hale, 1968, 18). Freud avait donc bien raison de craindre de &laquo;<em>choquer<\/em>&raquo; en parlant de r\u00eave (1910x, 72-73). Mais les deux commentaires de James ne sont pas contradictoires entre eux : la psychanalyse est l&rsquo;avenir de la psychologie parce que c&rsquo;est la r\u00e9alit\u00e9 elle-m\u00eame qui d\u00e9raisonne. Pour comprendre quelque chose \u00e0 l&rsquo;objet de la science de l&rsquo;\u00e2me, il faut accepter d&rsquo;en \u00e9pouser les exc\u00e8s. A sa fa\u00e7on, James pourrait reprendre la formule de Theodor Adorno : &laquo;<em>Dans la psychanalyse, tout est faux, hormis les exag\u00e9rations<\/em>&raquo; (Jay, 1973, 109).<\/p>\n<\/p>\n<p><p>C&rsquo;est l&rsquo;acceptation du caract\u00e8re excessif de la r\u00e9alit\u00e9 telle que Freud invite \u00e0 la voir qui rend caduque les pr\u00e9tentions \u00e0 l&rsquo;am\u00e9ricanit\u00e9 de la neurasth\u00e9nie ou de quelqu&rsquo;autre pathologie. (10) Tant au niveau collectif qu&rsquo;individuel, les am\u00e9ricains sont confront\u00e9s \u00e0 la n\u00e9cessit\u00e9 de ne pas rester emp\u00eatr\u00e9s dans le pass\u00e9, qu&rsquo;il soit europ\u00e9en, hyst\u00e9rique ou neurasth\u00e9nique. Freud leur apporte une bien mauvaise nouvelle : non seulement on ne peut \u00e9chapper \u00e0 son pass\u00e9, mais de plus, ce pass\u00e9 est sexuel. Freud se risque \u00e0 la rappeler \u00e0 ses auditeurs de Clark :<\/p>\n<\/p>\n<p><p>&laquo;<em>Que la plupart des individus, observateurs m\u00e9decins ou autres personnes, ne veuillent pas entendre parler de la vie sexuelle de l&rsquo;enfant, cela ne s&rsquo;explique que trop bien. Ils ont oubli\u00e9 leur propre activit\u00e9 sexuelle infantile sous la pression de l&rsquo;\u00e9ducation qui les a conduits \u00e0 la vie civilis\u00e9e et ne veulent plus d\u00e8s lors entendre rappeler le refoul\u00e9<\/em>&raquo; (1910a, 94).<\/p>\n<\/p>\n<p><p>La marche en avant qui tient de mot d&rsquo;ordre de la culture, la tentative de r\u00e9gionalisation de la neurasth\u00e9nie, ressemblent d\u00e9cid\u00e9ment trop \u00e0 des rejetons des r\u00e9sistances que ne manquent jamais de susciter le sexuel. La mauvaise nouvelle de Freud est en somme la suivante : Am\u00e9rique ou pas, l&rsquo;humain n&rsquo;\u00e9chappe pas \u00e0 l&rsquo;humain.<\/p>\n<\/p>\n<p><p>Freud tentera de rassurer l&rsquo;auditoire, (11) en vain. Le mal est fait. L&rsquo;\u00e9ditorial qu&rsquo;une obscure gazette consacrait \u00e0 un travail de Jones condamne m\u00eame ces psychologues modernes qui &laquo;<em>ajoutent aux fardeaux de la civilisation moderne en nous infligeant des th\u00e9ories qui d\u00e9truisent notre foi en la nature humaine<\/em>&raquo; (Jones, 1955, 61). Freud ne pouvait ignorer que la r\u00e9sistance est le moyen d&rsquo;accueil privil\u00e9gi\u00e9 de la psychanalyse, et peut-\u00eatre n&rsquo;\u00e9tait-il pas m\u00e9content, en tant que &laquo;<em>\u00ab\u00a0incredulous Jew \u00ab\u00a0, maudit de Dieu<\/em>&raquo; (lettre \u00e0 Putnam, 18.08.1910) (Hale, 1968, 131), de contraindre l&rsquo;Am\u00e9rique \u00e0 rouvrir un vieux dossier am\u00e9ricain en voie de r\u00e8glement, celui de la Chute de l&rsquo;Homme.<\/p>\n<\/p>\n<p><h3 class=\"subtitleset_b.deepgreen\" style=\"color:#75714d; font-size:1.65em; font-variant:small-caps\">Le moment Putnam : le salut analytique<\/h3>\n<\/p>\n<p><p>Depuis le diagnostic de Beard et m\u00eame avant, les religions populaires am\u00e9ricaines, <em>Christian Science<\/em> et Mary Baker Eddy en t\u00eate, essayaient d&rsquo;all\u00e9ger la charg\u00e9 terrible qui pesait sur le croyant \u00e9lev\u00e9 dans la tradition calviniste, en faisant pr\u00e9valoir l&rsquo;id\u00e9e qu&rsquo;\u00e0 force de volont\u00e9 et d&rsquo;oeuvres, le p\u00e9ch\u00e9 originel serait rachet\u00e9. Le rire freudien accompagne le constat selon lequel &laquo; nous n&rsquo;aimons pas qu&rsquo;on nous rappelle combien il est difficile de concilier &mdash; en d\u00e9pit des affirmations solennelles de la \u00a0\u00bb Science chr\u00e9tienne \u00a0\u00bb &mdash; l&rsquo;ind\u00e9niable existence du mal avec la toute-puissance et la souveraine bonne volont\u00e9 divine &raquo; (1930a, 75). (12) La <em>Christian Science<\/em> n&rsquo;est bien s&ucirc;r pas la seule contestation de la doctrine calviniste.<\/p>\n<\/p>\n<p><p>Dans la salle o&ugrave; Freud donne ses conf\u00e9rences, un professeur de neurologie de 63 ans, \u00e9lev\u00e9 dans la tradition unitarienne de la Nouvelle Angleterre, entame sa conversion \u00e0 la psychanalyse : il s&rsquo;appelle James Jackson Putnam.<\/p>\n<\/p>\n<p><p>Le r\u00f4le jou\u00e9 par Putnam dans l&rsquo;histoire du mouvement psychanalytique est \u00e9troitement li\u00e9 \u00e0 l&rsquo;opinion qu&rsquo;en avait Freud. Freud l&rsquo;avait choisi comme ambassadeur, pour des raisons qui tenaient davantage \u00e0 la position strat\u00e9gique de Putnam qu&rsquo;\u00e0 ses r\u00e9elles capacit\u00e9s comme analyste. (13) Voici ce que Freud en \u00e9crit dans l&rsquo;article de 1914, &laquo;<em>Contribution \u00e0 l&rsquo;histoire du Mouvement psychanalytique<\/em>&raquo;.<\/p>\n<\/p>\n<p><p>&laquo;<em>C\u00e9dant aux grandes exigences morales et philosophiques de sa nature. M. Putnam a cependant cru devoir demander \u00e0 la psychanalyse plus qu&rsquo;elle ne pouvait donner et a voulu la mettre au service d&rsquo;une certaine conception \u00e9thico-philosophique du monde. 1l n&rsquo;en resta pas moins le principal d\u00e9fenseur et soutien du mouvement psychanalytique dans son pays<\/em>&raquo; (1914d, 104). (14)<\/p>\n<\/p>\n<p><p>Au passage, Freud formule parfaitement la nature du probl\u00e8me du contact entre son oeuvre et la culture am\u00e9ricaine : il s&rsquo;agit bien d&rsquo;une demande (<em>Foderung<\/em>) adress\u00e9e \u00e0 la psychanalyse, laquelle demande exige r\u00e9ponse, et d&rsquo;une certaine fa\u00e7on, la psychanalyse d&rsquo;un Erich Fromm constitue une tentative pour y r\u00e9pondre.<\/p>\n<\/p>\n<p><p>Putnam a une r\u00e9putation scientifique et morale bien \u00e9tablie lorsque touch\u00e9 par la gr\u00e2ce analytique, il prend fait et cause pour elle, apr\u00e8s l&rsquo;\u00e9v\u00e9nement d\u00e9terminant que fut sa rencontre personnelle avec Freud. Outre traiter sa n\u00e9vrose personnelle, dont il s&rsquo;ouvre dans les lettres \u00e0 Freud, il n&rsquo;est bien s&ucirc;r pas impossible que Putnam ait vu dans la th\u00e9orie freudienne le moyen de r\u00e9soudre les maux qui affligent l&rsquo;Am\u00e9rique et les am\u00e9ricains.<\/p>\n<\/p>\n<p><p>Par sa pratique, que d&rsquo;ailleurs nous ne connaissons que tr\u00e8s peu, Putnam est bien s&ucirc;r confront\u00e9 aux in\u00e9vitables pathologies fonctionnelles n\u00e9vrotiques &mdash;&laquo;<em>Freud l&rsquo;aide \u00e0 diagnostiquer des hyst\u00e9ries<\/em>&raquo; &mdash; mais Putnam croit d\u00e9celer un mal qui d\u00e9passe les cadres nosographiques en vigueur :<\/p>\n<\/p>\n<p><p>&laquo;<em>D\u00e8s lors que j &lsquo;\u00e9tudie mes malades et m&rsquo;efforce de tes soulager de leurs sympt\u00f4mes, je d\u00e9couvre qu&rsquo;il me faut \u00e9galement chercher \u00e0 am\u00e9liorer leur personnalit\u00e9 morale et leur caract\u00e8re. Ils doivent vouloir souhaiter se \u00ab\u00a0sublimer\u00a0\u00bb, et il leur faut consentir \u00e0 faire des sacrifices et \u00e0 se conformer \u00e0 leurs id\u00e9aux les plus nobles &#8230; je consid\u00e8re qu&rsquo;un patient n&rsquo;est pas r\u00e9ellement gu\u00e9ri s&rsquo;il ne devient pas meilleur du point de vue moral, plus ouvert, et inversement, je crois qu&rsquo;une r\u00e9g\u00e9n\u00e9ration morale contribue \u00e0 \u00e9liminer les sympt\u00f4mes<\/em>&raquo; (Hale, 1968, 145).<\/p>\n<\/p>\n<p><p>D&rsquo;un point de vue clinico-pragmatique, l&rsquo;id\u00e9e est loin d&rsquo;\u00eatre n\u00e9gligeable. Putnam semble appeler de ses voeux une sublimation r\u00e9ussie qui aurait effectivement le double effet recherch\u00e9 de gu\u00e9rison symptomatique et d&rsquo;am\u00e9lioration morale. L&rsquo;erreur, du point de vue freudien, consiste \u00e0 penser que l&rsquo;on peut isoler ce qui, dans l&rsquo;histoire du sujet, est intimement li\u00e9. Par rapport \u00e0 Beard, on note une certaine conformit\u00e9 des pr\u00e9occupations, avec toutefois quelques variantes importante. Putnam ne pose pas le probl\u00e8me de l&rsquo;intervention analytique en termes sociaux ; il n&rsquo;incrimine pas un niveau de civilisation propre \u00e0 l&rsquo;Am\u00e9rique. L&rsquo;\u00e9cart par rapport \u00e0 l&rsquo;id\u00e9al est un probl\u00e8me individuel, quitte \u00e0 constater apr\u00e8s-coup qu&rsquo;il y a convergence entre le niveau individuel et un int\u00e9r\u00eat social sup\u00e9rieur, car le bien qui habite l&rsquo;homme ne saurait \u00eatre \u00e9go\u00efste. Le lot de l&rsquo;am\u00e9ricain est le lot de l&rsquo;humain : si quelque chose d\u00e9passe ses propres id\u00e9aux, il ne doit s&rsquo;agir que d&rsquo;une transcendance, non une contingence socio-culturelle. L&rsquo;am\u00e9ricain incarne la figure de l&rsquo;homme. Plus question d&rsquo;un homme am\u00e9ricain, mais d&rsquo;une situation de l&rsquo;homme en Am\u00e9rique.<\/p>\n<\/p>\n<p><p>Ce que Putnam va demander \u00e0 la psychanalyse, ce sont les moyens pour permettre \u00e0 l&rsquo;individu d&rsquo;atteindre ses id\u00e9aux, ainsi qu&rsquo;une justification scientifique d&rsquo;un tel but de l&rsquo;analyse. Freud peut bien lui r\u00e9pondre qu&rsquo;il y a maldonne et que tel n&rsquo;est pas le propos de (analyse, Putnam n&rsquo;y insiste pas moins. Il ne saurait se r\u00e9soudre \u00e0 arriver si pr\u00e8s du coeur de l&rsquo;homme pour reculer au dernier moment devant la mission que la psychanalyse avait rendue possible. Cela ressemblerait trop \u00e0 une d\u00e9sertion. Putnam revient donc r\u00e9guli\u00e8rement \u00e0 la charge, notamment ici :<\/p>\n<\/p>\n<p><p>&laquo;<em>On entend dire &mdash; et je crois que c&rsquo;est vrai &mdash; qu&rsquo;un psychanalyste devrait avoir \u00e9t\u00e9 lui-m\u00eame analys\u00e9. Il n&rsquo;y a pas un jour o&ugrave; je n&rsquo;en ressente le besoin en ce qui me concerne. Mais par ailleurs, un grand nombre de psychanalystes ont \u00e9t\u00e9 analys\u00e9s, et ils sont loin d&rsquo;\u00eatre parfaits \u00e0 aucun point de vue. Si on se demande pourquoi il en est ainsi, pour quelles raisons l&rsquo;analyste n&rsquo;a pas r\u00e9ussi \u00e0 extirper toutes les tendances infantiles qui faisaient obstacle \u00e0 la meilleure sublimation dont ils \u00e9taient capables, c&rsquo;est, je pense, en partie parce que ceux qui ont conduit l&rsquo;analyse n&rsquo;ont pas une id\u00e9e juste du but que ces fixations infantiles les (leurs patients temporaires) ont emp\u00each\u00e9s d&rsquo;atteindre<\/em>&raquo; (Hale, 1968, 216).<\/p>\n<\/p>\n<p><p>La formation analytique tournerait autour d&rsquo;un point aveugle : l&rsquo;\u00e9lucidation des buts \u00e0 atteindre. Le patient perd de vue ses propres id\u00e9aux et cet aveuglement laisse le champ libre aux formations pathologiques. Pour Putnam, la n\u00e9vrose est une pathologie de l&rsquo;\u00e9garement. C&rsquo;est ainsi qu&rsquo;il faut entendre son credo en mati\u00e8re d&rsquo;analyse : il faut &laquo;<em>proposer au malade un but quelconque vers lequel tendre ses efforts<\/em>&raquo; (Hale, 1968, 112). Les r\u00e9ponses de Freud \u00e0 ses sollicitations r\u00e9p\u00e9t\u00e9es sont autant d&rsquo;illustration de la confidence \u00e0 Putnam, faisant \u00e9tat de son &laquo;<em>d\u00e9go&ucirc;t pour les adeptes de la saintet\u00e9<\/em>&raquo; (Hale, 1968, 219). Pour tenter de gu\u00e9rir Putnam de son id\u00e9alisme, Freud dira notamment :<\/p>\n<\/p>\n<p><p>&laquo;<em>J&rsquo;ai toujours \u00e9t\u00e9 frapp\u00e9 de la bassesse des hommes, m\u00eame des analystes; mais pourquoi les hommes et femmes analys\u00e9s devraient-ils \u00eatre meilleurs? L&rsquo;analyse permet une certaine unit\u00e9 de la personnalit\u00e9, mais elle ne rend pas bon en soi et pour soi [&#8230;]. Je pense que c. est trop demander \u00e0 l&rsquo;analyse que de vouloir qu&rsquo;elle r\u00e9alise les plus chers id\u00e9aux de chacun<\/em>&raquo; (Hale, 1968, 218).<\/p>\n<\/p>\n<p><p>De telles tensions ne vont pas sans exercer de profondes pressions sur l&rsquo;usage que Putnam fait de la r\u00e9f\u00e9rence \u00e0 la psychanalyse. Les deux volumes de ses oeuvres, <em>Addresses on Psychoanalysis<\/em> et <em>Hunan Motives<\/em> d\u00e9montrent le travail acharn\u00e9 de traduction, de rectification, auquel se livre Putnam. Il est clair que si l&rsquo;analyse de l&rsquo;\u00e2me m\u00e9rite son nom, il lui faudra permettre d&rsquo;extirper ce qui fait obstacle \u00e0 la &laquo;<em>r\u00e9alisation des plus hautes destin\u00e9es de l&rsquo;homme<\/em>&raquo; (Putnam, 1921, 80), toujours invoqu\u00e9es, mais jamais d\u00e9finies, tant elles sont \u00e9videntes pour lui. Retirer du mal comme on &laquo;<em>extirpe<\/em>&raquo; de l&rsquo;infantile, en mettant hors d&rsquo;\u00e9tat de nuire ce qui fait obstacle au bien&rsquo;: telle est la mission de l&rsquo;analyse.<\/p>\n<\/p>\n<p><p>L&rsquo;am\u00e9nagement th\u00e9orique le plus spectaculaire et le plus massif concerne sans doute le terrain d&rsquo;action de l&rsquo;analyse. Sans doute faut-il passer par l&rsquo;inconscient comme d&rsquo;autres passent par le d\u00e9sert, mais cela ne vaut la peine que parce que l&rsquo;on sait qu&rsquo;au bout du chemin se trouve une sorte de Terre Promise de la psych\u00e9, lieu du bien \u00e0 partir duquel rayonne l&rsquo;individu :<\/p>\n<\/p>\n<p><p>&laquo;<em>A cet \u00e9l\u00e9ment r\u00e9el et cr\u00e9ateur de la vie mentale, dont d\u00e9pendent toute notre volont\u00e9 et le renouvellement de nos pens\u00e9es, j&rsquo;oserais donner le nom de psyche generatrix ou men creativa [&#8230;]. Voir tant de mis\u00e8re humaine et de p\u00e9ch\u00e9 serait intol\u00e9rable si nous ne reconnaissions faiblement que l&rsquo;existence organique apporte avec elle le pouvoir et la n\u00e9cessit\u00e9 de tendre en permanence vers le monde cach\u00e9 de la vraie vie<\/em>&raquo; (Putnam, 1921, 84).<\/p>\n<\/p>\n<p><p>Direction, la <em>psyche generatrix<\/em> donc. Sans doute est-ce en partie l&rsquo;unitarien qui parle. Pour lui, la doctrine apport\u00e9e par ce &laquo;<em>juif ath\u00e9e<\/em>&raquo; (15) ressemble trop au dogme calviniste du p\u00e9ch\u00e9 originel. Putnam ne conteste pas ce que Freud appellera plus tard &laquo;<em>l&rsquo;ind\u00e9niable existence du mal<\/em>&raquo;, mais il veut aussi croire au bien :<\/p>\n<\/p>\n<p><p>&laquo;<em>C&rsquo;est \u00e9galement une erreur que de croire que \u00ab\u00a0l&rsquo;inconscient\u00a0\u00bb ne contient que le sens du mal, la partie sombre de notre nature. Reconna&icirc;tre le mal implique que l&rsquo;on reconnaisse le bien<\/em> [&hellip;] <em>et ce qu&rsquo;il y a de meilleur dans la vie mentale est repr\u00e9sent\u00e9 dans nos esprits inconscient et subconscient. C&rsquo;est inconscient parce que cela ne peut \u00eatre exprim\u00e9 en mots<\/em>&raquo; (Putnam, 1921, 87).<\/p>\n<\/p>\n<p><p>Le retournement op\u00e9r\u00e9 est total : l&rsquo;indicible s&rsquo;est ligu\u00e9 avec le bien. D&rsquo;une certaine fa\u00e7on, Putnam pourrait paraphraser une sentence sartrienne pour dire : le mal est d\u00e9j\u00e0 fait, reste \u00e0 dire le bien. Mais le bien est une virtualit\u00e9, non un contenu. Tant mieux : puisqu&rsquo;il ne saurait jamais \u00eatre mis en mots, il nous assure de longues ann\u00e9es de tentatives pour le dire. Toujours il se d\u00e9robe, et donc, toujours il nous porte. Le salut n&rsquo;est pas seulement au bout du chemin, il est le chemin m\u00eame. Le programme est \u00e9difiant. Ecoutons ce jugement de Freud :<\/p>\n<\/p>\n<p><p>&laquo;<em>Une certaine sympathie s&rsquo;\u00e9veilla; mais une sympathie particuli\u00e8re m\u00eal\u00e9e de piti\u00e9, comme celle que l&rsquo;on \u00e9prouve, en lisant. Cervant\u00e8s, pour son h\u00e9ros, le na\u00eff chevalier de la Manche. Et finalement, en comparant les forces de l&rsquo;homme et la grandeur de la tache qu&rsquo;il avait entreprise, cette piti\u00e9 devint irr\u00e9sistible qu&rsquo;elle domina tous les autres sentiments.<\/em>&raquo;<\/p>\n<\/p>\n<p><p>Ce n&rsquo;est pourtant pas Putnam que Freud compare ainsi \u00e0 Don Quichotte, mais le Pr\u00e9sident Wilson, auquel Freud et Bullit consacreront une \u00e9tude (1966b). Putnam aurait fait un Don Quichotte tout aussi acceptable. Freud \u00e9crivit \u00e0 Jones : &laquo;<em>La philosophie de Putnam me rappelle un de ces surtouts d\u00e9coratifs, qu&rsquo;on place, au milieu de la table: tout le monde l&rsquo;admire, mais personne n&rsquo;y touche<\/em>&raquo; (Hale, 1968, 77). Qu&rsquo;en faire ?<\/p>\n<\/p>\n<p><h3 class=\"subtitleset_b.deepgreen\" style=\"color:#75714d; font-size:1.65em; font-variant:small-caps\">L&rsquo;amour du tyran<\/h3>\n<\/p>\n<p><p>Le mal am\u00e9ricain a chang\u00e9. l&rsquo;Am\u00e9rique de l&rsquo;\u00e8re Wilson n&rsquo;a plus \u00e0 s&rsquo;interroger sur une urbanisation, une industrialisation d\u00e9sormais int\u00e9gr\u00e9es \u00e0 l&rsquo;histoire. Cette mutation a fait de l&rsquo;Am\u00e9rique la premi\u00e8re puissance mondiale. L&rsquo;\u00e9conomie nerveuse a tenu le coup. Lorsque Putnam insiste sur la n\u00e9cessit\u00e9 pour ses patients de r\u00e9aliser leurs id\u00e9aux, sans doute pointe-t-il un effet pervers de la croissance : pendant trop longtemps, les am\u00e9ricains ont poursuivi un id\u00e9al qu&rsquo;ils s&rsquo;\u00e9taient imagin\u00e9s \u00eatre le leur, alors qu&rsquo;il ne s&rsquo;agissait que d&rsquo;un id\u00e9al d\u00e9sincarn\u00e9, qui leur avait \u00e9t\u00e9 souffl\u00e9 par l&rsquo;histoire. Id\u00e9al de proth\u00e8se pour un peuple de peu de foi. On reconna&icirc;t ici l&rsquo;\u00e9bauche de ce qui sera le programme culturaliste d&rsquo;Erich Fromm et ou de Karen Horney. Putnam e&ucirc;t-il lu Marx qu&rsquo;il aurait sans doute parl\u00e9 d&rsquo;ali\u00e9nation.<\/p>\n<\/p>\n<p><p>Il serait tr\u00e8s int\u00e9ressant, mais tr\u00e8s difficile, de suivre les vicissitudes des id\u00e9aux dans la culture am\u00e9ricaine, le corps \u00e0 corps entre un destin et une histoire. Une telle enqu\u00eate ferait partie du programme fantastique \u00e9voqu\u00e9 par Freud : &laquo;<em>L&rsquo;\u00e9tude attentive du r\u00f4le jou\u00e9 par un surmoi dans les manifestations du processus culturel semble devoir promettre \u00e0 qui veut bien s&rsquo;y appliquer d&rsquo;autres clart\u00e9s encore<\/em>&raquo; (1930a, 105), notamment pour &laquo;<em>entreprendre la pathologie des soci\u00e9t\u00e9s civilis\u00e9es<\/em>&raquo; (1930a, 106). Vaste programme.<\/p>\n<\/p>\n<p><p>C&rsquo;est un paradoxe sans doute regrettable que de voir la notion de mod\u00e8le ainsi associ\u00e9e \u00e0 l&rsquo;id\u00e9e d&rsquo;une pathologie. Le constat, pourtant, s&rsquo;impose : le &laquo;<em>surmoi collectif<\/em>&raquo;, instance freudienne du mod\u00e8le, &laquo;<em>\u00e9dicte une loi et ne se demande pas s&rsquo;il est possible \u00e0 l&rsquo;homme de la suivre<\/em>&raquo;, impose de telles exigences qu&rsquo;il prend le risque de &laquo;<em>provoquer une r\u00e9volte ou une n\u00e9vrose<\/em>&raquo; (1930a, 104).<\/p>\n<\/p>\n<p><p>Entre le trop plein et le vide d&rsquo;id\u00e9al, sans doute convient-il de trouver la bonne mesure. Dans <em>Malaise dans la Civilisation<\/em>, Freud d\u00e9nonce le d\u00e9ficit d&rsquo;id\u00e9al qui afflige l&rsquo;Am\u00e9rique : sans personne pour incarner ses mod\u00e8les, la culture am\u00e9ricaine est pur malaise. Sans &laquo;<em>personnalit\u00e9s \u00e0 temp\u00e9rament de chefs<\/em>&raquo;, la masse menace de demeurer informe (1930a, 70). Wilson et Hoover ne sont pas des Moise des temps modernes. L&rsquo;Am\u00e9rique ne disposant pas d&rsquo;une grande tradition au sens o&ugrave; Freud l&rsquo;entend dans <em>L&rsquo;Homme Mo\u00efse<\/em>, l&rsquo;am\u00e9ricain, figure de l&rsquo;homme de la modernit\u00e9, est somm\u00e9 de s&rsquo;inventer de l&rsquo;id\u00e9al s&rsquo;il veut \u00e9chapper \u00e0 l&rsquo;anomie. Sans doute une allocution de Freud \u00e0 l&rsquo;Am\u00e9rique aurait-elle pu avoir comme exergue cette confidence faite \u00e0 Fliess :<\/p>\n<\/p>\n<p><p>&laquo;<em>un homme comme moi ne peut vivre sans (&#8230;) une passion qui le d\u00e9vore, sans, pour parler comme Schiffler, un tyran<\/em>&raquo; (lettre \u00e0 Fliess du 25 mai 1895).<\/p>\n<\/p>\n<p><h4>Patrick Du Mascio<\/h4>\n<\/p>\n<p><h2 class=\"titleset_c.deepgreen\" style=\"color:#75714d; font-size:1.25em\">NOTES<\/h2>\n<\/p>\n<p><p>(1) A Symposium on die Subconscious +, &laquo; Prefatory Note &raquo;, The Journal of Abnonnal Psychology, Vol. II, 1907-1908, p. 24.<\/p>\n<\/p>\n<p><p>(2) On peut lire l&rsquo;\u00e9vocation qu&rsquo;en fait Daniel Boorstin dans <em>The Americans<\/em>&mdash;   <em>The Democratic Experience<\/em>, (1973) New York, Vintage Books, 1974, pp. 4-87.<\/p>\n<\/p>\n<p><p>(3) &laquo; A sa mani\u00e8re &raquo; seulement, c&rsquo;est \u00e0 dire de fa\u00e7on tr\u00e8s rustique, Beard r\u00e9digera un livre sur la neurasth\u00e9nie sexuelle (1884) qui non seulement reste \u00e0 des consid\u00e9rations sur le caract\u00e8re actuel (au sens freudien) de la n\u00e9vrose, mais qui en plus, tend \u00e0 faire de la sexualit\u00e9 une grande consommatrice d&rsquo;\u00e9nergie, et donc une alli\u00e9e de l&rsquo;\u00e9puisement nerveux.<\/p>\n<\/p>\n<p><p>(4) Voir le livre le Donald Meyer, <em>The Positive Thinkers<\/em>, New York, Pantheon Books, 1980.<\/p>\n<\/p>\n<p><p>(5) Sur ce point, voir notre article, &laquo; Comment naissent les th\u00e9ories ? Le cas de la neurasth\u00e9nie &raquo;, <em>L&rsquo;\u00e9volution psychiatrique<\/em>, 51, 3, 1986, pp. 625-638.<\/p>\n<\/p>\n<p><p>(6) Voir (Gay, 1988, pp. 206-213 et passim), (Jones, 1955, pp. 55-66), (Clark, 1988), (Freud, 1914c), (Freud, 1925e), (Roazen, 1979, pp. 372-388), (Roazen, 1990, pp. 39-64), etc&#8230; L&rsquo;ouvrage de base reste bien entendu (Hale, 1976).<\/p>\n<\/p>\n<p><p>(7) La liste des travaux faisant allusion \u00e0 ce style caract\u00e9ristique est gigantesque. En revanche, ceux qui tentent de probl\u00e9matiser cette question, et en particulier d&rsquo;articuler la question du style \u00e0 celle, de l&rsquo;imaginaire culturel, sont fort peu nombreux. On pense notamment aux travaux de Hale (1968, 1975), Jacoby (1975) et Fuller (1986).<\/p>\n<\/p>\n<p><p>(8) La correspondance avec le Pasteur Pfister est une source tr\u00e8s pr\u00e9cieuse pour aborder la question du religieux chez Freud. Dans une lettre du 18.02.1909, Pfister \u00e9crit \u00e0 Freud : &laquo; D\u00e9j\u00e0 l&rsquo;\u00e9thique protestante avait retir\u00e9 aux relations sexuelles l&rsquo;odieux de l&rsquo;impuret\u00e9. A la v\u00e9rit\u00e9, la R\u00e9forme n&rsquo;est au fond rien d&rsquo;autre qu&rsquo;une analyse du refoulement sexuel catholique &raquo; (1963a, 49), \u00e0 quoi Freud r\u00e9pond : &laquo; Dans le sens historique que vous donnez \u00e0 ce mot, je peux, certes, me dire aussi \u00a0\u00bb protestant \u00a0\u00bb et me souviens, \u00e0 ce propos, que mon ami le professeur voit Ehrenfels, de Prague, a forg\u00e9 pour lui et moi le nom de \u00a0\u00bb protestants sexuels \u00a0\u00bb &raquo; (1963a, 50). Comme nous le verrons \u00e0 propos de Putnam, il semble bien exister une convergence d&rsquo;int\u00e9r\u00eat entre la psychanalyse telle que l&rsquo;entend Putnam, et la recherche des id\u00e9aux.<\/p>\n<\/p>\n<p><p>(9) Tel est bien ce dont Freud accuse l&rsquo;Am\u00e9rique. On se souvient que Freud refuse de distinguer entre <em>Kultur<\/em> et <em>Zivilitation<\/em> (1927c, 8). Le progr\u00e8s des techniques du mode de vie, qui se trouve plut\u00f4t du c\u00f4t\u00e9 de la <em>Zivilisation<\/em>, sans un progr\u00e8s, dans la spiritualit\u00e9, (<em>Geistigkeit<\/em>), dont la tradition juive donne pour lui le mod\u00e8le, aboutirait \u00e0 une barbarie. Or, la <em>Kultur<\/em> est absente des consid\u00e9rations de Beard. Sans doute Freud partagerait-il sur l&rsquo;Am\u00e9rique le jugement s\u00e9v\u00e8re d&rsquo;un autre penseur germanophone. Max Weber qui \u00e9crivait en 1904 : &laquo; Sp\u00e9cialistes sans esprit, sensualistes sans cour, cette nullit\u00e9 s&rsquo;imagine avoir atteint un niveau de civilisation sans pr\u00e9c\u00e9dent &raquo; (Weber, 1958, 182). Sur la distinction entre &laquo; culture &raquo; et &laquo; civilisation &raquo; en Allemagne, voir (Elias, 1973, l1-60). Pour la discussion de la <em>Geistigkeit<\/em>, voir (1939a : 210-215).<\/p>\n<\/p>\n<p><p>(10) Ce n&rsquo;est bien s&ucirc;r pas la seule raison qui explique l&rsquo;\u00e9clipse de la th\u00e9orie de Beard. Celle-ci \u00e9tait condamn\u00e9e par sa propre logique. Nous avons ailleurs tent\u00e9 de d\u00e9montrer comment cette th\u00e9orie de la neurasth\u00e9nie \u00e9tait une traduction scientifique d&rsquo;une mythologie de l&rsquo;\u00e9lection am\u00e9ricaine (Di Mascio, 1986).<\/p>\n<\/p>\n<p><p>(11) &laquo; On craint de nuire au moyen de la psychanalyse, on a peur d&rsquo;appeler \u00e0 la conscience du malade ses pulsions sexuelles refoul\u00e9es, comme si se liait \u00e0 cela le danger qu&rsquo;elles puissent surmonter chez lui les aspirations \u00e9thiques sup\u00e9rieures et les d\u00e9pouiller de ses acquisitions culturelles [&#8230;]. Le travail psychanalytique se met donc justement au service des tendances culturelles les plus hautes et les plus pr\u00e9cieuses, en tant qu&rsquo;il est un substitutif qui remplace en mieux le refoulement rest\u00e9 sans succ\u00e8s &raquo; (Freud, 1909, 113).<\/p>\n<\/p>\n<p><p>(12) Dans <em>La question de l&rsquo;analyse profane<\/em>, il s&rsquo;en prend \u00e0 nouveau \u00e0 la <em>Christian<\/em> Science : &laquo; Dans les pays de langue anglaise, les pratiques de la \u00a0\u00bb Christian Science \u00a0\u00bb ont pris une grande extension &mdash; sorte de d\u00e9ni dialectique des maux de l&rsquo;existence, se r\u00e9clamant des enseignements de la religion chr\u00e9tienne. Je n&rsquo;h\u00e9site pas \u00e0 affirmer que ces pratiques repr\u00e9sentent un regrettable errement de l&rsquo;esprit humain, mais qui, en Am\u00e9rique ou en Angleterre, songerait \u00e0 les interdire et \u00e0 les p\u00e9naliser ? &raquo; (1926e : 116-117).<\/p>\n<\/p>\n<p><p>(13) Sur ces questions, voir notre article (Di Mascio, 1990).<\/p>\n<\/p>\n<p><p>(14) On peut lire pratiquement le m\u00eame commentaire dans (1914c, 104) et (1919b, 315).<\/p>\n<\/p>\n<p><p>(15)Sur les tenants et les aboutissants de cette expression, voir (Gay, 1987).<\/p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Tyrannie de l&rsquo;id\u00e9al : le \u00ab\u00a0mal am\u00e9ricain\u00a0\u00bb Nous pr\u00e9sentons ci-apr\u00e8s le texte d&rsquo;une communication extraite du livre \u00e9dit\u00e9 par Jacques Portes, L&rsquo;Am\u00e9rique comme mod\u00e8le, l&rsquo;Am\u00e9rique sans mod\u00e8le (Diffusion Presses Universitaires de Lille, 4eme trimestre 1993). Les tyrannies de l&rsquo;id\u00e9al : le mal am\u00e9ricain et ses rem\u00e8des (1880-1918), de Patrick Di Mascio, de l&rsquo;Universit\u00e9 de Rouen,&hellip;&nbsp;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","footnotes":"","jetpack_post_was_ever_published":false},"categories":[8],"tags":[2769,3253,4312,3043,2662,4311,3041,4309,4280,4310,3099],"class_list":["post-66002","post","type-post","status-publish","format-standard","hentry","category-notre-bibliotheque","tag-americain","tag-americanisme","tag-avant","tag-beard","tag-en","tag-fuite","tag-mal","tag-nevrose","tag-pathologie","tag-progres","tag-psychologie"],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/66002","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/comments?post=66002"}],"version-history":[{"count":0,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/66002\/revisions"}],"wp:attachment":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/media?parent=66002"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/categories?post=66002"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/tags?post=66002"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}