{"id":66008,"date":"2004-06-23T00:00:00","date_gmt":"2004-06-23T00:00:00","guid":{"rendered":"https:\/\/new.dedefensa.org\/index.php\/2004\/06\/23\/le-grand-jeu-suite-autour-du-kurdistan-irakien-des-enjeux-vertigineux-entre-israel-et-les-usa-entre-israel-et-la-turquie\/"},"modified":"2004-06-23T00:00:00","modified_gmt":"2004-06-23T00:00:00","slug":"le-grand-jeu-suite-autour-du-kurdistan-irakien-des-enjeux-vertigineux-entre-israel-et-les-usa-entre-israel-et-la-turquie","status":"publish","type":"post","link":"https:\/\/new.dedefensa.org\/index.php\/2004\/06\/23\/le-grand-jeu-suite-autour-du-kurdistan-irakien-des-enjeux-vertigineux-entre-israel-et-les-usa-entre-israel-et-la-turquie\/","title":{"rendered":"<strong><em>Le \u201cGrand Jeu\u201d (suite) : autour du Kurdistan irakien, des enjeux vertigineux, \u2014 entre Isra\u00ebl et les USA, entre Isra\u00ebl et la Turquie<\/em><\/strong>"},"content":{"rendered":"<p><h2 class=\"common-article\">Le Grand Jeu (suite) : autour du Kurdistan irakien, des enjeux vertigineux,  entre Isra\u00ebl et les USA, entre Isra\u00ebl et la Turquie<\/h2>\n<\/p>\n<p><\/p>\n<p><p>\tAutour de l&rsquo;Irak, et en Irak m\u00eame, dans certaines r\u00e9gions, se mettent en place des forces d\u00e9stabilisatrices qui pourraient conduire \u00e0 des affrontements internationaux dans la r\u00e9gion et \u00e0 des r\u00e9alignements sensationnels. Le transfert de souverainet\u00e9 \u00e0 l&rsquo;ex\u00e9cutif irakien, tout cosm\u00e9tique qu&rsquo;il soit, n&rsquo;en repr\u00e9sente pas moins un facteur d&rsquo;importance dans la mesure o\u00f9 il ouvre les vannes \u00e0 de telles \u00e9volutions.<\/p>\n<\/p>\n<p><p>\tUn point d&rsquo;une grande importance dans ce qu&rsquo;on pourrait d\u00e9signer comme une sorte de Grand Jeu autour de l&rsquo;Irak, c&rsquo;est celui qui implique d&rsquo;une part Isra\u00ebl, particuli\u00e8rement dans ses rapports avec le Kurdistan irakien mais aussi dans ses rapports avec les USA, et, d&rsquo;autre part, la Turquie, \u00e9galement dans ses rapports avec le m\u00eame Kurdistan irakien et aussi dans ses rapports avec Isra\u00ebl (et indirectement, aussi, avec les USA).<\/p>\n<\/p>\n<p><p>\tLe premier point (la position et l&rsquo;activit\u00e9 d&rsquo;Isra\u00ebl) laisse percer un enseignement qui est plut\u00f4t une sp\u00e9culation, qui pourrait conduire \u00e0 la plus sensationnelle \u00e9volution strat\u00e9gique potentielle qu&rsquo;on puisse envisager aujourd&rsquo;hui : celle qui concerne les rapports strat\u00e9giques entre Isra\u00ebl et les USA.<\/p>\n<\/p>\n<p><\/p>\n<h3>Isra\u00ebl et son Plan B : comment rattraper la catastrophique campagne irakienne des Am\u00e9ricains ?<\/h3>\n<\/p>\n<p><p>\tDe r\u00e9cents articles ont commenc\u00e9 \u00e0 signaler des activit\u00e9s des Isra\u00e9liens dans le Kurdistan irakien, dans le sens du soutien au mouvement d&rsquo;autonomie des Kurdes. Les Isra\u00e9liens pr\u00e9parent l\u00e0 leur action pour l&rsquo;apr\u00e8s-30 juin, qui sera de soutenir \u00e0 fond le mouvement autonomiste kurde. Le journaliste Seymour M. Hersh, du <em>New Yorker<\/em>, publie <a href=\"http:\/\/www.truthout.org\/docs_04\/062204A.shtml\" class=\"gen\">le 21 juin un long article sur cette question<\/a>, qu&rsquo;il intitule notamment \u00ab <em>Plan B<\/em> \u00bb, signifiant par l\u00e0 le point fondamental qu&rsquo;il exprime dans cet article : les Isra\u00e9liens estiment que les Am\u00e9ricains ont totalement rat\u00e9 leur invasion de l&rsquo;Irak, que celle-ci est d&rsquo;ores et d\u00e9j\u00e0 un \u00e9chec strat\u00e9gique pour eux, que les Am\u00e9ricains sont totalement incapables d&rsquo;orienter la situation de l&rsquo;Irak dans un sens favorable \u00e0 celui qu&rsquo;attendait Isra\u00ebl. Par cons\u00e9quent, les Isra\u00e9liens prennent une mesure d&rsquo;urgence et agissent pour soutenir la constitution d&rsquo;un \u00c9tat kurde, avec empi\u00e9tement et bellig\u00e9rance larv\u00e9e avec la Syrie et l&rsquo;Iran, de fa\u00e7on \u00e0 disposer d&rsquo;un alli\u00e9-tampon face \u00e0 ces deux pays (principalement l&rsquo;Iran, qui est le pays qui fait le plus peur \u00e0 Isra\u00ebl, parce que les Isra\u00e9liens sont persuad\u00e9s que les Iraniens vont tr\u00e8s vite avoir l&rsquo;arme nucl\u00e9aire).<\/p>\n<\/p>\n<p><p>\tLe point mis en \u00e9vidence par Hersh est bien celui-ci : l&rsquo;action d&rsquo;Isra\u00ebl n&rsquo;est pas une action offensive, une action pour renforcer une position d\u00e9j\u00e0 bonne (celle qu&rsquo;on pourrait supposer avec l&rsquo;invasion US de l&rsquo;Irak), mais le contraire. C&rsquo;est une mesure d\u00e9fensive pr\u00e9cipit\u00e9e, presque une mesure de d\u00e9sespoir pour tenter de limiter les cons\u00e9quences catastrophiques de la catastrophique campagne am\u00e9ricaine en Irak. Les Isra\u00e9liens, explique Hersh, sont compl\u00e8tement d\u00e9courag\u00e9s par l&rsquo;action des Am\u00e9ricains.<\/p>\n<\/p>\n<p><\/p>\n<p><p>\t\u00ab <em>A former Administration official who had supported the war completed a discouraging tour of Iraq late last fall. He visited Tel Aviv afterward and found that the Israelis he met with were equally discouraged. As they saw it, their warnings and advice had been ignored, and the American war against the insurgency was continuing to founder. I spent hours talking to the senior members of the Israeli political and intelligence community, the former official recalled. Their concern was You&rsquo;re not going to get it right in Iraq, and shouldn&rsquo;t we be planning for the worst-case scenario and how to deal with it?&rsquo;<\/em> <\/p>\n<\/p>\n<p><p>\t\u00bb <em>Ehud Barak, the former Israeli Prime Minister, who supported the Bush Administration&rsquo;s invasion of Iraq, took it upon himself at this point to privately warn Vice-President Dick Cheney that America had lost in Iraq; according to an American close to Barak, he said that Israel had learned that there&rsquo;s no way to win an occupation. The only issue, Barak told Cheney, was choosing the size of your humiliation. Cheney did not respond to Barak&rsquo;s assessment. (Cheney&rsquo;s office declined to comment.)<\/em> \u00bb<\/p>\n<\/p>\n<p><\/p>\n<h3>L&rsquo;impensable est-il pensable: que les Isra\u00e9liens envisagent un jour de r\u00e9viser leur grande alliance strat\u00e9gique avec les USA ?<\/h3>\n<\/p>\n<p><p>\tLa pire des choses que pouvaient craindre les Isra\u00e9liens est arriv\u00e9e : dans cette d\u00e9sastreuse campagne irakienne des Am\u00e9ricains, ce sont les Iraniens qui, sans avoir rien fait, sont les vainqueurs. C&rsquo;est un constat important, mais, plus important encore, \u00e0 l&rsquo;occasion et au-del\u00e0 de ce constat, il y a cet autre constat que le d\u00e9couragement et le d\u00e9senchantement des Isra\u00e9liens \u00e0 l&rsquo;\u00e9gard des Am\u00e9ricains sont frappants dans le texte de Hersh.<\/p>\n<\/p>\n<p><p>\tC&rsquo;est un point qui doit \u00eatre gard\u00e9 \u00e0 l&rsquo;esprit, comme quelque chose d&rsquo;absolument essentiel. Il pourrait se r\u00e9v\u00e9ler d&rsquo;une extraordinaire importance dans le futur. Pour les Isra\u00e9liens, il pourrait signifier ceci : apr\u00e8s tout, la puissance am\u00e9ricaine, si totalement inepte et contre-productive dans son action, n&rsquo;est peut-\u00eatre pas la meilleure garantie de s\u00e9curit\u00e9 pour Isra\u00ebl. Il faut m\u00e9diter les cons\u00e9quences possibles d&rsquo;un tel constat, si les Isra\u00e9liens le poussent dans ses cons\u00e9quences \u00e0 long terme. Cela peut signifier potentiellement la marche vers la r\u00e9vision d&rsquo;un dogme intangible de la politique de s\u00e9curit\u00e9 d&rsquo;Isra\u00ebl depuis 1967, \u00e0 savoir que l&rsquo;alliance am\u00e9ricaine d\u00e9termine tout et que l&rsquo;alliance am\u00e9ricaine est quelque chose \u00e0 quoi tout doit \u00eatre sacrifi\u00e9. Une telle \u00e9volution serait un bouleversement sans pr\u00e9c\u00e9dent pour la r\u00e9gion et, d&rsquo;une fa\u00e7on plus g\u00e9n\u00e9rale, pour la situation des relations internationales et de la politique am\u00e9ricaine.<\/p>\n<\/p>\n<p><p>\t(En passant, on pourrait envisager que les circonstances d\u00e9crites par Hersh pourraient \u00e9galement impliquer une rupture entre les Isra\u00e9liens et leurs meilleurs alli\u00e9s \u00e0 Washington, les n\u00e9o-conservateurs. Certes, les n\u00e9o-conservateurs ne sont pas hostiles \u00e0 un Kurdistan ind\u00e9pendant, qui est un but tactique imm\u00e9diat d&rsquo;Isra\u00ebl. Mais sur la m\u00e9thode g\u00e9n\u00e9rale, celle qui a conduit \u00e0 la catastrophe irakienne ? Hersh nous dit bien que les n\u00e9o-conservateurs n&rsquo;ont pas chang\u00e9, qu&rsquo;ils continuent \u00e0 favoriser la m\u00e9thode strat\u00e9gique, fond\u00e9e sur l&rsquo;utopie d\u00e9mocratique, qui a abouti \u00e0 un d\u00e9sastre : \u00ab <em>The former senior American intelligence official told me, similarly, that the neocons still think they can pull the rabbit out of the hat in Iraq. What&rsquo;s the plan? They say, We don&rsquo;t need it. Democracy is strong enough. We&rsquo;ll work it out.&rsquo;<\/em> \u00bb)<\/p>\n<\/p>\n<p><\/p>\n<h3>La Turquie durcit son attitude vis-\u00e0-vis d&rsquo;Isra\u00ebl et craint le d\u00e9sordre kurde : la r\u00e9gion suivant le mod\u00e8le des Balkans et Kirkuk mena\u00e7ant d&rsquo;\u00eatre le Sarajevo de l&rsquo;Irak ?<\/h3>\n<\/p>\n<p><p>\tUn autre \u00e9l\u00e9ment appara\u00eet, plus visible, plus imm\u00e9diat, et qui a un poids strat\u00e9gique \u00e9galement fondamental : les rapports d&rsquo;Isra\u00ebl avec la Turquie, en fonction de l&rsquo;activisme d&rsquo;Isra\u00ebl au Kurdistan. Les rapports entre la Turquie et Isra\u00ebl se sont tendus ces derni\u00e8res semaines. Durant une r\u00e9union entre ministres turcs et ministres isra\u00e9liens, le 26 mai \u00e0 Ankara, <a href=\"http:\/\/english.aljazeera.net\/NR\/exeres\/A81ADBFD-6289-4CD2-9AC3-594F0C8702DE.htm\" class=\"gen\">le Premier ministre turc a qualifi\u00e9 Isra\u00ebl d&rsquo;\u00c9tat-terroriste<\/a>, \u00e0 cause du comportement isra\u00e9lien \u00e0 l&rsquo;encontre des Palestiniens. Le 7 juin, \u00e0 la suite de cet \u00e9change muscl\u00e9 du 26 mai, <a href=\"http:\/\/english.aljazeera.net\/NR\/exeres\/A81ADBFD-6289-4CD2-9AC3-594F0C8702DE.htm\" class=\"gen\">Ankara a temporairement rappel\u00e9 son ambassadeur en Isra\u00ebl<\/a> pour consultations. L\u00e0 encore, la cause est les actions isra\u00e9liennes contre les Palestiniens. (Mais on peut avancer que la question de l&rsquo;activisme isra\u00e9lien aupr\u00e8s des Kurdes irakiens \u00e9tait dans l&rsquo;esprit des Turcs, qu&rsquo;elle l&rsquo;\u00e9tait m\u00eame majoritairement, plus encore que celle des Palestiniens.)<\/p>\n<\/p>\n<p><p>\tLe climat turco-isra\u00e9lien est donc mauvais, alors que l&rsquo;alliance strat\u00e9gique entre les deux pays est l&rsquo;un des fondements du syst\u00e8me strat\u00e9gique pro-US dans la r\u00e9gion. Bien entendu, la question des rapports entre Isra\u00e9liens et Kurdes d&rsquo;Irak va beaucoup plus loin que la question palestinienne pour les Turcs. Elle touche au cur d&rsquo;une question essentielle pour eux. Voici notamment un passage de l&rsquo;article de Hersh o\u00f9 il aborde cette question.<\/p>\n<\/p>\n<p><\/p>\n<p><p>\t\u00ab <em> There may be no way to square it with Turkey. Over breakfast in Ankara, a senior Turkish official explained, Before the war, Israel was active in Kurdistan, and now it is active again. This is very dangerous for us, and for them, too. We do not want to see Iraq divided, and we will not ignore it. Then, citing a popular Turkish proverb  We will burn a blanket to kill a flea &#8211; he said, We have told the Kurds, We are not afraid of you, but you should be afraid of us.&rsquo; (A Turkish diplomat I spoke to later was more direct: We tell our Israeli and Kurdish friends that Turkey&rsquo;s good will lies in keeping Iraq together. We will not support alternative solutions.)<\/em> <\/p>\n<\/p>\n<p><p>\t\u00bb <em>If you end up with a divided Iraq, it will bring more blood, tears, and pain to the Middle East, and you will be blamed, the senior Turkish official said. From Mexico to Russia, everybody will claim that the United States had a secret agenda in Iraq: you came there to break up Iraq. If Iraq is divided, America cannot explain this to the world. The official compared the situation to the breakup of Yugoslavia, but added, In the Balkans, you did not have oil.\u00a0\u00bb He said, \u00a0\u00bbThe lesson of Yugoslavia is that when you give one country independence everybody will want it. If that happens, he said, Kirkuk will be the Sarajevo of Iraq. If something happens there, it will be impossible to contain the crisis.<\/em> \u00bb<\/p>\n<\/p>\n<p><\/p>\n<p><p>\tCes quelques appr\u00e9ciations permettent de proposer la conclusion que la d\u00e9stabilisation apport\u00e9e par les USA avec leur guerre irakienne ne fait que commencer, qu&rsquo;elle sera radicale, et qu&rsquo;elle risque surtout d&rsquo;apporter aux Am\u00e9ricains de bien d\u00e9sagr\u00e9ables surprises.<\/p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Le Grand Jeu (suite) : autour du Kurdistan irakien, des enjeux vertigineux, entre Isra\u00ebl et les USA, entre Isra\u00ebl et la Turquie Autour de l&rsquo;Irak, et en Irak m\u00eame, dans certaines r\u00e9gions, se mettent en place des forces d\u00e9stabilisatrices qui pourraient conduire \u00e0 des affrontements internationaux dans la r\u00e9gion et \u00e0 des r\u00e9alignements sensationnels. Le&hellip;&nbsp;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","footnotes":"","jetpack_post_was_ever_published":false},"categories":[3],"tags":[],"class_list":["post-66008","post","type-post","status-publish","format-standard","hentry","category-analyse"],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/66008","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/comments?post=66008"}],"version-history":[{"count":0,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/66008\/revisions"}],"wp:attachment":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/media?parent=66008"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/categories?post=66008"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/tags?post=66008"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}