{"id":66010,"date":"2004-06-25T00:00:00","date_gmt":"2004-06-25T00:00:00","guid":{"rendered":"https:\/\/new.dedefensa.org\/index.php\/2004\/06\/25\/finalement-clinton-sera-t-il-reelu\/"},"modified":"2004-06-25T00:00:00","modified_gmt":"2004-06-25T00:00:00","slug":"finalement-clinton-sera-t-il-reelu","status":"publish","type":"post","link":"https:\/\/new.dedefensa.org\/index.php\/2004\/06\/25\/finalement-clinton-sera-t-il-reelu\/","title":{"rendered":"<strong><em>Finalement, Clinton sera-t-il r\u00e9\u00e9lu ?<\/em><\/strong>"},"content":{"rendered":"<p><h2 class=\"common-article\">Finalement, Clinton sera-t-il r\u00e9\u00e9lu ?<\/h2>\n<\/p>\n<p><\/p>\n<p><p>\t25 juin 2004  La parution des m\u00e9moires de Bill Clinton (<em>My Life<\/em>) est d&rsquo;abord un \u00e9norme \u00e9v\u00e9nement de librairie (tirage initial d&rsquo;1,5 million d&rsquo;exemplaires, \u00e0 valoir de $12 millions pour le pr\u00e9sident). Mis \u00e0 la suite de l&rsquo;\u00e9v\u00e9nement du lancement des m\u00e9moires d&rsquo;Hillary, il y a un an, il confirme que le couple Clinton est un cas exceptionnel pour le monde de l&rsquo;\u00e9dition.<\/p>\n<\/p>\n<p><p>\tEt l&rsquo;on parle ici, aussi bien, des USA que du reste du monde. La France, o\u00f9 la traduction du livre a \u00e9t\u00e9 mise en vente presque simultan\u00e9ment, est le cas qui nous int\u00e9resse ici. Nous nous attachons essentiellement \u00e0 ce fait que, le 23 juin, le quotidien de r\u00e9f\u00e9rence, le journal <em>Le Monde<\/em>, a fait de cette publication un \u00e9v\u00e9nement politique international. Le titre le dit \u00e0 suffisance, d&rsquo;autant plus qu&rsquo;il tr\u00f4na en manchette du journal : \u00ab <em>Bill Clinton bouscule l&rsquo;Am\u00e9rique<\/em> \u00bb ; non seulement le titre le dit \u00e0 suffisance, mais il est \u00e9galement d&rsquo;un tr\u00e8s grand int\u00e9r\u00eat. Ce titre aurait aussi bien pu \u00eatre Clinton r\u00e9veille l&rsquo;Am\u00e9rique et Clinton lance la campagne \u00e9lectorale, ou, mieux encore, les deux m\u00e9lang\u00e9s. En for\u00e7ant \u00e0 peine et en r\u00eavant un peu, il aurait pu \u00eatre : le candidat Clinton prend une option sur la victoire en novembre. Pendant ce temps, John Kerry serait invit\u00e9 \u00e0 \u00e9crire ses m\u00e9moires<\/p>\n<\/p>\n<p><p>\t[Notons que le titre du <a href=\"http:\/\/www.lemonde.fr\/web\/imprimer_article\/0,1-0@2-3222,36-369945,0.html\" class=\"gen\"> texte du Monde extrait de l&rsquo;\u00e9dition papier et publi\u00e9 sur le site<\/a> n&rsquo;est pas moins explicite en un sens : \u00ab <em>Bill Clinton revient et radicalise le d\u00e9bat politique am\u00e9ricain.<\/em> \u00bb Cela n&rsquo;est effectivement pas loin de nous dire que Clinton lance la campagne \u00e9lectorale et qu&rsquo;il est au fond le vrai candidat]<\/p>\n<\/p>\n<p><p>\tOn ajoutera, autre pi\u00e8ce quoique d&rsquo;une autre dimension allant dans le m\u00eame sens, une interview de l&rsquo;ancien ministre des affaires \u00e9trang\u00e8res Hubert V\u00e9drine, \u00e0 qui <a href=\"http:\/\/www.lefigaro.fr\/international\/20040623.FIG0022.html\" class=\"gen\">Le Figaro du 23 juin posait quelques questions sur Clinton<\/a>. De fa\u00e7on assez curieuse si l&rsquo;on se rem\u00e9more pr\u00e9cis\u00e9ment l&rsquo;histoire des ann\u00e9es Clinton et, pour ce qui est du texte cit\u00e9, l&rsquo;action de l&rsquo;administration Clinton du temps o\u00f9 Hubert V\u00e9drine \u00e9tait au Quai d&rsquo;Orsay, ce dernier trace un pan\u00e9gyrique sans gu\u00e8re de restriction de Bill Clinton, qui appara\u00eet ainsi  comme un pr\u00e9sident am\u00e9ricain g\u00e9nial ayant d\u00e9velopp\u00e9 une politique qui fut marqu\u00e9e en tous points par l&rsquo;originalit\u00e9 et le succ\u00e8s.<\/p>\n<\/p>\n<p><p>\t[Nous renvoyons nos lecteurs \u00e0 <a href=\"http:\/\/www.dedefensa.org\/article.php?art_id=161\" class=\"gen\"> un texte F&#038;C sur ce site<\/a>, \u00e0 l&rsquo;occasion de l&rsquo;annonce du contrat de Bill Clinton pour ses m\u00e9moires, suivi de la publication d&rsquo;une <em>Analyse<\/em> parue dans notre Lettre d&rsquo;Analyse <em>de defensa<\/em>, pour le d\u00e9part du pr\u00e9sident d\u00e9mocrate de la Maison-Blanche. De surcro\u00eet, pour un acc\u00e8s plus imm\u00e9diat, nous reproduisons ce texte ci-dessous.]<\/p>\n<\/p>\n<p><p>\tVoici quelques extraits de l&rsquo;interview de Hubert V\u00e9drine.<\/p>\n<\/p>\n<p><\/p>\n<p><p>\tLe Figaro  <em>George W. Bush vous fait-il regretter Bill Clinton?<\/em><\/p>\n<\/p>\n<p><p>\tHubert V\u00e9drine  <em>Ce qui est frappant, avec le recul et par comparaison, ce sont les qualit\u00e9s de Clinton: l&rsquo;intelligence, l&rsquo;ouverture, la souplesse et la curiosit\u00e9 pour tout ce qui n&rsquo;est pas l&rsquo;Am\u00e9rique. Clinton aurait pu \u00eatre ce genre d&rsquo;hommes politiques am\u00e9ricains que les Europ\u00e9ens adorent mais qui ne r\u00e9ussissent jamais aux \u00c9tats-Unis. Or, contrairement \u00e0 certains intellectuels d\u00e9mocrates d&rsquo;autrefois, il a r\u00e9ussi \u00e0 se faire aimer des Am\u00e9ricains et \u00e0 se faire r\u00e9\u00e9lire.<\/em><\/p>\n<\/p>\n<p><p>\tLe Figaro  <em>D&rsquo;apr\u00e8s vous, son double mandat fut une r\u00e9ussite, y compris sur le plan int\u00e9rieur?<\/em><\/p>\n<\/p>\n<p><p>\tHubert V\u00e9drines  <em>Clinton a formidablement r\u00e9ussi, sur tous les plans. En prenant les crit\u00e8res un par un, y compris les crit\u00e8res \u00e9conomiques, on constate qu&rsquo;il a obtenu de meilleurs param\u00e8tres que Reagan, que ce soit pour la croissance, l&#8217;emploi, la rentabilit\u00e9, etc. Il a un talent exceptionnel et multiforme.<\/em><\/p>\n<\/p>\n<p><p>\t()<\/p>\n<\/p>\n<p><p>\tLe Figaro  <em>Quel fut le principal succ\u00e8s de politique \u00e9trang\u00e8re de Clinton?<\/em><\/p>\n<\/p>\n<p><p>\tHubert V\u00e9drine  <em>Le talent de Clinton, c&rsquo;est d&rsquo;avoir r\u00e9ussi \u00e0 rendre la puissance de son pays, que j&rsquo;ai appel\u00e9e l&rsquo;hyperpuissance, aimable et s\u00e9duisante. C&rsquo;est une r\u00e9ussite prodigieuse. Mais c&rsquo;est un hommage au talent de l&rsquo;artiste, li\u00e9 \u00e0 lui et forc\u00e9ment fragile, plut\u00f4t qu&rsquo;un legs politique. La preuve: quand les \u00c9tats-Unis sont gouvern\u00e9s de fa\u00e7on brutale, on voit bien aujourd&rsquo;hui \u00e0 quel point ils peuvent susciter de l&rsquo;hostilit\u00e9 dans le monde.<\/em><\/p>\n<\/p>\n<p><\/p>\n<p><p>\tIl y a, en Europe, particuli\u00e8rement en France, un coup de sang \u00e0 l&rsquo;occasion de la sortie des m\u00e9moires de Clinton. Ce coup de sang est \u00e0 la mesure de l&rsquo;atterrement chaque jour grandissant que produisent l&rsquo;administration GW Bush et son action. D&rsquo;une certaine fa\u00e7on, pendant quelques jours, on r\u00eave d&rsquo;un Kerry \u00e9lu qui serait finalement un Clinton-bis, avec le retour des beaux jours, \u00e0 un point qu&rsquo;on pourrait parfois croire que c&rsquo;est Bill Clinton et nul autre le candidat. Il s&rsquo;agit plus de psychologie que de politique, comme c&rsquo;est le cas aujourd&rsquo;hui dans le temps historique \u00e9trange que nous traversons.<\/p>\n<\/p>\n<p><p>\tPour autant, tous ces commentaires, notamment ceux qu&rsquo;on lit sur Clinton, oublient de nombreuses choses de l&rsquo;administration Clinton, et simplement le fait que l&rsquo;action de l&rsquo;administration Clinton n&rsquo;a pas \u00e9t\u00e9 loin, \u00e0 bien des \u00e9gards, de pr\u00e9parer le terrain pour l&rsquo;administration Bush.<\/p>\n<\/p>\n<p><p>\t&bull; C&rsquo;est Clinton qui fit voter en 1996 la premi\u00e8re loi anti-terroriste s\u00e9rieuse, qui est un <em>blueprint<\/em> pour le PATRIOT Act.<\/p>\n<\/p>\n<p><p>\t&bull; C&rsquo;est le secr\u00e9taire d&rsquo;\u00c9tat de Clinton, Madeleine Albright, \u00e9galement c\u00e9l\u00e9br\u00e9e par V\u00e9drine, qui fit le 15 f\u00e9vrier 1999, \u00e0 son arriv\u00e9e en France avant les ultimes n\u00e9gociations avec les Serbes d\u00e9bouchant sur l&rsquo;attaque du Kosovo, un discours o\u00f9 elle d\u00e9clarait qu&rsquo;il \u00e9tait temps de ne plus s&#8217;embarrasser de la souverainet\u00e9 nationale des autres lorsqu&rsquo;il s&rsquo;agissait de punir l&rsquo;un ou l&rsquo;autre \u00c9tat r\u00e9calcitrant.<\/p>\n<\/p>\n<p><p>\t&bull; C&rsquo;est l&rsquo;administration Clinton qui lan\u00e7a la guerre du Kosovo, o\u00f9 la brutalit\u00e9 US, les bombardements massifs am\u00e9ricains, affol\u00e8rent \u00e0 plus d&rsquo;une reprise les alli\u00e9s europ\u00e9ens, notamment les Fran\u00e7ais.<\/p>\n<\/p>\n<p><p>\t&bull; C&rsquo;est l&rsquo;administration Clinton qui mena \u00e0 grand train la globalisation financi\u00e8re qui pr\u00e9cipita des crises majeures en Asie, r\u00e9duisit la Russie \u00e0 un \u00c9tat semi-mafieux, pr\u00e9cipita l&rsquo;effondrement de certains pays d&rsquo;Am\u00e9rique Latine, etc.<\/p>\n<\/p>\n<p><p>\t&bull; C&rsquo;est l&rsquo;administration Clinton qui maintint l&#8217;embargo contre l&rsquo;Irak, qui fit entre 500.000 et un million de morts civils, et pilonna r\u00e9guli\u00e8rement ce pays de mani\u00e8re d\u00e9lib\u00e9r\u00e9e et pr\u00e9-emptive.<\/p>\n<\/p>\n<p><p>\t&bull; Quant \u00e0 ce que nous dit V\u00e9drine sur la bienveillance de l&rsquo;administration Clinton concernant les efforts europ\u00e9ens pour constituer une d\u00e9fense europ\u00e9enne (\u00ab <em>Les avanc\u00e9es des Europ\u00e9ens en mati\u00e8re de politique \u00e9trang\u00e8re ou de d\u00e9fense <\/em>[n&rsquo;inqui\u00e9taient pas Clinton] <em>outre mesure. Si les Europ\u00e9ens avaient \u00e9t\u00e9 capables de faire de vrais progr\u00e8s dans ces domaines, Clinton s&rsquo;en serait sans doute accommod\u00e9<\/em> \u00bb], on rappellera simplement l&rsquo;hyst\u00e9rie qui saisit Washington lorsque les Britanniques lanc\u00e8rent en 1998 leur initiative qui aboutit aux accords franco-britanniques de Saint-Malo ; et ainsi de suite<\/p>\n<\/p>\n<p><p>\tPar-dessus tout, les uns et les autres oublient que le Clinton dont ils parlent est le Clinton pr\u00e9-9\/11. Il aurait \u00e9t\u00e9 int\u00e9ressant, et sans doute piquant, de voir ce qu&rsquo;un Clinton, si compl\u00e8tement prisonnier de son image aupr\u00e8s d&rsquo;un public devenu soudain hyper-patriotard, aurait fait apr\u00e8s l&rsquo;attaque du 11 septembre.<\/p>\n<\/p>\n<p><p>\tQuant \u00e0 Clinton et au giga-lancement de ses m\u00e9moires, on voit que l&rsquo;hypoth\u00e8se la plus g\u00e9n\u00e9ralement accept\u00e9e est que cette action, plus que d&rsquo;aider Kerry, pourrait bien conduire \u00e0 mettre en \u00e9vidence, par contraste, la m\u00e9diocrit\u00e9 du candidat d\u00e9mocrate. Il n&rsquo;est pas s\u00fbr que cela d\u00e9plaise aux Clinton. Si Hillary a des ambitions pr\u00e9sidentielles, c&rsquo;est pour 2008 qu&rsquo;elle les r\u00e9serve. Et 2008 avec un GW catastrophique en fin de parcours, et sans doute un parti r\u00e9publicain exsangue, c&rsquo;est bien mieux que 2008 avec un Kerry toujours tent\u00e9 par un deuxi\u00e8me mandat. Et comme, par ailleurs, tout le monde sait que les Clinton forment un couple exemplaire et que Bill n&rsquo;a jamais rien su refuser \u00e0 Hillary<\/p>\n<\/p>\n<p><\/p>\n<p><p>\t[En attendant les \u00e9lections de novembre o\u00f9 Bill ne sera pas candidat et celle de 2008 o\u00f9 Hillary le sera peut-\u00eatre, un rappel sur la carri\u00e8re pr\u00e9sidentielle du premier. Ci-dessous, le texte <em>Analyse<\/em> paru le 25 janvier 2001 dans la Lettre d&rsquo;Analyse <em>de defensa<\/em>.]<\/p>\n<\/p>\n<p><\/p>\n<h2 class=\"common-article\">See You, Bill<\/h2>\n<\/p>\n<p><\/p>\n<p><p>\t\u00ab <em>See you<\/em> \u00bb, c&rsquo;est-\u00e0-dire \u00ab\u00a0\u00e0 bient\u00f4t\u00a0\u00bb en langage un peu leste, comme sa personne. Le d\u00e9part de Bill Clinton a \u00e9t\u00e9 comme celui d&rsquo;un copain qu&rsquo;on sera amen\u00e9 \u00e0revoir. Il y a fort \u00e0 parier qu&rsquo;on entendra encore parler de lui. (Ne serait-ce que comme <em>First Gentleman<\/em> d&rsquo;une Hillary pr\u00e9sidente en 2004 ou 2008, &mdash; si elle n&rsquo;a pas abandonn\u00e9 Clinton pour devenir Hillary Rodham tout court.) En d&rsquo;autres mots : William Jefferson Clinton n&rsquo;est pas un homme dont on se d\u00e9barrasse facilement.<\/p>\n<\/p>\n<p><p>\tIl y a des hypoth\u00e8ses pour l&rsquo;avenir de Clinton. Celle de Ed Vulliamy, correspondant \u00e0 Washington du <em>Guardian<\/em> vaut qu&rsquo;on s&rsquo;y arr\u00eate. Vulliamy \u00e9crit que Clinton, devenu rien moins que \u00ab <em>president in exile<\/em> \u00bb, a des ambitions plan\u00e9taires (\u00ab <em>Yesterday America&#8230; and tomorrow the world<\/em> \u00bb, titre de l&rsquo;article de Vulliamy du 7 janvier 2001 dans <em>The Guardian<\/em>).<\/p>\n<\/p>\n<p><p>\tVulliamy s&rsquo;explique : Clinton va se lancer dans un grand projet, dont on a d\u00e9j\u00e0, sans y prendre garde (et pour cause), entendu les pr\u00e9misses les ann\u00e9es pr\u00e9c\u00e9dentes. C&rsquo;est la mirobolante \u00ab\u00a0troisi\u00e8me voie\u00a0\u00bb (\u00ab <em>Third Way<\/em> \u00bb), qui annonce un mouvement politique moderniste, social-d\u00e9mocrate modernis\u00e9, entre le capitalisme pur et dur et le d\u00e9funt socialisme. Clinton est intronis\u00e9, sous la plume de Vulliamy, \u00ab <em>World President of the Third Way<\/em> \u00bb, avec le soutien, para\u00eet-il, de nombreux amis du c\u00f4t\u00e9 de chez Tony Blair, Lionel Jospin, Gerhardt Schr\u00f6der. On en saura plus vers le milieu de cette ann\u00e9e, \u00e0 la \u00ab\u00a0Conf\u00e9rence de la Troisi\u00e8me Voie\u00a0\u00bb \u00e0 Stockholm, patrie de la social-d\u00e9mocratie moderne (conf\u00e9rence pr\u00e9vue au moment de la fin de la pr\u00e9sidence su\u00e9doise de l&rsquo;UE). Vulliamy explique encore (on conserve les termes originaux pour qu&rsquo;il n&rsquo;y ait aucune confusion) que cette conf\u00e9rence est destin\u00e9e \u00e0 \u00eatre \u00ab <em>a coming-out party for the shadow Atlantic Alliance<\/em> \u00bb. Vaste programme, \u00e0 la lumi\u00e8re duquel la bataille post-\u00e9lectorale de novembre-d\u00e9cembre 2000 prend une autre place et acquiert une autre dimension : son poulain battu dans les conditions qu&rsquo;on sait, il s&rsquo;agit de rien moins qu&rsquo;une entr\u00e9e en dissidence de l&rsquo;ancien pr\u00e9sident des \u00c9tats-Unis Bill Clinton apr\u00e8s une issue de la crise qui installe un pr\u00e9sident soi-disant r\u00e9actionnaire \u00e0 la Maison-Blanche. On n&rsquo;y peut rien si tout cela fait un peu bande dessin\u00e9e.<\/p>\n<\/p>\n<p><p>\tIl y a l\u00e0, dans cette hypoth\u00e8se et cette interpr\u00e9tation de Vulliamy qui refl\u00e8tent des hypoth\u00e8ses et des interpr\u00e9tations venues de l&rsquo;entourage de Clinton, une construction virtualiste qui est bien de son temps. Pour autant, il ne faut pas l&rsquo;\u00e9carter d&rsquo;un haussement d&rsquo;\u00e9paules. Le principal legs de Clinton \u00e0 l&rsquo;Am\u00e9rique et au monde, le seul digne vraiment d&rsquo;\u00eatre mentionn\u00e9, c&rsquo;est d&rsquo;avoir install\u00e9 quelque chose de tout \u00e0 fait nouveau ; c&rsquo;est d&rsquo;avoir install\u00e9 dans le compte-rendu des affaires du monde, dans l&rsquo;\u00e9cho m\u00e9diatique qui en est obtenu, dans l&rsquo;image qui en est v\u00e9hicul\u00e9e par les formidables moyens modernes de la communication, une repr\u00e9sentation qui s&rsquo;est d\u00e9cisivement d\u00e9marqu\u00e9e de la r\u00e9alit\u00e9 (d\u00e9finitivement, c&rsquo;est moins s\u00fbr). Par ailleurs (voir notre rubrique <em>de defensa<\/em>), nous nommons cela la \u00ab\u00a0r\u00e9alit\u00e9-virtuelle\u00a0\u00bb (pour la diff\u00e9rencier de la \u00ab\u00a0r\u00e9alit\u00e9-r\u00e9elle\u00a0\u00bb qui, elle, continue son petit bonhomme de chemin, et c&rsquo;est l\u00e0 tout le sel de l&rsquo;existence). La puissance des moyens employ\u00e9s \u00e0 cette t\u00e2che et l&rsquo;uniformit\u00e9 de l&rsquo;attitude de conformisme qui caract\u00e9rise aujourd&rsquo;hui notre d\u00e9marche d&rsquo;appr\u00e9ciation des affaires publiques ont puissamment contribu\u00e9 \u00e0 l&rsquo;installation de ce ph\u00e9nom\u00e8ne. Une nouvelle \u00ab\u00a0r\u00e9alit\u00e9\u00a0\u00bb s&rsquo;est install\u00e9e dans l&rsquo;esprit des gens et dans les conceptions et les analyses de ceux qui sont charg\u00e9s d&rsquo;informer les gens, ce milieu m\u00e9diatique et de l&rsquo;information o\u00f9 s&rsquo;\u00e9bat d\u00e9sormais ce qu&rsquo;on nomme encore \u00ab\u00a0la politique\u00a0\u00bb.<\/p>\n<\/p>\n<p><p>\tVoil\u00e0 pourquoi il faut \u00e0 la fois sourire et prendre au s\u00e9rieux les projets de monsieur-\u00ab <em>World President of the Third Way<\/em> \u00bb. Cela n&rsquo;est plus de l&rsquo;histoire ni de la politique. C&rsquo;est la bataille conduite dans la r\u00e9alit\u00e9-virtuelle. On ne peut en parler en termes de politique concr\u00e8te, car tout cela n&rsquo;a au bout du compte aucune r\u00e9alit\u00e9 concr\u00e8te ; mais on doit en parler en termes de d\u00e9sordre grandissant introduit dans le syst\u00e8me (le syst\u00e8me, notamment : \u00e9conomie et syst\u00e8me boursier globalis\u00e9s, puissance du complexe militaro-industriel, d\u00e9veloppement incontr\u00f4l\u00e9 des technologies, etc). D&rsquo;ailleurs, et pour corser le paradoxe, ce syst\u00e8me a lui-m\u00eame acquis une dimension de compl\u00e8te virtualit\u00e9 au long des ann\u00e9es Clinton, et \u00e9galement avec l&rsquo;aide puissante de Clinton.<\/p>\n<\/p>\n<p><p>\tEn d&rsquo;autres termes, et pour expliciter cette derni\u00e8re phrase \u00e9nigmatique qui fait de Clinton l&rsquo;architecte du syst\u00e8me qu&rsquo;il entend par ailleurs combattre avec sa \u00ab\u00a0pr\u00e9sidence mondiale de la troisi\u00e8me voie\u00a0\u00bb, cet homme joue double jeu. Il ne le fait pas par calcul, mais plut\u00f4t par m\u00e9garde, par inadvertance et par nonchalance, par n\u00e9cessit\u00e9, par penchant du caract\u00e8re, enfin parce que l&rsquo;aubaine est l\u00e0, comme une jeune stagiaire tra\u00eenant dans les couloirs de la Maison-Blanche. On ne s&rsquo;\u00e9tonnera pas de nous voir conclure qu&rsquo;il y a chez Clinton deux hommes (on nous trouverait m\u00eame un peu chiche, sans doute). Ils ont successivement occup\u00e9 la Maison-Blanche sans que nous nous en soyons vraiment aper\u00e7us. Pour dire autrement et en revenir pr\u00e9cis\u00e9ment aux ann\u00e9es du mandat Clinton, il y a cette id\u00e9e que, quelque part au coeur des ann\u00e9es Clinton, il y a eu une sorte de coup d&rsquo;\u00c9tat dont nul ne s&rsquo;est avis\u00e9.<\/p>\n<\/p>\n<p><\/p>\n<h3>La rupture de novembre 1994 : ses espoirs an\u00e9antis, Clinton va devoir jouer le r\u00f4le d&rsquo;un acteur qui joue au pr\u00e9sident<\/h3>\n<\/p>\n<p><p>\tLe personnage, d&rsquo;abord. Quoiqu&rsquo;on en veuille, Clinton n&rsquo;est pas un homme de concept ni un homme de vision, ni un homme de r\u00e9flexion, ni un homme d&rsquo;action qui d\u00e9cide. C&rsquo;est un homme qui bouge, comme un gosse qui est \u00e0 la recherche de quelque chose \u00e0 faire. C&rsquo;est un \u00ab <em>pr\u00e9sident-ado<\/em> \u00bb (mot du journaliste Richard Bernstein en novembre 1996), sensible aux ors et aux discours, aux paillettes, \u00e0 la pompe, aux images en d&rsquo;autres mots. Il est l&rsquo;enfant de son \u00e9poque, et il joue impeccablement le r\u00f4le d&rsquo;un enfant de son \u00e9poque qui jouerait le r\u00f4le d&rsquo;un acteur jouant le r\u00f4le du pr\u00e9sident, avec un texte mille fois r\u00e9p\u00e9t\u00e9 et qui s&rsquo;ins\u00e8re merveilleusement dans l&rsquo;esprit du temps. Clinton est <em>fun<\/em>, il est extraordinairement \u00e0 la mode, puisqu&rsquo;il est un peu le cr\u00e9ateur de notre r\u00e9alit\u00e9-virtuelle. C&rsquo;est l&rsquo;explication de sa popularit\u00e9 \u00e9galement extraordinaire dans tous les milieux de la communication, de la gauche humanitariste, en Europe surtout et \u00e0 Paris principalement, malgr\u00e9 deux bons tiers de sa pr\u00e9sidence pass\u00e9s \u00e0 prendre toutes les mesures r\u00e9clam\u00e9es par les r\u00e9publicains r\u00e9actionnaires, et le soutien \u00e0 une politique \u00e9conomique de globalisation d\u00e9vastatrice. Il leur joue leur r\u00f4le favori, et il joue avec suffisamment de distance pour qu&rsquo;on voit qu&rsquo;il joue fort bien et suffisamment d&rsquo;alacrit\u00e9 pour qu&rsquo;on croit \u00e0 son jeu.<\/p>\n<\/p>\n<p><p>\tC&rsquo;est pourquoi il est un acteur fantastique (voir son <em>clip<\/em> sur le pr\u00e9sident cherchant \u00e0 s&rsquo;occuper apr\u00e8s la fin de sa pr\u00e9sidence) ; un acteur bien plus int\u00e9ressant que le vieux Reagan poussi\u00e9reux et fig\u00e9 dans son sourire hollywoodien. Il y a des tonnes et des milliers de kilom\u00e8tres de diff\u00e9rence entre un Reagan qui rit, fa\u00e7on Hollywood-ann\u00e9es quarante, et un Clinton pris d&rsquo;un fou-rire devant un Eltsine qui a un peu forc\u00e9 sur la vodka, devant les journalistes s\u00e9rieux de Washington, \u00e9bahis et conquis. Il y a chez Clinton une sorte de sinc\u00e9rit\u00e9 du menteur convaincu ou, encore mieux, du menteur  compl\u00e8tement sinc\u00e8re, un \u00ab\u00a0paradoxe du com\u00e9dien\u00a0\u00bb soutenu sans faillir. (Cela doit d&rsquo;ailleurs nous faire mesurer ce que vaut son principal legs, la r\u00e9alit\u00e9-virtuelle d\u00e9crite plus haut : c&rsquo;est d&rsquo;abord la cr\u00e9ation du menteur sinc\u00e8re ; cela en a la solidit\u00e9, la profondeur, la r\u00e9alit\u00e9. Dont acte.)<\/p>\n<\/p>\n<p><p>\tCet homme qui bouge, ce menteur sinc\u00e8re, ce com\u00e9dien qui nous en bouche en coin se devait d&rsquo;\u00eatre multiple durant sa pr\u00e9sidence. Il le fut. Mais il ne faut pas trop le soup\u00e7onner de machiav\u00e9lisme car la manipulation clintonienne s&rsquo;arr\u00eate l\u00e0. C&rsquo;est m\u00eame le contraire. En fait de manipulation, sans doute pourrait-on \u00e9crire un jour que Clinton fut manipul\u00e9 par son destin, et, par cons\u00e9quent, conclure qu&rsquo;il y a aussi quelque chose de path\u00e9tique, voire de tragique, dans l&rsquo;histoire de ce clown-ado devenu pr\u00e9sident. (Clown-ado devenu pr\u00e9sident, il n&rsquo;y a qu&rsquo;en Am\u00e9rique qu&rsquo;on voit cela. Ce sont les exclamations, avec r\u00e9f\u00e9rence \u00e0 l&rsquo;<em>American Dream<\/em> en arri\u00e8re-plan, qui salu\u00e8rent en Europe l&rsquo;\u00e9lection du soi-disant inconnu [pour l&rsquo;Europe] Bill Clinton. Nous ne sommes attach\u00e9s qu&rsquo;\u00e0 ce qu&rsquo;il y a de spectacle et d&rsquo;apparence aguicheuse dans l&rsquo;Am\u00e9rique. Nous en ratons les drames et les trag\u00e9dies.)<\/p>\n<\/p>\n<p><p>\tMieux (ou pire) : il se pourrait que Clinton ait \u00e9t\u00e9 manipul\u00e9 par quelque chose qui ressemblerait \u00e0 de la na\u00efvet\u00e9, et qu&rsquo;il aurait eue lui-m\u00eame, et qui lui aurait fait croire de fa\u00e7on irr\u00e9aliste \u00e0 certaines perspectives. C&rsquo;est l\u00e0 qu&rsquo;on en arrive \u00e0 ce que nous avons \u00e9voqu\u00e9 plus haut, cette \u00ab <em>sorte de coup d&rsquo;\u00c9tat dont nul ne s&rsquo;est avis\u00e9<\/em> \u00bb.<\/p>\n<\/p>\n<p><p>\tIl y a un tournant de la pr\u00e9sidence Clinton : en novembre 1994, aux \u00e9lections <em>mid-term<\/em> qui virent la victoire des r\u00e9publicains (majorit\u00e9 dans les deux assembl\u00e9es). D\u00e9faite terrible, et bien plus qu&rsquo;une d\u00e9faite, l&rsquo;effondrement de ses ambitions. Clinton avait des ambitions rooseveltiennes (FDR, 1933-1945, mais surtout celui de la Grande D\u00e9pression, 1933-1940). Question \u00e9vidente d&rsquo;image, l\u00e0 aussi : le grand pr\u00e9sident social derri\u00e8re des allures \u00e0-la-Kennedy. Cette d\u00e9faite de novembre 1994 venait sanctionner deux ann\u00e9es de rude combat, pied \u00e0 pied, au Congr\u00e8s, face aux r\u00e9publicains d\u00e9j\u00e0 majoritaires \u00e0 la Chambre. D\u00e9sormais, en novembre 1994, devant les r\u00e9publicains victorieux conduits par l&rsquo;impitoyable Newt Gingrich, c&rsquo;en \u00e9tait fini. Le Pr\u00e9sident \u00e9tait pieds et poings li\u00e9s. Une source proche de la Maison-Blanche, au NSC, nous a rapport\u00e9 combien cette p\u00e9riode fut terrible pour Clinton, &mdash; et cette p\u00e9riode qui reste bien peu connue. Clinton subit une terrible d\u00e9pression, et l&rsquo;on parle de cela au sens m\u00e9dical. On le trouvait dans les couloirs de la Maison-Blanche en robe de chambre et mal ras\u00e9, ou bien prostr\u00e9, refusant de prendre les appels t\u00e9l\u00e9phoniques. \u00ab <em>Cela dura plusieurs semaines, <\/em>rapporte la source, <em>pendant lesquelles le pr\u00e9sident des \u00c9tats-Unis n&rsquo;\u00e9tait plus qu&rsquo;une ombre incertaine, incapable de remplir sa fonction.<\/em> \u00bb<\/p>\n<\/p>\n<p><p>\tLe r\u00e9tablissement vint peu \u00e0 peu, mais dans une situation qui \u00e9tait radicalement diff\u00e9rente. Nous avons d\u00e9j\u00e0 signal\u00e9 combien ce tournant se marquait dans les faits : de janvier 1993 \u00e0 juin 1995, pas un seul veto contre le Congr\u00e8s, ce qui repr\u00e9sente un cas unique pour cette dur\u00e9e dans l&rsquo;histoire de la pr\u00e9sidence am\u00e9ricaine ; puis, \u00e0 partir de juin 1995, le pr\u00e9sident n&rsquo;h\u00e9site plus \u00e0 user du veto au rythme habituel d&rsquo;un pr\u00e9sident d\u00e9cid\u00e9 \u00e0 tenter de marquer son autorit\u00e9. Ce tournant de juin 1995, c&rsquo;est la marque l\u00e9gislative que Clinton a compris qu&rsquo;il ne pourrait rien faire avec le Congr\u00e8s sinon se battre contre lui, que son programme int\u00e9rieur est mort. C&rsquo;est alors que Clinton a commenc\u00e9 \u00e0 \u00eatre compl\u00e8tement ce qu&rsquo;il n&rsquo;avait \u00e9t\u00e9 jusqu&rsquo;alors qu&rsquo;en partie : un acteur jouant le r\u00f4le d&rsquo;un acteur qui serait pr\u00e9sident, &mdash; de fa\u00e7on qu&rsquo;on sache bien qu&rsquo;il y avait interpr\u00e9tation de sa part (ce en quoi, l\u00e0 encore, il est diff\u00e9rent de Reagan et il lui est sup\u00e9rieur).<\/p>\n<\/p>\n<p><\/p>\n<h3>Clinton a \u00e9t\u00e9 autant l&rsquo;enfant du syst\u00e8me qu&rsquo;il en a \u00e9t\u00e9 le prisonnier<\/h3>\n<\/p>\n<p><p>\tD&rsquo;un autre c\u00f4t\u00e9, il faut savoir que Clinton \u00e9tait d\u00e9j\u00e0 \u00e0 moiti\u00e9 pris, avant le  coup de novembre 1994. On conna\u00eet son grand succ\u00e8s, affirm\u00e9 et r\u00e9p\u00e9t\u00e9 \u00e0 sati\u00e9t\u00e9 et <em>a posteriori<\/em>, le <em>boom<\/em> \u00e9conomique. Chronologiquement autant que dans le cours des chose, Clinton n&rsquo;y est pas pour grand&rsquo;chose. L&rsquo;essentiel avait \u00e9t\u00e9 d\u00e9cid\u00e9, boucl\u00e9, verrouill\u00e9, d\u00e8s 1991-92. Cela est connu du c\u00f4t\u00e9 de Greenspan (le patron de la Federal Reserve mit en place d\u00e8s le d\u00e9but de 1992, pour r\u00e9pondre aux demandes de son ami le pr\u00e9sident Bush-p\u00e8re, les mesures qui men\u00e8rent assez rapidement au red\u00e9marrage de la croissance). Cela a \u00e9t\u00e9 \u00e9crit et d\u00e9taill\u00e9, en long et en large (1), pour ce qui concerne le c\u00f4t\u00e9 des d\u00e9mocrates : r\u00e9unions en 1991 des dirigeants du parti et des banquiers d\u00e9mocrates de Wall Street, d\u00e9cision (dans le cas d&rsquo;une victoire d\u00e9mocrate en 1992) de lancer une politique de globalisation et d&rsquo;hyper-croissance appuy\u00e9e sur l&rsquo;endettement, le d\u00e9veloppement des technologies et l&rsquo;hyper-expansion boursi\u00e8re. Bill Clinton ne fit qu&rsquo;appliquer la consigne du parti, en confiant le contr\u00f4le des m\u00e9canismes financiers de l&rsquo;\u00e9conomie au banquier d\u00e9mocrate de Wall Street Robert Rubin (vice-secr\u00e9taire puis secr\u00e9taire au tr\u00e9sor), avec l&rsquo;appui amical et attentif de Greenspan.<\/p>\n<\/p>\n<p><p>\tLorsqu&rsquo;on rappelle tout cela, on se dit que les projets int\u00e9rieurs de Clinton (des Clinton, en fait, Hillary \u00e9tant partie prenante) avaient bien peu de chance d&rsquo;aboutir, que le d\u00e9sastre de novembre 1994 n&rsquo;a fait que sanctionner la d\u00e9faite g\u00e9n\u00e9rale qui \u00e9tait inscrite dans l&rsquo;histoire de ce candidat apparemment sorti de nulle part, mais d\u00e8s l&rsquo;origine fortement d\u00e9biteur des puissances politiques et (surtout) \u00e9conomiques et financi\u00e8res du syst\u00e8me. La d\u00e9pression de Bill \u00e9tait \u00e9crite.<\/p>\n<\/p>\n<p><p>\tIl fallut un certain temps avant que Bill Clinton compr\u00eet tr\u00e8s pr\u00e9cis\u00e9ment ce qu&rsquo;on attendait de lui, notamment le temps de s&rsquo;apercevoir que ses projets avaient bien peu de chances d&rsquo;aboutir (novembre 1994). Ce qu&rsquo;on attendait de lui, comme disent les journalistes s\u00e9rieux qui ont des choses \u00e0 dire : \u00ab\u00a0g\u00e9rer\u00a0\u00bb la croissance (d\u00e9cid\u00e9e et instrument\u00e9e par les autres). Nous, nous dirions plut\u00f4t, \u00e0 la lumi\u00e8re du rythme syncop\u00e9 et du s\u00e9rieux des choses \u00e9conomiques aujourd&rsquo;hui, des variations du NASDAQ, des coups de la Bourse et des coups de pub : on attendait de Bill Clinton qu&rsquo;il dev\u00eent le <em>disc-jockey<\/em> (DJ) du <em>boom<\/em> des ann\u00e9es 1990. Malgr\u00e9 ses qualit\u00e9s naturelles, cela ne lui fut pas si facile. Les Am\u00e9ricains ne mordirent \u00e0 l&rsquo;id\u00e9e qu&rsquo;ils \u00e9taient en pleine croissance et compl\u00e8tement heureux qu&rsquo;\u00e0 partir de l&rsquo;\u00e9t\u00e9 1996 (apparition d&rsquo;un courant d&rsquo;optimisme majoritaire, selon les sondages), alors que l&rsquo;\u00e9conomie tournait \u00e0 plein depuis 1993-94. Preuve, peut-\u00eatre, qu&rsquo;ils (les Am\u00e9ricains) se doutaient de quelque chose, &mdash; \u00e0 la fois sur la validit\u00e9 de ce <em>boom<\/em> \u00e9conomique et sur la qualit\u00e9 r\u00e9elle de la situation qu&rsquo;on leur repr\u00e9sentait comme exceptionnelle. Puis tout bascula en une d\u00e9bauche m\u00e9diatique et de communication pour pr\u00e9senter effectivement le triomphe am\u00e9ricain : la folie-Wall Street, l&rsquo;\u00e9conomie \u00ab <em>beyond history<\/em> \u00bb, c&rsquo;est-\u00e0-dire, la \u00ab <em>nouvelle \u00e9conomie<\/em> \u00bb. (Et aussi la dette ext\u00e9rieure colossale, l&rsquo;endettement \u00e9galement colossal des Am\u00e9ricains, ces bombes \u00e0 retardement qui continuent \u00e0 cliqueter.)<\/p>\n<\/p>\n<p><p>\tEn d&rsquo;autres termes, d\u00e8s l&rsquo;origine Bill \u00e9tait prisonnier du syst\u00e8me autant qu&rsquo;il en \u00e9tait l&rsquo;enfant. Cela n&rsquo;a rien pour surprendre tant c&rsquo;est dans l&rsquo;ordre des choses. Mais l&rsquo;exc\u00e8s des qualit\u00e9s et des d\u00e9fauts de Clinton font la diff\u00e9rence et accordent une place exceptionnelle \u00e0 cet \u00e9trange statut d&rsquo;enfant et de prisonnier d&rsquo;un syst\u00e8me, et permettent des \u00e9chapp\u00e9es inattendues. C&rsquo;est l\u00e0, on le verra plus loin, que la chose devient int\u00e9ressante et, pour tout dire, irr\u00e9sistible.<\/p>\n<\/p>\n<p><p>\tDevenu DJ de l&rsquo;\u00e9conomie US triomphante une fois ses ambitions int\u00e9rieures pulv\u00e9ris\u00e9es, Clinton devait conclure aussit\u00f4t que c&rsquo;\u00e9tait insuffisant pour remplir une pr\u00e9sidence dont il esp\u00e9rait, en acteur consomm\u00e9, que l&rsquo;histoire se souviendrait. Un acteur ne peut jouer dans une situation sans mouvement, sans  intrigue, sans sc\u00e9nario, \u00e0 simplement faire la promotion des mouvements saccad\u00e9s et obs\u00e9dants autour de lui (Wall Street). Il s&rsquo;inventa donc une politique \u00e9trang\u00e8re, domaine qu&rsquo;il avait jusqu&rsquo;alors plut\u00f4t laiss\u00e9 au second plan. L\u00e0 aussi, les dates s&rsquo;encha\u00eenent bien pour confirmer cette interpr\u00e9tation de la pr\u00e9sidence Clinton : rupture de sa politique avec le Congr\u00e8s (premier veto le 7 juin 1995), implication en Bosnie en ao\u00fbt-septembre 1995, accords de Dayton de novembre 1995 et ainsi de suite.<\/p>\n<\/p>\n<p><p>\tTout dans l&rsquo;activit\u00e9 de politique ext\u00e9rieure de Bill Clinton \u00e0 partir de 1995 confirme cette hypoth\u00e8se d&rsquo;une repr\u00e9sentation d&rsquo;acteur, dans un domaine nomm\u00e9 r\u00e9alit\u00e9-virtuelle. Laissons de c\u00f4t\u00e9 la th\u00e8se de l\u00ab <em>hyperpuissance<\/em> \u00bb \u00e0 qui le pr\u00e9sident Clinton aurait donn\u00e9 tout son allant h\u00e9g\u00e9monique et son poids dominateur d&rsquo;aujourd&rsquo;hui. On ne peut que r\u00e9p\u00e9ter une fois encore que l&rsquo;Am\u00e9rique domine le monde depuis 1945 comme aucune puissance ne l&rsquo;a fait avant elle, que sa domination \u00e9tait encore plus r\u00e9elle, mais plus discr\u00e8te et, \u00e0 notre sens, plus efficace, en 1950 ou en 1970, que son statut actuel est une pente \u00e9vidente apr\u00e8s la disparition de l&rsquo;URSS, et une pente qui, en plus, ne manque pas d&rsquo;obstacles.<\/p>\n<\/p>\n<p><p>\tCe qui est plus int\u00e9ressant, c&rsquo;est l&rsquo;activit\u00e9 de Clinton, troquant ses ambitions de nouveau-Roosevelt (projets int\u00e9rieurs jusqu&rsquo;en 1994-1995) pour celle d&rsquo;un nouveau-Wilson (n\u00e9o-internationalisme wilsonien). C&rsquo;est le Clinton \u00ab\u00a0faiseur de paix\u00a0\u00bb, amorc\u00e9 d\u00e8s la poign\u00e9e de mains Arafat-Rabin de d\u00e9cembre 1993, o\u00f9 les \u00c9tats-Unis kidnappaient \u00e0 leur compte un processus discr\u00e8tement lanc\u00e9 par l&rsquo;entremise de l&rsquo;honn\u00eate Norv\u00e8ge (les accords d&rsquo;Oslo). Cette activit\u00e9 clintonienne est bien du domaine du virtuel, puisqu&rsquo;elle finit, au Proche-Orient comme en Irlande, par cr\u00e9er l&rsquo;illusion d&rsquo;une paix virtuelle en train de s&rsquo;\u00e9tablir alors que les probl\u00e8mes demeurent et parfois s&rsquo;amplifient de fa\u00e7on dramatique (voir la situation entre Isra\u00e9liens et Palestiniens aujourd&rsquo;hui). Mais peut-on vraiment lui en vouloir ? Clinton a agi toujours avec cette m\u00eame conviction de l&rsquo;acteur qui joue le r\u00f4le de l&rsquo;acteur jouant au pr\u00e9sident, plein de cette \u00e9trange sinc\u00e9rit\u00e9 du faiseur de mensonges, appuy\u00e9e sur une situation fabriqu\u00e9e de toutes pi\u00e8ces.<\/p>\n<\/p>\n<p><\/p>\n<h3>Clinton est-il cet homme qui aurait pu \u00eatre un grand homme d&rsquo;\u00c9tat, et \u00e0 qui a tout g\u00e2ch\u00e9 par faiblesse de caract\u00e8re ?<\/h3>\n<\/p>\n<p><p>\tBien s\u00fbr, il y a encore un autre Clinton, inratable : celui des collectes de fonds sans fin, celui des invitations des <em>sponsors<\/em> \u00e0 la Maison-Blanche, o\u00f9 une nuit\u00e9e dans la couche de Lincoln se payait plusieurs centaines de milliers de dollars de contribution au parti ; il y a le Clinton des tourn\u00e9es de propagande \u00e9lectorale tout au long de l&rsquo;ann\u00e9e, m\u00eame hors-campagne, toujours pour r\u00e9unir des fonds, une activit\u00e9 dont l&rsquo;addition du temps consacr\u00e9 montrerait qu&rsquo;elles prenaient un bon gros cinqui\u00e8me, voire un quart du temps de travail de \u00ab <em>l&rsquo;homme le plus puissant de la plan\u00e8te<\/em> \u00bb ; il y a le Clinton des scandales qui n&rsquo;en sont pas vraiment mais qui le sont peut-\u00eatre, le Clinton des affaires scabreuses mais pas vraiment m\u00e9chantes, le Clinton de la petite Lewinsky et de la farce de la destitution. Vraiment, quand on sait le reste, peut-on lui en vouloir ? Doit-on s&rsquo;en \u00e9tonner, et, par cons\u00e9quent, s&rsquo;en scandaliser ? N&rsquo;y a-t-il pas l\u00e0 une logique du personnage, la continuit\u00e9 d&rsquo;une psychologie ?<\/p>\n<\/p>\n<p><p>\tIls l&rsquo;ont tous dit, les seuls vrais amis, ou, disons, les amis et collaborateurs qui avaient \u00e9t\u00e9 fascin\u00e9s par sa personnalit\u00e9 pour finir par \u00eatre d\u00e9go\u00fbt\u00e9s par sa personnalit\u00e9, jusqu&rsquo;\u00e0 d\u00e9cider de s&rsquo;en aller, &mdash; bref les \u00ab\u00a0amoureux\u00a0\u00bb de Bill qui l&rsquo;ont quitt\u00e9 : son premier secr\u00e9taire au travail Robert Reich, son chef de la communication George Stefanopoulos, son porte-parole Mike McCurry : Bill avait un certain nombre de ces qualit\u00e9s qui font vraiment un grand homme d&rsquo;\u00c9tat. Mais voil\u00e0, il lui manquait quelque chose de d\u00e9cisif dont l&rsquo;absence g\u00e2chait tout ; c&rsquo;est un de ces d\u00e9fauts cach\u00e9s qu&rsquo;on prend du temps \u00e0  distinguer, et qui, aux moments essentiels, devant les cas fondamentaux, fausse d\u00e9finitivement le jugement et interdit l&rsquo;acte d\u00e9cisif ; une faiblesse fatale du caract\u00e8re, l&rsquo;absence d&rsquo;une certaine rigueur, d&rsquo;une fermet\u00e9 d&rsquo;\u00e2me, ou bien peut-\u00eatre simplement n&rsquo;avait-il pas d&rsquo;\u00e2me disponible pour sa fonction.<\/p>\n<\/p>\n<p><p>\tCeux qui nous racontent que Bill Clinton est, apr\u00e8s tout, tous comptes faits, un grand pr\u00e9sident, pas loin d&rsquo;un homme d&rsquo;\u00c9tat, et qui nous pr\u00e9sentent son bilan pour appuyer l&rsquo;affirmation, ceux-l\u00e0 sont assommants parce qu&rsquo;ils n&rsquo;ont rien compris. Ceux-l\u00e0, c&rsquo;est-\u00e0-dire les admirateurs intellectuels de Clinton, ceux qui voudraient d\u00e9couvrir dans sa pr\u00e9sidence des raisons de croire \u00e0 l&rsquo;excellence d&rsquo;un syst\u00e8me qui vous ferait sortir un homme d&rsquo;\u00c9tat d&rsquo;un trou perdu de l&rsquo;Arkansas, et qui entendent le prouver par des arguments rationnels ; c&rsquo;est-\u00e0-dire, en g\u00e9n\u00e9ral, les Europ\u00e9ens, et, comme toujours, encore plus pr\u00e9cis\u00e9ment les parisiens et les germanopratins de la rive gauche, parce qu&rsquo;il faut toujours que les Fran\u00e7ais justifient leurs emportements du coeur par une construction de l&rsquo;esprit. Ceux-l\u00e0 sont assommants parce qu&rsquo;ils n&rsquo;ont rien compris \u00e0 l&rsquo;essence du syst\u00e8me. Bien entendu, Clinton n&rsquo;a rien fait dans les affaires de l&rsquo;\u00c9tat. On a fait pour lui. Le syst\u00e8me est l\u00e0 pour \u00e7a.<\/p>\n<\/p>\n<p><p>\tDans son film <em>Nixon<\/em>, Oliver Stone rapporte cette sc\u00e8ne, cette rencontre m\u00e9morable qui eut r\u00e9ellement lieu, un soir de 1971, avec des manifestants gauchistes qui ha\u00efssaient Nixon et qui campaient pr\u00e8s de la Maison-Blanche ; et Nixon, pris d&rsquo;une inspiration, vient les visiter, impromptu, et engage une discussion surr\u00e9aliste avec eux ; et les uns et les autres, ils se parlent, et Nixon, enfin, confie \u00e0 une jeune <em>hippy<\/em>-contestatrice qu&rsquo;il a une t\u00e2che \u00e0 accomplir et qu&rsquo;il ignore s&rsquo;il parviendra \u00e0 son terme, et que cette t\u00e2che essentielle est de tenter de \u00ab <em>dompter la B\u00eate<\/em> \u00bb (\u00ab <em>to tame the Beast<\/em> \u00bb). La jeune fille en reste abasourdie. \u00ab <em>The Beast<\/em> \u00bb ? Nixon parle de cet ensemble d&rsquo;\u00e9normes forces qui pressent le pays et le pouvoir politique, le complexe militaro-industriel, la bureaucratie f\u00e9d\u00e9rale, Wall Street, les m\u00e9dias et la communication, qui travaillent tous, conspirent tous \u00e0 renforcer leur propre pouvoir, \u00e0 renforcer la situation acquise o\u00f9 ils tiennent le haut du pav\u00e9. En un mot, il s&rsquo;agit du \u00ab\u00a0syst\u00e8me\u00a0\u00bb, cette esp\u00e8ce d&rsquo;entit\u00e9 insaisissable, cette m\u00e9canique, l\u00e0 o\u00f9 il n&rsquo;y a aucun coupable et o\u00f9 tout le monde est un peu coupable.<\/p>\n<\/p>\n<p><p>\tC&rsquo;est \u00e0 Bill Clinton qu&rsquo;il revenait, encore plus qu&rsquo;\u00e0 Nixon, de tenter de dompter la B\u00eate, qui avait pris des proportions prodigieusement monstrueuses pendant la Guerre froide, et qui n&rsquo;avait plus de raison d&rsquo;\u00eatre dans ces proportions prodigieusement monstrueuses, qui n&rsquo;avait plus d&rsquo;argument pour interdire qu&rsquo;on la touch\u00e2t puisque la Guerre froide \u00e9tait finie. Bien s\u00fbr, il n&rsquo;en a rien fait. Il a laiss\u00e9 faire. La B\u00eate lui a impos\u00e9 sa politique. Lui, il a invent\u00e9 quelque chose de compl\u00e8tement nouveau, une r\u00e9alit\u00e9-virtuelle pour faire croire qu&rsquo;il n&rsquo;y avait plus de B\u00eate \u00e0 dompter. Il a fait pire que tout. Il a camoufl\u00e9 la B\u00eate derri\u00e8re le manteau de la morale et des vertus d\u00e9mocratiques dont il a fait le miel de sa technique qui lui est naturellement venue, de la r\u00e9alit\u00e9-virtuelle.<\/p>\n<\/p>\n<p><\/p>\n<h3>Evidemment, ce menteur sinc\u00e8re est l&rsquo;homme absolument de tous les paradoxes.<\/h3>\n<\/p>\n<p><p>\t&#8230; Oui, finalement homme de tous les paradoxes. A c\u00f4t\u00e9 de cette condamnation sans appel de la pr\u00e9sidence Clinton qui n&rsquo;a rien fait contre la structure \u00e9crasante et oppressive du syst\u00e8me de la Guerre froide, il y a quelque chose qui est compl\u00e8tement le contraire d&rsquo;une condamnation. Peut-\u00eatre Bill Clinton a-t-il trouv\u00e9, oh ! certainement sans le vouloir ni m\u00eame y songer une seconde, ce qui pourrait \u00eatre l&rsquo;arme supr\u00eame contre le syst\u00e8me. Ou bien, disons autrement : s&rsquo;il peut y avoir une arme supr\u00eame contre le syst\u00e8me, qui serait le seul espoir d&rsquo;envisager d&rsquo;y changer quelque chose, c&rsquo;est celle-l\u00e0 et pas une autre.<\/p>\n<\/p>\n<p><p>\tCar Bill, on l&rsquo;a vu, a invent\u00e9 pour son compte la r\u00e9alit\u00e9-virtualiste, pour l&rsquo;usage de sa fonction d&rsquo;acteur jouant \u00e0 l&rsquo;acteur qui jouerait le pr\u00e9sident. Il a ainsi mis en \u00e9vidence, toujours sans le vouloir, l&rsquo;extraordinaire facilit\u00e9, l&rsquo;\u00e9vidence de ce proc\u00e9d\u00e9 qui est une transformation de substance d&rsquo;une tendance vieille comme la politique \u00e0 la tromperie accept\u00e9e gr\u00e2ce au mensonge sinc\u00e8re et \u00e0 la complicit\u00e9 de tous. (Non, ce n&rsquo;est pas nouveau pour ce qui est des composants de cette tendance. La Bo\u00e9tie, au XVIe si\u00e8cle, nous en a parl\u00e9 avec lucidit\u00e9, dans son <em>Discours de la servitude volontaire<\/em> : ces hommes-tromp\u00e9s, ces citoyens-tromp\u00e9s qui ne demandent qu&rsquo;\u00e0 l&rsquo;\u00eatre, qui pr\u00eatent la main, qui participent au mensonge qu&rsquo;ils se r\u00e9jouissent d\u00e9j\u00e0 de croire, qui sont partie prenante de ce qui devient ce faisant une sorte de \u00ab\u00a0mensonge sinc\u00e8re\u00a0\u00bb.)<\/p>\n<\/p>\n<p><p>\tBill Clinton \u00e0 la pr\u00e9sidence, avec ses frasques, avec l&rsquo;insouciance de \u00ab\u00a0l&rsquo;acteur qui joue le r\u00f4le de l&rsquo;acteur qui &#8230;\u00a0\u00bb, a contribu\u00e9 \u00e0 une formidable d\u00e9stabilisation d&rsquo;une fonction qui est l&rsquo;un des piliers de soutien du syst\u00e8me, quoiqu&rsquo;en veuillent ceux qui occupent la fonction. En corrompant la fonction, il a mis encore plus en \u00e9vidence la corruption du syst\u00e8me. On a pu voir pendant l&rsquo;affaire Lewinsky ce spectacle \u00e9trange d&rsquo;un Clinton jouant le r\u00f4le de l&rsquo;adversaire populaire (et m\u00eame populiste !) de l&rsquo;<em>establishment<\/em> alors qu&rsquo;il en \u00e9tait si compl\u00e8tement l&rsquo;\u00e9lu et le d\u00e9l\u00e9gu\u00e9. Le jeu de miroirs de la r\u00e9alit\u00e9-virtuelle conduit \u00e0 des contre-emplois d&rsquo;une signification consid\u00e9rable.<\/p>\n<\/p>\n<p><p>\tClinton a install\u00e9 l&rsquo;image de \u00ab\u00a0l&#8217;empire du monde\u00a0\u00bb qu&rsquo;est l&rsquo;Am\u00e9rique en jouant le r\u00f4le d&rsquo;une diplomatie de la gesticulation, de la proclamation, une affirmation pompeuse de la puissance universelle. Ce faisant, il a fait perdre \u00e0 l&rsquo;Am\u00e9rique ce qui \u00e9tait sa vertu du temps de la Guerre froide ; d\u00e9sormais, on se demande si cette puissance qui, hier, prot\u00e9geait la libert\u00e9, ne la menace pas aujourd&rsquo;hui. Cela, nous le devons \u00e0 la politique de r\u00e9alit\u00e9-virtuelle du pr\u00e9sident Clinton, \u00e0 ce r\u00f4le outrancier que Clinton a jou\u00e9 avec tant de candeur.<\/p>\n<\/p>\n<p><p>\tDurant ces \u00e9tranges ann\u00e9es de sa pr\u00e9sidence, Bill Clinton, enfant et prisonnier du syst\u00e8me, a mis en place les br\u00fblots capables d&rsquo;alimenter un contre-feu face \u00e0 l&rsquo;incendie que propage le syst\u00e8me. C&rsquo;est un peu comme Internet, enfant du syst\u00e8me, favori du syst\u00e8me, objet de toutes les cajoleries du syst\u00e8mes, qui fournit en m\u00eame temps et de fa\u00e7on impr\u00e9vue un formidable outil de contre, et m\u00eame de contre-attaque, aux dissidents du syst\u00e8me jusqu&rsquo;ici d\u00e9munis dans cette mati\u00e8re essentielle de la communication de l&rsquo;information.<\/p>\n<\/p>\n<p><p>\tClinton, tel qu&rsquo;il fut, charmeur, menteur-sinc\u00e8re, peloteur de stagiaires, avide d&rsquo;argent, extraordinaire acteur, ambitieux et d\u00e9risoire <em>President of the World<\/em> &#8230; Peut-\u00eatre son legs, sa marque dans l&rsquo;histoire, peut-\u00eatre est-ce bien ceci : avoir mis en \u00e9vidence les rouages, les limites, les montages du syst\u00e8me universel de l&rsquo;am\u00e9ricanisme. Si c&rsquo;est le cas, cela aura \u00e9t\u00e9 involontaire et cela n&rsquo;en sera que plus beau. Et si c&rsquo;est le cas, il nous aura rendu un signal\u00e9 service. On verra.<\/p>\n<\/p>\n<p><p>\t<em>See you<\/em>, Bill.<\/p>\n<\/p>\n<p><\/p>\n<p><p>\t@NOTES = (1) Voir les articles du New York Times, des 15-17 f\u00e9vrier 1998, sur cette question.<\/p>\n<\/p>\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Finalement, Clinton sera-t-il r\u00e9\u00e9lu ? 25 juin 2004 La parution des m\u00e9moires de Bill Clinton (My Life) est d&rsquo;abord un \u00e9norme \u00e9v\u00e9nement de librairie (tirage initial d&rsquo;1,5 million d&rsquo;exemplaires, \u00e0 valoir de $12 millions pour le pr\u00e9sident). Mis \u00e0 la suite de l&rsquo;\u00e9v\u00e9nement du lancement des m\u00e9moires d&rsquo;Hillary, il y a un an, il confirme&hellip;&nbsp;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[],"class_list":["post-66010","post","type-post","status-publish","format-standard","hentry","category-faits-et-commentaires"],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/66010","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/comments?post=66010"}],"version-history":[{"count":0,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/66010\/revisions"}],"wp:attachment":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/media?parent=66010"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/categories?post=66010"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/tags?post=66010"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}