{"id":66027,"date":"2004-07-15T00:00:00","date_gmt":"2004-07-15T00:00:00","guid":{"rendered":"https:\/\/new.dedefensa.org\/index.php\/2004\/07\/15\/antimissiles-pour-la-nouvelle-europe\/"},"modified":"2004-07-15T00:00:00","modified_gmt":"2004-07-15T00:00:00","slug":"antimissiles-pour-la-nouvelle-europe","status":"publish","type":"post","link":"https:\/\/new.dedefensa.org\/index.php\/2004\/07\/15\/antimissiles-pour-la-nouvelle-europe\/","title":{"rendered":"Antimissiles pour la \u201cnouvelle Europe\u201d&#8230;"},"content":{"rendered":"<p><h2 class=\"titleset_a.deepblue\" style=\"color:#0f3955;font-size:2em;\">Antimissiles pour la \u00ab\u00a0nouvelle Europe\u00a0\u00bb&#8230;<\/h2>\n<\/p>\n<p><p>15 juillet 2004 &mdash; Le <em>Guardian<\/em> vient d&rsquo;annoncer que <a class=\"gen\" href=\"http:\/\/www.guardian.co.uk\/international\/story\/0,3604,1259903,00.html\">les Am\u00e9ricains envisagent de d\u00e9ployer des sites anti-missiles<\/a> en Europe centrale, en Pologne et en Tch\u00e9quie.<\/p>\n<\/p>\n<p><p>Voici quelques \u00e9l\u00e9ments d&rsquo;information sortis de l&rsquo;article :<\/p>\n<\/p>\n<blockquote class=\"normal\" style=\"font-size:1.05em;\">\n<p><p>&laquo; <em>The US administration is negotiating with Poland and the Czech Republic over its controversial missile defence programme, with a view to positioning the biggest missile defence site outside the US in central Europe. <\/em><\/p>\n<\/p>\n<p><p>&raquo; <em>Polish government officials confirmed to the Guardian that talks have been going on with Washington for eight months and made clear that Poland was keen to take part in the project, which is supposed to shield the US and its allies from long-range ballistic missile attacks. Senior officials in Prague also confirmed that talks were under way over the establishment of American advanced radar stations in the Czech Republic as part of the missile shield project.<\/em><\/p>\n<\/p>\n<p><p>&raquo; <em>\u00ab\u00a0We&rsquo;re very interested in becoming a concrete part of the arrangement,\u00a0\u00bb said Boguslaw Majewski, the Polish foreign ministry spokesman. \u00ab\u00a0We have been debating this with the Americans since the end of last year.\u00a0\u00bb<\/em><\/p>\n<\/p>\n<p><p>&raquo; <em>Other sources in Warsaw said Pentagon officers have been scouting the mountain territory of southern Poland, pinpointing suitable sites for two or three radar stations connected to the so-called Son of Star Wars programme. As well as radar sites, the Poles say they want to host a missile interceptor site, a large reinforced underground silo from where long-range missiles would be launched to intercept and destroy incoming rockets.<\/em><\/p>\n<\/p>\n<p><p>&raquo; <em>Under Bush administration plans, two missile interceptor sites are being built in the US &mdash; one in California, the other in Alaska. Such a site in Poland would be the first outside America and the only one in Europe.<\/em> &raquo;<\/p>\n<\/p>\n<p><p>Tel que le journal britannique pr\u00e9sente l&rsquo;affaire, il appara&icirc;t manifeste que les Polonais sont particuli\u00e8rement enthousiastes pour cette perspective d&rsquo;avoir sur leur territoire ce qui sera la base la plus importante du r\u00e9seau anti-missiles am\u00e9ricain, hors des &Eacute;tats-Unis. Selon nos sources, l&rsquo;initiative serait venue autant sinon plus des Polonais que des Am\u00e9ricains, m\u00eame si des contacts informels des Am\u00e9ricains vers les Europ\u00e9ens existent depuis plusieurs ann\u00e9es sur cette question du r\u00e9seau anti-missiles.<\/p>\n<\/p>\n<\/blockquote>\n<p><p>Divers probl\u00e8mes existent d&rsquo;ores et d\u00e9j\u00e0, qui sont signal\u00e9s par l&rsquo;article et qui peuvent prendre des dimensions explosives.<\/p>\n<\/p>\n<p><p>&bull; Le premier est celui des rapports entre la Pologne et la Russie. Les Russes peuvent consid\u00e9rer cette initiative comme particuli\u00e8rement d\u00e9stabilisante et inqui\u00e9tante pour eux. L&rsquo;article semble dire que les Am\u00e9ricains sont tr\u00e8s avertis de cet aspect du probl\u00e8me et comptent bien vouloir le traiter de mani\u00e8re sp\u00e9cifique. Le porte-parole du minist\u00e8re des affaires \u00e9trang\u00e8res polonais a d\u00e9clar\u00e9 au <em>Guardian<\/em> : &laquo; <em>The Americans are working quite hard on this. They need to clear the path with the Russians and reach a consensus before we will move ahead.<\/em> &raquo; Cette affirmation suppose que les Am\u00e9ricains sont prudents et diplomates, ce qui est une hypoth\u00e8se bien audacieuse par les temps qui courent.<\/p>\n<\/p>\n<p><p>&bull; Un autre aspect, beaucoup plus \u00e9trange, est que les n\u00e9gociations ont \u00e9t\u00e9 men\u00e9es secr\u00e8tement, du c\u00f4t\u00e9 am\u00e9ricain, par John Bolton, du d\u00e9partement d&rsquo;&Eacute;tat, un ultra-dur mis au d\u00e9partement d&rsquo;&Eacute;tat par les n\u00e9o-conservateurs pour \u00ab\u00a0marquer\u00a0\u00bb Powell.<\/p>\n<\/p>\n<blockquote class=\"normal\" style=\"font-size:1.05em;\">\n<p><p>&laquo; <em> The talks are at the exploratory stage and no decisions have been taken, officials stressed. US officials played down talk of central European participation in the missile shield. But the confidential nature of the negotiations, being led on the US side by John Bolton, the hardline under-secretary of state for arms control, has angered senior defence officials in the region, who have been kept in the dark.<\/em> &raquo;<\/p>\n<\/p>\n<\/blockquote>\n<p><p>Cet aspect de l&rsquo;information laisse \u00e0 penser que nous sommes en pr\u00e9sence d&rsquo;une affaire particuli\u00e8rement explosive et d\u00e9stabilisante, dans la mesure o&ugrave; elle implique des tensions, en g\u00e9n\u00e9ral consid\u00e9rables, entre le d\u00e9partement d&rsquo;&Eacute;tat et le Pentagone, entre Bolton et les mod\u00e9r\u00e9s du d\u00e9partement d&rsquo;&Eacute;tat, etc. On peut m\u00eame faire l&rsquo;hypoth\u00e8se que les n\u00e9gociations du c\u00f4t\u00e9 US pourraient avoir \u00e9t\u00e9 lanc\u00e9es pour l&rsquo;essentiel sur des initiatives personnelles (celles de Bolton ?), sans refl\u00e9ter compl\u00e8tement une politique officielle US, &mdash; s&rsquo;il y a v\u00e9ritablement \u00ab\u00a0une politique officielle US\u00a0\u00bb.<\/p>\n<\/p>\n<p><p>Dans tous les cas, il s&rsquo;agit d&rsquo;une affaire hautement d\u00e9stabilisatrice, pour l&rsquo;Europe \u00e9galement. Alors que l&rsquo;engagement britannique et danois pour soutenir le r\u00e9seau anti-missiles US par des stations de radar se situe dans une norme classique ouest-occidentale (entre atlantistes, favorables au r\u00e9seau et \u00ab\u00a0europ\u00e9anistes\u00a0\u00bb, plus m\u00e9fiants \u00e0 cet \u00e9gard), l&rsquo;affaire polonaise est compl\u00e8tement nouvelle et diff\u00e9rente. Il y a la perspective du d\u00e9ploiement de missiles, de l&rsquo;installation d&rsquo;un \u00e9norme complexe am\u00e9ricain. Au niveau europ\u00e9en, une telle affaire ne pourra qu&rsquo;accro&icirc;tre les tensions, voire conduire \u00e0 des menaces de rupture, dans la mesure o&ugrave; un pays de l&rsquo;UE s&rsquo;engage dans une politique militaire compl\u00e8tement d\u00e9pendante des USA, \u00e0 un point de tension maximale avec la Russie, sur une mati\u00e8re militaire compl\u00e8tement fondamentale et d\u00e9stabilisatrice (des anti-missiles contre quoi sinon les missiles russes?). Plus encore, l&rsquo;affaire est r\u00e9v\u00e9l\u00e9e au moment o&ugrave; le courant g\u00e9n\u00e9ral, en Pologne, \u00e0 cause de l&rsquo;Irak, est de plus en plus m\u00e9fiant vis-\u00e0-vis des Am\u00e9ricains. Le contexte g\u00e9n\u00e9ral, avec une Europe \u00e0 25 dont on ne sait ce qu&rsquo;elle va donner, des r\u00e9f\u00e9rendums sur la Constitution europ\u00e9enne \u00e0 l&rsquo;horizon qui vont engendrer de tr\u00e8s durs d\u00e9bats nationaux sur l&rsquo;Europe, est lui aussi tr\u00e8s d\u00e9favorable.<\/p>\n<\/p>\n<p><p>Conclusion : un nouveau point de tension transatlantique et intra-europ\u00e9en, \u00e0 propos d&rsquo;un syst\u00e8me dont l&rsquo;utilit\u00e9 est totalement contestable et l&rsquo;inefficacit\u00e9 quasiment prouv\u00e9e par des ratages successifs dans les essais r\u00e9alis\u00e9s. &Eacute;tait-ce tellement n\u00e9cessaire? Mais poser cette question, c&rsquo;est s&rsquo;adresser \u00e0 des gens raisonnables, c&rsquo;est-\u00e0-dire crier dans le d\u00e9sert.<\/p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Antimissiles pour la \u00ab\u00a0nouvelle Europe\u00a0\u00bb&#8230; 15 juillet 2004 &mdash; Le Guardian vient d&rsquo;annoncer que les Am\u00e9ricains envisagent de d\u00e9ployer des sites anti-missiles en Europe centrale, en Pologne et en Tch\u00e9quie. Voici quelques \u00e9l\u00e9ments d&rsquo;information sortis de l&rsquo;article : &laquo; The US administration is negotiating with Poland and the Czech Republic over its controversial missile defence&hellip;&nbsp;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[4056,4314,1092,398,2642],"class_list":["post-66027","post","type-post","status-publish","format-standard","hentry","category-faits-et-commentaires","tag-antimissiles","tag-bmde","tag-bolton","tag-europe","tag-nouvelle"],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/66027","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/comments?post=66027"}],"version-history":[{"count":0,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/66027\/revisions"}],"wp:attachment":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/media?parent=66027"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/categories?post=66027"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/tags?post=66027"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}