{"id":66029,"date":"2004-07-17T00:00:00","date_gmt":"2004-07-17T00:00:00","guid":{"rendered":"https:\/\/new.dedefensa.org\/index.php\/2004\/07\/17\/kerry-appelle-hillary-a-la-rescousse\/"},"modified":"2004-07-17T00:00:00","modified_gmt":"2004-07-17T00:00:00","slug":"kerry-appelle-hillary-a-la-rescousse","status":"publish","type":"post","link":"https:\/\/new.dedefensa.org\/index.php\/2004\/07\/17\/kerry-appelle-hillary-a-la-rescousse\/","title":{"rendered":"<strong><em>Kerry appelle Hillary \u00e0 la rescousse<\/em><\/strong>"},"content":{"rendered":"<p><h2 class=\"common-article\">Kerry appelle Hillary \u00e0 la rescousse<\/h2>\n<\/p>\n<p><\/p>\n<p><p>\t17 juillet 2004  La s\u00e9natrice Hillary Clinton sera <a href=\"http:\/\/www.guardian.co.uk\/uselections2004\/story\/0,13918,1263402,00.html\" class=\"gen\">l&rsquo;une des vedettes de la Convention d\u00e9mocrate, \u00e0 la fin du mois<\/a>. La d\u00e9cision a \u00e9t\u00e9 prise par l&rsquo;\u00e9quipe Kerry, alors que cette intervention n&rsquo;\u00e9tait pas initialement pr\u00e9vue et que Kerry avait pris bien soin de tenir ses distances de Hillary, class\u00e9e trop \u00e0 gauche.<\/p>\n<\/p>\n<p><\/p>\n<p><p>\t\u00ab <em>Presidential candidate John Kerry has bowed to pressure from Hillary Clinton&rsquo;s supporters and invited her to address the Democratic party convention in Boston at the end of the month, it was reported yesterday.<\/em><\/p>\n<\/p>\n<p><p>\t\u00bb <em>Senator Clinton had been omitted from the list of speakers issued by the Kerry campaign, provoking uproar from loyalists and a quick U-turn by the candidate. Senator Kerry phoned her in person on Thursday to ask her to make a primetime speech introducing her husband, Bill Clinton, on July 26, the convention&rsquo;s opening night. A Kerry spokeswoman, Stephanie Cutter, yesterday said the campaign was thrilled that Mrs Clinton had accepted the invitation.<\/em> <\/p>\n<\/p>\n<p><p>\t\u00bb <em>It remained unclear why Mrs Clinton, who is extraordinarily popular among liberal activists, was excluded in the first place. Some explained it by the campaign&rsquo;s fear that she might overshadow Mr Kerry and his running mate, John Edwards, whom she is likely to confront in the 2008 nomination race if Mr Kerry is defeated in November. Others suggested that her initial exclusion could have been a reflection of her polarising reputation, and fears that her mere appearance would galvanise Mr Kerry&rsquo;s Republican opponents.<\/em> \u00bb<\/p>\n<\/p>\n<p><\/p>\n<p><p>\tLa d\u00e9cision de Kerry d&rsquo;en appeler \u00e0 Hillary Clinton est une indication politique int\u00e9ressante. Qu&rsquo;elle ait accept\u00e9 en est une autre. Les deux indications devraient aller dans le sens d&rsquo;une interpr\u00e9tation selon laquelle le camp Kerry devient de plus en plus nerveux dans une situation o\u00f9 la d\u00e9gringolade de GW Bush dans les sondages ne se concr\u00e9tise pas, pour lui, en une mont\u00e9e significative de Kerry. On peut expliciter cette interpr\u00e9tation de la fa\u00e7on suivante :<\/p>\n<\/p>\n<p><p>\t&bull; Le camp Kerry commence \u00e0 admettre que, pour marquer des points de fa\u00e7on significative, il serait peut-\u00eatre n\u00e9cessaire que le candidat d\u00e9mocrate s&rsquo;affirme plus nettement, c&rsquo;est-\u00e0-dire plus nettement \u00e0 gauche que GW Bush. Le constat serait que le rassemblement de soutien de Kerry par des \u00e9lecteurs d&rsquo;abord pr\u00e9occup\u00e9s de battre Bush (les ABBA, ou <em>Anything But Bush Again<\/em>) n&rsquo;est pas du tout une garantie suffisante de victoire. L&rsquo;appel \u00e0 Hillary Clinton, c&rsquo;est une caution prise avec la gauche du parti. Le probl\u00e8me est que Hillary, si elle est \u00e0 gauche dans les domaines int\u00e9rieur, social, \u00e9thique, etc, ne l&rsquo;est pas du tout en politique ext\u00e9rieure, notamment sur la crise irakienne, sur les relations avec Isra\u00ebl ; or, la question reste enti\u00e8rement ouverte de savoir si ce que l&rsquo;\u00e9lectorat reproche \u00e0 Kerry n&rsquo;est pas son suivisme de GW dans le cas irakien, moyennant quoi le soutien d&rsquo;Hillary devient illusoire.<\/p>\n<\/p>\n<p><p>\t&bull; L&rsquo;acceptation rapide et sans probl\u00e8me d&rsquo;Hillary Clinton est plut\u00f4t peu rassurante pour Kerry que le contraire. Hillary est une fine mouche, qui joue 2008 (candidate d\u00e9mocrate \u00e0 la pr\u00e9sidence en 2008). Si elle accepte de soutenir Kerry, n&rsquo;est-ce pas parce qu&rsquo;elle le juge battu d&rsquo;avance, qu&rsquo;elle renforce sa stature nationale en le soutenant, qu&rsquo;elle se met en position, plus que jamais, pour une candidature au terme du deuxi\u00e8me mandat GW Bush ?<\/p>\n<\/p>\n<p><p>\tSp\u00e9culations politiques, tout cela. Il reste une autre hypoth\u00e8se \u00e0 \u00e9voquer, qui est la n\u00f4tre depuis l&rsquo;origine de cette campagne : la position naturelle de Kerry, celle o\u00f9 il a de bonnes chances de l&#8217;emporter, c&rsquo;est une position radicale d&rsquo;opposition. Nous <a href=\"http:\/\/www.dedefensa.org\/article.php?art_id=1020\" class=\"gen\">avancions en mars dernier l&rsquo;hypoth\u00e8se que Kerry l&rsquo;avait compris ou le comprendrait vite<\/a>. Il est vite apparu que cela serait <a href=\"http:\/\/www.dedefensa.org\/article.php?art_id=1023\" class=\"gen\">difficilement le cas<\/a>. Mais Kerry est tout de m\u00eame oblig\u00e9 d&rsquo;\u00e9voluer vers la gauche, vers une position d&rsquo;opposition un peu plus affirm\u00e9e. Quant \u00e0 dire que c&rsquo;est suffisant, on ne s&rsquo;y risquera pas une seconde. Trop peu, trop tard serait plut\u00f4t la caract\u00e9ristique de cette manuvre de Kerry pour faire entrer Hillary Clinton. Moyennant quoi, ce serait plut\u00f4t Hillary qui aurait mis, en passant, John Kerry dans son jeu pour avancer ses pions vers 2008.<\/p>\n<\/p>\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Kerry appelle Hillary \u00e0 la rescousse 17 juillet 2004 La s\u00e9natrice Hillary Clinton sera l&rsquo;une des vedettes de la Convention d\u00e9mocrate, \u00e0 la fin du mois. La d\u00e9cision a \u00e9t\u00e9 prise par l&rsquo;\u00e9quipe Kerry, alors que cette intervention n&rsquo;\u00e9tait pas initialement pr\u00e9vue et que Kerry avait pris bien soin de tenir ses distances de Hillary,&hellip;&nbsp;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[934],"class_list":["post-66029","post","type-post","status-publish","format-standard","hentry","category-faits-et-commentaires","tag-clinton"],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/66029","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/comments?post=66029"}],"version-history":[{"count":0,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/66029\/revisions"}],"wp:attachment":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/media?parent=66029"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/categories?post=66029"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/tags?post=66029"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}