{"id":66072,"date":"2004-09-03T00:00:00","date_gmt":"2004-09-03T00:00:00","guid":{"rendered":"https:\/\/new.dedefensa.org\/index.php\/2004\/09\/03\/de-la-paradoxale-vertu-de-la-cruelle-pratique-de-la-prise-dotages\/"},"modified":"2004-09-03T00:00:00","modified_gmt":"2004-09-03T00:00:00","slug":"de-la-paradoxale-vertu-de-la-cruelle-pratique-de-la-prise-dotages","status":"publish","type":"post","link":"https:\/\/new.dedefensa.org\/index.php\/2004\/09\/03\/de-la-paradoxale-vertu-de-la-cruelle-pratique-de-la-prise-dotages\/","title":{"rendered":"<strong><em>De la paradoxale vertu de la cruelle pratique de la prise d&rsquo;otages<\/em><\/strong>"},"content":{"rendered":"<p><h2 class=\"common-article\">De la paradoxale vertu de la cruelle pratique de la prise d&rsquo;otages<\/h2>\n<\/p>\n<p><\/p>\n<p><p>\t3 septembre 2004  Il y a peu, le 27 ao\u00fbt, <a href=\"http:\/\/www.iht.com\/bin\/print.php?file=535973.html\" class=\"gen\">Elaine Sciolino, du New York Times et de l&rsquo;International Herald Tribune<\/a>, nous annon\u00e7ait, et avec bien des arguments si l&rsquo;on s&rsquo;en tient \u00e0 l&rsquo;apparente raison, l&rsquo;effacement de la France glorieuse et empanach\u00e9e \u00e0-la-Villepin. Le principal argument \u00e9tait le visage, le verbe et l&rsquo;esprit du nouveau ministre des affaires \u00e9trang\u00e8res Michel Barnier,  qui nous dit, rapporte Sciolino : \u00ab <em>The first reflex, I say bluntly, must be European<\/em> \u00bb<\/p>\n<\/p>\n<p><\/p>\n<p><p>\t\u00ab <em>The fact is that Barnier was once the Quai d&rsquo;Orsay&rsquo;s point man on Europe and served for four years as the European Union&rsquo;s commissioner for regional policy and institutional reform before becoming foreign minister. He tends to see the world through the lens, not of France, but of Europe.<\/em> <\/p>\n<\/p>\n<p><p>\t\u00bb <em>He told his envoys that the only way to maximize their influence around the world was to think European. The first reflex, I say bluntly, must be European, he said. I know that this evolution is not inscribed in the long and prestigious history of our ministry. But the influence of our country depends on it.<\/em> <\/p>\n<\/p>\n<p><p>\t\u00bb <em>In a tonal shift, Barnier called for a France that is humble. That adjective was not normally associated with de Villepin, who once was described in a profile in the French magazine Le Point as a silver wolf with burning eyes and who became Europe&rsquo;s most vocal critic of the Bush administration&rsquo;s march to war against Iraq.<\/em> <\/p>\n<\/p>\n<p><p>\t\u00bb <em>France is not great when it is arrogant, said Barnier, a former deputy in parliament in the Savoy region. France is not strong if it is alone.<\/em> <\/p>\n<\/p>\n<p><p>\t\u00bb <em>His performance, the first time a number of ambassadors have seen their minister in action, caught many unprepared. He is at base a local politician coming from the Savoy, not a traditional Gaullist at all, said one ambassador. He came across as the anti-de Villepin.<\/em> \u00bb<\/p>\n<\/p>\n<p><\/p>\n<p><p>\tMais, comme on dit (essentiellement aujourd&rsquo;hui, o\u00f9 c&rsquo;est la r\u00e8gle),   le ministre propose, les \u00e9v\u00e9nements disposent. C&rsquo;est fait. Une semaine apr\u00e8s cette solennelle europ\u00e9anisation de la France, voici la France forc\u00e9e \u00e0 une offensive stup\u00e9fiante d&rsquo;efficacit\u00e9, gaullienne jusqu&rsquo;au bout des ongles, assimilant grande politique arabe, indiff\u00e9rence pour d&rsquo;\u00e9ventuelles m\u00e9thodes am\u00e9ricaines, affirmation fran\u00e7aise et le reste. Pas un seul leader arabe ne s&rsquo;est encore aper\u00e7u que Michel Barnier a remplac\u00e9 de Villepin. \u00ab <em>The first reflex must be European<\/em> \u00bb ? La Commission europ\u00e9enne a assur\u00e9 la France de sa solidarit\u00e9 Mais soyons s\u00e9rieux : le r\u00e9sultat, lui, est purement fran\u00e7ais, et <a href=\"http:\/\/www.lemonde.fr\/web\/article\/0,1-0@2-3218,36-377536,0.html\" class=\"gen\">il surprend les dirigeants fran\u00e7ais eux-m\u00eames, comme l&rsquo;observe Le Monde<\/a> :<\/p>\n<\/p>\n<p><\/p>\n<p><p>\t\u00ab <em>Nombreux sont les gouvernements qui auraient souhait\u00e9 faire l&rsquo;objet d&rsquo;une telle d\u00e9monstration d&rsquo;unanimit\u00e9 : les autorit\u00e9s fran\u00e7aises avouent qu&rsquo;elles sont les premi\u00e8res \u00e0 \u00eatre  agr\u00e9ablement  surprises. L&rsquo;expression publique de sympathie manifest\u00e9e \u00e0 l&rsquo;endroit de la France et des journalistes Christian Chesnot et Georges Malbrunot, d&rsquo;un bout \u00e0 l&rsquo;autre du monde arabe, est sans pr\u00e9c\u00e9dent.<\/em> <\/p>\n<\/p>\n<p><p>\t\u00bb <em>Elle est d&rsquo;autant plus remarquable qu&rsquo;elle a balay\u00e9 les clivages en tout genre. Gouvernants et opposants, mod\u00e9r\u00e9s et extr\u00e9mistes, religieux et la\u00efques ont joint leurs voix pour r\u00e9clamer la lib\u00e9ration des deux journalistes et rendre un hommage plus ou moins appuy\u00e9 \u00e0 la politique de Paris dans cette partie du monde.<\/em> \u00bb<\/p>\n<\/p>\n<p><\/p>\n<p><p>\tVoyons les choses d&rsquo;un autre point de vue : on peut discuter \u00e0 l&rsquo;infini cette extraordinaire mobilisation d&rsquo;un pays de la puissance et de la taille de la France pour deux hommes, fussent-ils de tr\u00e8s honorables journalistes, alors que tant de morts et d&rsquo;injustices passent inaper\u00e7ues, ignor\u00e9es, m\u00e9pris\u00e9es, par ce m\u00eame pays comme par tant d&rsquo;autres. C&rsquo;est l\u00e0 le ph\u00e9nom\u00e8ne caract\u00e9ristique de cette \u00e9poque sans pens\u00e9e ni capacit\u00e9 d&rsquo;action politiques, o\u00f9 la morale et le symbole remplacent respectivement la pens\u00e9e et l&rsquo;action politiques.<\/p>\n<\/p>\n<p><p>\tPar contre, l&rsquo;occasion est \u00e9clatante,  contre tous les raisonnements, toutes les th\u00e9ories, toutes les hyst\u00e9ries id\u00e9ologiques et lib\u00e9rales, tous les habituels mensonges anglo-saxons et germano-pratins,  d&rsquo;observer la persistance, la continuit\u00e9 et la puissance des caract\u00e9ristiques et des grands traits de la politique traditionnelle de la France. La diplomatie fran\u00e7aise, prise par surprise et sur la d\u00e9fensive, a r\u00e9agi selon le r\u00e9flexe du seul pays restant aujourd&rsquo;hui souverain et autonome, par nature plus que par politique,  en ne se tournant pas vers Washington ni en d\u00e9tournant les yeux du forfait accompli, mais en s&rsquo;adressant aux musulmans et aux Arabes puisque c&rsquo;est d&rsquo;eux qu&rsquo;il s&rsquo;agit. La r\u00e9ponse est un tonnerre de solidarit\u00e9, de bonne volont\u00e9, d&rsquo;offres d&rsquo;aide en tous genres. Et voil\u00e0 Barnier, qui, normalement, \u00ab <em>must be European<\/em> \u00bb,  Barnier catapult\u00e9 en vrai Fran\u00e7ais dans cette r\u00e9gion strat\u00e9gique vitale o\u00f9 seuls les Etats-Unis ont le droit d&rsquo;\u00e9voluer, paradant comme un Villepin qui se prendrait pour un Colin Powell. La France n&rsquo;avait plus de politique puisqu&rsquo;on \u00e9tait europ\u00e9en ; plac\u00e9e devant l&rsquo;urgence selon la d\u00e9finition des conditions du temps pr\u00e9sent (urgence d\u00e9finie par le symbole et la pression de la communication), elle r\u00e9agit selon ses r\u00e9flexes fondamentaux.<\/p>\n<\/p>\n<p><p>\tQu&rsquo;importe,  l&rsquo;\u00e9pisode, quelle que soit l&rsquo;issue pour les otages, conduit \u00e0 plusieurs remarques.<\/p>\n<\/p>\n<p><p>\t&bull; L&rsquo;extraordinaire sottise de la politique US est magnifiquement d\u00e9montr\u00e9e <em>a contrario<\/em>. Il suffit de s&rsquo;ouvrir aux pays arabes et aux autorit\u00e9s musulmanes de toutes les tendances de pr\u00e9occupations humaines courantes, sur un ton diplomatique et amical, pour recevoir aussit\u00f4t un soutien sans faille. La demande fran\u00e7aise a m\u00eame re\u00e7u <a href=\"http:\/\/www.guardian.co.uk\/france\/story\/0,11882,1294182,00.html\" class=\"gen\">le soutien de al Sadr, le rebelle de Najaf,<\/a> qui tirait, hier encore, sur les Marines. Mais existe-t-il une seule chance, une seule toute petite chance de faire comprendre \u00e0 un Perle, \u00e0 un Wolfowitz, \u00e0 un Cheney, \u00e0 un GW, que l&rsquo;on peut parler avec les gens avant de larguer sur eux une pluie de bombes hyper-guid\u00e9es sur GPS ?<\/p>\n<\/p>\n<p><p>\t&bull; Mais bien s\u00fbr, d&rsquo;autre part et <em>a contrario<\/em>, seule la France pouvait r\u00e9agir comme elle l&rsquo;a fait parce qu&rsquo;elle est \u00e0 peu pr\u00e8s le seul pays significatif, aujourd&rsquo;hui, \u00e0 \u00eatre ind\u00e9pendant et souverain. (Verrait-on un Berlusconi agir de la sorte ? Un Aznar, du temps o\u00f9 il existait encore ? Un dirigeant polonais, ex-cadre du PC local, plein de sa vaniteuse pr\u00e9tention \u00e0 la d\u00e9mocratie et de son empressement \u00e0 la flatterie pour la force du moment ?) Bien entendu, cette r\u00e9action fran\u00e7aise ne doit rien, ni au personnel politique fran\u00e7ais, ni au discours g\u00e9n\u00e9ral fran\u00e7ais, ni aux soi-disant conceptions politiques fran\u00e7aises,  tout cela d&rsquo;une m\u00e9diocrit\u00e9 de comportement au-del\u00e0 de tout comme le veut le temps courant, sauf quelques si rares exceptions. Ce qui a parl\u00e9 aux pays arabes et musulmans, qui vivent sous la contrainte des pressions anglo-saxonnes et occidentales en g\u00e9n\u00e9ral, c&rsquo;est le langage quasi-automatique chez les Fran\u00e7ais de l&rsquo;ind\u00e9pendance et de la souverainet\u00e9, parce que ce langage implique par d\u00e9finition le respect de ce qu&rsquo;il y a d&rsquo;ind\u00e9pendance et de souverainet\u00e9 chez l&rsquo;autre.<\/p>\n<\/p>\n<p><p>\t&bull; Corollaire des points pr\u00e9c\u00e9dents : l&rsquo;affirmation de l&rsquo;ind\u00e9pendance et de la souverainet\u00e9 cr\u00e9e \u00e9videmment l&rsquo;identit\u00e9, et c&rsquo;est autour d&rsquo;elle et en elle que s&rsquo;est reconnue l&rsquo;unanimit\u00e9 fran\u00e7aise. Il y a m\u00eame un r\u00e9flexe qu&rsquo;on qualifierait quasiment de z\u00e8le des repr\u00e9sentants de la communaut\u00e9 musulmane de France qui ont tenu \u00e0 montrer qu&rsquo;ils \u00e9taient utiles, voire n\u00e9cessaires \u00e0 la France (leur intervention dans la crise), pour mieux se faire accepter dans l&rsquo;identit\u00e9 fran\u00e7aise. Si ce n&rsquo;est pas d\u00e9montrer l&rsquo;importance de l&rsquo;identit\u00e9 dans le rassemblement des \u00e9nergies et, <em>a contrario<\/em>, que le cur de notre crise est l&rsquo;attaque g\u00e9n\u00e9rale men\u00e9e contre l&rsquo;identit\u00e9 (et contre l&rsquo;ind\u00e9pendance, contre la souverainet\u00e9, etc)<\/p>\n<\/p>\n<p><p>\t&bull; Cet \u00e9pisode nous dit enfin, d&rsquo;une fa\u00e7on absolument d\u00e9vastatrice et qui pr\u00e9sage des lendemains terribles, l&rsquo;absurdit\u00e9 g\u00e9n\u00e9rale et la sottise compl\u00e8te de la guerre contre la terreur, de la fa\u00e7on dont elle est men\u00e9e, des effets terrifiants de l&#8217;emploi d&rsquo;une force aveugle marqu\u00e9e par le nihilisme complet des conceptions et des perspectives,  jusqu&rsquo;aux d\u00e9sormais habituels \u00ab <em>catastrophic success<\/em> \u00bb, selon l&rsquo;expression ch\u00e8re au g\u00e9n\u00e9ral Franks et reprise par GW comme une bonne trouvaille \u00e9lectorale.<\/p>\n<h3>Post-Scriptum<\/h3>\n<\/p>\n<p><p>\tQuelle est la pens\u00e9e et quel est le jugement du syst\u00e8me de l&rsquo;am\u00e9ricanisme face \u00e0 cette d\u00e9monstration faite du triomphe de conceptions qui lui sont totalement \u00e9trang\u00e8res et compl\u00e8tement antagonistes ? On peut estimer que la r\u00e9action du Premier ministre irakien int\u00e9rimaire, agent quasi-officiel de la CIA, l&rsquo;exprime assez bien,  et m\u00eame d&rsquo;une fa\u00e7on indubitable si l&rsquo;on s&rsquo;en r\u00e9f\u00e8re \u00e0 la compl\u00e8te stupidit\u00e9 du propos, exprim\u00e9e avec une mauvaise foi pleine de hargne, si caract\u00e9ristique : \u00ab <em>Puisant dans la rancur qu&rsquo;il \u00e9prouve visiblement \u00e0 l&rsquo;\u00e9gard de la France, pour avoir refus\u00e9 de se joindre \u00e0 la guerre contre l&rsquo;Irak, Iyad Allaoui n&rsquo;a pas eu un seul mot de compassion pour le sort des deux journalistes. Ass\u00e9nant aux autorit\u00e9s fran\u00e7aises une le\u00e7on de lutte contre le terrorisme, il a estim\u00e9 que Paris ne peut se contenter de demi-mesures ni d&rsquo;une position passive. Les gouvernements qui d\u00e9cident de rester sur la d\u00e9fensive seront les prochaines cibles des terroristes. (&#8230;) Laissez-moi vous dire que les Fran\u00e7ais, malgr\u00e9 tout le bruit qu&rsquo;ils font  Nous ne voulons pas la guerre&rsquo;  auront bient\u00f4t \u00e0 combattre les terroristes, a-t-il dit sans le moindre \u00e9gard, ne serait-ce que pour la gravit\u00e9 du moment.<\/em> \u00bb (Selon <a href=\"http:\/\/www.lemonde.fr\/web\/article\/0,1-0@2-3218,36-377536,0.html\" class=\"gen\">Le Monde du 3 septembre<\/a>.) <\/p>\n<\/p>\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>De la paradoxale vertu de la cruelle pratique de la prise d&rsquo;otages 3 septembre 2004 Il y a peu, le 27 ao\u00fbt, Elaine Sciolino, du New York Times et de l&rsquo;International Herald Tribune, nous annon\u00e7ait, et avec bien des arguments si l&rsquo;on s&rsquo;en tient \u00e0 l&rsquo;apparente raison, l&rsquo;effacement de la France glorieuse et empanach\u00e9e \u00e0-la-Villepin.&hellip;&nbsp;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[2687,4169,4345,2937,2746],"class_list":["post-66072","post","type-post","status-publish","format-standard","hentry","category-faits-et-commentaires","tag-france","tag-identite","tag-independance","tag-nationale","tag-souverainete"],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/66072","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/comments?post=66072"}],"version-history":[{"count":0,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/66072\/revisions"}],"wp:attachment":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/media?parent=66072"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/categories?post=66072"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/tags?post=66072"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}