{"id":66083,"date":"2004-09-19T00:00:00","date_gmt":"2004-09-19T00:00:00","guid":{"rendered":"https:\/\/new.dedefensa.org\/index.php\/2004\/09\/19\/savez-vous-pauvres-ignorants-que-les-neocons-travaillent-pour-nos-petits-enfants\/"},"modified":"2004-09-19T00:00:00","modified_gmt":"2004-09-19T00:00:00","slug":"savez-vous-pauvres-ignorants-que-les-neocons-travaillent-pour-nos-petits-enfants","status":"publish","type":"post","link":"https:\/\/new.dedefensa.org\/index.php\/2004\/09\/19\/savez-vous-pauvres-ignorants-que-les-neocons-travaillent-pour-nos-petits-enfants\/","title":{"rendered":"<strong><em>Savez-vous, pauvres ignorants, que les \u201cneocons\u201d travaillent pour nos petits-enfants?<\/em><\/strong>"},"content":{"rendered":"<p><h2 class=\"common-article\">Savez-vous, pauvres ignorants, que les neocons travaillent pour nos petits-enfants ?<\/h2>\n<\/p>\n<p><\/p>\n<p><p>\t19 septembre 2004  Pendant ce temps (on veut dire : pendant que des choses se passent <a href=\"http:\/\/www.dedefensa.org\/article.php?art_id=1222\" class=\"gen\">en Irak<\/a> et <a href=\"http:\/\/www.dedefensa.org\/article.php?art_id=1223\" class=\"gen\">\u00e0 Washington<\/a>), les n\u00e9o-conservateurs, ou <em>neocons<\/em>, pensent \u00e0 votre avenir. \u00c9coutez-les penser.<\/p>\n<\/p>\n<p><p>\tPlac\u00e9s devant le d\u00e9sastre irakien, les n\u00e9o-conservateurs ont r\u00e9agi comme il se doit,  d&rsquo;abord en posant, en r\u00e9affirmant la justesse de leur id\u00e9ologie : nous avons raison, donc voyons ce qui se passe. Ils en ont conclu que ce qui se passe est normal, \u00e0 d\u00e9faut d&rsquo;avoir \u00e9t\u00e9 exactement pr\u00e9vu. La premi\u00e8re explication donn\u00e9e, celle de la conjoncture, nous vient de Wolfowitz, cit\u00e9 incidemment tout au bout, en trois lignes, d&rsquo;<a href=\"http:\/\/news.ft.com\/cms\/s\/a373d488-07a9-11d9-9673-00000e2511c8.html\" class=\"gen\">un texte du Financial Times du 17 septembre.<\/a> Il s&rsquo;agit de comprendre que ce qui se passe est simplement la cons\u00e9quence de ce qui s&rsquo;est pass\u00e9 : Saddam \u00e9tait un monstre encore plus monstrueux qu&rsquo;on a dit, et les d\u00e9g\u00e2ts qu&rsquo;il a caus\u00e9s expliquent qu&rsquo;il soit si difficile de les r\u00e9parer. (C&rsquo;est, d\u00e9sormais, dans l&rsquo;esprit de Wolfowitz, un monstre manifestement pire que Hitler lorsqu&rsquo;on voit la diff\u00e9rence entre les d\u00e9lais et la facilit\u00e9 d&rsquo;imposer la <em>pax americana<\/em> \u00e0 l&rsquo;Allemagne nazie vaincue, par comparaison \u00e0 ce qui se passe en Irak. Mais qui a jamais dout\u00e9 de cette sup\u00e9riorit\u00e9 dans le Mal de Saddam ?)<\/p>\n<\/p>\n<p><\/p>\n<p><p>\t\u00ab <em>Paul Wolfowitz, deputy defence secretary, told Iraqi officials visiting Washington that extraordinary and difficult times lay ahead. No one should underestimate the challenges of repairing the 30 years of damage and abuse committed by the old regime, he said.<\/em> \u00bb<\/p>\n<\/p>\n<p><\/p>\n<p><p>\tIl y a presque une suggestion de sym\u00e9trie chez Wolfowitz : il a fallu 30 ans \u00e0 Saddam pour faire le mal qu&rsquo;il a fait, il faudra bien 30 ans pour r\u00e9parer. Cela signifie que les n\u00e9o-conservateurs pensent \u00e0 long, tr\u00e8s long terme. C&rsquo;est effectivement l&rsquo;explication centrale de leur comportement, telle qu&rsquo;elle est propos\u00e9e aujourd&rsquo;hui, qui permet de faire des ennuis en Irak non pas un signe de leur vue erron\u00e9e mais une preuve \u00e9vidente de leur don de double vue, pour le moins, et de toutes les fa\u00e7ons une confirmation \u00e9clatante de la justesse de leur vue. Il fallait y penser. Certains intellectuels-satellites s&rsquo;occupent de nous y faire penser.<\/p>\n<\/p>\n<p><p>\tDans une chronique du <a href=\"http:\/\/atimes.com\/atimes\/Middle_East\/FI14Ak01.html\" class=\"gen\">14 septembre sur atimes.com<\/a>, l&rsquo;universitaire am\u00e9ricain Richard Daniel Ewing nous explique \u00ab <em>What the neo-cons can&rsquo;t tell Americans<\/em> \u00bb. <\/p>\n<\/p>\n<p><\/p>\n<p><p>\t\u00ab <em>Bush&rsquo;s foreign-policy team is a bold group. They do not see history in terms of news cycles or election intervals. These grand strategists view the world in century-long sweeps. Deputy Secretary of Defense Paul Wolfowitz, often identified as the chief neo-conservative architect, is a gifted intellectual. He fully appreciates the Iraq campaign&rsquo;s complexities and the historic parallels to Vietnam. Still, Wolfowitz and Bush&rsquo;s other advisers perceive the world in a light that ordinary Americans do not.<\/em> <\/p>\n<\/p>\n<p><p>\t\u00bb <em>So what did they see on September 11, 2001? As New York&rsquo;s World Trade Center burned, this group saw two new terrifying trends coming together with devastating results. First, they saw a deadly new terrorist enemy and a greater Middle East festering with anti-Americanism. But we all saw this. Wolfowitz, however, saw this trend arcing decades into the future. To him, the Persian Gulf was becoming more dangerous and increasingly unstable. Next, Wolfowitz saw the inevitable spread of weapons of mass destruction. In 1950, only the US and the Soviet Union had atomic bombs. By 2000, poverty-stricken Pakistan and autarkic North Korea had acquired nuclear capabilities. With the threshold clearly dropping, what&rsquo;s to stop Micronesia or Sudan from getting the bomb in 2050? Only lack of effort.<\/em> <\/p>\n<\/p>\n<p><p>\t\u00bb <em>Foreseeing a porous anti-American region possessing nuclear weapons, the architects of Bush&rsquo;s security strategy became driven by the fear of a nuclear terrorist attack on a major US city. While the odds of a mushroom cloud over Manhattan are unlikely this year, it increases substantially over the longer term. If by 2050 the Gulf region became a mix of unstable nuclear-armed autocracies, weapons would inevitably leak to nameless terrorist groups &#8211; resulting in undeterrable destruction.<\/em> <\/p>\n<\/p>\n<p><p>\t\u00bb <em>Like the Greek prophet Cassandra, endowed with the gift of prophecy but fated by Apollo never to be believed, Wolfowitz &#038; Co see a doomsday looming on the horizon and they are desperately working backward to change our fate. They decided to divert either the diffusion of nuclear technology or Middle Eastern instability. Because globalization makes technological quarantine impossible, and they hold multilateral conventions in low esteem, they chose to accelerate the spread of democracy. If the region is going nuclear down the road, it must be as benign as possible. With no confidence that a participatory government was likely in the next few decades on its own, the administration wanted to give the region a superpower push. September 11 gave them the perfect opportunity to act.<\/em> <\/p>\n<\/p>\n<p><p>\t\u00bb <em>Iraq became the lever to transform the region for several reasons. To start, the US had been making a case against Iraqi leader Saddam Hussein for more than a decade. Advancing that argument was easier than starting over with another country. Second, Iraq would certainly acquire nuclear weapons  it might just take decades for the technology to spread. But if Iraq could become a stable democracy, it would send shock waves through the region, forcing other governments to change. In that case, the inevitable spread of nuclear technology would involve safe democracies, not hostile theocracies.<\/em> \u00bb <\/p>\n<\/p>\n<p><\/p>\n<p><p>\tAinsi nous est d\u00e9voil\u00e9 le comportement des n\u00e9o-conservateurs : aller au-devant de l&rsquo;Histoire, la pr\u00e9c\u00e9der,  au fond, l&rsquo;accoucher avant m\u00eame qu&rsquo;elle soit enceinte, pr\u00e9voyant par avance l&rsquo;acte, les cons\u00e9quences de l&rsquo;acte, et sa propre intervention qui en d\u00e9coule. Il y a dans ce raisonnement un sophisme fascinant, bien caract\u00e9ristique de notre \u00e9poque. Ce qu&rsquo;on nous explique, c&rsquo;est que les n\u00e9o-conservateurs, pr\u00e9voyant des \u00e9v\u00e9nements catastrophiques pour dans 50 ou 100 ans, vont au-devant, \u00e9ventuellement,  on le constate chaque jour en Irak,  en provoquant eux-m\u00eames ces \u00e9v\u00e9nements catastrophiques pour pouvoir mieux contr\u00f4ler demain ceux qui ne manqueront pas de s&rsquo;encha\u00eener. On les croirait prisonniers d&rsquo;une fatalit\u00e9 de l&rsquo;Histoire et les voil\u00e0 qui proposent d&rsquo;\u00eatre quittes de cette fatalit\u00e9 en la contr\u00f4lant par avance. Les questions qu&rsquo;on ne peut tout de m\u00eame s&#8217;emp\u00eacher de poser sont de cette sorte : ces \u00e9v\u00e9nements catastrophiques sont-ils in\u00e9luctables ? Plut\u00f4t que les provoquer, ne vaudrait-il pas mieux tenter de les pr\u00e9venir, et, par cons\u00e9quent, de les emp\u00eacher de survenir, notamment (m\u00e9thode classique) en travaillant \u00e0 en supprimer les causes ? A moins qu&rsquo;il n&rsquo;y ait pas de causes, qu&rsquo;il s&rsquo;agisse d&rsquo;une g\u00e9n\u00e9ration spontan\u00e9e d&rsquo;\u00e9v\u00e9nements catastrophiques ?<\/p>\n<\/p>\n<p><p>\t(La stupidit\u00e9 sophistique des arguments est fascinante, dans le texte de Daniel Richard Ewing, notamment l&rsquo;argument sur la prolif\u00e9ration. Ewing ne sait-il pas que l&rsquo;activisme US dans la r\u00e9gion, depuis les ann\u00e9es 1960, est en bonne partie la cause du programme nucl\u00e9aire pakistanais, avec des aides indirectes \u00e0 cet \u00e9gard, notamment dans les ann\u00e9es 1980 (alliance serr\u00e9e USA-Pakistan derri\u00e8re les moudjahiddines afghans) ? Ignore-t-il que la prolif\u00e9ration fut au contraire un \u00e9v\u00e9nement extr\u00eamement lent par rapport aux pr\u00e9visions faites \u00e0 la fin des ann\u00e9es 1940, o\u00f9 l&rsquo;on estimait, apr\u00e8s l&rsquo;explosion atomique sovi\u00e9tique, qu&rsquo;une quinzaine d&rsquo;\u00c9tats seraient nucl\u00e9aires \u00e0 la fin des ann\u00e9es 1960 ?)<\/p>\n<\/p>\n<p><p>\tLa psychologie n\u00e9o-conservatrice est une psychologie ferm\u00e9e, repoussant toute possibilit\u00e9 d&rsquo;acquisition de connaissances par l&rsquo;exp\u00e9rience. Cette psychologie est inflexiblement li\u00e9e \u00e0 la doctrine de l&rsquo;id\u00e9ologie, laquelle a d\u00e9j\u00e0 programm\u00e9 l&rsquo;avenir (parlant de l&rsquo;Irak de Saddam : \u00ab <em>Iraq would certainly acquire nuclear weapons  it might just take decades for the technology to spread<\/em> \u00bb). Le reste du monde, ou le reste de la r\u00e9alit\u00e9, n&rsquo;a qu&rsquo;\u00e0 s&rsquo;y conformer. En ce sens, les n\u00e9o-conservateurs sont parfaitement am\u00e9ricanistes. S&rsquo;ils n&rsquo;existaient pas, il faudrait les inventer : ils disent tout haut ce que les Am\u00e9ricains pensent tout bas.<\/p>\n<\/p>\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Savez-vous, pauvres ignorants, que les neocons travaillent pour nos petits-enfants ? 19 septembre 2004 Pendant ce temps (on veut dire : pendant que des choses se passent en Irak et \u00e0 Washington), les n\u00e9o-conservateurs, ou neocons, pensent \u00e0 votre avenir. \u00c9coutez-les penser. Plac\u00e9s devant le d\u00e9sastre irakien, les n\u00e9o-conservateurs ont r\u00e9agi comme il se doit,&hellip;&nbsp;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[4349,1448],"class_list":["post-66083","post","type-post","status-publish","format-standard","hentry","category-faits-et-commentaires","tag-ewings","tag-wolfowitz"],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/66083","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/comments?post=66083"}],"version-history":[{"count":0,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/66083\/revisions"}],"wp:attachment":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/media?parent=66083"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/categories?post=66083"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/tags?post=66083"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}