{"id":66141,"date":"2004-11-25T00:00:00","date_gmt":"2004-11-25T00:00:00","guid":{"rendered":"https:\/\/new.dedefensa.org\/index.php\/2004\/11\/25\/boeing-et-le-pentagone-battus-par-mccain-et-la-corruption\/"},"modified":"2004-11-25T00:00:00","modified_gmt":"2004-11-25T00:00:00","slug":"boeing-et-le-pentagone-battus-par-mccain-et-la-corruption","status":"publish","type":"post","link":"https:\/\/new.dedefensa.org\/index.php\/2004\/11\/25\/boeing-et-le-pentagone-battus-par-mccain-et-la-corruption\/","title":{"rendered":"Boeing et le Pentagone battus par McCain et la corruption"},"content":{"rendered":"<p><h2 class=\"titleset_a.deepblue\" style=\"color:#0f3955;font-size:2em;\">Boeing batt par McCain et la corruption<\/h2>\n<\/p>\n<p><p>25 novembre 2004 &mdash; Le Pentagone a rouvert <a class=\"gen\" href=\"http:\/\/www.govexec.com\/dailyfed\/1104\/112204cdpm1.htm\">la comp\u00e9tition pour un march\u00e9 de cent avions ravitailleurs en vol<\/a> (<em>tankers<\/em>), pour un budget compris entre $19 et $23 milliards. Ce march\u00e9 consid\u00e9rable secoue le Pentagone depuis trois ans, alors qu&rsquo;il semblait initialement ne s&rsquo;agir que d&rsquo;une simple formalit\u00e9 pour que Boeing emporte le budget d&rsquo;un peu plus de $17 milliards pour cent Boeing 767 (d\u00e9sign\u00e9s KC-767) en <em>leasing<\/em> pour dix ans. La proposition introduite dans le trouble et l&rsquo;atmosph\u00e8re hyper-patriotarde qui suivait le 11 septembre 2001 ne semblait ne devoir soulever aucune difficult\u00e9. A la fin du printemps 2003, tout semblait enfin finalis\u00e9 et, en juin 2003, le Pentagone donna son accord, suivant en cela la recommandation de l&rsquo;USAF.<\/p>\n<\/p>\n<p><p>Le march\u00e9, marqu\u00e9 par des interventions diverses et des cas de corruption importants, assurait \u00e0 Boeing un b\u00e9n\u00e9fice colossal calcul\u00e9 \u00e0 $2.3 milliards (l&rsquo;\u00e9quivalent du b\u00e9n\u00e9fice r\u00e9alis\u00e9 sur la vente de 1.033 Boeing 737), qui permettait \u00e0 la soci\u00e9t\u00e9 g\u00e9ante de r\u00e9soudre des probl\u00e8mes financiers graves. En juillet 2003, <a class=\"gen\" href=\"http:\/\/counterpunch.org\/stclair07262003.html\">Jeffrey Saint-Clair, de CounterPunch<\/a>, avait expos\u00e9 cet aspect du march\u00e9.<\/p>\n<\/p>\n<blockquote class=\"normal\" style=\"font-size:1.05em;\">\n<p><p>&laquo; <em> Early this summer, a top Wall Street stock picker issued a glowing report about Boeing: buy, buy, buy. The unusually rosy assessment for the troubled company had nothing to do with the need to replenish the Pentagon&rsquo;s arsenal of cruise missiles depleted by the Iraq war or the Bush administration&rsquo;s drive to implement Star War, both of which will net Boeing billions. No, this analysis, written by Heidi Wood, a vice-president at Morgan Stanley, pointed to \u00a0\u00bba no risk\u00a0\u00bb risk deal with the federal government to lease 100 Boeing-767 tanker aircraft.<\/em><\/p>\n<\/p>\n<p><p>&raquo; <em>According to Wood&rsquo;s report, the deal will generate $2.3 billion in profit for Boeing. To put this in perspective, that&rsquo;s about as much profit as Boeing reaps for the sale of 1,033 of its 737 commercial airliners. From Boeing&rsquo;s perspective, the great part of the tanker deal is that the company has few obligations, yet the government is locked into the leases, even if it proves that the Pentagon doesn&rsquo;t need the planes. Boeing is guaranteed a 15 percent profit on each plane it delivers. \u00a0\u00bbThere&rsquo;s substantially less risk than is common in the commercial aircraft market,\u00a0\u00bb Wood wrote.<\/em><\/p>\n<\/p>\n<p><p>&raquo; <em>Wood should know what she&rsquo;s talking about. The Wall Street Journal calls her the top stock analyst in the Aerospace \/ Defense sector and she also serves as a Bush appointee to the Commission on the Future of the US Aerospace Industry.<\/em> &raquo;<\/p>\n<\/p>\n<\/blockquote>\n<p><p>Des difficult\u00e9s ont surgi <em>in extremis<\/em>, notamment avec la susceptibilit\u00e9 du s\u00e9nateur McCain, jugeant Boeing un peu trop s&ucirc;r d&#8217;emporter ce march\u00e9 et furieux du comportement du Pentagone qui refusa de communiquer certains documents aux l\u00e9gislateurs. Effectivement, le contractant et son acheteur ont pr\u00e9sent\u00e9 le programme comme s&rsquo;il \u00e9tait d&rsquo;ores et d\u00e9j\u00e0 acquis. La r\u00e9sistance du s\u00e9nateur McCain s&rsquo;est d&rsquo;autre part appuy\u00e9 sur le constat que ce programme n&rsquo;avait pas suivi les r\u00e8gles de s\u00e9lection par concurrence, que Boeing s&rsquo;\u00e9tait pr\u00e9sent\u00e9 dans cette affaire comme d\u00e9tenteur d&rsquo;un v\u00e9ritable monopole. Il est vrai que le seul concurrent possible \u00e9tait EADS, le consortium europ\u00e9en, avec une proposition Airbus. Cette proposition n&rsquo;a jamais figur\u00e9 s\u00e9rieusement dans la non-comp\u00e9tition ayant abouti \u00e0 la d\u00e9cision du Pentagone de juin 2003 de faire d\u00e9marrer le programme Boeing.<\/p>\n<\/p>\n<p><p>Enfin, une grave affaire de corruption est venue encore alourdir le dossier. Entre juin 2003 et le d\u00e9but 2004, le programme s&rsquo;est compl\u00e8tement effondr\u00e9 et d\u00e8s le printemps 2004, l&rsquo;abandon \u00e9tait acquis. La d\u00e9cision du Pentagone du 23 novembre de rouvrir le programme \u00e0 une comp\u00e9tition est la sanction logique de cette suite d&rsquo;\u00e9v\u00e9nements. Sans aucun doute, c&rsquo;est l&rsquo;affaire de corruption impliquant Darleen A. Druyun, qui est l&rsquo;aspect le plus pr\u00e9occupant. Druyun a occup\u00e9 pendant 9 ans (1993-2002) le poste de l&rsquo;attribution des grands contrats du Pentagone, pratiquement sans surveillance, <a class=\"gen\" href=\"http:\/\/www.washingtonpost.com\/wp-dyn\/articles\/A8689-2004Nov23.html\">comme l&rsquo;a reconnu avec embarras Donald Rumsfeld<\/a>, le 23 novembre. Druyun a quitt\u00e9 le Pentagone en 2002 pour un poste de vice-pr\u00e9sident chez Boeing. Inculp\u00e9 de corruption, elle vient d&rsquo;\u00eatre condamn\u00e9e \u00e0 neuf mois de prison.<\/p>\n<\/p>\n<blockquote class=\"normal\" style=\"font-size:1.05em;\">\n<p><p>&laquo; <em>Defense Secretary Donald H. Rumsfeld blamed an Air Force procurement scandal on high turnover in top management positions, which he said reduced the amount of \u00a0\u00bbadult supervision\u00a0\u00bb of major weapons contracts over the past decade.<\/em><\/p>\n<\/p>\n<p><p>&raquo; <em>Cautioning that his view isn&rsquo;t yet \u00a0\u00bbdefinitive,\u00a0\u00bb Rumsfeld said at a Pentagon news briefing yesterday that he had recently been looking into the case of former Air Force acquisition official Darleen A. Druyun, who last month was sentenced to nine months in prison after admitting to granting favors in contracts to aerospace giant Boeing Co. before going to work there. Earlier this month, Michael M. Sears, Boeing&rsquo;s former chief financial officer, pleaded guilty to a conflict-of-interest charge for his role in hiring Druyun while she was overseeing large contracts with the company.<\/em><\/p>\n<\/p>\n<p><p>&raquo; <em>Rumsfeld said he was struck that during the nine years in which Druyun had been a top Air Force weapons buyer, there had been heavy turnover among other senior managers who might have questioned some of her decisions if they had been on the job longer. From the time Druyun became the Air Force&rsquo;s deputy acquisition chief in 1993 until her retirement in 2002, he said, the positions of secretary of the Air Force, assistant secretary for acquisition and senior military official for acquisition had all changed several times.<\/em><\/p>\n<\/p>\n<p><p>&raquo; <em>\u00a0\u00bbSo what you had with all these vacancies over a 10-year period . . . the only continuity was that single person, who&rsquo;s now pled guilty and is going to go to jail,\u00a0\u00bb he said. \u00a0\u00bbWhen you have that long period of time, with . . . no one above her and no one below her, over time I&rsquo;m told that what she did was acquire a great deal of authority and make a lot of decisions, and there was very little adult supervision.\u00a0\u00bb<\/em> &raquo;<\/p>\n<\/p>\n<\/blockquote>\n<p><p>McCain a \u00e9galement <a class=\"gen\" href=\"http:\/\/www.govexec.com\/dailyfed\/1104\/111904cdpm1.htm\">mis en cause le secr\u00e9taire \u00e0 l&rsquo;Air Force<\/a> d\u00e9missionnaire depuis la mi-novembre, James Roche, qui est d\u00e9fendu par Rumsfeld. Le r\u00f4le de Roche est ambigu, dans la mesure o&ugrave; c&rsquo;est lui qui a \u00e9galement d\u00e9nonc\u00e9 le contrat avec Boeing. Roche a mis en cause tout le processus de restructuration de l&rsquo;industrie a\u00e9rospatiale US (pourtant pr\u00e9sent\u00e9 unanimement comme un mod\u00e8le du genre). Selon lui, ce sch\u00e9ma de restructuration m\u00e8ne au monopole.<\/p>\n<\/p>\n<p><p>En mars 2004, Roche d\u00e9clarait au <em>National Defense Magazine<\/em> :<\/p>\n<\/p>\n<blockquote class=\"normal\" style=\"font-size:1.05em;\">\n<p><p>&laquo; <em>The debacle could have been avoided if there had been a legitimate competition. The European consortium Airbus is the only other vendor that could have competed with Boeing, but a contract of that magnitude &mdash; worth about $23 billion &mdash; would not likely have been awarded to a non-U.S. supplier.<\/em><\/p>\n<\/p>\n<p><p>&raquo; <em>Part of the problem is the collapse of the defense industry. We are increasingly dealing with monopolies. When I was in the industry, I said it was wrong to over-consolidate, and that we would come to regret it.<\/em> &raquo;<\/p>\n<\/p>\n<\/blockquote>\n<p><p>Le march\u00e9 rouvert, on devrait essentiellement trouver un concurrent Boeing sur la d\u00e9fensive et dans une situation extr\u00eamement d\u00e9licate, politiquement et financi\u00e8rement, et un concurrent EADS\/Airbus revigor\u00e9, avec la perspective mirifique d&rsquo;un \u00e9norme march\u00e9 du Pentagone pour un concurrent europ\u00e9en, &mdash; ce que certains, en Europe, voient comme une v\u00e9ritable r\u00e9volution dans les rapports transatlantiques.<\/p>\n<\/p>\n<p><p>En r\u00e9alit\u00e9, on est tr\u00e8s loin du compte et d&rsquo;une telle issue, m\u00eame si, techniquement et industriellement, cela para&icirc;t la seule voie possible. Il est \u00e9vident que cette \u00e9norme affaire n&rsquo;en restera pas l\u00e0, &mdash; c&rsquo;est-\u00e0-dire qu&rsquo;elle ne se d\u00e9roulera pas calmement, simplement en suivant un processus d&rsquo;\u00e9valuation et de s\u00e9lection o&ugrave; EADS est favori. Ce qui est en cause, au travers de divers points de controverse politique qu&rsquo;on a vu, c&rsquo;est toute la validit\u00e9 du syst\u00e8me industriel et bureaucratique de l&rsquo;armement aux USA, &mdash; c&rsquo;est-\u00e0-dire, rien de moins que le fondement de la puissance am\u00e9ricaine.<\/p>\n<\/p>\n<p><h3>Liens sur <strong><em>dedefensa.org<\/em><\/strong><\/h3>\n<\/p>\n<p><p>Sur cet important probl\u00e8me, on peut consulter d&rsquo;autres textes sur <em>dedefensa.org<\/em><\/p>\n<\/p>\n<p><p>&bull; Nous mettons en ligne aujourd&rsquo;hui une analyse extraite de <em>Context<\/em>, juillet 2004, sur <a class=\"gen\" href=\"http:\/\/www.dedefensa.org\/article.php?art_id=1284\">la consolidation de l&rsquo;industrie de d\u00e9fense US, dix ans apr\u00e8s<\/a>, dans laquelle cette question du march\u00e9 des avions ravitailleurs est \u00e9voqu\u00e9e.<\/p>\n<\/p>\n<p><p>&bull; On trouve \u00e9galement la rubrique <em>Analyse<\/em> de <em>de defensa<\/em>-papier, en date du 25 juin 2004, consacr\u00e9e \u00e0 la m\u00eame question <a class=\"gen\" href=\"http:\/\/www.dedefensa.org\/article.php?art_id=1161\">de l&rsquo;\u00e9chec de la restructuration de l&rsquo;industrie de d\u00e9fense US<\/a>.<\/p>\n<\/p>\n<p><p>&bull; La bataille l\u00e9gale Airbus-Boeing, voulue par Boeing, est \u00e9galement li\u00e9e \u00e0 cette affaire des ravitailleurs en vol. Voir <a class=\"gen\" href=\"http:\/\/www.dedefensa.org\/article.php?art_id=1267\">notre Analyse du 11 novembre<\/a>.<\/p>\n<\/p>\n<p><p>&bull; On doit \u00e9galement se r\u00e9f\u00e9rer \u00e0 l&rsquo;extraordinaire discours sur le danger de la bureaucratie US, <a class=\"gen\" href=\"http:\/\/www.dedefensa.org\/article.php?art_id=201\">prononc\u00e9 par Rumsfeld la veille de l&rsquo;attaque du 11 septembre 2001<\/a>.<\/p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Boeing batt par McCain et la corruption 25 novembre 2004 &mdash; Le Pentagone a rouvert la comp\u00e9tition pour un march\u00e9 de cent avions ravitailleurs en vol (tankers), pour un budget compris entre $19 et $23 milliards. Ce march\u00e9 consid\u00e9rable secoue le Pentagone depuis trois ans, alors qu&rsquo;il semblait initialement ne s&rsquo;agir que d&rsquo;une simple formalit\u00e9&hellip;&nbsp;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[3191,4391,4215,3234,569],"class_list":["post-66141","post","type-post","status-publish","format-standard","hentry","category-faits-et-commentaires","tag-airbus","tag-druyun","tag-eads","tag-roche","tag-rumsfeld"],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/66141","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/comments?post=66141"}],"version-history":[{"count":0,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/66141\/revisions"}],"wp:attachment":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/media?parent=66141"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/categories?post=66141"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/tags?post=66141"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}