{"id":66216,"date":"2005-01-31T00:00:00","date_gmt":"2005-01-31T00:00:00","guid":{"rendered":"https:\/\/new.dedefensa.org\/index.php\/2005\/01\/31\/la-deuxieme-legitimation-de-gw\/"},"modified":"2005-01-31T00:00:00","modified_gmt":"2005-01-31T00:00:00","slug":"la-deuxieme-legitimation-de-gw","status":"publish","type":"post","link":"https:\/\/new.dedefensa.org\/index.php\/2005\/01\/31\/la-deuxieme-legitimation-de-gw\/","title":{"rendered":"La deuxi\u00e8me l\u00e9gitimation de GW"},"content":{"rendered":"<p><h2 class=\"common-article\">La deuxi\u00e8me l\u00e9gitimation de GW<\/h2>\n<\/p>\n<p><p>\t31 janvier 2005  Faut-il s&rsquo;attarder aux chiffres? Ceux qui, hier 30 janvier, accompagn\u00e8rent (encore plus que suivirent) les \u00e9lections irakiennes furent marqu\u00e9s \u00e0 la fois par l&rsquo;\u00e9lan des commentaires occidentaux,  une sorte de \u00ab <em>solidarit\u00e9 mondialis\u00e9e<\/em> \u00bb pour faire accueil compl\u00e8tement enthousiaste \u00e0 la d\u00e9mocratie triomphante,  et par une confusion sympathique dans leur fonction premi\u00e8re d&rsquo;annonce des r\u00e9sultats. Hier soir, <em>BBC.News<\/em> titrait: \u00ab <em>Iraq election declared success<\/em> \u00bb, un peu comme on d\u00e9clare la victoire. GW fut \u00e9mu en nous d\u00e9clarant, lui, que c&rsquo;\u00e9tait \u00ab <em>a great and historical achievement<\/em> \u00bb.<\/p>\n<\/p>\n<p><p>\tMaintenant, voyons le plus int\u00e9ressant, qui est la petite m\u00e9canique qui a \u00e9t\u00e9 mise en route. L&rsquo;unanimit\u00e9 a \u00e9t\u00e9 quasiment obtenue, sauf chez les irr\u00e9ductibles, les grincheux et les Ast\u00e9rix de la globalisation d\u00e9mocratique, pour proclamer un plein soutien au scrutin. Tout l&rsquo;Occident bien-pensant s&rsquo;est lev\u00e9 comme un seul homme pour commenter dans un sens non pas favorable, mais quasiment extatique, la journ\u00e9e du 30 janvier. L&rsquo;esprit est court dans nos \u00e9poques virtualistes, et la m\u00e9moire encore plus. Entendant ces commentaires, c&rsquo;est comme si rien n&rsquo;avait exist\u00e9 vraiment des causes profondes du d\u00e9sordre, des tueries et du reste. C&rsquo;\u00e9tait un jour de grande r\u00e9conciliation des commentaires occidentaux.<\/p>\n<\/p>\n<p><p>\tLe Washington officiel ne pouvait laisser passer cela; d&rsquo;ailleurs, le Washington officiel s&rsquo;y \u00e9tait pr\u00e9par\u00e9. Le Washington officiel a \u00e9t\u00e9 parfaitement confirm\u00e9 dans son attente, non par les \u00e9lections elles-m\u00eames mais par les r\u00e9actions massives et \u00e9motionnelles de nos commentaires. Quoiqu&rsquo;il en soit de la r\u00e9elle situation en Irak, l&rsquo;\u00e9tat d&rsquo;esprit assez vague mais tr\u00e8s puissant par l&rsquo;\u00e9motion sentimentale qui r\u00e9gna partout dans les r\u00e9dactions et dans les studios se traduit ainsi : la journ\u00e9e du 30 janvier est un triomphe pour la d\u00e9mocratie, donc pour la civilisation. Il faut savoir \u00e0 qui va le cr\u00e9dit de cet \u00e9v\u00e9nement formidable.<\/p>\n<\/p>\n<p><p>\tLa rapidit\u00e9 des r\u00e9actions officielles US et la rapidit\u00e9 des commentaires favorables \u00e0 la rapidit\u00e9 des r\u00e9actions officielles US sont deux traits \u00e9galement remarquables. On citera ce passage d&rsquo;une <a href=\"http:\/\/story.news.yahoo.com\/news?tmpl=story&#038;u=\/afp\/20050130\/wl_mideast_afp\/iraqvoteus_050130162732&#038;e=1\" class=\"gen\">d\u00e9p\u00eache d&rsquo;AFP en fin d&rsquo;apr\u00e8s-midi le 30 janvier<\/a>. Elle nous donne effectivement une impression de gaiet\u00e9 roborative, de satisfaction du devoir bien rempli, d&rsquo;une sorte de modestie heureuse devant l&rsquo;accomplissement d&rsquo;une t\u00e2che morale et humanitaire auquel on a puissamment particip\u00e9, etc. Ces gens sont des mod\u00e8les de s\u00e9rieux et de vertu.<\/p>\n<\/p>\n<p><p>\t\u00ab <em>The United States hailed Iraq&rsquo;s national elections as a great day for the country with better than expected turnout, but warned the polls would likely spark a new round of violence by insurgents.<\/em> <\/p>\n<\/p>\n<p><p>\t\u00bb <em>President George W. Bush was incredibly encouraged by the turnout, Secretary of State Condoleeeza Rice told Fox News after speaking with him. He just said that this was a great day for the Iraqi people.<\/em><\/p>\n<\/p>\n<p><p>\t\u00bb <em>But despite the upbeat reaction to the vote for a national assembly, Rice refused to provide a timetable for the eventual withdrawal of the 150,000 US troops in Iraq facing a stubborn insurgency.<\/em> <\/p>\n<\/p>\n<p><p>\t\u00bb <em>The Bush administration had a lot riding politically and diplomatically on the elections, which went ahead despite a campaign of violence by the insurgents battling on nearly two years after the US-led invasion to topple Saddam Hussein.<\/em> <\/p>\n<\/p>\n<p><p>\t\u00bb <em>US officials were clearly exultant by initial reports of the turnout.<\/em> <\/p>\n<\/p>\n<p><p>\t\u00bb <em>What we are seeing is that Iraqis are voting in large numbers, Rice said in a round of interviews on US television. I think everybody believes it&rsquo;s better than expected.<\/em><\/p>\n<\/p>\n<p><p>\t\u00bb <em>Rice acknowledged the elections were not perfect and that some voters had been scared off by the violence that was rampant in largely Sunni areas. But she said the polls represented a huge step foward for the country&rsquo;s transition to democracy.<\/em> \u00bb <\/p>\n<\/p>\n<p><p>\tNe retenons qu&rsquo;un commentaire de cet extrait, qui concerne la r\u00e9action de GW: il est <em>incredibly encouraged<\/em> par les r\u00e9sultats. Par ailleurs, nous signalons cette remarque de Mariam Fam, de AP, \u00e9galement <a href=\"http:\/\/story.news.yahoo.com\/news?tmpl=story&#038;cid=514&#038;e=1&#038;u=\/ap\/20050130\/ap_on_re_mi_ea\/iraq_the_vote_53\" class=\"gen\">dans une d\u00e9p\u00eache de fin d&rsquo;apr\u00e8s-midi<\/a>, le 30 janvier: \u00ab <em>The election is a major test of President Bush&rsquo;s goal of promoting democracy in the Middle East. If successful, it also could hasten the day when the United States brings home its 150,000 troops.<\/em> \u00bb<\/p>\n<\/p>\n<p><p>\tLa bri\u00e8vet\u00e9 dans le contenu de ces r\u00e9actions, qui sont cantonn\u00e9es \u00e0 la fin d&rsquo;apr\u00e8s-midi du 30, peu apr\u00e8s que les bureaux de vote aient \u00e9t\u00e9 ferm\u00e9s et alors que les premi\u00e8res indications sont extraordinairement optimistes (72% de participation, jusqu&rsquo;\u00e0 95% dans certains quartier de Bagdad), n&rsquo;a d&rsquo;\u00e9gale que leur poids \u00e9norme, leur unanimit\u00e9 et leur caract\u00e8re massif. Tout le monde, \u00e0 ce moment-l\u00e0, dit la m\u00eame chose parce que tout le monde pense la m\u00eame chose, parce que l&rsquo;\u00e9motion conformiste transmise par le syst\u00e8me de communication postmoderne les submerge tous. GW Bush a dit la m\u00eame chose parce qu&rsquo;il a entendu et lu la m\u00eame chose. C&rsquo;est ce qu&rsquo;il retiendra de ces \u00e9lections, comme la plupart des citoyens et journalistes occidentaux. Cette atmosph\u00e8re de f\u00eate, ce triomphe de la d\u00e9mocratie, c&rsquo;est le <a href=\"http:\/\/www.dedefensa.org\/article.php?art_id=1337\" class=\"gen\">good news only<\/a> de GW; ce 30 janvier, il est sanctionn\u00e9 par le reste du monde (le conformiste et le bien-pensant).<\/p>\n<\/p>\n<p><p>\tLa chose a une importance consid\u00e9rable du point de vue psychologique. R\u00e9sumons son effet sur l&rsquo;esprit de GW, par deux points:<\/p>\n<\/p>\n<p><p>\t GW va penser \u00e9videmment que ce scrutin est une v\u00e9ritable seconde l\u00e9gitimation, apr\u00e8s celle du 2 novembre 2004. C&rsquo;est ainsi qu&rsquo;il va interpr\u00e9ter un scrutin qui correspond si compl\u00e8tement \u00e0 tous les lieux communs du virtualisme washingtonien depuis des mois, que lui-m\u00eame a entretenus auxquels lui-m\u00eame s&rsquo;abreuve. Si l&rsquo;on veut, pour lui <strong>la chose est vraie<\/strong> puisqu&rsquo;il l&rsquo;a v\u00e9cue en direct. Tout le reste, les <em>chicayas<\/em> qui vont suivre, les estimations r\u00e9vis\u00e9es, les attentats, les affrontements politiques, ne sont plus, comme dit la citation, que vile turpitude humaine qu&rsquo;un peu de sable efface.<\/p>\n<\/p>\n<p><p>\t\u00a0La cons\u00e9quence est que l&rsquo;esprit simple de GW se sent consid\u00e9rablement renforc\u00e9 dans ses id\u00e9es simples sur la globalisation de la d\u00e9mocratie et sur la globalisation de la libert\u00e9 dans le monde. Sa guerre est compl\u00e8tement justifi\u00e9e, elle est quasiment l\u00e9galis\u00e9e <em>a posteriori<\/em>, par rien de moins que la sanction magique d&rsquo;un enthousiasme indescriptible du peuple iranien. (Les ADM, les votes \u00e0 l&rsquo;ONU, les liens de Saddam avec Al Qa\u00efda? Les tueries de tous les c\u00f4t\u00e9s, les tortures, les voitures pi\u00e9g\u00e9es et les bombardements depuis le <em>Mission accomplished<\/em> du 1er mai 2003? Pffuittt, tout cela est si loin qu&rsquo;il semblerait qu&rsquo;on n&rsquo;en ait jamais parl\u00e9, que, finalement, cela n&rsquo;ait pas vraiment exist\u00e9. On sautera \u00e0 la conclusion et on dira que c&rsquo;est le cas.)<\/p>\n<\/p>\n<p><p>\tLe scrutin du 30 janvier tel qu&rsquo;il a \u00e9t\u00e9 \u00e9clair\u00e9 par nos commentaires emport\u00e9es et enthousiastes confirme la politique de GW Bush dans l&rsquo;esprit du pr\u00e9sident am\u00e9ricain et nous fait avancer l&rsquo;hypoth\u00e8se qu&rsquo;il se juge lui-m\u00eame confirm\u00e9 dans son intention de poursuivre la croisade pour la libert\u00e9 ou contre la tyrannie. Le principal enseignement psychologique, et donc politique, de cette journ\u00e9e du 30 janvier 2005, est bien celui-ci: les commentateurs enthousiastes d&rsquo;Europe occidentale, et parmi ceux-ci plus pr\u00e9cis\u00e9ment ceux qui furent par ailleurs contre la guerre contre l&rsquo;Irak sous la forme o\u00f9 elle fut faite, ont contribu\u00e9 \u00e0 renforcer consid\u00e9rablement la conviction du pr\u00e9sident am\u00e9ricain qu&rsquo;il est juste, qu&rsquo;il est \u00e9clair\u00e9, que sa politique d&rsquo;attaque pr\u00e9ventive est la bonne. Ces m\u00eames commentateurs pourront donc, demain, s&rsquo;effrayer encore un peu plus, et crier leur indignation, devant les nouvelles entreprises guerri\u00e8res de GW. Les deux,  ceux qui protesteront contre l&rsquo;action de GW et GW qui conduira ces actions,  le feront \u00e9galement au nom de la d\u00e9mocratie et de la libert\u00e9, auxquelles ils croient tous dur comme fer.<\/p>\n<\/p>\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>La deuxi\u00e8me l\u00e9gitimation de GW 31 janvier 2005 Faut-il s&rsquo;attarder aux chiffres? Ceux qui, hier 30 janvier, accompagn\u00e8rent (encore plus que suivirent) les \u00e9lections irakiennes furent marqu\u00e9s \u00e0 la fois par l&rsquo;\u00e9lan des commentaires occidentaux, une sorte de \u00ab solidarit\u00e9 mondialis\u00e9e \u00bb pour faire accueil compl\u00e8tement enthousiaste \u00e0 la d\u00e9mocratie triomphante, et par une confusion&hellip;&nbsp;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[4426,4427,2825,4141,857],"class_list":["post-66216","post","type-post","status-publish","format-standard","hentry","category-faits-et-commentaires","tag-bonne","tag-conscience","tag-democratie","tag-elections","tag-irak"],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/66216","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/comments?post=66216"}],"version-history":[{"count":0,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/66216\/revisions"}],"wp:attachment":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/media?parent=66216"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/categories?post=66216"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/tags?post=66216"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}