{"id":66217,"date":"2005-01-31T00:00:00","date_gmt":"2005-01-31T00:00:00","guid":{"rendered":"https:\/\/new.dedefensa.org\/index.php\/2005\/01\/31\/les-elections-irakiennes-comme-evenement-virtualiste\/"},"modified":"2005-01-31T00:00:00","modified_gmt":"2005-01-31T00:00:00","slug":"les-elections-irakiennes-comme-evenement-virtualiste","status":"publish","type":"post","link":"https:\/\/new.dedefensa.org\/index.php\/2005\/01\/31\/les-elections-irakiennes-comme-evenement-virtualiste\/","title":{"rendered":"Les \u00e9lections irakiennes comme \u00e9v\u00e9nement virtualiste"},"content":{"rendered":"<p><h2 class=\"common-article\">Les \u00e9lections irakiennes comme \u00e9v\u00e9nement virtualiste<\/h2>\n<\/p>\n<p><p>\tFaut-il s&rsquo;attarder aux chiffres? <a href=\"http:\/\/www.dedefensa.org\/article.php?art_id=1357\" class=\"gen\">demandons-nous par ailleurs<\/a>. Pas vraiment n\u00e9cessaire, c&rsquo;est-\u00e0-dire qu&rsquo;il est pr\u00e9f\u00e9rable de ne chercher une pr\u00e9cision qui, par ailleurs, semble pour l&rsquo;instant bien insaisissable. Par ailleurs, c&rsquo;est sur cette pr\u00e9cision insaisissable que les commentaires se sont appuy\u00e9s d\u00e8s dimanche apr\u00e8s-midi pour d\u00e9crire l&rsquo;\u00e9lection en Irak comme un triomphe de la d\u00e9mocratie, jusqu&rsquo;\u00e0 d\u00e9cider que c&rsquo;est bien le cas (\u00ab <em>Iraq election declared success<\/em> \u00bb titrait le 30 au soir BBC.News). Nous essayons d&rsquo;abord de tracer une description de ce processus par rapport \u00e0 ce qui nous \u00e9tait donn\u00e9 des chiffres de l&rsquo;\u00e9lection.<\/p>\n<\/p>\n<p><p>\tNous ne pr\u00e9tendons pas, surtout pas, rendre une image pr\u00e9cise de ce tourbillon brutal et confus, enfi\u00e9vr\u00e9 et parfois involontairement comique (tragi-comique?) que furent les \u00e9lections irakiennes. Nous pr\u00e9tendons, \u00e0 l&rsquo;aide d&rsquo;exemples \u00e0 notre port\u00e9e qui ne sont \u00e9videmment pas exhaustifs, donner une image de la confusion sentimentale et fi\u00e9vreuse des commentateurs europ\u00e9ens et \u00f4 combien d\u00e9mocratiques. Leur z\u00e8le fut extr\u00eame pour rendre compte de l&rsquo;\u00e9v\u00e9nement du 30 janvier, et pour en en rendre compte de fa\u00e7on \u00e0 satisfaire leurs sentiments les plus insoup\u00e7onnables.<\/p>\n<h3>Triomphe de la d\u00e9mocratie et \u00e9v\u00e9nement historique<\/h3>\n<\/p>\n<p><p>\tLe 30 janvier, pour tous (disons : la plupart?) les reporteurs, commentateurs, journalistes et propagandistes, c&rsquo;\u00e9tait comme si le sort de la d\u00e9mocratie, donc de la civilisation, \u00e9tait en jeu. On ne peut imaginer enjeu, d\u00e9fi plus important. (Pr\u00e9sentation de la journ\u00e9e en Irak, \u00e0 19H00 le 30 janvier, de notre gentille RTBF  radio-t\u00e9l\u00e9vision belge francophone, habituellement subtilement anti-Bush, comme on trempe un doigt de pied pour voir si l&rsquo;eau est froide ; pr\u00e9sentation \u00e9videmment exultante devant le spectacle d\u00e9mocratique: \u00ab <em>Les Irakiens ont relev\u00e9 le d\u00e9fi de la d\u00e9mocratie<\/em> \u00bb. Tout est dit : le 30 janvier comme duel \u00e9pique entre civilisation et barbarie.)<\/p>\n<\/p>\n<p><p>\tVoici quelques observations, citations, extraits, etc., de nos commentaires occidentaux et notablement \u00e9mus sur cette journ\u00e9e historique. Ils sont donn\u00e9s sans souci, de notre part, d&rsquo;exactitude statistique (cette absence de souci pour l&rsquo;exactitude statistique \u00e9tait d&rsquo;ailleurs la r\u00e8gle, le 30 janvier) mais au gr\u00e9 de l&rsquo;exaltation souvent po\u00e9tique des enthousiasmes divers que nous relevons. (N.B. : nous donnons des liens pour les diverses citations mais en ayant conscience qu&rsquo;ils ne seront effectifs que durant un temps tr\u00e8s court. Peu importe : ces liens ne sont pas d&rsquo;un int\u00e9r\u00eat r\u00e9el,  hier, les d\u00e9p\u00eaches disaient toutes la m\u00eame chose, qui est sans int\u00e9r\u00eat politique,  ils sont l\u00e0 comme r\u00e9f\u00e9rences \u00e9ventuelles.)<\/p>\n<\/p>\n<p><p>\tOn voudra bien voir dans cet exercice innocent, non une d\u00e9monstration politique (pour ou contre l&rsquo;importance du scrutin, sa signification politique, etc.) mais plut\u00f4t une analyse sur la fa\u00e7on dont la tendance \u00e0 l&rsquo;appr\u00e9ciation d&rsquo;un \u00e9v\u00e9nement (son triomphe pour ce cas, comme un \u00e9v\u00e9nement aussit\u00f4t class\u00e9 historique, selon une forme de jugements qui va aussit\u00f4t \u00e0 l&rsquo;extr\u00eame) d\u00e9pend d&rsquo;\u00e9l\u00e9ments subjectifs extraordinairement t\u00e9nus. On voudra bien aussi y voir une indication du conformisme des m\u00e9dias occidentaux face \u00e0 la tendance implicite de la pens\u00e9e dominante (chacun fera son choix pour l&rsquo;identifier). On voudra bien enfin y voir les ravages de la pens\u00e9e r\u00e9duite au symbolisme id\u00e9ologique, tournant dans ce cas,  c&rsquo;est le cas le plus g\u00e9n\u00e9ral  autour du mot d\u00e9mocratie consid\u00e9r\u00e9 comme une sorte de formule magique et vertueuse de l&rsquo;appr\u00e9ciation morale.<\/p>\n<h3>Les chaotiques \u00e9lections irakiennes<\/h3>\n<\/p>\n<p><p>\t\u00a0On trouvait une premi\u00e8re trace de l&rsquo;ambiance sur <a href=\"http:\/\/www.lefigaro.fr\/international\/20050130.FIG0229.html\" class=\"gen\">le site du Figaro dans l&rsquo;apr\u00e8s-midi du 30 janvier<\/a>, annon\u00e7ant (titre) son texte sur les \u00e9lections par un sympathique \u00ab <em>Les Irakiens ont vot\u00e9 en nombre malgr\u00e9 les attaques meurtri\u00e8res<\/em> \u00bb et poursuivant (chapeau) par un carr\u00e9ment enthousiaste \u00ab <em>Les Irakiens ont massivement vot\u00e9 ce dimanche pour un scrutin historique<\/em> \u00bb.<\/p>\n<\/p>\n<p><p>\t\u00a0Il est juste et infiniment significatif de noter que la m\u00eame expression du voter massivement est retrouv\u00e9e \u00e0 la une et dans l&rsquo;article <a href=\"http:\/\/www.lefigaro.fr\/international\/20050131.FIG0176.html\" class=\"gen\">du 31 janvier du m\u00eame Figaro<\/a>, alors que les chiffres de participation avaient \u00e9t\u00e9 modifi\u00e9s dans le texte conform\u00e9ment \u00e0 la mode au jour le jour (voir plus loin), de 72% \u00e0 60%. Cela signifie qu&rsquo;une participation de 72% est consid\u00e9r\u00e9e comme massive le dimanche, et une participation de 60% est consid\u00e9r\u00e9e comme massive le lundi. Accessoirement, notons que tout cela est chapeaut\u00e9 du titre \u00ab <em>une le\u00e7on de d\u00e9mocratie<\/em> \u00bb. En pr\u00e9sence de tous ces \u00e9l\u00e9ments, on en vient \u00e0 se demander, impoliment, par qui la le\u00e7on est donn\u00e9e, et \u00e0 qui.<\/p>\n<\/p>\n<p><p>\t\u00a0Une premi\u00e8re trace des r\u00e9sultats estim\u00e9s des \u00e9lections, nous la trouvions dans <a href=\"http:\/\/story.news.yahoo.com\/news?tmpl=story&#038;u=\/afp\/20050130\/wl_mideast_afp\/iraqvoteus_050130162732&#038;e=1\" class=\"gen\">une d\u00e9p\u00eache d&rsquo;AFP du 30 janvier, en fin d&rsquo;apr\u00e8s-midi<\/a>, qui nous disait: \u00ab <em>An electoral commission official in Baghdad said 72 percent of Iraq&rsquo;s voters  excluding those in three restive Sunni Muslim provinces  cast ballots in the country&rsquo;s first free election in half a century.<\/em> \u00bb (Notez l&rsquo;important \u00ab <em> excluding those in three restive Sunni Muslim provinces<\/em> \u00bb, qui interdit de consid\u00e9rer le 72% comme un r\u00e9sultat pour l&rsquo;Irak entier.)<\/p>\n<\/p>\n<p><p>\t\u00a0&#8230; Mais une nouvelle d\u00e9p\u00eache AFP, un peu plus tard cet apr\u00e8s-midi du 30 janvier, reprenait l&rsquo;information en la modifiant sans trop en avoir l&rsquo;air, mais de fa\u00e7on radicale: \u00ab <em>But with a massive security clampdown nationwide, the Iraqi election commission said preliminary figures indicated 72 percent of the 14 million registered voters had turned out even three hours before polls closed.<\/em> \u00bb Cette fois, les sunnites semblaient dans le coup et le r\u00e9sultat semblait triomphal, avec 72% de participants \u00ab <em>even three hours before polls closed<\/em> \u00bb. <\/p>\n<\/p>\n<p><p>\t\u00a0<a href=\"http:\/\/story.news.yahoo.com\/news?tmpl=story&#038;cid=514&#038;e=1&#038;u=\/ap\/20050130\/ap_on_re_mi_ea\/iraq_the_vote_53\" class=\"gen\">Une d\u00e9p\u00eache d&rsquo;AP parall\u00e8le<\/a> reprenait l&rsquo;information en l&rsquo;assortissant de pr\u00e9cisions qui tendaient plut\u00f4t \u00e0 en obscurcir le sens, et l&rsquo;on apprenait \u00e9galement que le chiffre avait \u00e9t\u00e9 annonc\u00e9 quelques heures avant la fermeture des bureaux de vote: \u00ab <em>A few hours before polls closed at 5 p.m., one Iraqi official, Adel al-Lami of the Independent Electoral Commission, said 72 percent of the 14 million eligible voters cast ballots but offered no overall figure of the number who participated.<\/em> \u00bb  <\/p>\n<\/p>\n<p><p>\t\u00a0Une autre <a href=\"http:\/\/seattlepi.nwsource.com\/national\/apmideast_story.asp?category=1107&#038;slug=Iraq%20Turnout\" class=\"gen\">d\u00e9p\u00eache d&rsquo;AP<\/a> reprenait les d\u00e9clarations de Adel al-Lami, qui semblait devenir la principale source d&rsquo;information de l&rsquo;Occident, en y ajoutant cette pr\u00e9cision enthousiaste: \u00ab <em>Al-Lami said the percentage of registered voters who had gone to the polls in some Baghdad neighborhoods was as high as 95 percent.<\/em> \u00bb<\/p>\n<\/p>\n<p><p>\t\u00a0Employant le mot confusion pour qualifier les \u00e9lections, <a href=\"http:\/\/english.aljazeera.net\/NR\/exeres\/B49A6A7B-9FE7-4C65-BA06-11461071FEAA.htm\" class=\"gen\">le site Aljazeera.net<\/a> \u00e9tait le premier, \u00e0 20H14 (GMT) le 30 janvier, \u00e0 annoncer que les 72% de participation tombaient \u00e0 autour de 60%. Tout cela se faisait \u00e0 l&rsquo;extr\u00eame confusion de Adel al-Lami. Les choses \u00e9taient prises en main par le porte-parole de la Commission des \u00c9lections, Farid Ayar, qui parlait d&rsquo;une estimation autour de 8 millions d&rsquo;\u00e9lecteurs, soit autour de 60%: \u00ab <em>Turnout figures recently announced represent the enormous and understandable enthusiasm felt in the field on this historic day. However, these figures are only very rough,word-of-mouth estimates gathered informally from the field. It will take some time for the Independent Electoral Commission of Iraq to issue accurate figures on turnout.<\/em> \u00bb<\/p>\n<\/p>\n<p><p>\t\u00a0Apparition du chiffre de 57%, qui semble avoir \u00e9t\u00e9 la pr\u00e9diction de la participation, mais ici pour \u00eatre \u00e9cart\u00e9e; apparition \u00e9galement du concept nouveau pour une \u00e9lection d\u00e9mocratique en g\u00e9n\u00e9ral de <em>anecdotal information<\/em>. Voici ce que nous dit Sally Buzbee, de AP, dans une d\u00e9p\u00eache dat\u00e9e du <a href=\"http:\/\/story.news.yahoo.com\/news?tmpl=story2&#038;u=\/ap\/20050131\/ap_on_re_mi_ea\/iraq_the_vote\" class=\"gen\">31 janvier 2005<\/a> au matin (la rh\u00e9torique de l&rsquo;h\u00e9ro\u00efsme d\u00e9mocratique reste fortement pr\u00e9sente):<\/p>\n<\/p>\n<p><p>\t\u00ab <em>Iraqis embraced democracy in large numbers Sunday, standing in long lines to vote in defiance of mortar attacks, suicide bombers and boycott calls. Pushed in wheelchairs or carts if they couldn&rsquo;t walk, the elderly, the young and women in veils cast ballots in Iraq&rsquo;s first free election in a half-century.<\/em><\/p>\n<\/p>\n<p><p>\t\u00bb <em>The electoral commission said it believed, based on that anecdotal information, that turnout among the estimated 14 million eligible Iraqi voters appeared higher than the 57 percent that had been predicted, although it would be some time before any precise turnout figure was confirmed.<\/em> \u00bb<\/p>\n<\/p>\n<p><p>\t\u00a0En m\u00eame temps (le 31 au matin), le <em>Guardian<\/em> de Londres met en ligne son \u00e9dition du jour (31 janvier) en affichant le chiffre de 57% pour la participation. On retrouve ce chiffre dans <a href=\"http:\/\/www.guardian.co.uk\/Iraq\/Story\/0,2763,1402260,00.html\" class=\"gen\">le texte de l&rsquo;envoy\u00e9 sp\u00e9cial du journal \u00e0 Bagdad, Rory Mac Carthy<\/a>, \u00e9galement dat\u00e9 du 31 janvier. Rh\u00e9torique h\u00e9ro\u00efque toujours d&rsquo;actualit\u00e9. \u00ab <em>Millions of Iraqis defied a surge of bombings and suicide attacks yesterday to go to the polls in greater than expected numbers for the first democratic elections for 50 years. The electoral commission&rsquo;s provisional estimate of turnout was 57%.<\/em> \u00bb.<\/p>\n<\/p>\n<p><p>\t\u00a0Pour terminer cette revue s\u00e9lective du lendemain matin de l&rsquo;\u00e9lection, <a href=\"http:\/\/english.aljazeera.net\/NR\/exeres\/94682ECB-4904-4CE1-94A4-BFBE41ADE2C8.htm\" class=\"gen\">citons Aljazeera.com du 31 janvier, \u00e0 09H30<\/a>, qui s&rsquo;est enquis de la situation \u00e0 Bagdad, o\u00f9 des quartiers nous \u00e9taient d\u00e9crits comme ayant vot\u00e9 \u00e0 95%.<\/p>\n<\/p>\n<p><p>\t\u00ab <em>Election reports from Baghdad have indicated that turnout was particularly low in the capital and come as Iraq&rsquo;s election commission backtracks on a statement that 72% of registered voters countrywide cast their ballots.<\/em><\/p>\n<\/p>\n<p><p>\t\u00bb <em>Iraqi journalist Ziyad al-Samarrai told Aljazeera on Monday that voter turnout in Baghdad was poor, especially in the al-Yarmuk, al-Amiriya, and al-Adhamiya districts &#8211; the main population centres in central and western Baghdad.<\/em> \u00bb<\/p>\n<\/p>\n<p><p>\t\u00a0Ajoutons, comme <em>anecdotal information<\/em>, que, dans la journ\u00e9e du 31, la tendance semblait remonter. A 17H00, un journaliste de la RTHB d\u00e9j\u00e0 cit\u00e9e pouvait annoncer, avec une certaine jubilation contenue, que \u00ab <em>La Commission \u00e9lectorale estime que la participation \u00e9lectorale se situe entre 60 et 75%<\/em> \u00bb. Adel al-Lami retrouvait un peu de cr\u00e9dit. <\/p>\n<h3>Installation d&rsquo;une r\u00e9alit\u00e9 virtualiste<\/h3>\n<\/p>\n<p><p>\tDans un pays si malheureux, martyris\u00e9, soumis \u00e0 tant d&rsquo;agressions et de mauvais coups, on comprend que l&rsquo;attente soit grande d&rsquo;une accalmie, d&rsquo;une am\u00e9lioration, et acceptable l&rsquo;id\u00e9e qu&rsquo;une \u00e9lection r\u00e9ussie en soit la voie, voire m\u00eame qu&rsquo;une \u00e9lection un peu r\u00e9ussie et qui reste tr\u00e8s douteuse est d\u00e9j\u00e0 une excellente chose. Mais dans le cas qui nous attache aujourd&rsquo;hui et qui concerne notre attitude, \u00e0 nous Occidentaux, on a l&rsquo;impression que l&rsquo;attente si grande dont nous parlons est moins que l&rsquo;Irak retrouve l&rsquo;apaisement, et plus que l&rsquo;Irak nous donne \u00ab <em>une le\u00e7on de d\u00e9mocratie<\/em> \u00bb,  c&rsquo;est-\u00e0-dire, au bout du compte, que l&rsquo;Irak nous apporte la confirmation que la d\u00e9mocratie est ce r\u00e9gime id\u00e9al, cette recette mirifique que nous avons bien raison d&rsquo;imposer au monde entier, par la mani\u00e8re forte si n\u00e9cessaire. Notre appr\u00e9ciation est par cons\u00e9quent \u00e0 la mesure de cette attente, et elle pr\u00e9c\u00e8de m\u00eame l&rsquo;\u00e9v\u00e9nement dans les consciences aux limites de l&rsquo;inconscient: le 30 janvier <strong>doit<\/strong> \u00eatre un triomphe, les Irakiens <strong>doivent<\/strong> voter massivement, ils <strong>doivent<\/strong> donner une le\u00e7on de d\u00e9mocratie, ils <strong>doivent<\/strong> d\u00e9fier la menace terroriste et en triompher, etc.<\/p>\n<\/p>\n<p><p>\tNotre impression est que nous f\u00fbmes, dans nos commentaires et nos sentiments divers, les premiers int\u00e9ress\u00e9s \u00e0 voir nos suggestions pressantes, nos conceptions ambitieuses, etc., s&rsquo;imposer dans ce pays. La chose qui nous passionne avant tout, c&rsquo;est de voir que la d\u00e9mocratie \u00e7a marche (m\u00eame chez les Irakiens, si l&rsquo;on ose dire).<\/p>\n<\/p>\n<p><p>\tApr\u00e8s tout, pourquoi pas dit le r\u00e9aliste ou celui qui se veut tel,  si \u00e7a marche? Mais cela marche-t-il? Nous ferions bien d&rsquo;attendre quelques semaines pour en avoir le cur net. Nous ne l&rsquo;avons pas fait. C&rsquo;est l\u00e0 o\u00f9 notre attente extr\u00eame, notre besoin de voir notre vertu confirm\u00e9e par le reste du monde, comme si notre vertu \u00e9tait d\u00e9faillante, se trouve en contradiction avec l&rsquo;application de la d\u00e9mocratie en Irak et ses effets. Nous ne pouvons pas nous permettre de prendre le risque de remettre le sort de notre vertu au gr\u00e9 de la r\u00e9alit\u00e9. C&rsquo;est l\u00e0 o\u00f9 nous proposons l&rsquo;identification d&rsquo;un second ph\u00e9nom\u00e8ne, qui compl\u00e8te le premier.<\/p>\n<\/p>\n<p><p>\tL&rsquo;interpr\u00e9tation de ces \u00e9lections s&rsquo;est d\u00e9velopp\u00e9e d&rsquo;une fa\u00e7on parfaitement virtualiste, selon la d\u00e9finition que nous proposons de ce concept. L&rsquo;on voit bien notre id\u00e9e qu&rsquo;il ne s&rsquo;agit ni de propagande \u00e0 proprement parler, ni de censure, ni de manipulations, ni de mensonges, m\u00eame si l&rsquo;une ou l&rsquo;autre de ces activit\u00e9s peut \u00eatre utilis\u00e9e comme moyen \u00e0 un moment ou l&rsquo;autre, et parfois fort souvent. Fondamentalement, la d\u00e9marche est virtualiste. Une phrase le montre. Lorsque la Commission veut expliquer l&rsquo;affirmation risqu\u00e9e de Adel al-Lami (72% de votants), elle d\u00e9clare: \u00ab <MI>: \u00ab <em>Turnout figures recently announced represent the enormous and understandable enthusiasm felt in the field on this historic day.<\/em> \u00bb Cela veut dire que ce jour est d\u00e9clar\u00e9 historique par avance et quoi qu&rsquo;il en soit, que l&rsquo;enthousiasme est grand par cons\u00e9quent, ce qui conduit \u00e0 des exag\u00e9rations et \u00e0 des interpr\u00e9tations enfi\u00e9vr\u00e9es. Dans ce cas, on comprend que la r\u00e9alit\u00e9 devrait \u00eatre conforme \u00e0 ces sensations et \u00e0 ces comportements ; d&rsquo;o\u00f9 la tentation d&rsquo;en appeler aux chiffres, ces faits objectifs, pour justifier toutes ces agitations ; et d&rsquo;annoncer qu&rsquo;il y a 72% de votants, pour que les faits qui forment une r\u00e9alit\u00e9 confirment la r\u00e9alit\u00e9 virtualiste Mais d&rsquo;ailleurs, est-ce si faux? On h\u00e9sitait encore au soir du 31 janvier et on h\u00e9sitera encore quelques jours.<\/p>\n<\/p>\n<p><p>\tLe virtualisme consiste d\u00e9sormais en une mobilisation de la perception de chacun  essentiellement par les pressions diverses et collectives qui sont port\u00e9es par les r\u00e9seaux de communication et anim\u00e9es par le conformisme g\u00e9n\u00e9ral. Ces pressions s&rsquo;exercent bien plus sur les psychologies que sur les donn\u00e9es de la connaissance, et elles sont bien s\u00fbr au service d&rsquo;une cause grandiose: une r\u00e9alit\u00e9 id\u00e9ale (celle du triomphe de la d\u00e9mocratie, qui est notre vertu supr\u00eame). Apr\u00e8s cette mise en place initiale, toujours tr\u00e8s rapide, comme la communication de nos jours, pr\u00e9c\u00e9dant m\u00eame souvent l&rsquo;\u00e9v\u00e9nement,  les faits de la vraie r\u00e9alit\u00e9 surviennent et se bousculent. Il s&rsquo;agit, comme on dit, de les g\u00e9rer. On comprend, sans stupidement devoir parler de mensonges ou de propagandes, que naissent la tentation, puis bient\u00f4t l&rsquo;obligation d&rsquo;adapter les faits de la r\u00e9alit\u00e9 courantes \u00e0 cette r\u00e9alit\u00e9 nouvelle.<\/p>\n<\/p>\n<p><p>\tVoil\u00e0 les donn\u00e9es de base. Maintenant il faut r\u00e9fl\u00e9chir: quels r\u00e9sultats correspondraient les mieux \u00e0 la nouvelle r\u00e9alit\u00e9 virtualiste, dont GW Bush est si satisfait? En r\u00e9alit\u00e9 (!), d&rsquo;ici dix jours les chiffres auront beaucoup moins d&rsquo;importance. En fait (!), l&rsquo;affaire est close. L&rsquo;\u00e9v\u00e9nement virtualiste est entr\u00e9 dans notre courte m\u00e9moire virtualiste (\u00ab <em>Iraq election declared success<\/em> \u00bb) et notre courte m\u00e9moire virtualiste qui ne s&rsquo;arrange que de l&rsquo;\u00e9v\u00e9nement imm\u00e9diat n&rsquo;en voudra aucun autre. La r\u00e9alit\u00e9 virtualiste est, pour nous, install\u00e9e.<\/p>\n<\/p>\n<p><p>\tIl n&rsquo;est pas du tout assur\u00e9 que la r\u00e9alit\u00e9 (la vraie) en soit impressionn\u00e9e jusqu&rsquo;\u00e0 changer son cours des choses pour nous convenir. On verra.<\/p>\n<\/p>\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Les \u00e9lections irakiennes comme \u00e9v\u00e9nement virtualiste Faut-il s&rsquo;attarder aux chiffres? demandons-nous par ailleurs. Pas vraiment n\u00e9cessaire, c&rsquo;est-\u00e0-dire qu&rsquo;il est pr\u00e9f\u00e9rable de ne chercher une pr\u00e9cision qui, par ailleurs, semble pour l&rsquo;instant bien insaisissable. Par ailleurs, c&rsquo;est sur cette pr\u00e9cision insaisissable que les commentaires se sont appuy\u00e9s d\u00e8s dimanche apr\u00e8s-midi pour d\u00e9crire l&rsquo;\u00e9lection en Irak comme&hellip;&nbsp;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","footnotes":"","jetpack_post_was_ever_published":false},"categories":[3],"tags":[4428,4141,857,4321,610],"class_list":["post-66217","post","type-post","status-publish","format-standard","hentry","category-analyse","tag-bbc-news","tag-elections","tag-irak","tag-narrative","tag-virtualisme"],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/66217","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/comments?post=66217"}],"version-history":[{"count":0,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/66217\/revisions"}],"wp:attachment":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/media?parent=66217"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/categories?post=66217"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/tags?post=66217"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}