{"id":66225,"date":"2005-02-08T00:00:00","date_gmt":"2005-02-08T00:00:00","guid":{"rendered":"https:\/\/new.dedefensa.org\/index.php\/2005\/02\/08\/tsunami-au-moyen-orient\/"},"modified":"2005-02-08T00:00:00","modified_gmt":"2005-02-08T00:00:00","slug":"tsunami-au-moyen-orient","status":"publish","type":"post","link":"https:\/\/new.dedefensa.org\/index.php\/2005\/02\/08\/tsunami-au-moyen-orient\/","title":{"rendered":"<strong><em>Tsunami au Moyen-Orient<\/em><\/strong>"},"content":{"rendered":"<p><h2 class=\"common-article\"><em>Tsunami<\/em> au Moyen-Orient<\/h2>\n<\/p>\n<p><\/p>\n<p><p>\t8 f\u00e9vrier 2005  Les \u00e9v\u00e9nements se succ\u00e8dent, s&rsquo;accumulent au Moyen-Orient, pour changer la situation et la r\u00e9orienter d\u00e9cisivement. Il faut se garder de l&rsquo;appr\u00e9cier selon une vision d\u00e9terministe, ou lin\u00e9ariste, qui conviendrait aux partisans de la politique US. Entre autres choses, cela supposerait, grave erreur, qu&rsquo;il y a une politique US.<\/p>\n<\/p>\n<p><p>\tIl faut se garder de voir dans la succession g\u00e9n\u00e9rale des \u00e9v\u00e9nements une marche bienheureuse vers la paix d\u00e9mocratique et de concorde g\u00e9n\u00e9rale. Il est pr\u00e9f\u00e9rable de l&rsquo;appr\u00e9cier comme un d\u00e9placement g\u00e9n\u00e9ral, comme celui qu&rsquo;engendre le mouvement de plaques tectoniques, \u00e0 la suite du choc d\u00e9clencheur initial que fut l&rsquo;intervention US.  Il ne s&rsquo;agit pas de passer du r\u00e8glement r\u00e9alis\u00e9 de certains probl\u00e8mes pour poursuivre en nous pr\u00e9parant \u00e0 en r\u00e9gler d&rsquo;autres. Les probl\u00e8mes \u00e9voluent de fa\u00e7on importante dans cette fin de p\u00e9riode, \u00e0 peu pr\u00e8s depuis la mort d&rsquo;Arafat, mais ils subsistent. Tout cela nous conduit \u00e0 une nouvelle situation, un nouveau sch\u00e9ma.<\/p>\n<\/p>\n<p><p>\tQuatre \u00e9v\u00e9nements sont \u00e0 consid\u00e9rer.<\/p>\n<\/p>\n<p><p>\t&bull; Les \u00e9lections en Irak n&rsquo;ont rien r\u00e9gl\u00e9 fondamentalement du probl\u00e8me irakien mais elles l&rsquo;ont fait \u00e9videmment \u00e9voluer. En un sens, il s&rsquo;est sensiblement d\u00e9s-am\u00e9ricanis\u00e9 pour se r\u00e9gionaliser. Il n&rsquo;en reste pas moins un probl\u00e8me, un probl\u00e8me grave, et, peut-\u00eatre, un probl\u00e8me encore plus grave qu&rsquo;il n&rsquo;\u00e9tait. Les \u00e9l\u00e9ments suivants sont \u00e0 consid\u00e9rer : la majorit\u00e9 chiite est en train de prendre le pouvoir, qui sera fortement marqu\u00e9 par sa dimension religieuse ; la gu\u00e9rilla continue, plus forte que jamais, et reste un tr\u00e8s grave abc\u00e8s de fixation pour les forces US. Le paradoxe de cette s\u00e9quence est que cette \u00e9volution capitale n&rsquo;a nullement lib\u00e9r\u00e9 les Am\u00e9ricains de l&rsquo;hypoth\u00e8que militaire irakienne tout en installant un pouvoir dont la fid\u00e9lit\u00e9 aux Am\u00e9ricains est sujette \u00e0 tr\u00e8s forte caution.<\/p>\n<\/p>\n<p><p>\t&bull; Pour autant, Washington (insistons sur cette sp\u00e9cificit\u00e9 r\u00e9gionale et psychologique de la capitale des USA) a, lui, saut\u00e9 le pas. Washington, qui vit dans son monde virtuel, a proclam\u00e9 que le probl\u00e8me irakien \u00e9tait r\u00e9solu pour lui et compl\u00e8tement \u00e0 son avantage,  point final. Cette illusion psychologique est n\u00e9anmoins un fait politique, puisque nous vivons dans une \u00e9poque virtualiste o\u00f9 la repr\u00e9sentation p\u00e8se d&rsquo;un poids plus fort que la r\u00e9alit\u00e9 dans les prises de d\u00e9cision des directions qui y sont soumises. L&rsquo;illusion devient donc fait politique et, pour le tr\u00e8s, tr\u00e8s court terme (comme d&rsquo;habitude), dans le cas irakien, la combinaison arrange Washington. Par contre, lorsqu&rsquo;on en reviendra \u00e0 la r\u00e9alit\u00e9, elle pourrait r\u00e9server de bien vilaines surprises, notamment aux forces US en Irak parce que la r\u00e9bellion est plus que jamais active, mais aussi dans le domaine de la politique US \u00e0 cause de l&rsquo;\u00e9volution de la situation politique dans ce m\u00eame Irak. Les certitudes am\u00e9ricaines sur le contr\u00f4le qu&rsquo;ils se jugent capable d&rsquo;assurer sur l&rsquo;\u00e9volution du futur gouvernement chiite (il n&rsquo;y aura pas une nouvelle r\u00e9publique islamique, dit Cheney) font craindre le pire : les Am\u00e9ricains se trompent en g\u00e9n\u00e9ral compl\u00e8tement dans cette sorte d&rsquo;\u00e9valuation et leur assurance risque bien de d\u00e9tourner leur attention d&rsquo;une \u00e9volution effectivement religieuse, qui en serait alors grandement facilit\u00e9e.<\/p>\n<\/p>\n<p><p>\t&bull; Les perspectives de raccommodement entre Isra\u00ebl et les Palestiniens sont brusquement formidables. Elles montrent que l&rsquo;antagonisme depuis 4 ans \u00e9tait d&rsquo;abord une question d&rsquo;homme (la haine de l&rsquo;\u00e9quipe Sharon pour Arafat, l&rsquo;intransigeance d&rsquo;Arafat). En supposant que les choses aillent le mieux possible, nous aurons des  concerts de louange pour la b\u00e9n\u00e9diction de la paix, mais il y aura surtout, l\u00e0 aussi comme en Irak, ce ph\u00e9nom\u00e8ne d&rsquo;une re-r\u00e9gionalisation du probl\u00e8me isra\u00e9lo-palestinien : son intensit\u00e9 baissant notablement, la polarisation d&rsquo;une situation d&rsquo;affrontement le c\u00e9dera \u00e0 la complexit\u00e9 d&rsquo;une situation de n\u00e9gociations et d&rsquo;arrangement. Le principal aiguillon politique et une des principales justifications de la politique agressive de GW Bush au Moyen-Orient, et m\u00eame contre la terreur, auront tendance \u00e0 s&rsquo;estomper ; le soutien de la puissante communaut\u00e9 juive aura moins d&rsquo;alacrit\u00e9. Tout cela est essentiel parce qu&rsquo;il indique que la mobilisation maximale qui existait jusqu&rsquo;alors va tendre \u00e0 se diluer si l&rsquo;accord Isra\u00ebl-Palestiniens se concr\u00e9tise, alors que GW a plus que jamais besoin d&rsquo;une mobilisation g\u00e9n\u00e9rale,  pour le quatri\u00e8me point.<\/p>\n<\/p>\n<p><p>\t&bull; Le quatri\u00e8me point, c&rsquo;est l&rsquo;essentiel d\u00e9sormais : l&rsquo;Iran. Plus que jamais, l&rsquo;Iran est la crise \u00e0 venir. Les Am\u00e9ricains sont fermement embarqu\u00e9s dans ce qu&rsquo;ils nomment une <em>collision course<\/em> impliquant une frappe. L&rsquo;<em>establishment<\/em> washingtonien est bien plus uni sur cette question qu&rsquo;il n&rsquo;\u00e9tait sur l&rsquo;attaque contre l&rsquo;Irak, alors que le programme nucl\u00e9aire de l&rsquo;Iran est bien plus une r\u00e9alit\u00e9 pour tous que ne l&rsquo;\u00e9tait celui de l&rsquo;Irak. Ce m\u00eame <em>establishment<\/em> washingtonien suppose donc,  virtualisme pour virtualisme,  que le soutien \u00e0 Washington sera bien plus fort qu&rsquo;il a \u00e9t\u00e9 pour l&rsquo;Irak. De ce point de vue, l&rsquo;initiative des Europ\u00e9ens en faveur d&rsquo;une issue n\u00e9goci\u00e9e agace d&rsquo;autant plus. Peu d&rsquo;experts et de dirigeants US croient que les Europ\u00e9ens pourront r\u00e9sister longtemps aux pressions de Washington pour le soutien actif d&rsquo;une attaque. Ils se trompent notablement. D&rsquo;autre part, les Am\u00e9ricains pensent qu&rsquo;ils vont pouvoir obtenir d&rsquo;Isra\u00ebl la m\u00eame mobilisation de soutien que celle qu&rsquo;ils ont eue pour l&rsquo;Irak,  ce en quoi ils se trompent encore, parce que Isra\u00ebl devrait plut\u00f4t \u00eatre d\u00e9mobilis\u00e9 avec le rapprochement avec les Palestiniens, et parce qu&rsquo;Isra\u00ebl, contrairement \u00e0 ce proclament les Am\u00e9ricains, n&rsquo;a pas vraiment envie de frapper ou qu&rsquo;on frappe l&rsquo;Irak (les militaires isra\u00e9liens ne croient pas qu&rsquo;on puisse r\u00e9soudre le probl\u00e8me par une attaque). Les Am\u00e9ricains esp\u00e8rent \u00e9galement le soutien des Irakiens, qu&rsquo;ils jugent d\u00e9sormais acquis \u00e0 leur camp,  alors qu&rsquo;on comprend \u00e9videmment qu&rsquo;un pouvoir chiite pourrait bien \u00eatre conduit \u00e0 choisir le contraire (le soutien, plus ou moins discret \u00e0 l&rsquo;Iran).<\/p>\n<\/p>\n<p><p>\tLa situation actuelle est clairement interm\u00e9diaire entre deux \u00e9poques, celle qui se termine s&rsquo;\u00e9tant ouverte le 19 mars 2003 (ou, peut-\u00eatre, le 11 septembre 2001?). Celle qui s&rsquo;ouvre, qui sera essentiellement iranienne, sera encore plus incertaine et chaotique. <\/p>\n<\/p>\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Tsunami au Moyen-Orient 8 f\u00e9vrier 2005 Les \u00e9v\u00e9nements se succ\u00e8dent, s&rsquo;accumulent au Moyen-Orient, pour changer la situation et la r\u00e9orienter d\u00e9cisivement. Il faut se garder de l&rsquo;appr\u00e9cier selon une vision d\u00e9terministe, ou lin\u00e9ariste, qui conviendrait aux partisans de la politique US. Entre autres choses, cela supposerait, grave erreur, qu&rsquo;il y a une politique US. Il&hellip;&nbsp;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[],"class_list":["post-66225","post","type-post","status-publish","format-standard","hentry","category-faits-et-commentaires"],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/66225","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/comments?post=66225"}],"version-history":[{"count":0,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/66225\/revisions"}],"wp:attachment":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/media?parent=66225"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/categories?post=66225"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/tags?post=66225"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}