{"id":66239,"date":"2005-02-24T00:00:00","date_gmt":"2005-02-24T00:00:00","guid":{"rendered":"https:\/\/new.dedefensa.org\/index.php\/2005\/02\/24\/bae-veut-laccord-de-washington-autant-que-celui-de-londres-pour-vendre-des-armes-a-la-chine\/"},"modified":"2005-02-24T00:00:00","modified_gmt":"2005-02-24T00:00:00","slug":"bae-veut-laccord-de-washington-autant-que-celui-de-londres-pour-vendre-des-armes-a-la-chine","status":"publish","type":"post","link":"https:\/\/new.dedefensa.org\/index.php\/2005\/02\/24\/bae-veut-laccord-de-washington-autant-que-celui-de-londres-pour-vendre-des-armes-a-la-chine\/","title":{"rendered":"<strong><em>BAE veut l&rsquo;accord de Washington autant que celui de Londres pour vendre des armes \u00e0 la Chine<\/em><\/strong>"},"content":{"rendered":"<p><h2 class=\"common-article\">BAE veut l&rsquo;accord de Washington autant que celui de Londres pour vendre des armes \u00e0 la Chine<\/h2>\n<\/p>\n<p><\/p>\n<p><p>\t24 f\u00e9vrier 2005  La journ\u00e9e du 22 f\u00e9vrier 2005 \u00e0 Bruxelles nous a indiqu\u00e9 de fa\u00e7on extr\u00eamement marqu\u00e9e que la question de la lev\u00e9e de l&#8217;embargo des armes europ\u00e9ennes vers la Chine est d\u00e9sormais centrale au d\u00e9bat,  \u00e0 l&rsquo;affrontement ?  transatlantique. Cette question a domin\u00e9 les entretiens de GW Bush avec les dirigeants de l&rsquo;UE, dans l&rsquo;apr\u00e8s-midi du 23. Bush a clairement laiss\u00e9 entendre que l&rsquo;UE devrait affronter le Congr\u00e8s pour des sanctions in\u00e9vitables si l&#8217;embargo \u00e9tait lev\u00e9. Le pr\u00e9sident US a ainsi montr\u00e9 qu&rsquo;il consid\u00e9rait que le Congr\u00e8s occupait, par rapport \u00e0 sa propre position, une position radicalis\u00e9e.<\/p>\n<\/p>\n<p><p>\tL&rsquo;attention am\u00e9ricaine sur cette question s&rsquo;est r\u00e9v\u00e9l\u00e9e tardivement, mais elle a tr\u00e8s vite acquis une intensit\u00e9 sans pr\u00e9c\u00e9dent en m\u00eame temps qu&rsquo;elle \u00e9largissait radicalement le champ de la querelle. Pour les Am\u00e9ricains, les Europ\u00e9ens mettent en cause les relations strat\u00e9giques avec les USA en voulant \u00e9tablir des relations strat\u00e9giques fondamentales avec la Chine. Les Europ\u00e9ens ont une r\u00e9action tr\u00e8s vive devant les attaques am\u00e9ricaines, ce qui mesure les diff\u00e9rences d&rsquo;approche en m\u00eame temps que l&rsquo;activisme am\u00e9ricain (le journaliste <a href=\"http:\/\/atimes.com\/atimes\/Front_Page\/GB24Aa01.html\" class=\"gen\">Pepe Escobar, de Atimes.com<\/a>, rapporte \u00e0 ce sujet: \u00ab <em>EU diplomats are unanimous in stressing that the Americans are leading a disinformation campaign because Israel sells more weapons to China than anyone else<\/em> \u00bb).<\/p>\n<\/p>\n<p><p>\tUn fait important est que cette crise vient de prendre une dimension pratique inattendue, mesurant \u00e0 la fois ses ambigu\u00eft\u00e9s et sa gravit\u00e9. Il s&rsquo;agit d&rsquo;affirmations officieuses et d&rsquo;une prise de position officielle du groupe britannique BAE,  en principe int\u00e9ress\u00e9 au premier chef dans cette affaire puisqu&rsquo;il est le principal producteur de syst\u00e8mes d&rsquo;armes britannique. La chronologie de cette d\u00e9cision est elle-m\u00eame int\u00e9ressante: elle confirme l&rsquo;intensit\u00e9 grandissante de cette crise et, surtout, mesure l&rsquo;intensit\u00e9 radicale de la position am\u00e9ricaine.<\/p>\n<\/p>\n<p><p>\tD&rsquo;abord, <a href=\"http:\/\/www.timesonline.co.uk\/\" class=\"gen\">le Times de Londres du 22 f\u00e9vrier<\/a> indique que \u00ab <em>Britain&rsquo;s largest defence company, BAE Systems, will not sell arms to China if the European Union lifts its arms embargo, for fear of jeopardising its extensive American interests. <\/em>[&#8230;] <em>The suggestion by BAE Systems that it would prefer to protect its huge US investments rather than pursue new markets in China suggests that the American threats are biting. BAE Systems has greater potential to sell arms to China than any other British company, but senior sources said that there was no question of taking any action that might imperil the company&rsquo;s relationship with America.<\/em> \u00bb<\/p>\n<\/p>\n<p><p>\tLe lendemain, soit le 23 f\u00e9vrier, <a href=\"http:\/\/business.scotsman.com\/topics.cfm?tid=341&#038;id=202272005&#038;20050223124018\" class=\"gen\">Le quotidien Scotsman<\/a> d\u00e9taille une prise de position officielle de BAE, qui est actuellement le 12\u00e8me fournisseur du Pentagone. Cette prise de position nuance l&rsquo;information du <em>Times<\/em>, d&rsquo;un point de vue formel dans tous les cas, et selon l&rsquo;interpr\u00e9tation que donne le journal (\u00ab <em>Britain&rsquo;s biggest defence contractor BAE Systems said yesterday it would need backing from Washington and London before joining a European push to lift an arms embargo on China.<\/em> \u00bb). Sur le fond, bien entendu, l&rsquo;annonce de BAE revient au m\u00eame r\u00e9sultat que ce qu&rsquo;annonce le <em>Times<\/em>.<\/p>\n<\/p>\n<p><\/p>\n<p><p>\t\u00ab <em>A spokesman for BAE said: All licensing is a matter for the UK government and not for BAE Systems. Individual countries could have different responses <\/em>[if embargo is lifted]<em>. He added that each arms deal would have to be licensed by the country concerned.<\/em><\/p>\n<\/p>\n<p><p>\t\u00bb <em>The spokesman added: As a company we are of course concerned about the impact of these measures on the US. We very much hope the British government does everything it can to ensure the US government feels that we are supportive of their point of view.<\/em> \u00bb<\/p>\n<\/p>\n<p><\/p>\n<p><p>\tIl s&rsquo;agit d&rsquo;un cas extraordinaire si l&rsquo;on s&rsquo;en tient \u00e0 l&rsquo;estimation officielle et \u00e0 la croyance g\u00e9n\u00e9rale que BAE, anciennement British Aerospace, est \u00e9videmment une soci\u00e9t\u00e9 britannique, productrice d&rsquo;un bien strat\u00e9gique par excellence, et d&rsquo;un bien qui, par le biais des technologies d\u00e9velopp\u00e9es et utilis\u00e9es, constitue un des composants modernes essentiels de la souverainet\u00e9. Cette m\u00eame soci\u00e9t\u00e9 BAE annonce que, sur cette question vitale de la vente d&rsquo;armes \u00e0 la Chine, elle se place volontairement sous la d\u00e9pendance des d\u00e9cisions d&rsquo;autorisation de Londres et de Washington. Peu importe les arguments d\u00e9velopp\u00e9s par BAE, qui ont leur valeur, le fait essentiel est que BAE s&rsquo;estime d\u00e9pendre, pour une d\u00e9cision de cette importance, autant de Washington que de Londres (et certains interrogeraient: plus de Washington que de Londres?). Il s&rsquo;agit \u00e9videmment d&rsquo;un cas de souverainet\u00e9 partag\u00e9e, produit  \u00e9vident de la politique de Tony Blair, o\u00f9 l&rsquo;Angleterre perd ce qui fait la substance d&rsquo;une nation (car la souverainet\u00e9 ainsi partag\u00e9e, \u00e9videmment, est au d\u00e9part exclusivement britannique).<\/p>\n<\/p>\n<p><p>\tDans la pratique, plus encore qu&rsquo;une souverainet\u00e9 partag\u00e9e, il s&rsquo;agit bel et bien, <em>de facto<\/em>, d&rsquo;une remise compl\u00e8te de la souverainet\u00e9 dont d\u00e9pend BAE dans les mains de Washington. En effet, la position de Londres est connue dans cette affaire, puisque le gouvernement britannique est partisan de la lev\u00e9e de l&#8217;embargo: son autorisation, son soutien \u00e0 BAE dans ce cas est une forme de style; tout est mis dans les mains de Washington, \u00e0 qui est donn\u00e9 un droit de veto et dont on peut \u00eatre s\u00fbr qu&rsquo;il en usera et abusera. Bien entendu, la seule fa\u00e7on de r\u00e9soudre ce probl\u00e8me est de r\u00e9pondre \u00e0 la fameuse question <a href=\"http:\/\/www.dedefensa.org\/article.php?art_id=557\" class=\"gen\">\u00e9voqu\u00e9e depuis deux ans<\/a>, et d&rsquo;y r\u00e9pondre par la n\u00e9gative: non, BAE n&rsquo;est plus britannique.<\/p>\n<\/p>\n<p><p>\tL&rsquo;on voit que cette affaire des armes europ\u00e9ennes pour la Chine est porteuse de tous les cas possibles de d\u00e9stabilisation pour les rapports transatlantiques, alors qu&rsquo;elle constituait au d\u00e9part une d\u00e9marche anodine. D&rsquo;ores et d\u00e9j\u00e0, la crise de l&#8217;embargo peut \u00eatre illustr\u00e9e par trois remarques.<\/p>\n<\/p>\n<p><p>\t&bull; Elle va compl\u00e8tement exacerber les difficult\u00e9s et les contradictions du Royaume-Uni, avec la politique de Blair \u00e0 la fois europ\u00e9enne et pro-am\u00e9ricaine. L&rsquo;\u00e9volution de BAE ces derni\u00e8res ann\u00e9es est une application pratique \u00e9vidente de cette politique de Blair (y compris au niveau de sa substance m\u00eame, avec son \u00e9volution vers l&rsquo;actionnariat priv\u00e9 et la d\u00e9pendance grandissante de cet actionnariat pour sa politique, avec la recherche de rapports imm\u00e9diats et le sacrifice d&rsquo;une strat\u00e9gie \u00e0 long terme). Le cas BAE montre la situation de blocage o\u00f9 conduit la politique britannique, avec les affrontements qui en d\u00e9coulent.<\/p>\n<\/p>\n<p><p>\t&bull; La crise de l&#8217;embargo va interf\u00e9rer massivement dans les affaires industrielles transatlantiques, aussi bien du point de vue de la coop\u00e9ration et des transferts de technologies que du point de vue des structures industrielles. La pr\u00e9sence du Congr\u00e8s dans cette affaire va renforcer encore cette tendance (le Congr\u00e8s a un tr\u00e8s grand pouvoir d&rsquo;action, quasiment autonome et discr\u00e9tionnaire, dans les questions industrielles, de coop\u00e9ration, de transfert de technologies). Quelques programmes en cours vont \u00eatre secou\u00e9s, notamment le JSF.<\/p>\n<\/p>\n<p><p>\t&bull; L&rsquo;industrie am\u00e9ricaine va saisir ce biais pour tenter d&rsquo;attaquer l&rsquo;industrie europ\u00e9enne, soit en cherchant la limitation de l&rsquo;action de cette industrie europ\u00e9enne par un interventionnisme US qui mettra en cause le principe de souverainet\u00e9 (le cas de BAE \u00e9tendu \u00e0 d&rsquo;autres domaines), soit en bloquant toute tentative de p\u00e9n\u00e9tration du march\u00e9 US (cas de EADS cherchant \u00e0 figurer comme fournisseur du Pentagone pour un grand contrat d&rsquo;avions ravitailleurs en vol), soit en remettant en cause le statut et les conditions de certains programmes de coop\u00e9ration (cas du JSF), soit en tentant de susciter des regroupements et des achats de soci\u00e9t\u00e9s europ\u00e9ennes. <\/p>\n<\/p>\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>BAE veut l&rsquo;accord de Washington autant que celui de Londres pour vendre des armes \u00e0 la Chine 24 f\u00e9vrier 2005 La journ\u00e9e du 22 f\u00e9vrier 2005 \u00e0 Bruxelles nous a indiqu\u00e9 de fa\u00e7on extr\u00eamement marqu\u00e9e que la question de la lev\u00e9e de l&#8217;embargo des armes europ\u00e9ennes vers la Chine est d\u00e9sormais centrale au d\u00e9bat, \u00e0&hellip;&nbsp;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[],"class_list":["post-66239","post","type-post","status-publish","format-standard","hentry","category-faits-et-commentaires"],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/66239","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/comments?post=66239"}],"version-history":[{"count":0,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/66239\/revisions"}],"wp:attachment":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/media?parent=66239"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/categories?post=66239"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/tags?post=66239"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}