{"id":66240,"date":"2005-02-25T00:00:00","date_gmt":"2005-02-25T00:00:00","guid":{"rendered":"https:\/\/new.dedefensa.org\/index.php\/2005\/02\/25\/poutine-biden-et-les-autres-face-au-programme-du-20-janvier\/"},"modified":"2005-02-25T00:00:00","modified_gmt":"2005-02-25T00:00:00","slug":"poutine-biden-et-les-autres-face-au-programme-du-20-janvier","status":"publish","type":"post","link":"https:\/\/new.dedefensa.org\/index.php\/2005\/02\/25\/poutine-biden-et-les-autres-face-au-programme-du-20-janvier\/","title":{"rendered":"<strong><em>Poutine, Biden et les autres face au programme du 20 janvier<\/em><\/strong>"},"content":{"rendered":"<p><h2 class=\"common-article\">Poutine, Biden et les autres face au programme du 20 janvier<\/h2>\n<\/p>\n<p><\/p>\n<p><p>\t25 f\u00e9vrier 2005  On disait d\u00e9j\u00e0 que le plus remarquable dans le discours de GW, le 21 \u00e0 Bruxelles, avait \u00e9t\u00e9 <a href=\"http:\/\/www.iht.com\/articles\/2005\/02\/21\/news\/bush.html\" class=\"gen\">l&rsquo;attaque contre la Russie<\/a>. Ce durcissement, \u00e9videmment fleuri de l&rsquo;in\u00e9vitable rh\u00e9torique d\u00e9mocratique qui est aujourd&rsquo;hui le bagage intellectuel essentiel de la politique US, se confirma largement hier, lors de la rencontre avec Poutine, lorsque ce dernier dut subir une ennuyeuse le\u00e7on de d\u00e9mocratie. (Comme on le comprend, le climat en fut nettement rafra\u00eechi et <a href=\"http:\/\/news.independent.co.uk\/europe\/story.jsp?story=614535\" class=\"gen\">les mines devinrent plut\u00f4t sombres.<\/a>)<\/p>\n<\/p>\n<p><p>\tPourquoi ce durcissement vis-\u00e0-vis des Russes, d\u00e8s le 21 alors que GW rencontrait Poutine le 24, durcissement confirm\u00e9 le 24, alors que GW aurait eu au contraire int\u00e9r\u00eat \u00e0 s&rsquo;entendre avec Poutine pour diff\u00e9rentes raisons, ne serait-ce que contribuer \u00e0 la tentative de contrecarrer une toujours possible recherche d&rsquo;une entente entre la Russie et l&rsquo;UE, ou pour freiner une aide russe \u00e0 la Syrie et \u00e0 l&rsquo;Iran?  Plut\u00f4t qu&rsquo;une r\u00e9ponse appropri\u00e9e, sophistiqu\u00e9e, compliqu\u00e9e et qui ne r\u00e9pond \u00e0 rien, nous devrions m\u00e9diter ce mot du s\u00e9nateur Biden, d\u00e9mocrate du Delaware et sp\u00e9cialiste des affaires \u00e9trang\u00e8res, lanc\u00e9 \u00e0 Condoleeza Rice lors d&rsquo;une \u00e9mission t\u00e9l\u00e9vis\u00e9e le 13 f\u00e9vrier: \u00ab <em>I don&rsquo;t understand our policy. I&rsquo;m not being facetious. I don&rsquo;t understand the policy<\/em> \u00bb <\/p>\n<\/p>\n<p><p>\tConfidence pour confidence: ne craignez rien, s\u00e9nateur Biden, il n&rsquo;y a rien, rigoureusement rien \u00e0 comprendre \u00e0 la politique de l&rsquo;administration GW. C&rsquo;est une bouillie de chat au go\u00fbt enivrant, qui enchante ceux qui con\u00e7oivent la politique comme un exercice pratique m\u00ealant les contradictions vaniteuses de l&rsquo;utopie \u00e9lev\u00e9es en vertus politiques et le m\u00e9pris jusqu&rsquo;\u00e0 l&rsquo;ex\u00e9cration inconsciente de la responsabilit\u00e9 et de la logique dans la politique. C&rsquo;est une application du fameux <em>a fire in the mind<\/em> que son <em>speechwriter<\/em> a \u00e9t\u00e9 chercher chez Dosto\u00efevski (\u00ab <em>Nous avons allum\u00e9 un incendie dans les esprits des hommes. L&rsquo;incendie est dans les esprits non sur les toits des maisons<\/em> \u00bb) pour le mettre dans <LIEN=http:\/\/www.dedefensa.org\/article.php?art_id=1351>le discours d&rsquo;inauguration de GW, le 20 janvier (\u00ab <em>Par nos efforts nous avons allum\u00e9 un incendie dans les esprits des hommes. Il r\u00e9chauffe ceux qui sentent sa puissance ; il br\u00fble ceux qui combattent son progr\u00e8s. Et un jour ce feu indompt\u00e9 de la libert\u00e9 atteindra les coins les plus obscurs de notre monde<\/em> \u00bb). Il est largement \u00e9vident que GW <a href=\"http:\/\/www.amconmag.com\/2005_02_28\/article.html\" class=\"gen\">s&rsquo;est ainsi trouv\u00e9 lui-m\u00eame<\/a> et qu&rsquo;il ne variera plus d&rsquo;un <em>kopec<\/em> de cette ligne politique; bien entendu, l&rsquo;incendie est dans sa propre t\u00eate et \u00e9ventuellement celle de ses inspirateurs, bien plus que dans la t\u00eate des autres.<\/p>\n<\/p>\n<p><p>\t(Assez curieusement, et m\u00eame malicieusement quand on sait l&rsquo;estime o\u00f9 les durs de l&rsquo;\u00e9quipe GW tiennent l&rsquo;ancien pr\u00e9sident d\u00e9mocrate, la politique GW appara\u00eet de plus en plus, notamment \u00e0 la lumi\u00e8re de la rencontre avec Poutine, comme un recyclage pour notre \u00e9poque, en beaucoup plus militariste et agressif, de la politique humanitariste de Jimmy Carter. En 1977, dans un des actes majeurs de cette politique, Carter recevait le dissident Soljenitsyne,  au grand dam de son conseiller \u00e0 la s\u00e9curit\u00e9 nationale Zbigniew Brzezinski  pour faire indirectement la le\u00e7on \u00e0 son partenaire en n\u00e9gociations strat\u00e9giques Leonid Brejnev, enferm\u00e9 dans son Kremlin sans espoir, perclus d&rsquo;angoisses devant l&rsquo;activisme lib\u00e9rateur de la Maison-Blanche. Dans le m\u00eame registre, Carter soutenait le Shah d&rsquo;Iran tout en faisant des discours o\u00f9 il lui reprochait avec v\u00e9h\u00e9mence son peu d&#8217;empressement pour le respect des droits de l&rsquo;homme (on conna\u00eet la suite). Dans tous les cas, la seule r\u00e9f\u00e9rence qu&rsquo;\u00e9voquait Carter \u00e9tait la vertu am\u00e9ricaniste, l&rsquo;image  grandiose de l&rsquo;Am\u00e9rique. Cela lui valut une sorte de brouille avec Soljenitsyne lorsque, venu \u00e9couter <a href=\"http:\/\/www.dedefensa.org\/article.php?art_id=770\" class=\"gen\">le discours d&rsquo;Harvard<\/a> du grand \u00e9crivain russe, le 8 juin 1978, Carter eut la douloureuse surprise d&rsquo;entendre, \u00e0 c\u00f4t\u00e9 de la d\u00e9nonciation normale du communisme, un impitoyable proc\u00e8s de l&rsquo;illusion et de l&rsquo;inhumanit\u00e9 du syst\u00e8me lib\u00e9ral capitaliste.)<\/p>\n<\/p>\n<p><p>\tLa politique US n&rsquo;a plus (comme au temps de Carter) la prudence n\u00e9cessaire face \u00e0 la puissance apocalyptique de l&rsquo;URSS que l&rsquo;Am\u00e9rique avait elle-m\u00eame fard\u00e9e en menace agressive contre elle-m\u00eame parce qu&rsquo;il lui faut toujours un ennemi (aujourd&rsquo;hui, c&rsquo;est le terrorisme, image obtenue selon les m\u00eames moyens). Elle est devenue cette bouillie de chat o\u00f9 chacun met son petit ingr\u00e9dient qui est une incitation \u00e0 une agression de plus. GW recycle tout cela sans le moindre frein, sans y rien comprendre pour l&rsquo;existence r\u00e9elle et l&rsquo;effet sur le r\u00e9el, comme il a maintenant l&rsquo;habitude de faire. Pour GW, l&rsquo;essentiel de sa politique est et reste d&rsquo;enluminer chaque jour l&rsquo;image de la puissance vertueuse qui sert de r\u00e9alit\u00e9 virtualiste \u00e0 l&#8217;empire am\u00e9ricain. Un jour on attaque l&rsquo;Iran. Le lendemain, c&rsquo;est la Syrie. <em>In illo tempore<\/em>, on laissait entendre bien des horreurs \u00e0 propos des Fran\u00e7ais mais cette fois on embrasse Chirac. Deux jours apr\u00e8s, Poutine en prend pour son grade apr\u00e8s avoir \u00e9t\u00e9 c\u00e9l\u00e9br\u00e9. Pendant ce temps, la d\u00e9mocratie est proclam\u00e9e triomphante partout et l&rsquo;on nomme ministre de la Justice l&rsquo;homme qui a codifi\u00e9 l&#8217;emploi syst\u00e9matique de la torture, de Guantanamo \u00e0 l&rsquo;Irak. Peut-\u00eatre quelqu&rsquo;un se dit-il que cet \u00e9trange ballet doit d\u00e9router partenaires et adversaires. C&rsquo;est le cas mais c&rsquo;est par inadvertance bien plus que par maladresse et c&rsquo;est le signe du d\u00e9sordre bien plus que d&rsquo;un machiav\u00e9lisme rendu maladroit par le besoin de vertu. L&rsquo;essentiel est d&rsquo;appliquer le programme du 20 janvier, qui est vraiment le fondement de la pens\u00e9e-GW, l&rsquo;id\u00e9e ma\u00eetresse qui para\u00eet \u00eatre au pr\u00e9sident le moyen d&rsquo;acc\u00e9der \u00e0 sa place dans l&rsquo;Histoire, pour rester dans la m\u00e9moire des hommes,  tout cela pendant que Biden se lamente parce qu&rsquo;il n&rsquo;y comprend rien. <\/p>\n<\/p>\n<p><p>\tL&rsquo;\u00e9trange m\u00e9lange de simili-r\u00e9alisme virtualiste et de vertu morale belliciste qui constitue les ingr\u00e9dients de cette politique am\u00e9ricaine que le s\u00e9nateur Biden ne comprend pas, et qui existe finalement pour \u00e9viter justement de faire une politique r\u00e9elle, ce m\u00e9lange est l\u00e0 pour durer tout au long du mandat. Nous aurons GW le missionnaire-guerrier jusqu&rsquo;en 2009. L&rsquo;effet de sa politique se traduira par l&rsquo;incapacit\u00e9 pour l&rsquo;Am\u00e9rique de trouver des alli\u00e9s utiles, sinon loyaux, et par l&rsquo;ali\u00e9nation poursuivie et aggrav\u00e9e du reste du monde, y compris des trois grands blocs de puissance plus ou moins alternatifs actuels : l&rsquo;Europe, la Russie et la Chine. Quant \u00e0 la puissance am\u00e9ricaniste elle-m\u00eame, elle sera servie \u00e0 mesure par cet activisme : elle continuera de s&rsquo;ab\u00eemer dans le virtualisme d&rsquo;une image de puissance, correspondant parfaitement \u00e0 sa structure fondamentale <a href=\"http:\/\/www.dedefensa.org\/article.php?art_id=41\" class=\"gen\">d&#8217;empire de la communication<\/a>, et risquant de ce fait des accidents de rupture extr\u00eamement graves, acc\u00e9l\u00e9rant d\u00e9cisivement le d\u00e9clin am\u00e9ricain.<\/p>\n<\/p>\n<p><p>\t(On lira avec profit ces observations du site <a href=\"http:\/\/www.xymphora.blogspot.com\/<D\" class=\"gen\"> <\/p>\n<\/p>\n<p><p>\txymphora.com<\/a>, en date du 20 f\u00e9vrier, montrant que cette id\u00e9e d&#8217;empire de la communication, de virtualisme, etc., commence \u00e0 se r\u00e9pandre: \u00ab <em>The American empire is the first empire not to be built on military strength  the United States loses all the wars it fights  or on economic strength  its staggering economy is entirely dependent on the continued goodwill of its lenders  but on advertising its identity as an empire in the media. Since it is only an empire because people believe it to be an empire, its fall from power will be as sudden as the world realizing what a pile of bullshit the American empire really is.<\/em> \u00bb)<\/p>\n<\/p>\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Poutine, Biden et les autres face au programme du 20 janvier 25 f\u00e9vrier 2005 On disait d\u00e9j\u00e0 que le plus remarquable dans le discours de GW, le 21 \u00e0 Bruxelles, avait \u00e9t\u00e9 l&rsquo;attaque contre la Russie. Ce durcissement, \u00e9videmment fleuri de l&rsquo;in\u00e9vitable rh\u00e9torique d\u00e9mocratique qui est aujourd&rsquo;hui le bagage intellectuel essentiel de la politique US,&hellip;&nbsp;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[4461,3643,2825,4460,4033],"class_list":["post-66240","post","type-post","status-publish","format-standard","hentry","category-faits-et-commentaires","tag-brejnev","tag-carter","tag-democratie","tag-shah","tag-soljenitsyne"],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/66240","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/comments?post=66240"}],"version-history":[{"count":0,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/66240\/revisions"}],"wp:attachment":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/media?parent=66240"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/categories?post=66240"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/tags?post=66240"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}