{"id":66244,"date":"2005-03-02T00:00:00","date_gmt":"2005-03-02T00:00:00","guid":{"rendered":"https:\/\/new.dedefensa.org\/index.php\/2005\/03\/02\/lamerique-devant-lenigme-du-sphinx-europeen\/"},"modified":"2005-03-02T00:00:00","modified_gmt":"2005-03-02T00:00:00","slug":"lamerique-devant-lenigme-du-sphinx-europeen","status":"publish","type":"post","link":"https:\/\/new.dedefensa.org\/index.php\/2005\/03\/02\/lamerique-devant-lenigme-du-sphinx-europeen\/","title":{"rendered":"<strong><em>L&rsquo;Am\u00e9rique devant l&rsquo;\u00e9nigme du sphinx europ\u00e9en<\/em><\/strong>"},"content":{"rendered":"<p><h2 class=\"common-article\">L&rsquo;Am\u00e9rique devant l&rsquo;\u00e9nigme du sphinx europ\u00e9en<\/h2>\n<\/p>\n<p><\/p>\n<p><p>\t2 mars 2005  L&rsquo;Am\u00e9rique est, devant l&rsquo;Europe, comme devant le sphinx, incapable de r\u00e9soudre son \u00e9nigme. Elle ne comprend rien, ni \u00e0 son fonctionnement, ni \u00e0 la place et \u00e0 l&rsquo;influence diverses et r\u00e9ciproques des tr\u00e8s nombreux \u00e9l\u00e9ments de ses structures. L&rsquo;Am\u00e9rique ne comprend pas o\u00f9 est le pouvoir en Europe, alors qu&rsquo;elle constate de plus en plus que l&rsquo;Europe a une politique. Un point tr\u00e8s r\u00e9cemment mis en \u00e9vidence <a href=\"http:\/\/www.defensenews.com\/story.php?F=684979&#038;C=europe\" class=\"gen\">par l&rsquo;hebdomadaire Defense News<\/a> illustre ce constat.<\/p>\n<\/p>\n<p><\/p>\n<p><p>\t\u00ab <em>In a last-ditch effort to halt the European Union&rsquo;s move toward ending its arms embargo to China, the United States may negotiate with the entire 25-country bloc, a change from its preferred tactic of seeking agreements with individual states.<\/em> <\/p>\n<\/p>\n<p><p>\t\u00bb <em>But there is a stumbling block that is further stoking U.S. fears about technology transfers to China, say officials on both sides of the Atlantic: The EU cannot impose security rules on its member states.<\/em> \u00bb<\/p>\n<\/p>\n<p><\/p>\n<p><p>\tC&rsquo;est un probl\u00e8me r\u00e9current pour les Am\u00e9ricains depuis des d\u00e9cennies. Lorsque, en 1974, Kissinger remarquait sarcastiquement qu&rsquo;il ne pouvait jamais atteindre l&rsquo;Europe au t\u00e9l\u00e9phone, pour avoir sa position sur tel ou tel probl\u00e8me politique, il semblait impliquer le jugement ironique que l&rsquo;Europe n&rsquo;existait pas en tant que puissance politique unitaire. Ce sarcasme et cette ironie acqui\u00e8rent aujourd&rsquo;hui un go\u00fbt d&rsquo;amertume. Il s&rsquo;av\u00e8re que cette apparente faiblesse de l&rsquo;Europe constitue \u00e9galement un handicap extr\u00eamement irritant et embarrassant pour les Am\u00e9ricains: lorsque l&rsquo;Europe commence \u00e0 avoir une politique et que les Am\u00e9ricains veulent peser dessus, ils ne savent plus o\u00f9 appliquer leurs pressions car ils ne savent pas o\u00f9 est le pouvoir qui conduit cette politique. De fait, il est extr\u00eamement difficile de s&rsquo;y retrouver, du point de vue formel et du point de vue plus simplement politique.<\/p>\n<\/p>\n<p><p>\tLe cas iranien est, comme dans celui de l&#8217;embargo, tr\u00e8s \u00e9clairant. Dans l&rsquo;affaire iranienne, il y a au moins quatre pouvoirs europ\u00e9ens: les trois pays (Allemagne, France, UK) qui m\u00e8nent la n\u00e9gociation en font un; le Haut Commissaire (Solana) qui suit \u00e9videmment l&rsquo;affaire en est un autre; le pays assurant la pr\u00e9sidence de l&rsquo;UE (le Luxembourg) qui a \u00e9galement son mot \u00e0 dire, en est un troisi\u00e8me; la Commission europ\u00e9enne travaille \u00e9videmment sur le sujet et peut pr\u00e9tendre \u00eatre un quatri\u00e8me pouvoir. Cette cacophonie des pouvoirs qui d\u00e9clenchait l&rsquo;ironie et le sarcasme de Kissinger et fait g\u00e9mir les Europ\u00e9ens purs et durs qui voudraient une Europe \u00e0 l&rsquo;am\u00e9ricaine (Etats-Unis d&rsquo;Europe), devient un avantage extraordinaire d\u00e8s lors qu&rsquo;il y a entente sur une politique. Tous les pouvoirs travaillent dans le m\u00eame sens, chacun connaissant ses limites \u00e0 cause de la pratique des choses. Il devient tr\u00e8s difficile de les faire c\u00e9der parce que la responsabilit\u00e9 apparente va de l&rsquo;un \u00e0 l&rsquo;autre selon les pressions et chacun sait se d\u00e9lester tactiquement de cette responsabilit\u00e9 selon l&rsquo;orientation de ces pressions.<\/p>\n<\/p>\n<p><p>\tL&rsquo;Europe est en train de cr\u00e9er un ph\u00e9nom\u00e8ne nouveau: s\u00e9parer le lien entre le pouvoir de la politique. C&rsquo;est un avantage dans la mesure o\u00f9 le ph\u00e9nom\u00e8ne produit une garantie grandissante contre une situation o\u00f9 trop de pouvoir serait donn\u00e9 \u00e0 un organisme europ\u00e9en, conduisant \u00e0 une situation intol\u00e9rable d&rsquo;abus de pouvoir bureaucratique. L&rsquo;efficacit\u00e9 de ce syst\u00e8me qui s&rsquo;est d\u00e9velopp\u00e9 naturellement est de moins en moins contestable. La politique europ\u00e9enne vis-\u00e0-vis de l&rsquo;Iran est un cas \u00e9vident. Le d\u00e9veloppement de l&rsquo;outil militaire de la PESD, en passe de supplanter l&rsquo;OTAN sans tambour ni trompette, en est un autre. La question des relations strat\u00e9giques avec la Chine, \u00e0 partir du d\u00e9tonateur de l&#8217;embargo sur les armes, pourrait devenir un autre exemple.<\/p>\n<\/p>\n<p><p>\tLa situation europ\u00e9enne serait alors que le d\u00e9sordre actuel ne serait pas une situation de transition menant \u00e0 une Europe compl\u00e8tement int\u00e9gr\u00e9e mais la mise en place d&rsquo;une m\u00e9canique complexe mais efficace de divers pouvoirs donnant l&rsquo;apparence du d\u00e9sordre mais finissant par fournir une impulsion coordonn\u00e9e pour quelques grandes politiques sur lesquelles tous les pays s&rsquo;entendraient,  certains inspirant cette politique, d&rsquo;autres la suivant. En effet, la r\u00e9alit\u00e9 du pouvoir europ\u00e9en deviendrait celle de l&rsquo;inspiration et, bien entendu, ce seraient les pays-membres, et notamment ceux qui ont des options politiques tr\u00e8s affirm\u00e9es et une souverainet\u00e9 et une autonomie fortes, qui s&rsquo;av\u00e9reraient les plus influents \u00e0 cet \u00e9gard. Dans l&rsquo;id\u00e9al de ce sch\u00e9ma, le pouvoir est d\u00e9fini par l&rsquo;inspiration et par l&rsquo;influence qui en d\u00e9coule, aux d\u00e9pens de la force et du conformisme bureaucratique.     <\/p>\n<\/p>\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>L&rsquo;Am\u00e9rique devant l&rsquo;\u00e9nigme du sphinx europ\u00e9en 2 mars 2005 L&rsquo;Am\u00e9rique est, devant l&rsquo;Europe, comme devant le sphinx, incapable de r\u00e9soudre son \u00e9nigme. Elle ne comprend rien, ni \u00e0 son fonctionnement, ni \u00e0 la place et \u00e0 l&rsquo;influence diverses et r\u00e9ciproques des tr\u00e8s nombreux \u00e9l\u00e9ments de ses structures. L&rsquo;Am\u00e9rique ne comprend pas o\u00f9 est le pouvoir&hellip;&nbsp;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[3992,3977,1140,2773,3777],"class_list":["post-66244","post","type-post","status-publish","format-standard","hentry","category-faits-et-commentaires","tag-armes","tag-chine","tag-embargo","tag-iran","tag-solana"],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/66244","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/comments?post=66244"}],"version-history":[{"count":0,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/66244\/revisions"}],"wp:attachment":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/media?parent=66244"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/categories?post=66244"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/tags?post=66244"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}