{"id":66245,"date":"2005-03-03T00:00:00","date_gmt":"2005-03-03T00:00:00","guid":{"rendered":"https:\/\/new.dedefensa.org\/index.php\/2005\/03\/03\/le-vermont-qui-dit-non\/"},"modified":"2005-03-03T00:00:00","modified_gmt":"2005-03-03T00:00:00","slug":"le-vermont-qui-dit-non","status":"publish","type":"post","link":"https:\/\/new.dedefensa.org\/index.php\/2005\/03\/03\/le-vermont-qui-dit-non\/","title":{"rendered":"Le Vermont qui dit non"},"content":{"rendered":"<p><h2 class=\"common-article\">Le Vermont qui dit non<\/h2>\n<\/p>\n<p><p>\t4 mars 2005  Le Vermont est, aux \u00c9tats-Unis, un des tr\u00e8s petits \u00c9tats de l&rsquo;Union,  600.000 habitants, rien \u00e0 voir avec les monstres californien, texan ou new-yorkais. Qu&rsquo;importe, un \u00c9tat est un \u00c9tat dans l&rsquo;Union, et le Vermont a ses deux s\u00e9nateurs, comme la Californie, le Texas ou New York. C&rsquo;est m\u00eame ce qui donne tout son sens au syst\u00e8me originel, qui est, comme le rappelle Patrick J. Buchanan dans un article du 3 mars, <a href=\"http:\/\/www.antiwar.com\/pat\/?articleid=5015\" class=\"gen\">une r\u00e9publique et pas une d\u00e9mocratie<\/a>, malgr\u00e9 les gesticulations de GW et de ses acolytes id\u00e9ologues, sous les applaudissements des lib\u00e9raux postmodernes. (En plus, symbole non n\u00e9gligeable, le Vermont est un des 13 \u00c9tats fondateurs de l&rsquo;Union, en 1776-83.)<\/p>\n<\/p>\n<p><p>\tL&rsquo;acte \u00e9lectoral pos\u00e9 dans le Vermont (portant sur 52 des 246 localit\u00e9s de l&rsquo;\u00c9tat) est donc, par rapport aux conceptions des P\u00e8res Fondateurs, un acte fondamental. Le paradoxe est que le Vermont s&rsquo;affirme dans cette circonstance selon la conception r\u00e9publicaine (importance unique et \u00e9quivalente d&rsquo;un \u00c9tat au nom de son existence souveraine, quel que soit son poids d\u00e9mographique et g\u00e9ographique) par la m\u00e9thode d\u00e9mocratique (r\u00e9f\u00e9rendum). On voit bien que, selon cette conception, la d\u00e9mocratie n&rsquo;est qu&rsquo;un moyen et la r\u00e9publique un fondement, ce qui est \u00e0 l&rsquo;inverse de nos pratiques et conceptions postmodernistes.<\/p>\n<\/p>\n<p><p>\tSi la chose est mise ici en \u00e9vidence, c&rsquo;est parce que l&rsquo;acte partiel du Vermont, accompli dans la nuit du 1er au 2 mars, porte sur une,  non, sur la mati\u00e8re essentielle aujourd&rsquo;hui de la politique ext\u00e9rieure des USA, et qu&rsquo;il s&rsquo;oppose au centre f\u00e9d\u00e9ral qui d\u00e9termine cette politique. Le vote (48 localit\u00e9s sur les 52 ont adopt\u00e9 la r\u00e9solution sous une forme ou l&rsquo;autre) a exprim\u00e9 un sentiment populaire contre la guerre en Irak et demande qu&rsquo;on rapatrie les hommes de sa Garde Nationale qui se battent l\u00e0-bas.<\/p>\n<\/p>\n<p><p>\tBen Roche, procureur \u00e0 la retraite du Vermont a \u00e9t\u00e9 l&rsquo;un des organisateurs de la campagne anti-guerre qui a conduit au r\u00e9f\u00e9rendum. Il explique, (extrait d&rsquo;<a href=\"http:\/\/www.democracynow.org\/article.pl?sid=05\/03\/02\/154235\" class=\"gen\">une interview de Amy Goodman, de l&rsquo;organisation Democracy Now&rsquo;<\/a>), l&rsquo;historique de cette initiative.<\/p>\n<\/p>\n<p><p>\t\u00ab [I]<em>t all began with a rally against the war shortly after the election, and Montpelier and the rest of Vermont have seen a good number of rallies, and they&rsquo;re very spirited, but the organizers of the rally got together after and they said, what more can we do? We need to rally, but we also need to speak, and it became clear that the right place to speak was town meetings. That&rsquo;s been a tradition well over 200 years here in Vermont. We got busy collectively as a team. We drafted a resolution. We redrafted it, and it went through 19 different versions. We then circulated it to the towns. I&rsquo;m happy to say, Amy, that by midnight, we had 48 and not 38 towns, if you don&rsquo;t mind a very minor correction. We had 48 towns adopting resolutions that were very close to each other in text. There were some variations. We had three towns that voted it down, and just three towns that tabled it. We think that&rsquo;s really an overwhelming signal to the nation.<\/em> \u00bb<\/p>\n<\/p>\n<p><p>\tL&rsquo;autre explication de Ben Roche donn\u00e9e \u00e0 <em>Democracy Now!<\/em> concerne la demande de rapatriement des membres de la Garde Nationale du Vermont. (La Garde Nationale du Vermont, forte de 1.200 hommes, a le taux le plus haut de mobilisation pour l&rsquo;Irak de tous les \u00c9tats de l&rsquo;Union, avec 46% de l&rsquo;effectif.) Elle est int\u00e9ressante car elle est grosse d&rsquo;un d\u00e9bat fondamental pour un pays comme les Etats-Unis.<\/p>\n<\/p>\n<p><p>\tOn voit que Roche fait une distinction entre, d&rsquo;une part, la n\u00e9cessit\u00e9 pour un \u00c9tat de l&rsquo;Union de contribuer \u00e0 une action de guerre de l&rsquo;Union si cette action est n\u00e9e d&rsquo;une provocation, d&rsquo;une agression, d&rsquo;une mise en cause des principes de la R\u00e9publique ; et, d&rsquo;autre part, la soi-disant <em>war of choice<\/em>, c&rsquo;est-\u00e0-dire la guerre d\u00e9lib\u00e9r\u00e9e, volontairement d\u00e9clench\u00e9e par le centre (Washington) et jug\u00e9e <em>in fine<\/em> comme ne r\u00e9pondant \u00e0 aucune n\u00e9cessit\u00e9 ou urgence nationale. C&rsquo;est la mise en cause de la doctrine de la guerre pr\u00e9ventive. <\/p>\n<\/p>\n<p><p>\t\u00ab [L]<em>et me really summarize the resolution and hit its main points. I think I can really  I think I can reduce that to just four points. The resolutions, every single one, and it got up to 56, more than 52, every single resolution begins with a plea to support and respect the troops. We need these people here. They&rsquo;re first responders, they&rsquo;re family, they&rsquo;re friends, they&rsquo;re workers down the street. They make up the fabric of society in Vermont. They&rsquo;re an important part of that fabric. So, we began with that, and Amy, it wasn&rsquo;t just lip service, as some have suggested. The rest of the resolution also supports members of the Guard. Let me just give you the high points of what we asked for. We asked for our legislature to assess the impact of the deployment, not just on readiness, but on our communities, on our families. We&rsquo;re asking the delegation, Senator Leahy, Senator Jeffords, Congressman Sanders, to help restore a reasonable balance between states and the federal government, not in the case of every war, only in what we call wars of choice. We know that if this country is attacked, if there&rsquo;s an emergency, if there&rsquo;s an insurrection under the Constitution, there is no question that Guard members have signed up to serve, and that they would serve, and they would serve with enthusiasm and a sense of duty. Wars of choice are a whole different phenomenon. They&rsquo;re relatively new. We have no national policy governing the use of these wars. It&rsquo;s a big omission.<\/em> \u00bb <\/p>\n<\/p>\n<p><p>\tL&rsquo;acte partiel du Vermont est un \u00e9v\u00e9nement d&rsquo;un tr\u00e8s grand int\u00e9r\u00eat dans sa substance, quel que soit l&rsquo;accueil qu&rsquo;il recevra. La tactique de Washington, du gouvernement f\u00e9d\u00e9ral, dans un tel cas, compte tenu de la faiblesse actuelle d&rsquo;un ex\u00e9cutif washingtonien compl\u00e8tement atomis\u00e9 entre les int\u00e9r\u00eats particuliers et les bureaucraties concurrentes, est d&rsquo;ignorer de tels actes autant que faire se peut,  tactique de communication, comme ce gouvernement est coutumier. Il n&rsquo;en reste pas moins que le r\u00e9f\u00e9rendum, \u00e0 cause du sujet sur lequel il s&rsquo;exerce, est une mise en cause du pouvoir f\u00e9d\u00e9ral dans le droit absolu que ce pouvoir s&rsquo;est arrog\u00e9 en mati\u00e8re de conduite de la politique \u00e9trang\u00e8re, c&rsquo;est-\u00e0-dire dans la mati\u00e8re de la politique fondamentale de s\u00e9curit\u00e9 nationale. Il rappelle l&rsquo;existence d&rsquo;un contentieux jamais r\u00e9gl\u00e9 malgr\u00e9 la Guerre de S\u00e9cession entre les \u00c9tats et le pouvoir central. Le germe de ce contentieux est dans la Constitution de 1787-88, qui amorce la centralisation f\u00e9d\u00e9raliste aux d\u00e9pens de l&rsquo;impulsion initiale, plut\u00f4t conf\u00e9d\u00e9rale et bas\u00e9e sur l&rsquo;existence souveraine des \u00c9tats constituant les Etats-Unis.<\/p>\n<\/p>\n<p><p>\tA c\u00f4t\u00e9 de cela, et de fa\u00e7on plus conjoncturelle, le r\u00e9f\u00e9rendum rappelle l&rsquo;existence d&rsquo;une opposition \u00e0 la guerre d&rsquo;Irak. Il rappelle aussi que cette opposition est g\u00e9ographiquement identifi\u00e9e (voir les votes des deux derni\u00e8res pr\u00e9sidentielles), notamment dans le Nord-Est du pays, en Nouvelle-Angleterre.<\/p>\n<h4>La m\u00e9moire qui flanche&#8230;<\/h4>\n<p>Le 5 mars 2005  Nous avons trop fait confiance \u00e0 notre m\u00e9moire. Nous devons des excuses \u00e0 nos lecteurs. Le Vermont n&rsquo;est pas l&rsquo;un des 13 \u00c9tats initiaux de l&rsquo;Union comme nous l&rsquo;\u00e9crivons ci-dessus mais le 14\u00e8me, \u00e0 partir de 1791.<\/p>\n<\/p>\n<p><p>\tMerci \u00e0 notre lecteur John G. Mason qui nous signale notre erreur et la corrige <a href=\"http:\/\/www.dedefensa.org\/forum.php?art_id=1387\" class=\"gen\">en ajoutant d&rsquo;int\u00e9ressantes pr\u00e9cisions historiques<\/a>. Il recommande notamment d&rsquo;aller consulter <a href=\"http:\/\/www.vermontrepublic.org\/\" class=\"gen\">le site vermontrepublic.org<\/a> pour mesurer la vigueur du mouvement d&rsquo;opposition s\u00e9cessionniste \u00e0 l&rsquo;actuelle direction am\u00e9ricaniste de l&rsquo;Union.<\/p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Le Vermont qui dit non 4 mars 2005 Le Vermont est, aux \u00c9tats-Unis, un des tr\u00e8s petits \u00c9tats de l&rsquo;Union, 600.000 habitants, rien \u00e0 voir avec les monstres californien, texan ou new-yorkais. Qu&rsquo;importe, un \u00c9tat est un \u00c9tat dans l&rsquo;Union, et le Vermont a ses deux s\u00e9nateurs, comme la Californie, le Texas ou New York.&hellip;&nbsp;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[2949,4462],"class_list":["post-66245","post","type-post","status-publish","format-standard","hentry","category-faits-et-commentaires","tag-secession","tag-vermont"],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/66245","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/comments?post=66245"}],"version-history":[{"count":0,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/66245\/revisions"}],"wp:attachment":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/media?parent=66245"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/categories?post=66245"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/tags?post=66245"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}