{"id":66279,"date":"2005-03-28T00:00:00","date_gmt":"2005-03-28T00:00:00","guid":{"rendered":"https:\/\/new.dedefensa.org\/index.php\/2005\/03\/28\/f-16-en-formation-serree-de-bras-dhonneur-a-leurope\/"},"modified":"2005-03-28T00:00:00","modified_gmt":"2005-03-28T00:00:00","slug":"f-16-en-formation-serree-de-bras-dhonneur-a-leurope","status":"publish","type":"post","link":"https:\/\/new.dedefensa.org\/index.php\/2005\/03\/28\/f-16-en-formation-serree-de-bras-dhonneur-a-leurope\/","title":{"rendered":"F-16 en formation serr\u00e9e de bras d&rsquo;honneur \u00e0 l&rsquo;Europe"},"content":{"rendered":"<p><h2 class=\"common-article\">F-16 en formation serr\u00e9e de bras d&rsquo;honneur \u00e0 l&rsquo;Europe<\/h2>\n<\/p>\n<p><p>\t28 mars 2005  Le voyage de Condi Rice dans le sous-continent indien a \u00e9t\u00e9 ponctu\u00e9 par la d\u00e9cision de vendre des F-16 au Pakistan apr\u00e8s 15 ans d&#8217;embargo, puis par une col\u00e8re indienne \u00e0 ce propos, puis ou parall\u00e8lement, dans la plus grande confusion, l&rsquo;affirmation d&rsquo;une vente similaire \u00e0 l&rsquo;Inde transform\u00e9e bient\u00f4t en perspective de vente.<\/p>\n<\/p>\n<p><p>\tL&rsquo;attitude am\u00e9ricaine concernant cette vente et la r\u00e9action indienne a \u00e9t\u00e9 inflexible, comme \u00e0 l&rsquo;habitude, du type am\u00e9ricaniste bien connu selon lequel nous savons mieux que vous ce qui convient \u00e0 votre s\u00e9curit\u00e9. On peut rappeler cet \u00e9change caract\u00e9ristique, rapport\u00e9 par AFP et <a href=\"http:\/\/www.defensenews.com\/story.php?F=745593&#038;C=asiapac\" class=\"gen\">Defense News du 25 mars<\/a>: \u00ab [Indian PM] <em>Singh expressed to Bush his great disappointment, saying <\/em>[the F-16&prime; sale to Pakistan] <em>could have negative consequences for India&rsquo;s security, according to the Indian leader&rsquo;s spokesman, Sanjaya Baru. But <\/em>[a] <em>U.S. official said we don&rsquo;t see any impact on the relevant military balances in the region. The sale was to make Pakistan more secure, the official said. It&rsquo;s in the interest of India, Pakistan and the United States that Pakistan feels secure.<\/em> \u00bb <\/p>\n<\/p>\n<p><p>\tLa confusion caract\u00e9ristiquement US de cet \u00e9pisode conduit \u00e0 r\u00e9server un jugement sur les faits \u00e0 venir, notamment sur l&rsquo;\u00e9volution de la suppos\u00e9e vente \u00e0 l&rsquo;Inde. Ce qui est un peu plus assur\u00e9, c&rsquo;est la mont\u00e9e renouvel\u00e9e de la tension entre le Pakistan et l&rsquo;Inde. Ce qui est encore plus assur\u00e9 et m\u00e9rite une mention sp\u00e9ciale, c&rsquo;est le bras d&rsquo;honneur superbe et am\u00e9ricaniste brandi \u00e0 la face de l&rsquo;Europe \u00e0 cette occasion. <\/p>\n<\/p>\n<p><p>\t Effectivement, un bras d&rsquo;honneur en passant aux Europ\u00e9ens qui sont en train de se d\u00e9bander sur la question de la lev\u00e9e de l&#8217;embargo des armes europ\u00e9ennes vers la Chine, sur la pression directe et impudente des Etats-Unis, qui brandissent les dangers d&rsquo;alimenter la tension entre P\u00e9kin et Ta\u00efwan. On peut citer \u00e0 cet \u00e9gard ce commentaire qui nous r\u00e9sume le soi disant probl\u00e8me,  <a href=\"http:\/\/www.sfgate.com\/cgi-bin\/article.cgi?file=\/news\/archive\/2005\/03\/25\/national\/w083245S77.DTL\" class=\"gen\">dans une d\u00e9p\u00eache AP du 25 mars<\/a> qui pr\u00e9cise que Washington propose \u00e9galement F-16 et F-18 \u00e0 l&rsquo;Inde : \u00ab <em>The sales to two nuclear countries that have warred over the Kashmir territory could raise eyebrows among U.S. allies in Europe who are under White House pressure not to lift an arms embargo on China. The Bush administration argues that European weapons could contribute to rising tensions between Beijing and Taiwan.<\/em> \u00bb<\/p>\n<\/p>\n<p><p>\tL&rsquo;initiative am\u00e9ricaine repr\u00e9sente un acte avec un formidable potentiel de d\u00e9stabilisation du sous-continent asiatique (et au-del\u00e0, on le verra). Les Am\u00e9ricains ont mis en place d&rsquo;ores et d\u00e9j\u00e0 les pr\u00e9misses d&rsquo;une nouvelle course aux armements dans cette zone, comme le montre la rh\u00e9torique en marche dans les deux pays, y compris au Pakistan lui-m\u00eame. Le chef de la force a\u00e9rienne pakistanaise, le Air Chief Marshal Kaleem Saadat, a donn\u00e9 une conf\u00e9rence de presse dimanche o\u00f9 plusieurs points sont apparus:<\/p>\n<\/p>\n<p><p>\t&bull; A c\u00f4t\u00e9 de la vente des F-16 au Pakistan, il y a une proposition (pressante) des Am\u00e9ricains pour que les Indiens ach\u00e8tent \u00e9ventuellement des F-18. (Il s&rsquo;agit sans doute du dernier mod\u00e8le, le F-18E\/F : mauvais avion, tr\u00e8s cher, mais accompagn\u00e9 d&rsquo;une publicit\u00e9 qui en fait un avion d&rsquo;une nouvelle g\u00e9n\u00e9ration. Cela suffit pour faire marcher le commentaire puis l&rsquo;argument dans le sens d&rsquo;une am\u00e9lioration d\u00e9cisive de l&rsquo;armement face \u00e0 cette nouvelle menace.) La chose a \u00e9t\u00e9 rappel\u00e9e \u00e0 Saadat par un journaliste.<\/p>\n<\/p>\n<p><p>\t&bull; Quoiqu&rsquo;en des termes prudents, mais dans le sens de la sollicitation ainsi faite, Saadat n&rsquo;a pas \u00e9cart\u00e9 la possibilit\u00e9 que le Pakistan ach\u00e8te des chasseurs de la quatri\u00e8me g\u00e9n\u00e9ration.<\/p>\n<\/p>\n<p><p>\t&bull; Classification assez myst\u00e9rieuse, au reste, cette quatri\u00e8me g\u00e9n\u00e9ration, dans laquelle on pourrait m\u00eame faire entrer, en poussant un peu, les F-16 livr\u00e9s au Pakistan s&rsquo;ils sont d&rsquo;un type avanc\u00e9. On a aussi de nombreux d\u00e9bats en vue avec l&rsquo;\u00e9quipement des F-16 pakistanais, l&rsquo;\u00e9lectronique, l&rsquo;armement (des AMRAAM AIM-120 aux capacit\u00e9s avanc\u00e9es ou pas ?). Ces d\u00e9bats alimenteront la tension, les alarmes, c&rsquo;est-\u00e0-dire la course aux armements entre Pakistan et Inde.<\/p>\n<\/p>\n<p><p>\t&bull; L&rsquo;effet est l\u00e0 : d&rsquo;ores et d\u00e9j\u00e0, l&rsquo;achat des F-16 est per\u00e7u par la presse pakistanaise comme le d\u00e9but d&rsquo;un r\u00e9\u00e9quipement g\u00e9n\u00e9ral de la force a\u00e9rienne pakistanaise, rendu n\u00e9cessaire en un sens par la guerre contre le terrorisme (?) et par le possible\/probable r\u00e9\u00e9quipement indien \u00e0 venir : \u00ab <em>Pakistan may go for 4th-generation jets: air chief<\/em> \u00bb, titre aujourd&rsquo;hui <a href=\"http:\/\/jang.com.pk\/thenews\/mar2005-daily\/28-03-2005\/main\/main3.htm\" class=\"gen\">The News International de Karachi<\/a>.<\/p>\n<\/p>\n<p><p>\tRarement les relations internationales auront montr\u00e9 le peu de cas que les Am\u00e9ricains font de l&rsquo;Europe, en contredisant si compl\u00e8tement, \u00e0 propos de la tension Pakistan-Inde, l&rsquo;argument utilis\u00e9 contre la lev\u00e9e de l&#8217;embargo europ\u00e9en vers la Chine, \u00e0 propos de la tension P\u00e9kin-Ta\u00efwan. Il n&rsquo;y a aucune chance que les Europ\u00e9ens les plus convaincus et les plus vertueux en tirent quelque le\u00e7on que ce soit, parce que cette le\u00e7on mettrait en cause l&rsquo;appr\u00e9ciation oblig\u00e9e des relations euro-am\u00e9ricaines et du comportement am\u00e9ricain qu&rsquo;entretiennent ces m\u00eames Europ\u00e9ens. Par contre, elle rendra beaucoup plus difficile d&rsquo;enterrer le cas de la lev\u00e9e de l&#8217;embargo, surtout si les Chinois utilisent l&rsquo;argument \u00e9vident de l&rsquo;analogie aupr\u00e8s de leurs interlocuteurs europ\u00e9ens. Cela est d&rsquo;autant plus concevable si les Am\u00e9ricains poursuivent leur projet d&rsquo;armer les Indiens. Le projet inqui\u00e9tera les Pakistanais, eux-m\u00eames surarm\u00e9s, mais ne manquera pas non plus d&rsquo;inqui\u00e9ter les Chinois, puisque ceux-ci sont aussi des rivaux des Indiens. Comment les Europ\u00e9ens vont-ils repousser cette sorte d&rsquo;argument ?<\/p>\n<\/p>\n<p><p>\tL&rsquo;avantage (?) de l&rsquo;activit\u00e9 ext\u00e9rieure (cette expression est pr\u00e9f\u00e9rable \u00e0 celle de politique ext\u00e9rieure) des USA, c&rsquo;est que, outre d&rsquo;\u00eatre impudente et m\u00e9prisante pour l&rsquo;Europe, elle est \u00e9galement totalement irresponsable et aveugle. Rien de nouveau, mais toujours plus d&rsquo;exemples divertissants. Cette affaire des F-16 pakistanais a toutes les chances de d\u00e9clencher un effet-domino de tensions diverses aboutissant, notamment, \u00e0 renouveler les tensions entre l&rsquo;Europe et le USA. <\/p>\n<\/p>\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>F-16 en formation serr\u00e9e de bras d&rsquo;honneur \u00e0 l&rsquo;Europe 28 mars 2005 Le voyage de Condi Rice dans le sous-continent indien a \u00e9t\u00e9 ponctu\u00e9 par la d\u00e9cision de vendre des F-16 au Pakistan apr\u00e8s 15 ans d&#8217;embargo, puis par une col\u00e8re indienne \u00e0 ce propos, puis ou parall\u00e8lement, dans la plus grande confusion, l&rsquo;affirmation d&rsquo;une&hellip;&nbsp;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[3977,4479,398,1015,3713,4481,3378,3379,4480],"class_list":["post-66279","post","type-post","status-publish","format-standard","hentry","category-faits-et-commentaires","tag-chine","tag-destabilisation","tag-europe","tag-f-16","tag-f-18","tag-generation","tag-inde","tag-pakistan","tag-quatrieme"],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/66279","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/comments?post=66279"}],"version-history":[{"count":0,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/66279\/revisions"}],"wp:attachment":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/media?parent=66279"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/categories?post=66279"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/tags?post=66279"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}