{"id":66295,"date":"2005-04-05T00:00:00","date_gmt":"2005-04-05T00:00:00","guid":{"rendered":"https:\/\/new.dedefensa.org\/index.php\/2005\/04\/05\/de-la-page-blanche-a-la-page-vide\/"},"modified":"2005-04-05T00:00:00","modified_gmt":"2005-04-05T00:00:00","slug":"de-la-page-blanche-a-la-page-vide","status":"publish","type":"post","link":"https:\/\/new.dedefensa.org\/index.php\/2005\/04\/05\/de-la-page-blanche-a-la-page-vide\/","title":{"rendered":"De la page blanche \u00e0 la \u201cpage vide\u201d"},"content":{"rendered":"<p><p>Maureen Dowd, Dieu la prot\u00e8ge, nous offre une notion nouvelle et particuli\u00e8rement \u00e9difiante: la page vide (compl\u00e8tement diff\u00e9rent de la page blanche, celle qui donne le vertige \u00e0 l&rsquo;\u00e9crivain ou celle o\u00f9 la censure est pass\u00e9e). Nous nous r\u00e9p\u00e9tons (nous l&rsquo;avons d\u00e9j\u00e0 \u00e9crit dans le chapeau de pr\u00e9sentation de l&rsquo;article) : lisez <a href=\"http:\/\/www.iht.com\/articles\/2005\/04\/03\/opinion\/eddowd.html\" class=\"gen\">son article du 4 avril dans l&rsquo;International Herald Tribune<\/a>, sur le rapport de 601 pages sur les erreurs commises pour ne pas trouver des ADM de Saddam qui n&rsquo;existait pas, avec son titre \u00ab <em> The latest intelligence study  601 empty pages<\/em> \u00bb. Ce monde du mensonge devenu structurel et ainsi d\u00e9passant sa nature de mensonge,  au-del\u00e0 du mensonge puisque c&rsquo;est le virtualisme,  est devenu notre monde g\u00e9n\u00e9ral. L&rsquo;acquiescement est complet, au point o\u00f9 l&rsquo;on ne peut parler de complicit\u00e9: c&rsquo;est la solidarit\u00e9 des \u00e9quilibres communs dans une r\u00e9alit\u00e9 invent\u00e9e.<\/p>\n<\/p>\n<p><p>\tDowd, qui ne fait pas partie des \u00e9quilibres communs, nous d\u00e9signe ce rapport de 601 pages, une montagne de papier o\u00f9 il n&rsquo;y a rien puisqu&rsquo;il manque l&rsquo;essence m\u00eame de la d\u00e9marche. Certes, les services de renseignement ont mal fonctionn\u00e9 par rapport \u00e0 la r\u00e9alit\u00e9 mais en r\u00e9alit\u00e9 ils ont suivi la consigne g\u00e9n\u00e9rale et imp\u00e9rative du pouvoir politique. Enqu\u00eater sur eux, observe Dowd, c&rsquo;est \u00ab <em>like an investigation into steroids in baseball that looks only at the drug companies, not the players who muscled up. We don&rsquo;t need a 14-month inquiry producing 601 pages at a cost of $10 million to tell us the data on arms in Iraq was flawed. We know that. When we got over there, we didn&rsquo;t find any.<\/em> \u00bb<\/p>\n<\/p>\n<p><p>\tLe plus int\u00e9ressant, le plus instructif dans cet article, apr\u00e8s avoir pass\u00e9 les faits, ou les non-faits qui justifient son emploi, c&rsquo;est bien cette expression de <em>empty pages<\/em>: des pages emplies de signes et de mots compr\u00e9hensibles, de phrases coh\u00e9rentes, et qui ne signifient rien. L&rsquo;id\u00e9e de page vide est bien plus effrayante que l&rsquo;id\u00e9e de page blanche, y compris la page blanche qui d\u00e9signe le passage du censeur. C&rsquo;est l&rsquo;id\u00e9e du signe coh\u00e9rent, de la lettre bien ordonn\u00e9e en mots et phrases, mis en ordre pour construire une r\u00e9alit\u00e9 compl\u00e8tement artificielle, devant laquelle tous les solidaires s&rsquo;inclinent. Si notre civilisation, c&rsquo;est d&rsquo;abord la parole et l&rsquo;\u00e9crit, alors notre civilisation est all\u00e9e au-del\u00e0 de la barbarie, au-del\u00e0 de son point de d\u00e9part. Elle \u00e9volue dans son double n\u00e9gatif.<\/p>\n<\/p>\n<p><\/p>\n<p><p>\tMis en ligne le 5 avril 2005 \u00e0 10H44<\/p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Maureen Dowd, Dieu la prot\u00e8ge, nous offre une notion nouvelle et particuli\u00e8rement \u00e9difiante: la page vide (compl\u00e8tement diff\u00e9rent de la page blanche, celle qui donne le vertige \u00e0 l&rsquo;\u00e9crivain ou celle o\u00f9 la censure est pass\u00e9e). Nous nous r\u00e9p\u00e9tons (nous l&rsquo;avons d\u00e9j\u00e0 \u00e9crit dans le chapeau de pr\u00e9sentation de l&rsquo;article) : lisez son article du&hellip;&nbsp;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","footnotes":"","jetpack_post_was_ever_published":false},"categories":[2],"tags":[],"class_list":["post-66295","post","type-post","status-publish","format-standard","hentry","category-bloc-notes"],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/66295","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/comments?post=66295"}],"version-history":[{"count":0,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/66295\/revisions"}],"wp:attachment":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/media?parent=66295"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/categories?post=66295"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/tags?post=66295"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}