{"id":66312,"date":"2005-04-10T00:00:00","date_gmt":"2005-04-10T00:00:00","guid":{"rendered":"https:\/\/new.dedefensa.org\/index.php\/2005\/04\/10\/un-troisieme-groupe-de-porte-avions-us-vers-le-moyen-orient\/"},"modified":"2005-04-10T00:00:00","modified_gmt":"2005-04-10T00:00:00","slug":"un-troisieme-groupe-de-porte-avions-us-vers-le-moyen-orient","status":"publish","type":"post","link":"https:\/\/new.dedefensa.org\/index.php\/2005\/04\/10\/un-troisieme-groupe-de-porte-avions-us-vers-le-moyen-orient\/","title":{"rendered":"Un troisi\u00e8me groupe de porte-avions US vers le Moyen-Orient?"},"content":{"rendered":"<p><p>Un groupe de porte-avions de l&rsquo;U.S. Navy, autour du porte-avions USS <em>Theodore Roosevelt<\/em>, serait en route vers le Moyen-Orient, rejoignant deux autres groupes de porte-avions d\u00e9j\u00e0 d\u00e9ploy\u00e9s dans la r\u00e9gion. Trois groupes de porte-avions d\u00e9ploy\u00e9s dans une telle r\u00e9gion, cela constitue un signal d&rsquo;alarme important pour une possibilit\u00e9 d&rsquo;op\u00e9ration offensive majeure.<\/p>\n<\/p>\n<p><p>\tOn doit aussit\u00f4t penser \u00e0 une attaque contre l&rsquo;Iran. Le nombre de commentateurs envisageant une telle op\u00e9ration contre l&rsquo;Iran d&rsquo;une fa\u00e7on pr\u00e9cise est d\u00e9sormais significatif. Il y a <a href=\" http:\/\/english.aljazeera.net\/NR\/exeres\/1B5FCF4A-FBF6-443A-93A9-5E37C43FDE0B.htm\" class=\"gen\">Scott Ritter<\/a>, qui cite des sources pr\u00e9cises \u00e0 la Maison-Blanche ; il y a aussi <a href=\"http:\/\/www.antiwar.com\/bock\" class=\"gen\">Alan Bock<\/a>, qui fait un parall\u00e8le entre la direction sovi\u00e9tique du temps de la Guerre froide et la direction am\u00e9ricaniste, pour constater la difficult\u00e9 de conna\u00eetre les intentions de la seconde, mais estimant tout de m\u00eame qu&rsquo;une attaque pourrait avoir lieu en juin \u00e0 partir d&rsquo;une analyse g\u00e9n\u00e9rale des signes et d\u00e9clarations allant dans ce sens.<\/p>\n<\/p>\n<p><\/p>\n<p><p>\tMis en ligne le 10 avril 2005 \u00e0 12H35<\/p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Un groupe de porte-avions de l&rsquo;U.S. Navy, autour du porte-avions USS Theodore Roosevelt, serait en route vers le Moyen-Orient, rejoignant deux autres groupes de porte-avions d\u00e9j\u00e0 d\u00e9ploy\u00e9s dans la r\u00e9gion. Trois groupes de porte-avions d\u00e9ploy\u00e9s dans une telle r\u00e9gion, cela constitue un signal d&rsquo;alarme important pour une possibilit\u00e9 d&rsquo;op\u00e9ration offensive majeure. On doit aussit\u00f4t penser&hellip;&nbsp;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","footnotes":"","jetpack_post_was_ever_published":false},"categories":[2],"tags":[],"class_list":["post-66312","post","type-post","status-publish","format-standard","hentry","category-bloc-notes"],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/66312","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/comments?post=66312"}],"version-history":[{"count":0,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/66312\/revisions"}],"wp:attachment":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/media?parent=66312"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/categories?post=66312"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/tags?post=66312"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}