{"id":66350,"date":"2005-04-23T00:00:00","date_gmt":"2005-04-23T00:00:00","guid":{"rendered":"https:\/\/new.dedefensa.org\/index.php\/2005\/04\/23\/la-gloire-des-marines\/"},"modified":"2005-04-23T00:00:00","modified_gmt":"2005-04-23T00:00:00","slug":"la-gloire-des-marines","status":"publish","type":"post","link":"https:\/\/new.dedefensa.org\/index.php\/2005\/04\/23\/la-gloire-des-marines\/","title":{"rendered":"La gloire des Marines"},"content":{"rendered":"<p><p>Pour la premi\u00e8re fois dans l&rsquo;histoire militaire des Etats-Unis, un Marine a \u00e9t\u00e9 nomm\u00e9 au plus haut poste de l&rsquo;arm\u00e9e, le pr\u00e9sident du Joint Chief of Staff (JCS). Le g\u00e9n\u00e9ral Peter Pace, 59 ans, est adjoint de l&rsquo;actuel pr\u00e9sident du JCS, le g\u00e9n\u00e9ral Myers, de l&rsquo;USAF. (Myers quittera sa fonction en septembre, remplac\u00e9 par Pace.) C&rsquo;est une deuxi\u00e8me premi\u00e8re pour le Marine Corps depuis le 11 septembre 2001, apr\u00e8s l&rsquo;accession au poste de SACEUR (commandant en chef alli\u00e9 en Europe), il y a deux ans, du g\u00e9n\u00e9ral James Jones.<\/p>\n<\/p>\n<p><p>\tL&rsquo;accession du Marine Corps \u00e0 ces postes de responsabilit\u00e9 central du dispositif militaire am\u00e9ricain illustre la volont\u00e9 d&rsquo;une \u00e9volution tr\u00e8s rapide de celui-ci vers une force exp\u00e9ditionnaire d&rsquo;intervention, souple, rapide, etc. (Pour l&rsquo;instant, nous en sommes au niveau des intentions.) Effectivement pour ce qui est de cette orientation, Pace a deux missions essentielles: favoriser la restructuration g\u00e9n\u00e9rale des forces arm\u00e9es US et d\u00e9velopper les op\u00e9rations de la guerre contre la terreur.<\/p>\n<\/p>\n<p><p>\tCette pr\u00e9pond\u00e9rance des corps combattants terrestres (l&rsquo;U.S. Army et le Marine Corps occupent aujourd&rsquo;hui les postes bureaucratiques et op\u00e9rationnels essentiels) implique l&rsquo;effacement des deux armes les plus techniques (l&rsquo;USAF et la Navy). Cet effacement reste \u00e0 \u00eatre concr\u00e9tis\u00e9 dans la programmation, les choix de programmes, la pr\u00e9pond\u00e9rance bureaucratique et industrielle. C&rsquo;est une autre paire de manche. On aura les premi\u00e8res indications des effets de ces orientations avec la programmation de la QDR 2005, qui devrait \u00eatre d\u00e9voil\u00e9e \u00e0 l&rsquo;automne.<\/p>\n<\/p>\n<p><\/p>\n<p><p>\tMis en ligne le 23 avril 2005 \u00e0 11H45<\/p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Pour la premi\u00e8re fois dans l&rsquo;histoire militaire des Etats-Unis, un Marine a \u00e9t\u00e9 nomm\u00e9 au plus haut poste de l&rsquo;arm\u00e9e, le pr\u00e9sident du Joint Chief of Staff (JCS). Le g\u00e9n\u00e9ral Peter Pace, 59 ans, est adjoint de l&rsquo;actuel pr\u00e9sident du JCS, le g\u00e9n\u00e9ral Myers, de l&rsquo;USAF. (Myers quittera sa fonction en septembre, remplac\u00e9 par Pace.)&hellip;&nbsp;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","footnotes":"","jetpack_post_was_ever_published":false},"categories":[2],"tags":[4520,3539,4519,4482],"class_list":["post-66350","post","type-post","status-publish","format-standard","hentry","category-bloc-notes","tag-4520","tag-jcs","tag-pace","tag-qdr"],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/66350","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/comments?post=66350"}],"version-history":[{"count":0,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/66350\/revisions"}],"wp:attachment":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/media?parent=66350"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/categories?post=66350"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/tags?post=66350"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}