{"id":66359,"date":"2005-04-26T00:00:00","date_gmt":"2005-04-26T00:00:00","guid":{"rendered":"https:\/\/new.dedefensa.org\/index.php\/2005\/04\/26\/airbus-jusqua-los\/"},"modified":"2005-04-26T00:00:00","modified_gmt":"2005-04-26T00:00:00","slug":"airbus-jusqua-los","status":"publish","type":"post","link":"https:\/\/new.dedefensa.org\/index.php\/2005\/04\/26\/airbus-jusqua-los\/","title":{"rendered":"<strong><em>Airbus jusqu&rsquo;\u00e0 l&rsquo;os<\/em><\/strong>"},"content":{"rendered":"<p><h2 class=\"common-article\">Airbus jusqu&rsquo;\u00e0 l&rsquo;os<\/h2>\n<\/p>\n<p><\/p>\n<p><p>\t26 avril 2005  La guerre entre Boeing et Airbus sera terrible, elle sera sans merci. <a href=\"http:\/\/www.dedefensa.org\/article.php?art_id=1267\" class=\"gen\">N\u00e9e, pour la phase actuelle, \u00e0 l&rsquo;automne 2004<\/a>, elle entre dans le cadre de ce que nous nommons <a href=\"http:\/\/www.dedefensa.org\/article.php?art_id=1500\" class=\"gen\">la guerre technologique<\/a>, dont un autre volet est l&rsquo;affrontement USA-Europe \u00e0 l&rsquo;occasion de la crise de la lev\u00e9e de l&#8217;embargo europ\u00e9en (armements) vers la Chine, dont l&rsquo;un des prolongements est les restrictions de transfert de technologies US vers l&rsquo;Europe. <\/p>\n<\/p>\n<p><p>\tIl existe aujourd&rsquo;hui un courant tr\u00e8s puissant au Congr\u00e8s pour s&rsquo;opposer \u00e0 l&rsquo;Europe dans tous les domaines touchant aux questions technologiques, avec les dimensions compl\u00e9mentaires du militaire, du commercial, etc., et dans une mesure o\u00f9 l&rsquo;ensemble est devenu intens\u00e9ment politique et strat\u00e9gique. Des parlementaires se sp\u00e9cialisent dans certaines actions, dans certains domaines, ce qui a l&rsquo;avantage de leur procurer une notori\u00e9t\u00e9 durable. Le sp\u00e9cialiste de la lutte anti-Airbus est d\u00e9sormais le d\u00e9put\u00e9 d\u00e9mocrate de l&rsquo;\u00c9tat de Washington Norm Dicks. Sa position est \u00e9videmment compr\u00e9hensible, son \u00c9tat \u00e9tant celui des usines Boeing, qui s&rsquo;oppose \u00e0 Airbus,  Dicks est donc le d\u00e9put\u00e9 de Boeing, comme le s\u00e9nateur d\u00e9mocrate <em>Scoop<\/em> Jackson, parrain des n\u00e9o-conservateurs (on reste dans la famille), \u00e9tait <em>in illo tempore<\/em> (dans les ann\u00e9es 1960-70) le s\u00e9nateur de Boeing. L&rsquo;action actuelle de Dicks, au niveau l\u00e9gislatif, semble indiquer que Boeing, qui se trouve compl\u00e8tement et de mani\u00e8re sonnante et tr\u00e9buchante derri\u00e8re le s\u00e9nateur, estime qu&rsquo;on peut obtenir des avanc\u00e9es d\u00e9cisives anti-Airbus au niveau l\u00e9gislatif am\u00e9ricain.<\/p>\n<\/p>\n<p><p>\tLa derni\u00e8re initiative de Dicks est son intention confirm\u00e9e de d\u00e9poser un projet de loi anti-Airbus, qui emp\u00eacherait le constructeur europ\u00e9en de participer \u00e0 la comp\u00e9tition pour les ravitailleurs en vol de l&rsquo;USAF. <a href=\"http:\/\/www.defensenews.com\/story.php?F=798911&#038;C=airwar\" class=\"gen\">Defense News rapporte, le 25 avril<\/a>, les intentions de Dicks.<\/p>\n<\/p>\n<p><\/p>\n<p><p>\t\u00ab <em>With the European Union refusing to halt subsidies to its giant aircraft company, Airbus, Rep. Norm Dicks, D-Wash., said he may propose a law that would prevent the company from building airborne refueling tankers for the U.S. Air Force. Dicks said he is considering legislation that would bar companies that violate World Trade Organization (WTO) regulations from receiving U.S. defense contracts. European government subsidies to Airbus are a per se violation of the WTO, he said. I don&rsquo;t think somebody should be able to compete, or at least win a competition, if they&rsquo;re in violation of the WTO, Dicks said during a meeting with reporters April 20.<\/em> <\/p>\n<\/p>\n<p><p>\t(&#8230;)<\/p>\n<\/p>\n<p><p>\t\u00bb <em>In January, the U.S. and the European Union agreed to suspend the WTO case and try to negotiate a resolution. Three months of talks produced no results, and in March the U.S. Trade Representative&rsquo;s Office announced it would pursue the WTO case. That hasn&rsquo;t happened yet. U.S. negotiators are still hoping that they can work out something, Dicks said. They&rsquo;re still giving the EU a chance to come back and say they&rsquo;re willing to seriously negotiate. But that seems unlikely, Dicks said. We&rsquo;re headed for the WTO  the sooner the better.<\/em> <\/p>\n<\/p>\n<p><p>\t\u00bb <em>Dicks&rsquo; legislation would be a tougher House follow-up to a nonbinding resolution passed in mid-April by the Senate, urging the European Union to halt the Airbus subsidies and President George W. Bush to pursue WTO action. Although the Senate voted 96-0, the European Union has ignored the resolution, Dicks said.<\/em> \u00bb<\/p>\n<\/p>\n<p><\/p>\n<p><p>\tIl est certain, comme on a pu le voir avec <a href=\"http:\/\/www.dedefensa.org\/article.php?art_id=1451\" class=\"gen\">la brutalit\u00e9 des derniers \u00e9changes<\/a> lorsqu&rsquo;on est arriv\u00e9 au bout du d\u00e9lai du 10 avril, que le climat est d\u00e9grad\u00e9 (doux euph\u00e9misme) entre les deux n\u00e9gociateurs. Il est d\u00e9grad\u00e9 parce que, aux USA, progresse l&rsquo;id\u00e9e que les subsides \u00e0 Airbus sont inacceptables dans l&rsquo;absolu, donc qu&rsquo;il ne peut \u00eatre logiquement question d&rsquo;\u00e9change, de r\u00e9ciprocit\u00e9, de n\u00e9gociations, etc., avec dans la balance la mise en cause des mesures US que d\u00e9nonce l&rsquo;UE. Pour les Am\u00e9ricains et dans le climat exalt\u00e9 qu&rsquo;on conna\u00eet aujourd&rsquo;hui sur ces questions, l&rsquo;id\u00e9e m\u00eame d&rsquo;un subside gouvernemental est monstrueuse, un anath\u00e8me qui ne peut \u00eatre discut\u00e9.<\/p>\n<\/p>\n<p><p>\t(Peu importe que les USA fassent de m\u00eame de leur c\u00f4t\u00e9. Ils le font d&rsquo;une fa\u00e7on dissimul\u00e9e qui n&rsquo;engage pas l&rsquo;apparence de vertu qui fait aujourd&rsquo;hui l&rsquo;essentiel de l&rsquo;argument US. La minceur de la cause et la force du sentiment garantissent l&rsquo;extr\u00e9misme de la position am\u00e9ricaine. Il s&rsquo;agit d&rsquo;une <a href=\"http:\/\/www.dedefensa.org\/article.php?art_id=1250\" class=\"gen\">faith-based argumentation<\/a>, qui est du domaine quasiment religieux. Ce genre de choses est, \u00e0 Washington, irr\u00e9sistible.)<\/p>\n<\/p>\n<p><p>\tPour toutes ces raisons, les intentions de Dicks semblent r\u00e9pondre \u00e0 l&rsquo;air du temps et ont de bonnes chances de faire leur chemin et d&rsquo;aboutir \u00e0 une l\u00e9gislation <em>de facto<\/em> anti-Airbus qui pervertira par avance l&rsquo;esprit de toute n\u00e9gociation. Il est \u00e9galement probable que la d\u00e9marche de Dicks, si elle est couronn\u00e9e de succ\u00e8s, ouvrira la voie \u00e0 d&rsquo;autres l\u00e9gislations du m\u00eame esprit (c&rsquo;est-\u00e7\u00e0-dire interdisant <em>de facto<\/em> le choix d&rsquo;Airbus au nom d&rsquo;un jugement de valeur soi-disant objectif: \u00ab <em>&#8230;subsidies to Airbus are a per se violation of the WTO<\/em> \u00bb). Une telle l\u00e9gislation placerait l&rsquo;UE, toujours selon l&rsquo; esprit de la loi, dans la redoutable position de devoir riposter par des mesures unilat\u00e9rales de son c\u00f4t\u00e9, ou de perdre tout cr\u00e9dit vis-\u00e0-vis du monde industriel europ\u00e9en et des \u00c9tats-membres.<\/p>\n<\/p>\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Airbus jusqu&rsquo;\u00e0 l&rsquo;os 26 avril 2005 La guerre entre Boeing et Airbus sera terrible, elle sera sans merci. N\u00e9e, pour la phase actuelle, \u00e0 l&rsquo;automne 2004, elle entre dans le cadre de ce que nous nommons la guerre technologique, dont un autre volet est l&rsquo;affrontement USA-Europe \u00e0 l&rsquo;occasion de la crise de la lev\u00e9e de&hellip;&nbsp;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[],"class_list":["post-66359","post","type-post","status-publish","format-standard","hentry","category-faits-et-commentaires"],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/66359","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/comments?post=66359"}],"version-history":[{"count":0,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/66359\/revisions"}],"wp:attachment":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/media?parent=66359"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/categories?post=66359"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/tags?post=66359"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}