{"id":66360,"date":"2005-04-27T00:00:00","date_gmt":"2005-04-27T00:00:00","guid":{"rendered":"https:\/\/new.dedefensa.org\/index.php\/2005\/04\/27\/panique-a-bord-2\/"},"modified":"2005-04-27T00:00:00","modified_gmt":"2005-04-27T00:00:00","slug":"panique-a-bord-2","status":"publish","type":"post","link":"https:\/\/new.dedefensa.org\/index.php\/2005\/04\/27\/panique-a-bord-2\/","title":{"rendered":"Panique \u00e0 bord?"},"content":{"rendered":"<p><p>La grande presse am\u00e9ricaine se fait l&rsquo;\u00e9cho insistant de cas de d\u00e9passements budg\u00e9taires des divers programmes en d\u00e9veloppement au Pentagone. Ces cas sont de plus en plus nombreux, ces d\u00e9passements sont de plus en plus monstrueux, alors que le budget du DoD augmente vertigineusement et que les limitations sur les programmes et sur les forces sont de plus en plus pesantes par manque d&rsquo;argent. <\/p>\n<\/p>\n<p><p>\tAvant-hier, le New York <em>Times<\/em>, relay\u00e9 par <LIEN=http:\/\/www.iht.com\/articles\/2005\/04\/24\/opinion\/ednavy.php>The International <em>Herald Tribune<\/em>, s&rsquo;inqui\u00e9tait du sort du programme de destroyers DD(X) de l&rsquo;U.S. Navy, dont le prix unitaire apr\u00e8s d\u00e9rive incontr\u00f4l\u00e9e est pr\u00e9sent\u00e9 officiellement \u00e0 largement plus de $3 milliards, et, en fait, aurait d\u00e9pass\u00e9 les $4 milliards.<\/p>\n<\/p>\n<p><p>\tConstatant l&rsquo;accumulation des technologies dans ce programme \u00e0 mesure de son d\u00e9veloppement, le journal notait que  \u00ab [t]<em>he only realistic answer is to jettison the DD(X) for a redesigned, more cost-effective large combat ship. Unfortunately, America&rsquo;s military contracting system is biased against such a sensible outcome. Like the other services, the navy does not know how to say no to impressive technology, whether it&rsquo;s needed and affordable or not. In addition, consolidation in the defense industry has left only two main contractors capable of producing the navy&rsquo;s ships  Northrop Grumman and General Dynamics  and they apportion the business between them.<\/em> \u00bb<\/p>\n<\/p>\n<p><p>\tIl y a moins d&rsquo;un mois (<LIEN=http:\/\/www.nytimes.com\/2005\/03\/28\/politics\/28weapons.html?ex=1112590800&#038;en=1ba5a30bdf3e64d5&#038;ei=5070>le 28 mars : <em>An Army Program to Build a High-Tech Force Hits Cost Snags<\/em>), le m\u00eame New York <em>Times<\/em> d\u00e9taillait les d\u00e9passements de co\u00fbt du Future Combat Systems de l&rsquo;U.S. Army, un syst\u00e8me de communication qui atteint en pr\u00e9visions budg\u00e9taires pr\u00e8s de $200 milliards et qui, on l&rsquo;a appris r\u00e9cemment, \u00e9tait pr\u00e9vu pour $30-$40 milliards il y a trois ans. Les journaux sont \u00e9galement pleins des annonces de d\u00e9passement budg\u00e9taire des avions de combat F\/A-22 et du F-35 JSF.<\/p>\n<\/p>\n<p><p>\tLa perception d&rsquo;une crise de perte de contr\u00f4le des budgets militaires est en train de se r\u00e9pandre, notamment au Congr\u00e8s. Un lien est fait entre cette situation et l&rsquo;incapacit\u00e9 de l&rsquo;administration d&rsquo;attribuer tous les postes de contr\u00f4le du cabinet civil (actuellement 13 des 47 postes de la direction civile sont vacants). C&rsquo;est Gordon England, ancien secr\u00e9taire \u00e0 la Navy et sur le point d&rsquo;\u00eatre confirm\u00e9 comme n\u00b02 du Pentagone (\u00e0 la place de Wolfowitz), qui va \u00eatre charg\u00e9 de la t\u00e2che d&rsquo;urgence de contr\u00f4ler ce probl\u00e8me qui menace de faire exploser le budget du DoD. <em>Defense News<\/em> \u00e9crit le 25 avril: \u00ab <em>When he moves up to the No. 2 job at the Defense Department, <\/em>[the senators] <em>want him to tackle such tasks as reining in the rising cost of weapons, reforming nine programs labeled high risk by government auditors, writing more realistic budgets and maintaining a larger Navy.<\/em> \u00bb<\/p>\n<\/p>\n<p><p>\tL&rsquo;\u00e8re des id\u00e9ologues \u00e0-la-Wolfowitz (et Douglas Feith) est finie au Pentagone. C&rsquo;est l&rsquo;\u00e8re des comptables, avec England, qui s&rsquo;ouvre. Avec une situation d&rsquo;urgence, une crise qui empire de jour en jour. Du point de vue washingtonien, bien plus grave qu&rsquo;\u00e0 Bagdad.<\/p>\n<\/p>\n<p><\/p>\n<p><p>\tMis en ligne le 27 avril 2005 \u00e0 09H20<\/p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>La grande presse am\u00e9ricaine se fait l&rsquo;\u00e9cho insistant de cas de d\u00e9passements budg\u00e9taires des divers programmes en d\u00e9veloppement au Pentagone. Ces cas sont de plus en plus nombreux, ces d\u00e9passements sont de plus en plus monstrueux, alors que le budget du DoD augmente vertigineusement et que les limitations sur les programmes et sur les forces&hellip;&nbsp;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","footnotes":"","jetpack_post_was_ever_published":false},"categories":[2],"tags":[3127,568,4526,250],"class_list":["post-66360","post","type-post","status-publish","format-standard","hentry","category-bloc-notes","tag-budget","tag-dod","tag-england","tag-jsf"],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/66360","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/comments?post=66360"}],"version-history":[{"count":0,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/66360\/revisions"}],"wp:attachment":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/media?parent=66360"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/categories?post=66360"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/tags?post=66360"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}