{"id":66418,"date":"2005-05-16T00:00:00","date_gmt":"2005-05-16T00:00:00","guid":{"rendered":"https:\/\/new.dedefensa.org\/index.php\/2005\/05\/16\/gw-a-besoin-de-bolton-a-lonu-pour-attaquer-liran\/"},"modified":"2005-05-16T00:00:00","modified_gmt":"2005-05-16T00:00:00","slug":"gw-a-besoin-de-bolton-a-lonu-pour-attaquer-liran","status":"publish","type":"post","link":"https:\/\/new.dedefensa.org\/index.php\/2005\/05\/16\/gw-a-besoin-de-bolton-a-lonu-pour-attaquer-liran\/","title":{"rendered":"<strong><em>GW a besoin de Bolton \u00e0 l&rsquo;ONU pour attaquer l&rsquo;Iran<\/em><\/strong>"},"content":{"rendered":"<p><h2 class=\"common-article\">GW a besoin de Bolton \u00e0 l&rsquo;ONU pour attaquer l&rsquo;Iran<\/h2>\n<\/p>\n<p><\/p>\n<p><p>\t16 mai 2005  \u00ab <em>Stay tuned, especially during June and July<\/em> \u00bb, nous recommande Gordon Prather, dans <a href=\"http:\/\/www.antiwar.com\/prather\/?articleid=5951\" class=\"gen\">sa rubrique du 14 mai sur Antiwar.com<\/a> (il confirme sa recommandation <a href=\"http:\/\/www.antiwar.com\/prather\/?articleid=5953\" class=\"gen\">dans sa chronique du 16 mai<\/a>).<\/p>\n<\/p>\n<p><p>\tAutre recommandation du m\u00eame type, sur le m\u00eame site aujourd&rsquo;hui, <a href=\"http:\/\/www.antiwar.com\/wanniski\/?articleid=5956\" class=\"gen\">celle de Jude Wanniski<\/a> sous la forme d&rsquo;un m\u00e9mo aux s\u00e9nateurs r\u00e9publicains \u00e0 qui on s&rsquo;appr\u00eate \u00e0 faire voter la confirmation de John Bolton comme ambassadeur des USA \u00e0 l&rsquo;ONU. Pourquoi cette urgence? Parce que Bolton doit \u00eatre sur place en juin-juillet, pour la grande bataille onusienne qui devrait d\u00e9boucher sur des raids am\u00e9ricains contre l&rsquo;Iran. Cette analyse rencontre <a href=\"http:\/\/www.dedefensa.org\/article.php?art_id=1392\" class=\"gen\">nos propres analyses<\/a> sur la nomination de Bolton, qui est tr\u00e8s loin d&rsquo;\u00eatre une mise \u00e0 l&rsquo;\u00e9cart ou une voie de garage pour lui. Nous \u00e9crivions le 8 mars:<\/p>\n<\/p>\n<p><\/p>\n<p><p>\t\u00ab <em>D\u00e8s ces premi\u00e8res lignes, une hypoth\u00e8se doit \u00eatre avanc\u00e9e : outre le r\u00f4le g\u00e9n\u00e9ral qu&rsquo;on attend de lui,  ultra-dur, voire violent, dans les d\u00e9bats de l&rsquo;ONU, \u00e0 la fois contre l&rsquo;Organisation et contre les pressions ext\u00e9rieures,  il est possible, sinon probable, que les Etats-Unis pr\u00e9parent avec un homme comme Bolton l&rsquo;\u00e9ventuelle venue de la question iranienne \u00e0 l&rsquo;ONU. Si les n\u00e9gociations entre Europ\u00e9ens et Iraniens n&rsquo;aboutissent pas, cette affaire pourrait effectivement \u00eatre port\u00e9e \u00e0 l&rsquo;ONU par les Am\u00e9ricains \u00e0 la fin juin, et l&rsquo;on peut compter sur Bolton pour en faire une machine de guerre sans pr\u00e9c\u00e9dent onusien dans le registre de la violence.<\/em> \u00bb<\/p>\n<\/p>\n<p><\/p>\n<p><p>\tDes pressions extraordinaires sont exerc\u00e9es sur les s\u00e9nateurs r\u00e9publicains pour qu&rsquo;ils confirment la nomination de Bolton, au nom des imp\u00e9ratifs de s\u00e9curit\u00e9 nationale: si vous ne confirmez pas Bolton, leur est-il dit, vous compromettez la s\u00e9curit\u00e9 nationale des Etats-Unis dans la crise iranienne. Il se confirme de plus en plus nettement que Bolton, s&rsquo;il est confirm\u00e9, aura bien pour mission, \u00e0 l&rsquo;ONU, de d\u00e9terrer la hache de guerre contre l&rsquo;Iran. Il le fera dans sa mani\u00e8re habituelle, sans vergogne ni le moindre scrupule, avec une brutalit\u00e9 extraordinaire, employant tous les moyens possibles,  pressions, espionnage, diverses m\u00e9thodes de coercition, et jusqu&rsquo;aux menaces physiques. Nous vivons des temps extraordinaires, o\u00f9 le souvenir de John Wayne appara\u00eet comme un id\u00e9al de finesse, de mesure et de diplomatie, et ses films comme des mod\u00e8les de situation sous contr\u00f4le.<\/p>\n<\/p>\n<p><p>\tWanniski nous donne en passant une pr\u00e9cieuse indication, avec ce rapport d&rsquo;une intervention du g\u00e9n\u00e9ral en retraite de l&rsquo;USAF Thomas McInerney, qui est la courroie de transmission la plus directe de Rumsfeld, porteur de tous les bobards possibles et de toutes les menaces n\u00e9cessaires,  ici, nous sommes plut\u00f4t au rayon menaces.<\/p>\n<\/p>\n<p><\/p>\n<p><p>\t\u00ab <em>On a recent, quite incredible Fox News special, Lt. Gen. Thomas McInerney said we are already moving aircraft carriers into positions from which we could strike. He was then asked: If you had to put a percentage on it, the chances that the U.S. will eventually have to take military actions against Iran, what would you put it at? to which McInerney replied casually: Well, I would put 1 percent of using ground forces, boots on the ground in Iran, I would put up 50 percent on a blockade, and I would put up 50 to 60 percent on precision air strikes on their nuclear development sites. He also observed casually that Iran wouldn&rsquo;t dare take on the United States. Perhaps the 60 million Iranians would greet our bombers with garlands and sweets. Do you see what I mean? Fox News, as you may know, is commonly known as The War Channel,&rsquo; for similar work it did in promoting the war against Iraq.<\/em> \u00bb <\/p>\n<\/p>\n<p><\/p>\n<p><p>\tLa nouvelle des porte-avions se rassemblant \u00e0 proximit\u00e9 de l&rsquo;Iran <a href=\"http:\/\/www.dedefensa.org\/article.php?art_id=1454\" class=\"gen\">n&rsquo;en est pas vraiment une<\/a>. Dite par McInerney, sur les antennes de <em>Fox News<\/em>, elle nous en dit long sur la volont\u00e9 de l&rsquo;administration GW de dramatiser la situation pour pr\u00e9parer l&rsquo;entr\u00e9e dans le cur de la crise avec l&rsquo;Iran.<\/p>\n<\/p>\n<p><p>\tComme \u00e0 l&rsquo;habitude, les Europ\u00e9ens vont \u00eatre confront\u00e9s \u00e0 des pressions extr\u00eames dans un jeu o\u00f9 ils n&rsquo;ont ni les m\u00eames int\u00e9r\u00eats, ni les m\u00eames libert\u00e9s d&rsquo;action. Pire, ces Europ\u00e9ens sont dans des positions diff\u00e9rentes et incertaines du point de vue int\u00e9rieur, avec par exemple un Blair en difficult\u00e9s et un Chirac pour l&rsquo;instant plac\u00e9 devant l&rsquo;incertitude du r\u00e9f\u00e9rendum. Mais ces incertitudes int\u00e9rieures comptent diff\u00e9remment,  le Britannique est dans une position structurellement faible, le Fran\u00e7ais dans une position conjoncturellement et tr\u00e8s temporairement incertaine. Les Britanniques ont signal\u00e9 des positions diff\u00e9rentes ou des nuances compl\u00e9mentaires, soit en affirmant <a href=\"http:\/\/www.dedefensa.org\/article.php?art_id=1509\" class=\"gen\">leur complet refus de soutenir une attaque US contre l&rsquo;Iran<\/a>, soit en signalant, comme le traduit Prather un peu \u00e0 l&#8217;emporte-pi\u00e8ce: \u00ab <em>Poodle Blair promptly announced, We certainly will support referral to the UN Security Council if Iran breaches its undertakings and obligations.<\/em> \u00bb (L\u00e0-dessus, Prather ajoute justement qu&rsquo;il n&rsquo;y a jamais eu, de la part des Iraniens, ni <em>undertakings<\/em> ni <em>obligations<\/em> dans les n\u00e9gociations en cours, donc qu&rsquo;on ne peut parler de manquement ou de violation au sens l\u00e9gal s&rsquo;ils reprenaient la production d&rsquo;uranium enrichi. Le d\u00e9bat \u00e0 l&rsquo;ONU sera plein de ces interpr\u00e9tations.)<\/p>\n<\/p>\n<p><p>\tIl y aura encore beaucoup de manuvres et d&rsquo;\u00e9volutions tactiques dans cette affaire. Pour le terme de cette s\u00e9quence de la crise, il y a deux remarques \u00e0 proposer:<\/p>\n<\/p>\n<p><p>\t&bull; Quoi qu&rsquo;il se passe, il semble bien se confirmer que juin-juillet sera un moment central de la crise iranienne.<\/p>\n<\/p>\n<p><p>\t&bull; Le but de Washington reste plus que jamais de mettre en place les conditions pour une attaque a\u00e9rienne de l&rsquo;Iran. Sur ce point pr\u00e9cis, les Europ\u00e9ens, Britanniques compris, seront bel et bien plac\u00e9s devant la n\u00e9cessit\u00e9 de refuser leur soutien aux Am\u00e9ricains, ouvrant une crise transatlantique majeure.<\/p>\n<\/p>\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>GW a besoin de Bolton \u00e0 l&rsquo;ONU pour attaquer l&rsquo;Iran 16 mai 2005 \u00ab Stay tuned, especially during June and July \u00bb, nous recommande Gordon Prather, dans sa rubrique du 14 mai sur Antiwar.com (il confirme sa recommandation dans sa chronique du 16 mai). Autre recommandation du m\u00eame type, sur le m\u00eame site aujourd&rsquo;hui, celle&hellip;&nbsp;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[705,4569],"class_list":["post-66418","post","type-post","status-publish","format-standard","hentry","category-faits-et-commentaires","tag-blair","tag-mcinerney"],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/66418","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/comments?post=66418"}],"version-history":[{"count":0,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/66418\/revisions"}],"wp:attachment":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/media?parent=66418"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/categories?post=66418"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/tags?post=66418"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}