{"id":66432,"date":"2005-05-22T00:00:00","date_gmt":"2005-05-22T00:00:00","guid":{"rendered":"https:\/\/new.dedefensa.org\/index.php\/2005\/05\/22\/karzai-ou-les-limites-de-la-servilite\/"},"modified":"2005-05-22T00:00:00","modified_gmt":"2005-05-22T00:00:00","slug":"karzai-ou-les-limites-de-la-servilite","status":"publish","type":"post","link":"https:\/\/new.dedefensa.org\/index.php\/2005\/05\/22\/karzai-ou-les-limites-de-la-servilite\/","title":{"rendered":"Karza\u00ef ou les limites de la servilit\u00e9"},"content":{"rendered":"<p><h2 class=\"titleset_a.deepblue\" style=\"color:#0f3955;font-size:2em;\">Karza\u00ef ou les limites de la servilit\u00e9<\/h2>\n<\/p>\n<p><p>22 mai 2005 &mdash; &Ecirc;tre un alli\u00e9 des USA n&rsquo;est pas chose ais\u00e9e. Blair le sait bien. Mais \u00eatre un alli\u00e9 install\u00e9 et directement manipul\u00e9 par les USA, \u00ab\u00a0une marionnette\u00a0\u00bb (<em>pupett<\/em>) comme l&rsquo;on dit, devient quasiment impossible. L&rsquo;Afghan Karza\u00ef s&rsquo;en aper\u00e7oit, alors que son pays est plong\u00e9 dans un nouveau scandale des tortures US, qui vaut bien celui d&rsquo;Abou Ghraib, en Irak, il y a exactement un an.<\/p>\n<\/p>\n<p><p>Karza\u00ef arrive aujourd&rsquo;hui aux USA pour des entretiens et il annonce qu&rsquo;il soul\u00e8vera la question des tortures et, plus g\u00e9n\u00e9ralement, du comportement et du contr\u00f4le des forces arm\u00e9es US. <a class=\"gen\" href=\"http:\/\/news.independent.co.uk\/world\/middle_east\/story.jsp?story=640378\">The Independent d&rsquo;aujourd&rsquo;hui<\/a> note ceci :<\/p>\n<\/p>\n<blockquote class=\"normal\" style=\"font-size:1.05em;\">\n<p><p>&laquo; <em>Afghanistan&rsquo;s President has demanded \u00ab\u00a0very, very strong\u00a0\u00bb action by the United States against any military personnel found to be abusing prisoners, after a newspaper revealed maltreatment of detainees at the main US base in Kabul.<\/em><\/p>\n<\/p>\n<p><p>&raquo; <em>President Hamid Karzai also demanded greater control over US military operations here, including an end to raids by American troops on Afghans&rsquo; homes without the knowledge of his administration.<\/em><\/p>\n<\/p>\n<p><p>&raquo; <em>\u00ab\u00a0No operations inside Afghanistan should take place without the consultation of the Afghan government,\u00a0\u00bb the President said. He will raise both issues when he meets American leaders during a four-day visit to the US starting today.<\/em> &raquo;<\/p>\n<\/p>\n<\/blockquote>\n<p><p>Bien entendu, il n&rsquo;est pas question de voir dans le comportement de Karza\u00ef un brusque tournant politique, une \u00ab\u00a0trahison\u00a0\u00bb du contr\u00f4le am\u00e9ricain. Il s&rsquo;agit d&rsquo;une simple attitude de survie. La situation en Afghanistan est devenue intenable, quant aux rapports entre la population et les diff\u00e9rentes forces dont d\u00e9pend Karza\u00ef au niveau int\u00e9rieur, et les forces am\u00e9ricaines dont le comportement est compl\u00e8tement brutal et hors de tout contr\u00f4le. Les r\u00e9centes manifestations pour l&rsquo;affaire du Coran d\u00e9sacralis\u00e9, avec les victimes caus\u00e9es par ces m\u00eames forces US, ont montr\u00e9 \u00e0 Karza\u00ef l&rsquo;extr\u00eame fragilit\u00e9 de sa position. On se rapproche du point o&ugrave; il deviendrait plus pressant pour Karza\u00ef d&rsquo;agir pour garder le soutien de la population et des diff\u00e9rents chefs locaux, que de continuer \u00e0 suivre les consignes US. D\u00e9sormais, les deux obligations se contredisent directement.<\/p>\n<\/p>\n<p><p>Bien entendu, Karza\u00ef n&rsquo;obtiendra rien aux USA, car la politique Bush-Rumsfeld est non seulement de soutenir les exc\u00e8s de leurs forces m\u00eame s&rsquo;ils sacrifient ici ou l\u00e0 quelques lampistes, mais parce que cette politique va plus loin encore : elle est bas\u00e9e sur les exc\u00e8s des forces US. Il est aujourd&rsquo;hui manifeste que la \u00ab\u00a0politique\u00a0\u00bb militaire de Washington est bas\u00e9e sur deux \u00ab\u00a0principes\u00a0\u00bb :<\/p>\n<\/p>\n<p><p>&bull; Employer tous les moyens contre tous les suspects, c&rsquo;est-\u00e0-dire les contraintes, la torture, les abus de toutes sortes, y compris contre des innocents puisque la qualit\u00e9 ex\u00e9crable du renseignement et des forces US conduit \u00e0 faire de l&rsquo;erreur sur la personne une sorte de syst\u00e8me g\u00e9n\u00e9ral d&rsquo;action. Les territoires de cette \u00ab\u00a0action\u00a0\u00bb sont bien s&ucirc;r, en premier lieu, l&rsquo;Irak et <a class=\"gen\" href=\"http:\/\/www.guardian.co.uk\/afghanistan\/story\/0,1284,1488919,00.html\">l&rsquo;Afghanistan<\/a>.<\/p>\n<\/p>\n<p><p>&bull; Laisser toute latitude d&rsquo;action aux forces US, c&rsquo;est-\u00e0-dire accepter qu&rsquo;elles soient compl\u00e8tement incontr\u00f4lables, y compris aux plus irresponsables d&rsquo;entre elles : les forces sp\u00e9ciales et les contractants priv\u00e9s de mercenaires. Leurs actions l\u00e0 o&ugrave; ces forces se trouvent dans les pays qui y sont soumis, &mdash; l&rsquo;Afghanistan et l&rsquo;Irak, &mdash; font de ces pays des territoires mis \u00e0 sac, expos\u00e9s \u00e0 l&rsquo;arbitraire et au racket.<\/p>\n<\/p>\n<p><p>L&rsquo;action am\u00e9ricaine est \u00e0 l&rsquo;image de son gouvernement : compl\u00e8tement unilat\u00e9rale, indiff\u00e9rente aux lois qui ne proc\u00e8dent pas du maintien du conformisme, des privil\u00e8ges et des int\u00e9r\u00eats en place \u00e0 l&rsquo;int\u00e9rieur du syst\u00e8me, soumise aux lois (\u00e0 l&rsquo;absence de lois) de l&rsquo;\u00e9conomie priv\u00e9e, du profit et de l&rsquo;arbitraire. Il s&rsquo;agit d&rsquo;un syst\u00e8me compl\u00e8tement d\u00e9gag\u00e9 de tout contr\u00f4le r\u00e9galien, agissant comme le font les gangs du crime organis\u00e9 ou les entreprises multinationales am\u00e9ricaines.<\/p>\n<\/p>\n<p><p>C&rsquo;est loin d&rsquo;\u00eatre un probl\u00e8me accessoire pour la politique am\u00e9ricaine, dont on pourrait croire que l&rsquo;essentiel repose sur sa strat\u00e9gie. La principale raison est que la politique US ne repose sur aucune strat\u00e9gie ; son action \u00ab\u00a0tactique\u00a0\u00bb g\u00e9n\u00e8re naturellement une strat\u00e9gie qui est celle du d\u00e9sordre avec toutes ses tares, et de l&rsquo;inefficacit\u00e9. Aujourd&rsquo;hui, le caract\u00e8re insupportable de la pression am\u00e9ricaine touche encore plus les alli\u00e9s des Am\u00e9ricains que les autres. Karza\u00ef est un exemple. L&rsquo;Irak en est un autre, mais qui va dans un sens diff\u00e9rent, plut\u00f4t <a class=\"gen\" href=\"http:\/\/www.wpherald.com\/storyview.php?StoryID=20050520-123904-7147r\">vers une alliance avec l&rsquo;Iran<\/a> qui heurtera tr\u00e8s vite les int\u00e9r\u00eats US. D&rsquo;autres pays sont dans ce m\u00eame cas d&rsquo;une alliance am\u00e9ricaine insupportable : l&rsquo;&Eacute;gypte, l&rsquo;Arabie&hellip; Certains parlent m\u00eame d&rsquo;Isra\u00ebl, o&ugrave; la conscience ne cesse de grandir qu&rsquo;une v\u00e9ritable r\u00e9solution du probl\u00e8me de la s\u00e9curit\u00e9 de ce pays passe par un effacement am\u00e9ricain, g\u00e9n\u00e9rateur continuel du d\u00e9sordre de la r\u00e9gion.<\/p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Karza\u00ef ou les limites de la servilit\u00e9 22 mai 2005 &mdash; &Ecirc;tre un alli\u00e9 des USA n&rsquo;est pas chose ais\u00e9e. Blair le sait bien. Mais \u00eatre un alli\u00e9 install\u00e9 et directement manipul\u00e9 par les USA, \u00ab\u00a0une marionnette\u00a0\u00bb (pupett) comme l&rsquo;on dit, devient quasiment impossible. L&rsquo;Afghan Karza\u00ef s&rsquo;en aper\u00e7oit, alors que son pays est plong\u00e9 dans&hellip;&nbsp;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[3236,4575,4576,4079],"class_list":["post-66432","post","type-post","status-publish","format-standard","hentry","category-faits-et-commentaires","tag-afghanistan","tag-karzai","tag-marionnette","tag-servilite"],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/66432","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/comments?post=66432"}],"version-history":[{"count":0,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/66432\/revisions"}],"wp:attachment":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/media?parent=66432"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/categories?post=66432"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/tags?post=66432"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}