{"id":66448,"date":"2005-05-28T00:00:00","date_gmt":"2005-05-28T00:00:00","guid":{"rendered":"https:\/\/new.dedefensa.org\/index.php\/2005\/05\/28\/de-the-economist-aux-souverainistes-meme-combat\/"},"modified":"2005-05-28T00:00:00","modified_gmt":"2005-05-28T00:00:00","slug":"de-the-economist-aux-souverainistes-meme-combat","status":"publish","type":"post","link":"https:\/\/new.dedefensa.org\/index.php\/2005\/05\/28\/de-the-economist-aux-souverainistes-meme-combat\/","title":{"rendered":"De The Economist aux souverainistes, m\u00eame combat"},"content":{"rendered":"<p><p><em>The Economist<\/em> est un hebdomadaire connu, prestigieux et id\u00e9ologiquement tr\u00e8s marqu\u00e9 parce qu&rsquo;identifi\u00e9 sans h\u00e9sitationcomme un d\u00e9fenseur de la globalisation, du march\u00e9 libre et de l&rsquo;ouverture des fronti\u00e8res. Dans son num\u00e9ro qui salue les deux r\u00e9f\u00e9rendums, il nous offre <a href=\"http:\/\/www.economist.com\/opinion\/\" class=\"gen\">un plaidoyer ferme<\/a> pour le non. C&rsquo;est un signe convainquant de la confusion qui accompagne la signification et la caract\u00e9risation des choix, au contraire de la nettet\u00e9 du caract\u00e8re r\u00e9volutionnaire de la campagne r\u00e9f\u00e9rendaire.<\/p>\n<\/p>\n<p><p>\tUn courrier officieux europ\u00e9en nous donne cette analyse du contenu de l&rsquo;\u00e9ditorial du magazine britannique:<\/p>\n<\/p>\n<p><p>\t\u00ab <em>L&rsquo;influent hebdomadaire \u00e9conomique britannique The Economist appelle vendredi Fran\u00e7ais et N\u00e9erlandais \u00e0 voter non \u00e0 la Constitution europ\u00e9enne, assurant qu&rsquo;un tel rejet permettrait une pause pour r\u00e9fl\u00e9chir, et ne constituerait nullement une catastrophe pour l&rsquo;union. Non&rsquo; serait la bonne r\u00e9ponse lors des r\u00e9f\u00e9rendums fran\u00e7ais et n\u00e9\u00e9rlandais (&#8230;) et une bonne r\u00e9ponse pour l&rsquo;Europe, d\u00e9clare l&rsquo;hebdomadaire dans son \u00e9ditorial. Une d\u00e9faite de la Constitution ne serait pas la catastrophe que certains europhiles semblent penser: la vie suivrait son cours, m\u00eame \u00e0 Bruxelles, et une Union qui a v\u00e9cu pendant pr\u00e8s d&rsquo;un demi-si\u00e8cle est certainement assez forte pour s&rsquo;accommoder d&rsquo;une rebuffade occasionnelle des \u00e9lecteurs. Si elle r\u00e9pond en faisant une pause pour r\u00e9fl\u00e9chir, cela pourrait m\u00eame \u00eatre profitable, affirme The Economist.<\/em><\/p>\n<\/p>\n<p><p>\t\u00bb <em> Le journal estime que les divergences de vues et les pr\u00e9jug\u00e9s nationaux dans l&rsquo;Union europ\u00e9enne sont tellement importants qu&rsquo;il est erron\u00e9 de tenter de faire entrer de plus en plus de domaines dans un cadre unique. Un tel processus centralisateur a des limites. Un processus \u00e9loign\u00e9 des gens a peu de chances de rester longtemps populaire. Et une Union plus large, qu&rsquo;elle soit comme avant \u00e0 15, aujourd&rsquo;hui \u00e0 25, ou m\u00eame plus grande dans l&rsquo;avenir, a plus de chances de s&rsquo;\u00e9loigner que de se rapprocher (des populations), surtout si elle adopte de plus en plus de politiques communes. The Economist affirme \u00e9galement que la r\u00e9forme envisag\u00e9e par le trait\u00e9 constitutionnel est tr\u00e8s ambigu\u00eb. Il va transf\u00e9rer de nouveaux pouvoirs, des gouvernements nationaux vers l&rsquo;Union, mais avec des effets dont personne ne peut \u00eatre s\u00fbr.<\/em> \u00bb<\/p>\n<\/p>\n<p><p>\tC&rsquo;est une caract\u00e9ristique tr\u00e8s forte de la crise actuelle que les effets de la pol\u00e9mique de la Constitution renvoient dans un m\u00eame camp des groupes totalement oppos\u00e9s dans leurs conceptions,  comme, pour ce cas, <em>The Economist<\/em> compar\u00e9, par exemple, aux souverainistes ou aux altermondialistes fran\u00e7ais.  Il est remarquable de constater combien chacun lit dans la Constitution ce qui le pr\u00e9occupe,  plut\u00f4t que ce qui l&rsquo;arrange,  m\u00eame s&rsquo;il s&rsquo;agit de choses compl\u00e8tement oppos\u00e9es. C&rsquo;est un signe pr\u00e9occupant quant \u00e0 la validit\u00e9 de cette Constitution qui est le salmigondis qu&rsquo;on sait : elle ne parvient qu&rsquo;\u00e0 fixer sur elle tous les m\u00e9contentements possibles, au lieu de rassembler les satisfactions (alors que les uns et les autres peuvent y trouver leur d\u00fb).  <\/p>\n<\/p>\n<p><p>\tPar ailleurs, et quelles que soient les arri\u00e8re-pens\u00e9es de <em>The Economist<\/em>, certainement vastes et complexes, l&rsquo;argumentaire dont on a lu un extrait peut \u00eatre consid\u00e9r\u00e9 comme marqu\u00e9 d&rsquo;un excellent bon sens. Cela ne signifie pas que <em>The Economist<\/em> a raison pour la globalisation et le reste mais que ses journalistes sont intelligents,  nul n&rsquo;en a jamais dout\u00e9  et qu&rsquo;il y a quelque chose d&rsquo;\u00e9vident dans l&rsquo;opposition \u00e0 la Constitution,  ce qui est le handicap le plus grand de ce texte.<\/p>\n<\/p>\n<p><\/p>\n<p><p>\tMis en ligne le 28 mai 2005 \u00e0 06H00<\/p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>The Economist est un hebdomadaire connu, prestigieux et id\u00e9ologiquement tr\u00e8s marqu\u00e9 parce qu&rsquo;identifi\u00e9 sans h\u00e9sitationcomme un d\u00e9fenseur de la globalisation, du march\u00e9 libre et de l&rsquo;ouverture des fronti\u00e8res. Dans son num\u00e9ro qui salue les deux r\u00e9f\u00e9rendums, il nous offre un plaidoyer ferme pour le non. C&rsquo;est un signe convainquant de la confusion qui accompagne la&hellip;&nbsp;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","footnotes":"","jetpack_post_was_ever_published":false},"categories":[2],"tags":[4518,398,1225],"class_list":["post-66448","post","type-post","status-publish","format-standard","hentry","category-bloc-notes","tag-constitution","tag-europe","tag-referendum"],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/66448","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/comments?post=66448"}],"version-history":[{"count":0,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/66448\/revisions"}],"wp:attachment":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/media?parent=66448"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/categories?post=66448"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/tags?post=66448"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}