{"id":66476,"date":"2005-06-04T00:00:00","date_gmt":"2005-06-04T00:00:00","guid":{"rendered":"https:\/\/new.dedefensa.org\/index.php\/2005\/06\/04\/un-moment-sublime-rubrique-analyse-volume-20-n17-du-25-mai-2005\/"},"modified":"2005-06-04T00:00:00","modified_gmt":"2005-06-04T00:00:00","slug":"un-moment-sublime-rubrique-analyse-volume-20-n17-du-25-mai-2005","status":"publish","type":"post","link":"https:\/\/new.dedefensa.org\/index.php\/2005\/06\/04\/un-moment-sublime-rubrique-analyse-volume-20-n17-du-25-mai-2005\/","title":{"rendered":"<strong><em>Un moment \u201csublime\u201d? \u2014 Rubrique Analyse, Volume 20, n\u00b017 du 25 mai 2005<\/em><\/strong>"},"content":{"rendered":"<p><h2 class=\"common-article\">Un moment sublime?<\/h2>\n<\/p>\n<p><p>\t<strong>Nous sommes \u00e0 la veille du 29 mai. Laissons de c\u00f4t\u00e9 les pronostics, les certitudes et les incertitudes. Cessons de jouer au loto. Essayons de comprendre l&rsquo;esprit de cette campagne r\u00e9f\u00e9rendaire, qui renvoie \u00e0 une autre \u00e9poque tout ce qui a pr\u00e9c\u00e9d\u00e9 (y compris la glorieuse campagne de Maastricht). Tentons de distinguer l&rsquo;aspect sublime de ce moment de l&rsquo;Histoire.<\/strong><\/p>\n<\/p>\n<p><\/p>\n<p><p>\tUne fois de plus, le dilemme du chroniqueur trop attach\u00e9 aux \u00e9v\u00e9nements du temps courant. En choisissant de consacrer une analyse au r\u00e9f\u00e9rendum fran\u00e7ais,  une de plus, qui nous paraissait imp\u00e9rative, nous nous trouvions devant la perspective de donner \u00e0 lire un texte \u00e9crit dans l&rsquo;incertitude de la campagne, \u00e0 des esprits qui conna\u00eetraient la certitude du r\u00e9sultat. Il fallait choisir quelque chose qui f\u00fbt intemporel et qui, dans le feu de l&rsquo;action, tent\u00e2t d\u00e9j\u00e0 d&rsquo;en d\u00e9gager l&rsquo;esprit.<\/p>\n<\/p>\n<p><p>\tDes \u00e9v\u00e9nements autour des 2-3 mai, d\u00e9j\u00e0 signal\u00e9s par ailleurs, nous en donn\u00e8rent l&rsquo;occasion. Nous les r\u00e9sumerons \u00e0 deux, qui nous sugg\u00e8rent la voie \u00e0 suivre.<\/p>\n<\/p>\n<p><p>\t&bull; Le premier est cette quasi-analogie, dans le cas de cette paternit\u00e9 que Chirac livra aux Fran\u00e7ais le 3 mai au soir, devant ses journalistes habituels. Il fit de la Constitution europ\u00e9enne la fille spirituelle de la R\u00e9volution fran\u00e7aise. Cela devrait, avaient pens\u00e9 les esprits f\u00e9conds de la communication, plaire au peuple de gauche de la France, pr\u00e9tendument le plus r\u00e9tif.<\/p>\n<\/p>\n<p><p>\t&bull; Le second est ce rassemblement, en troupeau culturel et europ\u00e9en, des artistes \u00e9galement europ\u00e9ens, les 2 et 3 mai, \u00e0 Paris, berceau et relais oblig\u00e9 de la civilisation europ\u00e9enne. Il faut prendre la mesure de ce rassemblement extraordinaire, libert\u00e9 d&rsquo;esprit et force de cr\u00e9ation mises en troupeau pour faire assaut de conformisme. Il faut songer \u00e0 ce qu&rsquo;en eussent dit Baudelaire, Flaubert, Tocqueville et les fr\u00e8res Goncourt, ces grandes \u00e2mes si pleines de tristesse accabl\u00e9e devant l&rsquo;esprit d\u00e9mocratique. Les artistes s&rsquo;ex\u00e9cut\u00e8rent. Ils firent leur floril\u00e8ge. Ils dirent ceci (en anglais international, car c&rsquo;est la langue qui convient aux pens\u00e9es profondes). \u00ab <em>I am voting &lsquo;yes&rsquo;. It is as if you were walking by a stream and you came to a river. What do you do? Stay on the river bank? No. You get on a boat and see where it takes you.<\/em> \u00bb (Jeanne Moreau) \u00ab <em>Don&rsquo;t bore yourselves reading all 800 pages of the treaty. Just vote &lsquo;yes&rsquo;. It&rsquo;s so important.<\/em> \u00bb (Viviane Westwood, styliste \u00e0 Londres) \u00ab <em>We, the French, cannot remain outside Europe. That would be taking a step backwards. It would not be a good thing.<\/em> \u00bb (Johnny Halliday) Retenez ces phrases, <em>it&rsquo;s so important<\/em>.<\/p>\n<h3>Malgr\u00e9 la m\u00e9diocrit\u00e9 de la campagne du r\u00e9f\u00e9rendum&#8230;<\/h3>\n<\/p>\n<p><p>\tNous pourrions ironiser en observant que nous voil\u00e0 si charg\u00e9s des r\u00e9flexions de l&rsquo;Art sur l&rsquo;\u00e9v\u00e9nement, que nous pouvons aborder l&rsquo;analyse de l&rsquo;\u00e9v\u00e9nement. Nous ne le ferons pas (quoique, dire qu&rsquo;on ne le dit pas, c&rsquo;est tout de m\u00eame le dire&#8230;). Il n&#8217;emp\u00eache: ces quelques citations et avis nous sugg\u00e8rent la voie, d&rsquo;une fa\u00e7on assez arrangeante.<\/p>\n<\/p>\n<p><p>\tIl existe aujourd&rsquo;hui un int\u00e9r\u00eat nouveau pour les antimodernes. Antoine Compagnon, qui est professeur de lettres fran\u00e7aises \u00e0 la Sorbonne et \u00e0 Columbia (New York) consacre une \u00e9tude sur ce courant politique (<em>Les antimodernes, de Joseph de Maistre \u00e0 Roland Barthes<\/em>). Les antimodernes ne sont pas simplement des traditionalistes ou des r\u00e9actionnaires, ou des conservateurs. Il s&rsquo;agit d&rsquo;abord de modernes d\u00e9\u00e7us par le modernisme et devenus les ennemis les plus acharn\u00e9s du modernisme. (Un peu comme on fait les meilleurs anti-communistes et anti-am\u00e9ricanistes de ceux qui furent admirateurs de l&rsquo;URSS et des USA.) Inutile d&rsquo;ajouter que la cohorte des antimodernes, depuis la r\u00e9volution fran\u00e7aise (c&rsquo;est \u00e0 ce moment que na\u00eet ce courant), est prodigieuse d&rsquo;abondance et de talent, en France bien entendu mais aussi hors de France (Burke, Joseph de Maistre, Chateaubriand, Baudelaire, Flaubert, Schopenhauer, Nietzsche, P\u00e9guy, Proust, Bataille, Barthes, etc.)<\/p>\n<\/p>\n<p><p>\tUn des chapitres du livre de Compagnon est intitul\u00e9: <em>Sublime<\/em>. Il caract\u00e9rise l&rsquo;un des aspects de la pens\u00e9e des antimodernes, pour ce sentiment esth\u00e9tique qui d\u00e9passe le Beau, qui se situe par-del\u00e0 le Bien et le Mal (l&rsquo;\u00e9v\u00e9nement sublime peut-\u00eatre bon et mauvais dans ses effets politiques, il a quelque chose \u00e0 la fois de magique et de m\u00e9taphysique). Cette partie commence \u00e9galement sur un rappel de la distinction fondamentale que faisait Joseph de Maistre entre la politique exp\u00e9rimentale (la politique courante s&rsquo;appuyant sur l&rsquo;exp\u00e9rience hist- orique) et la m\u00e9tapolitique (celle qui manifeste l&rsquo;Histoire dans ses grands courants, jug\u00e9e providentialiste par Maistre). Maistre expliquait son appr\u00e9ciation par une r\u00e9f\u00e9rence \u00e0 Saint-Paul: \u00ab <em>Ce monde est un syst\u00e8me de choses invisibles manifest\u00e9es visiblement.<\/em> \u00bb<\/p>\n<\/p>\n<p><p>\tJoseph de Maistre est le premier des antimodernes et il l&rsquo;est parfaitement puisqu&rsquo;il vient de la franc-ma\u00e7onnerie et des id\u00e9es des Lumi\u00e8res. Devenu anti-r\u00e9volutionnaire radical, autant par la pratique que par la lecture de Burke, il ne cessera d&rsquo;appr\u00e9cier la R\u00e9volution comme l&rsquo;\u00e9v\u00e9nement proche du Mal absolu et pourtant comme un moment sublime de l&rsquo;Histoire. Il l&rsquo;observe comme un \u00e9v\u00e9nement d\u00e9vastateur, sauvage, vulgaire, mais portant en lui une f\u00e9condit\u00e9 cach\u00e9e et les germes d&rsquo;une renaissance, peut-\u00eatre justement \u00e0 cause de sa radicalit\u00e9. La R\u00e9volution n&rsquo;est pas un \u00e9v\u00e9nement, c&rsquo;est un temps historique nouveau.<\/p>\n<\/p>\n<p><p>\tC&rsquo;est ainsi que la R\u00e9volution est sublime, par ses aspects horribles et d\u00e9testables, c\u00f4toyant des aspects d&rsquo;une importance cr\u00e9atrice potentielle incommensurable. Chirac, avec sa filiation entre la R\u00e9volution et la Constitution, qui est une des plus mirobolantes trouvailles de communicateurs-historiens plut\u00f4t que d&rsquo;historiens sachant communiquer, ouvre la voie \u00e0 notre hypoth\u00e8se. Au moins, son id\u00e9e, celle du communicateur-historien, aura servi \u00e0 quelque chose.<\/p>\n<\/p>\n<p><p>\tC&rsquo;est en effet l&rsquo;id\u00e9e du moment m\u00e9tapolitique sublime, \u00e0 l&rsquo;image de la R\u00e9volution, que nous voudrions proposer pour le r\u00e9f\u00e9rendum. Loin de nous,  r\u00e9crions-nous vertueusement,  d&rsquo;y voir la cruaut\u00e9 et la violence de la R\u00e9volution. Nous vivons des temps diff\u00e9rents. On ne massacre plus de fa\u00e7on salissante. La peine de mort est abolie. Les droits de l&rsquo;homme sont partout proclam\u00e9s. Si la TV n&rsquo;est pas l\u00e0, le massacre n&rsquo;existe pas. Si elle est l\u00e0, le massacre est progressiste (\u00ab <em>les bombardements humanitaires<\/em> \u00bb de Havel, du temps du Kosovo) ou de haute technologie et au profit exclusif de la d\u00e9mocratie (Irak). D&rsquo;ailleurs, comme en Irak, notre politique est de ne pas d\u00e9compter les morts civils. Bref, l&rsquo;\u00e2me et la conscience en paix, ce qui est un beau progr\u00e8s par rapport \u00e0 la R\u00e9volution. N\u00e9anmoins, nous tenons \u00e0 notre analogie r\u00e9f\u00e9rendum-R\u00e9volution.<\/p>\n<h3>Analyse de la campagne<\/h3>\n<\/p>\n<p><p>\tL&rsquo;\u00e9tat d\u00e9pressif de la soci\u00e9t\u00e9 fran\u00e7aise et l&rsquo;\u00e9tat cr\u00e9pusculaire des \u00e9lites fran\u00e7aises ne pouvaient laisser esp\u00e9rer autre chose que ce que nous e\u00fbmes durant la campagne, si l&rsquo;on s&rsquo;en tient \u00e0 son seul contenu politique. Dans ce cas, le oui et le non partagent une responsabilit\u00e9 semblable. Ni les uns ni les autres, chez les partisans des deux camps, ne parvinrent vraiment, du point de vue politique, \u00e0 offrir cette alchimie miraculeuse qu&rsquo;on nomme, d&rsquo;une expression malheureusement galvaud\u00e9e: <strong>\u00e9lever le d\u00e9bat<\/strong> (le rendre plus grand et plus noble). A aucun moment, on n&rsquo;eut la sensation, toujours dans ce domaine du contenu, d&rsquo;atteindre \u00e0 ce que nous avons d\u00e9sign\u00e9, par le rappel historique ci-dessus, comme un moment sublime. Nulle part il ne manqua de volont\u00e9 affich\u00e9e, de tentatives \u00e9chevel\u00e9es d&rsquo;y parvenir, mais l&rsquo;on ne parvint qu&rsquo;\u00e0 la pompe et \u00e0 l&#8217;emphase, \u00e0 la rage impuissante, au travers arrogant de la censure intellectuelle et de la terreur conformiste, \u00e0 la faiblesse de se r\u00e9fugier dans la victimisation. Cette campagne fut, comme on dit dans le parler local en Wallonie, du type <em>ji vou, ji n&rsquo;pou<\/em> (je voudrais bien mais je ne peux pas, en substance: je voudrais bien \u00eatre mais je ne peux pas, sinon para\u00eetre).<\/p>\n<\/p>\n<p><p>\tLe oui ne parvint pas \u00e0 \u00e9carter les deux travers dont est affect\u00e9e l&rsquo;action des \u00e9lites, qui sont les seules et pi\u00e8tres armes dont ces \u00e9lites disposent pour ne pas c\u00e9der \u00e0 la honte de la r\u00e9alisation du conformisme de fer auquel elles se soumettent: la propagande et l&rsquo;affirmation terroriste. Il y eut un d\u00e9luge de propagande par tous les moyens dont dispose l&rsquo;\u00e2me damn\u00e9e de ces \u00e9lites, qui est la communication. Il y eut le n\u00e9gativisme de la diabolisation de l&rsquo;adversaire, sa r\u00e9duction \u00e0 des travers indignes et injustifi\u00e9s (le \u00ab <em>on ne peut \u00eatre europ\u00e9en et voter non<\/em> \u00bb, simplement grotesque). Il y eut la description <em>a contrario<\/em> d&rsquo;un tableau apocalyptique en cas de victoire de cet adversaire. Ce dernier point a constitu\u00e9 le principal argument de la campagne du oui,  l&rsquo;isolement de la France en cas de non. C&rsquo;est un argument indigne, dont l&rsquo;indignit\u00e9 fut renforc\u00e9e du grotesque involontaire de faire appel \u00e0 des \u00e9lites europ\u00e9ennes rameut\u00e9es en masse \u00e0 Paris, montrant que le d\u00e9bat \u00e9tait europ\u00e9en et non fran\u00e7ais, et que tout pouvait arriver en cas de victoire du non, sauf l&rsquo;isolement de la France. Le jugement britannique (\u00ab <em>If Britain alone votes no, it is a problem for Britain. If France votes no, it is a problem for Europe<\/em> \u00bb) fut confirm\u00e9 par le Commissaire europ\u00e9en \u00e0 la justice (27 avril, <em>Le Figaro<\/em>): si la France vote non, \u00ab <em>\u00e0 mon avis, on va devoir rouvrir le d\u00e9bat public europ\u00e9en. Si la France, pays fondateur, vote non, cela d\u00e9montrera qu&rsquo;il y a un d\u00e9ficit de l\u00e9gitimit\u00e9 populaire en Europe. Il faudra alors engager le d\u00e9bat bien plus largement, notamment avec les Parlements nationaux.<\/em> \u00bb<\/p>\n<\/p>\n<p><p>\tLe non fit une campagne furieuse, rageuse ou ironique, souvent confuse et \u00e0 fleur de peau, ou bien trop technicienne pour faire mesurer l&rsquo;ampleur de l&rsquo;enjeu. S&rsquo;il tentait d&rsquo;\u00eatre lyrique, il l&rsquo;\u00e9tait sans substance, ramenant le probl\u00e8me europ\u00e9en \u00e0 des r\u00e9criminations fran\u00e7aises, pr\u00eatant ainsi le flanc \u00e0 la critique d&rsquo;anti- europ\u00e9anisme qui lui \u00e9tait adress\u00e9e. D&rsquo;une fa\u00e7on g\u00e9n\u00e9rale, le non se pr\u00e9senta en position d\u00e9fensive, m\u00eame lorsqu&rsquo;il \u00e9tait en t\u00eate. Le non a manqu\u00e9 d&rsquo;imagination et d&rsquo;audace, il a manqu\u00e9 l&rsquo;occasion d&rsquo;\u00eatre effectivement europ\u00e9en,  alors qu&rsquo;il l&rsquo;\u00e9tait \u00e9videmment. Il a rat\u00e9 l&rsquo;occasion sublime (le mot est bien l\u00e0) qui est l&rsquo;article sur la d\u00e9pendance de l&rsquo;OTAN, sur l&rsquo;ind\u00e9pendance et l&rsquo;autonomie de l&rsquo;Europe,  c&rsquo;est-\u00e0-dire sur l&rsquo;Europe-puissance. A ce point, un vrai, grand, sublime d\u00e9bat e\u00fbt \u00e9t\u00e9 ouvert et l\u00e0, vraiment, le meilleur et le plus digne l&rsquo;e\u00fbt emport\u00e9. Le non a faut\u00e9 et s&rsquo;est abaiss\u00e9, quoique dans un autre registre, pas loin du niveau du oui. Dommage pour lui. Le oui n&rsquo;a pas saisi l&rsquo;occasion sublime de son c\u00f4t\u00e9, qui e\u00fbt \u00e9t\u00e9 de tendre la main au non, de le comprendre sans l&rsquo;approuver, de se poser en rassembleur et d&rsquo;ainsi confirmer sa pr\u00e9tention d&rsquo;\u00eatre majoritaire.<\/p>\n<\/p>\n<p><p>\tD&rsquo;un autre c\u00f4t\u00e9, cette double d\u00e9ception \u00e9tait in\u00e9vitable, puisque la campagne a d&rsquo;abord refl\u00e9t\u00e9 la crise qui d\u00e9chire la France, non pas d&rsquo;une France diff\u00e9rente des autres \u00e0 cet \u00e9gard, mais d&rsquo;une France exposant de fa\u00e7on plus nette que les autres un trouble qui touche tous les pays europ\u00e9ens.<\/p>\n<\/p>\n<p><p>\tCela explique finalement le c\u00f4t\u00e9 n\u00e9gatif, d\u00e9fensif, de toute la campagne (m\u00eame si celle-ci ne manqua ni de fi\u00e8vre ni de passion,  nous parlons du fond qui fut n\u00e9gatif, m\u00eame si l&rsquo;esprit fut extr\u00eamement passionn\u00e9). Cette campagne se trouvait devant le cas difficile de devoir marier une situation nationale qui pesait de tout son poids,  comme c&rsquo;est la logique m\u00eame des choses,  et une situation europ\u00e9enne qui \u00e9tait le sujet d\u00e9battu et sur laquelle tout aurait d\u00fb se concentrer. Les deux camps adverses \u00e9taient prisonniers de leur incapacit\u00e9 de passer d&rsquo;une dimension (nationale) \u00e0 l&rsquo;autre (europ\u00e9enne), par l&rsquo;absence d&rsquo;information concr\u00e8te (sur la r\u00e9alit\u00e9 des choses europ\u00e9ennes, diff\u00e9rant de l&rsquo;aspect formel d&rsquo;un texte) et des apriorismes d&rsquo;une force incroyable qui triomphaient dans les deux camps.<\/p>\n<\/p>\n<p><p>\tPour le camp du oui, l&rsquo;amalgame \u00e9tait impossible entre la crise nationale et la crise europ\u00e9enne puisque, par d\u00e9finition, le vote positif doit r\u00e9soudre la crise fran\u00e7aise en passant au niveau europ\u00e9en,  o\u00f9, selon la n\u00e9cessit\u00e9 de la dialectique virtualiste, ne r\u00e8gne pas la crise, o\u00f9, effectivement, la situation est un rem\u00e8de de la crise fran\u00e7aise. Pour le camp du non, l&rsquo;amalgame \u00e9tait \u00e9galement impossible puisque la crise nationale est justement la cons\u00e9quence de la perversit\u00e9 europ\u00e9enne actuelle, donc la plaidoirie sur la crise fran\u00e7aise se pla\u00e7ait, selon une n\u00e9cessit\u00e9 implicite difficile \u00e0 \u00e9carter, en opposition \u00e0 une Europe per\u00e7ue comme malfaisante et manipulatrice.<\/p>\n<\/p>\n<p><p>\tC&rsquo;est bien dommage. Si les Fran\u00e7ais acceptaient l&rsquo;id\u00e9e que leur crise est un reflet d&rsquo;une crise de civilisation colossale, qui touche \u00e9galement l&rsquo;Europe, le d\u00e9bat oui-non en f\u00fbt devenu pacifique et pacificateur, beaucoup plus constructif, pas du tout antagoniste et destructeur, etc. Mais non, bien s\u00fbr, il faut que les Fran\u00e7ais se distinguent, essentiellement en proclamant que cette distinction existe pour mettre en \u00e9vidence leur diff\u00e9rence destructrice. C&rsquo;est dommage,  mais cela n&rsquo;est peut-\u00eatre pas inutile.<\/p>\n<h3>Qu&rsquo;est-ce qui serait un moment sublime dans la campagne du r\u00e9f\u00e9rendum?<\/h3>\n<\/p>\n<p><p>\tPourtant, pourtant, tout cela n&rsquo;est pas \u00e0 jeter \u00e0 la poubelle. Les acteurs furent parfois d&rsquo;une m\u00e9diocrit\u00e9 consternante, plus souvent d&rsquo;une bonne foi un peu na\u00efve et sans inspiration, tr\u00e8s souvent d&rsquo;une roublardise accablante, presque toujours d&rsquo;une agressivit\u00e9 st\u00e9rile. Les acteurs de la R\u00e9volution, eux aussi, \u00e9taient d&rsquo;un pi\u00e8tre calibre. Vulgaire, verbeux, pompeux, sanguinaire, avec des foules \u00e9galement sauvages et vulgaires, et, partout, la crainte de n&rsquo;\u00eatre pas conforme devant l&rsquo;affirmation sanglante du d\u00e9sordre devenu majoritaire.<\/p>\n<\/p>\n<p><p>\tLa R\u00e9volution&#8230; Voil\u00e0 que la r\u00e9f\u00e9rence revient sous la plume et, avec elle, notre r\u00e9f\u00e9rence \u00e0 Joseph de Maistre. Certains aspects de la campagne, essentiellement du c\u00f4t\u00e9 du oui, ressembl\u00e8rent \u00e0 la R\u00e9volution, le sanguinaire en moins. Lorsqu&rsquo;on rassemble en troupeau les artistes de l&rsquo;Europe par centaines, qu&rsquo;ils sont convi\u00e9s \u00e0 c\u00e9l\u00e9brer l&rsquo;Europe et sa Constitution comme on c\u00e9l\u00e9brait l&rsquo;\u00catre Supr\u00eame, on se croirait \u00e0 une de ces f\u00eates de la f\u00e9d\u00e9ration, c\u00e9l\u00e9br\u00e9e au grand orgue de la messe par l&rsquo;\u00e9v\u00eaque d&rsquo;Autun (Talleyrand), ricanant en-dedans devant le spectacle; ou \u00e0 une s\u00e9ance de l&rsquo;Assembl\u00e9e en 1791 ou 1792, lors des discours-fleuves des d\u00e9put\u00e9s. M\u00eame terrorisme de la pens\u00e9e, m\u00eame conformisme z\u00e9l\u00e9 et pr\u00e9sent\u00e9 comme l&rsquo;audace m\u00eame dans la pens\u00e9e, etc. Si l&rsquo;on \u00e9largit l&rsquo;imagerie qui, aujourd&rsquo;hui, nous sert de bo\u00eete \u00e0 outils pour juger de l&rsquo;Histoire que nous vivons, nous constatons que nous vivons des temps que les commentateurs ont tendance \u00e0 d\u00e9finir effectivement par la r\u00e9f\u00e9rence \u00e0 la grande R\u00e9volution. Lorsqu&rsquo;un critique conservateur de la politique de GW Bush (Claes G. Ryn, professeur de politique \u00e0 l&rsquo;Universit\u00e9 Catholique de l&rsquo;Am\u00e9rique) veut affirmer un jugement exp\u00e9ditif pour condamner cette politique, il le qualifie de \u00ab <em>Jacobin in Chief<\/em> \u00bb et l&rsquo;accuse  \u00ab [of] <em>exporting the French Revolution to the world<\/em> \u00bb.<\/p>\n<\/p>\n<p><p>\tNe cherchons pas des analogies d&rsquo;\u00e9v\u00e9nements mais justifions-nous plut\u00f4t de notre choix par des analogies de tendances fondamentales et de mod\u00e8les de psychologies triomphantes. Toutes ces choses sont bien plus significatives que les \u00e9v\u00e9nements, qui d\u00e9pendent trop de la conjoncture.<\/p>\n<\/p>\n<p><p>\tLa globalisation est d\u00e9structurante de l&rsquo;ordre du monde comme le fut la grande R\u00e9volution, avec la centralisation jacobiniste ajout\u00e9e au d\u00e9sordre r\u00e9volutionnaire. Dans ce cadre de la globalisation, le projet europ\u00e9en, o\u00f9 il en est arriv\u00e9 aujourd&rsquo;hui selon le cours officiel qu&rsquo;on lui voit prendre, est per\u00e7u comme acqu\u00e9rant une r\u00e9elle puissance de d\u00e9structuration en s&rsquo;attaquant aux \u00c9tats-nations avec son projet f\u00e9d\u00e9raliste. On savait que c&rsquo;\u00e9tait l\u00e0 le but mais la campagne du r\u00e9f\u00e9rendum nous fait penser que, d\u00e9sormais, la d\u00e9structuration fait sentir ses effets.<\/p>\n<\/p>\n<p><p>\tLe conformisme terroriste qui sert de pens\u00e9e unique, sur le registre du th\u00e8me-unique de la d\u00e9mocratie, le symbolisme qui sert d&rsquo;analyse politique, l&rsquo;affirmation de l&rsquo;utopie comme une r\u00e9alit\u00e9, tout cela rappelle le climat intellectuel de la grande R\u00e9volution. Pour compl\u00e9ter ce domaine, parlons des acteurs de notre temps, hommes et femmes cens\u00e9s conduire la politique.<\/p>\n<\/p>\n<p><p>\tLes \u00e9v\u00e9nements sont tels qu&rsquo;ils se trouvent conduits \u00e0 utiliser les travers les plus consternants pour maintenir leur position et renforcer leurs th\u00e8ses dans le r\u00e9gime globalisant et d\u00e9structurant, tandis que les syst\u00e8mes poussent \u00e0 l&rsquo;intronisation de chefs d&rsquo;\u00c9tat et de gouvernement dont la stature peut \u00eatre r\u00e9sum\u00e9e par un caract\u00e8re qui est celui de leur m\u00e9diocrit\u00e9 et dont l&rsquo;activit\u00e9 politique est \u00e9galement r\u00e9sum\u00e9e par l&rsquo;autre caract\u00e8re de leur impuissance. Pour autant, qui ne sent combien ces temps sont exceptionnels, uniques, r\u00e9volutionnaires en essence?<\/p>\n<\/p>\n<p><p>\tDans ses <em>Consid\u00e9rations sur la France<\/em> (1796), Maistre commence par poser le paradoxe que la R\u00e9volution est un \u00e9v\u00e9nement merveilleux (un moment sublime de l&rsquo;Histoire). \u00ab <em>Mais la r\u00e9volution fran\u00e7aise, et tout ce qui se passe en Europe dans ce moment, est tout aussi merveilleux que la fructification instantan\u00e9e d&rsquo;un arbre au mois de janvier; cependant les hommes, au lieu d&rsquo;admirer, regardent ailleurs ou d\u00e9raisonnent.<\/em> \u00bb L\u00e0-dessus, Maistre ne manque pas d&rsquo;opposer avec une extr\u00eame vigueur le moment sublime de la R\u00e9volution et la m\u00e9diocrit\u00e9 des hommes qui croient l&rsquo;influencer, en fait qui sont emport\u00e9s par elle. \u00ab <em>On a remarqu\u00e9, avec grande raison, que la r\u00e9volution fran\u00e7aise m\u00e8ne les hommes plus que les hommes la m\u00e8nent. Cette observation est de la plus grande justesse&#8230;<\/em> [&#8230;] <em>Les sc\u00e9l\u00e9rats m\u00eames qui paraissent conduire la r\u00e9volution, n&rsquo;y entrent que comme de simples instruments; et d\u00e8s qu&rsquo;ils ont la pr\u00e9tention de la dominer, ils tombent ignoblement.<\/em> \u00bb<\/p>\n<\/p>\n<p><p>\tMaistre ne s&rsquo;exclame pas \u00e0 propos de la R\u00e9volution par estime r\u00e9elle. Au contraire, il la consid\u00e8re comme un \u00e9v\u00e9nement monstrueux en soi, mais il la place dans une continuit\u00e9 transcendantale; il la glorifie alors parce qu&rsquo;il la juge comme un \u00e9v\u00e9nement n\u00e9cessaire pour pr\u00e9cipiter la d\u00e9cadence fran\u00e7aise et conduire plus vite \u00e0 ce qu&rsquo;il juge \u00eatre la renaissance n\u00e9cessaire de la France.<\/p>\n<\/p>\n<p><p>\tLa th\u00e8se g\u00e9n\u00e9rale de Maistre, qui est le transcendantalisme, le pousse \u00e0 consid\u00e9rer avec m\u00e9fiance, voire avec une hostilit\u00e9 compl\u00e8te, les interdits que la raison mal comprise, celle qui d\u00e9forme l&rsquo;irrationnel qu&rsquo;elle ne peut expliquer pour en faire un \u00e9v\u00e9nement rationnel qu&rsquo;elle peut juger, oppose aux \u00e9v\u00e9nements qui la d\u00e9passent. \u00ab <em>Dans l&rsquo;ordre physique, o\u00f9 l&rsquo;homme n&rsquo;entre point comme cause, il veut bien admirer ce qu&rsquo;il ne comprend pas; mais dans la sph\u00e8re de son activit\u00e9, o\u00f9 il sent qu&rsquo;il est cause libre, son orgueil le porte ais\u00e9ment \u00e0 voir le d\u00e9sordre partout o\u00f9 son action est suspendue ou d\u00e9rang\u00e9e.<\/em> \u00bb<\/p>\n<\/p>\n<p><p>\tMaistre engage donc \u00e0 prendre l&rsquo;\u00e9v\u00e9nement merveilleux de la R\u00e9volution pour ce qu&rsquo;il est selon lui: une manifestation (divine pour Maistre) qui d\u00e9passe l&rsquo;homme et impose une acc\u00e9l\u00e9ration fondamentale de l&rsquo;Histoire. (De m\u00eame, mais cela va sans dire, Maistre condamne-t-il les th\u00e8ses sur le sens et le progr\u00e8s de l&rsquo;Histoire, qui feraient des hommes les ma\u00eetres d&rsquo;oeuvre de la R\u00e9volution en tant qu&rsquo;elle serait un \u00e9v\u00e9nement progressiste de rupture. Cette sorte de transcendantalisme mat\u00e9rialiste est r\u00e9duite \u00e0 n\u00e9ant par le jugement qu&rsquo;il fait sur ceux qui semblent machiner et dominer l&rsquo;\u00e9v\u00e9nement qu&rsquo;est la R\u00e9volution, alors qu&rsquo;ils n&rsquo;en sont que les jouets. Il ne s&rsquo;agit que d&rsquo;une monstruosit\u00e9 de la vanit\u00e9 humaine que cette pr\u00e9tention \u00e0 prendre la place de Dieu.)<\/p>\n<h3>Alors, la campagne du r\u00e9f\u00e9rendum est-elle un moment sublime de l&rsquo;Histoire?<\/h3>\n<\/p>\n<p><p>\tCitons encore Maistre et appliquons ce mot \u00e0 notre \u00e9poque; appliquons-le m\u00eame, plus pr\u00e9cis\u00e9ment pour notre propos, aux exclamations incr\u00e9dules et indign\u00e9es des partisans du oui devant l&rsquo;ent\u00eatement qui leur para\u00eet \u00e9trange d&rsquo;une si grande partie des Fran\u00e7ais \u00e0 avoir annonc\u00e9 leur intention de voter non: \u00ab <strong><em>Je n&rsquo;y comprends rien,<\/em><\/strong> <em>c&rsquo;est le grand mot du jour: ce mot est tr\u00e8s-sens\u00e9, s&rsquo;il nous ram\u00e8ne \u00e0 la cause premi\u00e8re qui donne dans ce moment un si grand spectacle aux hommes; c&rsquo;est une sottise, s&rsquo;il n&rsquo;exprime qu&rsquo;un d\u00e9pit ou un abattement st\u00e9rile.<\/em> \u00bb<\/p>\n<\/p>\n<p><p>\tEffectivement, il y a nombre de caract\u00e8res incompr\u00e9hensibles dans cette campagne du r\u00e9f\u00e9rendum, comme, de m\u00eame, dans nombre d&rsquo;\u00e9v\u00e9nements qui secouent le monde depuis quelques ann\u00e9es, au rythme de la globalisation et de la d\u00e9structuration qui en r\u00e9sulte. Effectivement, on pourrait y appliquer l&rsquo;image de Maistre, s&rsquo;exclamant devant un \u00e9v\u00e9nement qu&rsquo;il n&rsquo;aime pas, mais dont il appr\u00e9cie qu&rsquo;il porte \u00e0 son extr\u00eame la d\u00e9cadence d&rsquo;un syst\u00e8me de toutes les fa\u00e7ons condamn\u00e9,  cela, pour mieux nous rapprocher de sa renaissance par r\u00e9g\u00e9n\u00e9ration. L&rsquo;image peut aussi bien s&rsquo;appliquer de fa\u00e7on analogique \u00e0 cette campagne du r\u00e9f\u00e9rendum compl\u00e8tement sacril\u00e8ge, qui met en cause, bien plus qu&rsquo;en aucune autre occasion, l&rsquo;un des tabous de notre syst\u00e8me qui est la construction de l&rsquo;Europe vers un \u00c9tat supranational o\u00f9 les nations seront invit\u00e9es \u00e0 se fondre, vaille que vaille.<\/p>\n<\/p>\n<p><p>\tDe plusieurs points de vue, on observe que les circonstances, les \u00e9v\u00e9nements ponctuels sont beaucoup plus complexes que ceux de la R\u00e9volution. Il faut avoir une certaine agilit\u00e9 d&rsquo;esprit pour comprendre qu&rsquo;une puissance europ\u00e9enne est n\u00e9cessaire pour s&rsquo;opposer \u00e0 la folie d\u00e9structurante des \u00c9tats-Unis, et avec une dimension culturelle europ\u00e9enne affirm\u00e9e; et, qu&rsquo;en m\u00eame temps, une certaine construction de l&rsquo;Europe, qui bafoue les identit\u00e9s, d\u00e9truit les souverainet\u00e9s, fait cause commune avec cette m\u00eame folie de d\u00e9structuration de l&rsquo;am\u00e9ricanisme. Nos chefs politiques ne devraient pas lever les yeux au ciel devant de telles affirmations en apparence contradictoires, mais s&rsquo;informer aupr\u00e8s de quelques bonnes sources, dans les institutions europ\u00e9ennes. Ils apprendraient que ces structures, manipul\u00e9es avec habilet\u00e9 (par les Europ\u00e9ens), peuvent, selon les cas, s&rsquo;affirmer ponctuellement comme  de formidables armes contre la folie am\u00e9ricaniste, et, d&rsquo;autre part mais pas tr\u00e8s loin, s&rsquo;affirmer comme les plus z\u00e9l\u00e9es auxiliaires de cette folie si elles sont laiss\u00e9es \u00e0 elles-m\u00eames. La campagne du r\u00e9f\u00e9rendum a lev\u00e9 un voile sur cette formidable r\u00e9alit\u00e9 de notre temps de folie. C&rsquo;est bien un moment sublime de l&rsquo;Histoire, o\u00f9 l&rsquo;on sent que l&rsquo;on n&rsquo;est plus tr\u00e8s loin de quelques v\u00e9rit\u00e9s fondamentales et incroyables. La panique de nos dirigeants, ici ou l\u00e0 dans la campagne, nous a montr\u00e9 qu&rsquo;ils devinaient cela, \u00e0 d\u00e9faut de le comprendre.<\/p>\n<\/p>\n<p><p>\tPar ailleurs, rien n&rsquo;est fini. Moment sublime dans un cadre plus large, la campagne du r\u00e9f\u00e9rendum repr\u00e9sente une r\u00e9action de plus contre une pouss\u00e9e g\u00e9n\u00e9rale qui arrive \u00e0 son point de fusion. En effet,  et, l\u00e0 encore, on retrouve Maistre,  qui ne sent que nous sommes entr\u00e9s dans une phase d&rsquo;acc\u00e9l\u00e9ration des choses bien entendu hors de notre contr\u00f4le, comme la Grande R\u00e9volution de 1789-93? C&rsquo;est un constat suffisant pour nous faire comprendre que le r\u00e9sultat du 29 mai, s&rsquo;il est important, n&rsquo;a pas une importance fondamentale. D&rsquo;ici 2009, date d&rsquo;application si le oui l&#8217;emportait en France et ailleurs, bien des choses se passeront. Nos dirigeants politiques europ\u00e9ens s&rsquo;imaginent qu&rsquo;avec un de ces textes, qu&rsquo;ils qualifient curieusement de fondateurs (\u00e0 part la constitution US, a-t-on vu un texte r\u00e9ellement fondateur dans l&rsquo;Histoire?  Et quand on voit le r\u00e9sultat aux USA), on pourra \u00e9carter l&rsquo;incertitude, r\u00e9tablir l&rsquo;ordre, d\u00e9barrasser Bush de son encombrant conseiller divin et faire r\u00e9gner l&rsquo;harmonie. Cette esp\u00e9rance n&rsquo;a rien \u00e0 voir avec la r\u00e9alit\u00e9.<\/p>\n<\/p>\n<p><p>\tPlut\u00f4t, ce constat que ce r\u00e9f\u00e9rendum est bien dans le rythme infernal d&rsquo;une \u00e9poque dont l&rsquo;importance vaut, en la prolongeant, celle de la fin du XVIII\u00e8me si\u00e8cle d\u00e9crite par Maistre.<\/p>\n<\/p>\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Un moment sublime? Nous sommes \u00e0 la veille du 29 mai. Laissons de c\u00f4t\u00e9 les pronostics, les certitudes et les incertitudes. Cessons de jouer au loto. Essayons de comprendre l&rsquo;esprit de cette campagne r\u00e9f\u00e9rendaire, qui renvoie \u00e0 une autre \u00e9poque tout ce qui a pr\u00e9c\u00e9d\u00e9 (y compris la glorieuse campagne de Maastricht). Tentons de distinguer&hellip;&nbsp;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","footnotes":"","jetpack_post_was_ever_published":false},"categories":[5],"tags":[2631,4595,4596,2879],"class_list":["post-66476","post","type-post","status-publish","format-standard","hentry","category-de-defensa","tag-de","tag-joseph","tag-maistre","tag-revolution"],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/66476","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/comments?post=66476"}],"version-history":[{"count":0,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/66476\/revisions"}],"wp:attachment":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/media?parent=66476"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/categories?post=66476"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/tags?post=66476"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}