{"id":66483,"date":"2005-06-06T00:00:00","date_gmt":"2005-06-06T00:00:00","guid":{"rendered":"https:\/\/new.dedefensa.org\/index.php\/2005\/06\/06\/les-anglais-parlent-aux-francais\/"},"modified":"2005-06-06T00:00:00","modified_gmt":"2005-06-06T00:00:00","slug":"les-anglais-parlent-aux-francais","status":"publish","type":"post","link":"https:\/\/new.dedefensa.org\/index.php\/2005\/06\/06\/les-anglais-parlent-aux-francais\/","title":{"rendered":"Les Anglais parlent aux Fran\u00e7ais"},"content":{"rendered":"<p><p>L&rsquo;\u00e9ditorial du <a href=\"http:\/\/www.spectator.co.uk\/article.php?id=6207&#038;issue=2005-06-04\" class=\"gen\">Spectator du 4 juin<\/a> repr\u00e9sente certainement l&rsquo;un des textes les plus compl\u00e8tement anglais sur le r\u00e9f\u00e9rendum fran\u00e7ais,  s&rsquo;entend, le plus politiquement, sinc\u00e8rement et hypocritement anglais, avec l&rsquo;orientation id\u00e9ologique libre-\u00e9changiste d&rsquo;une presse compl\u00e8tement acquise aux conceptions \u00e9conomiques capitalistes (le <em>Spectator<\/em> appartient au groupe Black). L&rsquo;essentiel de l&rsquo;argument de <em>Spectator<\/em> s&rsquo;appuie sur ce constat qui saisit bien l&rsquo;essence du dilemme qui, aujourd&rsquo;hui, touche les grands pays europ\u00e9ens appuyant leur politique sur l&rsquo;id\u00e9ologie lib\u00e9rale, anti-f\u00e9d\u00e9raliste et anti-europ\u00e9enne :<\/p>\n<\/p>\n<p><p>\t\u00ab <em>&#8230;of course we are pleased that this federalising constitution&rsquo; has been rejected by the French. Our jubilation is alloyed, however, by an embarrassing reality. The French people unquestionably did the right thing. They did it, alas, for the wrong reasons.<\/em> \u00bb<\/p>\n<\/p>\n<p><p>\tL&rsquo;\u00e9dito du <em>Spectator<\/em> a au moins l&rsquo;avantage de ne rien dissimuler des facteurs essentiels de la crise europ\u00e9enne. L&rsquo;hebdomadaire est contre un super-\u00c9tat f\u00e9d\u00e9ral europ\u00e9en,  bravo, les Fran\u00e7ais ! Mais il est aussi partisan inconditionnel d&rsquo;un super-grand march\u00e9 de libre-\u00e9change en guise d&rsquo;Europe, une v\u00e9ritable Europe \u00e0 l&rsquo;anglaise la plus large et la plus \u00e9tendue possible,  hol\u00e0, les Fran\u00e7ais ! Le <em>Spectator<\/em> d\u00e9signe d\u00e9j\u00e0 ce qui est pour lui le danger, qui est de suivre la croisade des Fran\u00e7ais (en passant, notons son avis sur Sarkozy, qui n&rsquo;est pas loin de d\u00e9couvrir le vrai Sarkozy : celui qui, s&rsquo;il est \u00e9lu pr\u00e9sident en 2007 sur un argument lib\u00e9ral, pourrait bien redevenir un vrai pr\u00e9sident fran\u00e7ais, d\u00e9fendant le mod\u00e8le fran\u00e7ais): \u00ab <em>Already, French demagogues are starting to respond to this nonsense. <\/em>[UMP] <em>chief Nicolas Sarkozy is calling for more protection&rsquo;, and the danger is that a concerted attempt will now be made to palliate French opinion, by curbing the operation of the free market both within the EU and on its borders.<\/em> \u00bb <\/p>\n<\/p>\n<p><p>\tTout cela nous promet bien des quiproquos, bien des affrontements d&rsquo;incompr\u00e9hensions et autres, bien des coups fourr\u00e9s. Dans ces conditions, on comprend combien la premi\u00e8re condition d&rsquo;une telle bataille qui s&rsquo;annonce est d&rsquo;\u00e9carter une Constitution qui serait (aurait \u00e9t\u00e9) une contrainte, un corset insupportable pour tous, les partisans comme les adversaires d&rsquo;une Europe \u00e0 l&rsquo;anglaise.<\/p>\n<\/p>\n<p><p>\tLe <em>Spectator<\/em> termine par l&rsquo;habituelle touche d&rsquo;hypocrisie britannique qui est aussi la v\u00e9ritable crainte des Britanniques de voir les Fran\u00e7ais exercer l&rsquo;influence que leur donne leur coup de force du 29 mai. Il s&rsquo;agit d&rsquo;un conseil imp\u00e9ratif en forme d&rsquo;hypocrisie l\u00e9galiste qui est une tentative de dire aux Fran\u00e7ais : maintenant que vous avez parl\u00e9 d&rsquo;une fa\u00e7on n\u00e9gative, vous n&rsquo;avez plus rien \u00e0 dire et vous devez nous laisser faire: \u00ab <em>We should remind them that any country that says No to a treaty is conventionally deemed to have forfeited all rights of influence. It&rsquo;s certainly what they would have said to us.<\/em> \u00bb Nous continuerions en disant : certes, c&rsquo;est ce qu&rsquo;on aurait dit aux Anglais s&rsquo;ils avaient \u00e9mis un tel vote mais chacun sait que les Anglais n&rsquo;auraient pas tenu compte une seconde de l&rsquo;avis, eux qui ne sont pas dans l&rsquo;euro et s&#8217;emploient \u00e0 bouleverser de fond en comble les structures \u00e9conomiques europ\u00e9ennes comme s&rsquo;ils en \u00e9taient les ma\u00eetres et les inspirateurs.<\/p>\n<\/p>\n<p><p>\tD&rsquo;o\u00f9 notre conseil au Fran\u00e7ais, calqu\u00e9 sur l&rsquo;exemple donn\u00e9 au travers des si\u00e8cles par les Anglais : au contraire, appuyez-vous sur la notori\u00e9t\u00e9 que vous donne ce vote n\u00e9gatif et exercez plus que jamais toute l&rsquo;influence dont vous \u00eates capable,  et sans vergogne <em>please<\/em>. Faites donc le bonheur des Anglais contre leur gr\u00e9, ils vous en seront gr\u00e9, de la m\u00eame fa\u00e7on qu&rsquo;aujourd&rsquo;hui ils adorent ce qu&rsquo;ils ont br\u00fbl\u00e9 hier (Jeanne d&rsquo;Arc en l&rsquo;occurrence).<\/p>\n<\/p>\n<p><\/p>\n<p><p>\tMis en ligne le 6 juin 2005 \u00e0 16H00<\/p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>L&rsquo;\u00e9ditorial du Spectator du 4 juin repr\u00e9sente certainement l&rsquo;un des textes les plus compl\u00e8tement anglais sur le r\u00e9f\u00e9rendum fran\u00e7ais, s&rsquo;entend, le plus politiquement, sinc\u00e8rement et hypocritement anglais, avec l&rsquo;orientation id\u00e9ologique libre-\u00e9changiste d&rsquo;une presse compl\u00e8tement acquise aux conceptions \u00e9conomiques capitalistes (le Spectator appartient au groupe Black). L&rsquo;essentiel de l&rsquo;argument de Spectator s&rsquo;appuie sur ce constat qui&hellip;&nbsp;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","footnotes":"","jetpack_post_was_ever_published":false},"categories":[2],"tags":[],"class_list":["post-66483","post","type-post","status-publish","format-standard","hentry","category-bloc-notes"],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/66483","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/comments?post=66483"}],"version-history":[{"count":0,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/66483\/revisions"}],"wp:attachment":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/media?parent=66483"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/categories?post=66483"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/tags?post=66483"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}