{"id":66526,"date":"2005-06-20T00:00:00","date_gmt":"2005-06-20T00:00:00","guid":{"rendered":"https:\/\/new.dedefensa.org\/index.php\/2005\/06\/20\/une-tragedie-postmoderne-volume-20-n18-du-10-juin-2005\/"},"modified":"2005-06-20T00:00:00","modified_gmt":"2005-06-20T00:00:00","slug":"une-tragedie-postmoderne-volume-20-n18-du-10-juin-2005","status":"publish","type":"post","link":"https:\/\/new.dedefensa.org\/index.php\/2005\/06\/20\/une-tragedie-postmoderne-volume-20-n18-du-10-juin-2005\/","title":{"rendered":"<strong><em>Une trag\u00e9die postmoderne \u2014 Volume 20, n\u00b018 du 10 juin 2005<\/em><\/strong>"},"content":{"rendered":"<p><h2 class=\"common-article\">Une trag\u00e9die postmoderne<\/h2>\n<\/p>\n<p><\/p>\n<p><p>\t<strong>D\u00e9but de cette r\u00e9flexion sur un constat extra-ordinaire: s&rsquo;il n&rsquo;y avait eu les sondages, nous n&rsquo;aurions rien eu de cet \u00e9branlement extra-ordinaire qu&rsquo;est le r\u00e9f\u00e9rendum fran\u00e7ais. Aujourd&rsquo;hui, la R\u00e9volution passe par les outils qui ont servi \u00e0 liquider la R\u00e9volution.<\/strong><\/p>\n<\/p>\n<p><\/p>\n<p><p>\tImaginons ce qu&rsquo;auraient \u00e9t\u00e9 ces mois exaltants et stup\u00e9fiants de la campagne du r\u00e9f\u00e9rendum fran\u00e7ais, depuis \u00e0 peu pr\u00e8s le mois de mars, sans les sondages&#8230; (Mars, justement, parce que paraissent  \u00e0 partir du 13  les premiers sondages donnant le non vainqueur.) Rien, ou quasiment. Et l&rsquo;on aurait vot\u00e9; et peut-\u00eatre le non serait-il sorti vainqueur, nous donnant un coup de massue incompr\u00e9hensible, interdisant toute r\u00e9action, toute r\u00e9flexion, interdisant la moindre mesure en profondeur de cet \u00e9v\u00e9nement.<\/p>\n<\/p>\n<p><p>\tOn le sait parce que tous les experts n&rsquo;ont cess\u00e9 de s&rsquo;exclamer de plus en plus fortement \u00e0 ce propos, l&rsquo;histoire statistique ne fournit aucun pr\u00e9c\u00e9dent d&rsquo;une suite aussi marquante de renversements de tendances dans une campagne de cette importance. Le point compl\u00e9mentaire de cette remarque,  compl\u00e9mentaire et suppl\u00e9mentaire pour ouvrir notre analyse, c&rsquo;est que ces renversements de tendances, en m\u00eame temps qu&rsquo;ils animaient et dramatisaient le d\u00e9bat, l&rsquo;ont fait progresser en profondeur et en intensit\u00e9 dans cette profondeur. Le d\u00e9bat n&rsquo;a pas \u00e9t\u00e9 bon, il n&rsquo;a pas fait progresser, ni la compr\u00e9hension de la question europ\u00e9enne soumise au vote (la Constitution), ni la compr\u00e9hension de la situation europ\u00e9enne. Mais il a \u00e9t\u00e9 intense, path\u00e9tique, et il a fait deviner, sentir, percevoir que les enjeux \u00e9taient fondamentaux. Cette mont\u00e9e de l&rsquo;\u00e9motion et de l&rsquo;intuition collectives (le mot est essentiel, bien s\u00fbr) n&rsquo;a \u00e9t\u00e9 possible que parce que les sondages ont form\u00e9 la trame d&rsquo;un th\u00e9\u00e2tre extraordinairement tragique. Cette trag\u00e9die postmoderne ne l&rsquo;a \u00e9t\u00e9,  une trag\u00e9die,  que parce que les sondages ont fourni le rythme, le <em>tempo<\/em> de la trag\u00e9die. Mais tout cela n&rsquo;est pas gratuit. La situation th\u00e9\u00e2trale \u00e9voluant de la sorte, nous nous sommes aper\u00e7us qu&rsquo;il y avait effectivement, sous les planches si l&rsquo;on veut, une v\u00e9ritable trag\u00e9die. Sans les sondages, sans cette m\u00e9canique statistique qu&rsquo;on voit en g\u00e9n\u00e9ral comme un instrument de manipulation de la v\u00e9rit\u00e9, la mise en lumi\u00e8re de la v\u00e9rit\u00e9 fondamentale de cette trag\u00e9die postmoderne n&rsquo;eut pas \u00e9t\u00e9 r\u00e9alis\u00e9e.<\/p>\n<\/p>\n<p><p>\tCe constat m\u00e9rite qu&rsquo;on s&rsquo;y arr\u00eate: comment, de quelque chose, na\u00eet le contraire de ce qu&rsquo;on voulut y mettre?<\/p>\n<\/p>\n<p><\/p>\n<h3>Comment une technique de ma\u00eetrise et de manipulation postmoderne devient un instrument pour r\u00e9v\u00e9ler l&rsquo;\u00e2me d&rsquo;un peuple et la crise d&rsquo;une \u00e9poque<\/h3>\n<\/p>\n<p><p>\tLa technique du sondage est essentielle dans la d\u00e9mocratie moderne, disons la d\u00e9mocratie m\u00e9diatique, voire la d\u00e9mocratie virtualiste. Son utilit\u00e9, sa n\u00e9cessit\u00e9 ont certainement \u00e9volu\u00e9 dans leurs causes depuis que la technique est apparue, mais sans aucun doute dans le sens d&rsquo;un renforcement. Au d\u00e9part, il y a le besoin naturel de savoir, de conna\u00eetre l&rsquo;opinion du public, et, d&rsquo;une fa\u00e7on plus \u00e9labor\u00e9e d\u00e9j\u00e0, de pr\u00e9voir, ou disons plut\u00f4t d&rsquo;extrapoler (de projeter) ce que seraient \u00e9ventuellement les r\u00e9sultats d&rsquo;une \u00e9lection, de l&rsquo;\u00e9lection \u00e0 venir. Ce constat est encore assez neutre, m\u00eame s&rsquo;il se colore de d\u00e9marches dont on sent bien qu&rsquo;elles peuvent tr\u00e8s vite devenir suspectes: extrapoler, projeter, ce n&rsquo;est plus tr\u00e8s loin d&rsquo;influencer, voire de modifier ou, pour tout dire \u00e0 ce propos,  de manipuler.<\/p>\n<\/p>\n<p><p>\tPar ailleurs, on peut plaider que cette \u00e9volution n&rsquo;est pas que pernicieuse. Elle peut \u00eatre consid\u00e9r\u00e9e, assez justement lorsqu&rsquo;elle est plac\u00e9e dans le contexte de l&rsquo;\u00e9volution, non seulement de la d\u00e9mocratie mais de notre soci\u00e9t\u00e9 en g\u00e9n\u00e9ral, voire de notre civilisation, comme utile, voire m\u00eame n\u00e9cessaire. Il n&rsquo;est pas n\u00e9cessairement mauvais de conna\u00eetre mieux l&rsquo;opinion des gens, ne serait-ce que pour la rencontrer, voire satisfaire l&rsquo;objet de cette opinion. Il y a, pour satisfaire ces diff\u00e9rents jugements, suffisamment de cat\u00e9gories de sondages: les sondages simplement informatifs, qui s&rsquo;apparentent aux techniques de <em>marketing<\/em> et de vente et ne sont pas li\u00e9s \u00e0 une \u00e9ch\u00e9ance \u00e9lectorale, et les sondages ponctuels, qui concernent une \u00e9ch\u00e9ance \u00e9lectorale.<\/p>\n<\/p>\n<p><p>\tPourtant, cette diversit\u00e9 scientifique qui pourrait sembler exon\u00e9rer le sondage d&rsquo;intentions identifi\u00e9es (notamment l&rsquo;intention pernicieuse qui porte le principal soup\u00e7on de manipulation) en en faisant une op\u00e9ration relative aux circonstances, a sembl\u00e9 se r\u00e9duire consid\u00e9rablement ces derni\u00e8res ann\u00e9es, disons ces deux ou trois derni\u00e8res d\u00e9cennies. La cause en est le d\u00e9veloppement du ph\u00e9nom\u00e8ne des communications dans ce que ce ph\u00e9nom\u00e8ne a lui-m\u00eame engendr\u00e9 une tr\u00e8s grande acc\u00e9l\u00e9ration des \u00e9v\u00e9nements dans la perception que nous en avons.<\/p>\n<\/p>\n<p><p>\tLe ph\u00e9nom\u00e8ne de communication que nous connaissons aujourd&rsquo;hui, sous sa forme statistique et \u00e9lectronique, est une fatalit\u00e9 du d\u00e9veloppement technologique et du <em>marketing<\/em> au service du syst\u00e8me capitaliste. Il a \u00e9t\u00e9 aussit\u00f4t adopt\u00e9 comme un instrument de promotion extr\u00eamement dynamique et efficace du syst\u00e8me politique, puis, toujours selon la m\u00eame logique, comme une garantie dynamique de la survie du syst\u00e8me politique.<\/p>\n<\/p>\n<p><p>\tLe syst\u00e8me politique produisant de moins en moins de substance \u00e0 cause du poids grandissant (notamment \u00e0 cause du moyen des communications) du syst\u00e8me \u00e9conomique, il \u00e9tait important de prot\u00e9ger son existence en donnant une impression de dynamisme grandissant: tout ce qui bouge semble vivre utilement, donc justifier son existence. Les communications ont allong\u00e9 le cycle de promotion du monde politique pour son acte principal d&rsquo;existence,  l&rsquo;\u00e9ch\u00e9ance \u00e9lectorale,  et <em>de facto<\/em> install\u00e9 l&rsquo;impression que les \u00e9ch\u00e9ances \u00e9lectorales ne cessaient de se rapprocher. Dans certains cas, on conna\u00eet l&rsquo;impression actuelle d&rsquo;\u00eatre constamment en campagne \u00e9lectorale. Ainsi ne s&rsquo;attarde-t-on pas, ni \u00e0 l&rsquo;action politique ni au bilan de cette action, en renfor\u00e7ant l&rsquo;impression de la future \u00e9ch\u00e9ance \u00e9lectorale, donc en sugg\u00e9rant l&rsquo;id\u00e9e que comptent exclusivement la future action \u00e9lectorale et le futur bilan de la future action \u00e9lectorale.<\/p>\n<\/p>\n<p><p>\tAinsi s&rsquo;est install\u00e9e la tradition des sondages r\u00e9guliers, portant sur les partis, les hommes, les dossiers, etc.,  hors \u00e9ch\u00e9ances \u00e9lectorales, mais comme si le temps courant \u00e9tait une \u00e9lection potentielle. En soi, cette pratique est devenue une manipulation, on dirait: par la force des choses. La manipulation n&rsquo;est pas n\u00e9cessairement tromperie ou malhonn\u00eatet\u00e9, \u00e0 moins qu&rsquo;il faille r\u00e9viser la d\u00e9finition de ces deux mots.<\/p>\n<\/p>\n<p><p>\tLa manipulation est devenue une action politique, ou plut\u00f4t m\u00e9diatique, de recherche d&rsquo;effets, pour faire \u00e9voluer la soi-disant opinion publique en fonction des r\u00e9sultats des sondages. Un homme politique se trouve \u00e0 un tel niveau, insuffisant pour lui (le niveau est toujours insuffisant, d&rsquo;ailleurs), \u00e0 cause de telle ou telle circonstance, plus ou moins pr\u00e9cis\u00e9ment identifi\u00e9e (parfois la question pos\u00e9e cite la circonstance, parfois c&rsquo;est l&rsquo;\u00e9vidence des \u00e9v\u00e9nements, etc.); comment changer l&rsquo;opinion des gens, quelle mesure politique pour y parvenir, quelle d\u00e9claration suivie ou non d&rsquo;effets, quelle promesse tenue ou pas, etc. C&rsquo;est l\u00e0 qu&rsquo;est la manipulation: elle l&rsquo;est \u00e0 ciel ouvert, sans que des ill\u00e9galit\u00e9s soient absolument n\u00e9cessaires, m\u00eame si des remarques soup\u00e7onneuses peuvent \u00eatre faites sur les techniques (l&rsquo;\u00e9nonc\u00e9 de la question, l&rsquo;\u00e9chantillonnage, le d\u00e9pouillement, etc). Cette sorte de manipulation est irr\u00e9sistible. Elle est devenue une partie int\u00e9grante de la vie politique. La plupart des commentateurs conformes du syst\u00e8me s&rsquo;en satisfont et proclament que la d\u00e9mocratie en est renforc\u00e9e. C&rsquo;est aujourd&rsquo;hui une de ces v\u00e9rit\u00e9s implicites qu&rsquo;on ne peut plus \u00e9carter&#8230; Soit, il faut bien vivre avec. Mais alors, ce qui va suivre fait aussi partie du cycle du renforcement de la d\u00e9mocratie.<\/p>\n<\/p>\n<p><p>\tLe dernier point \u00e0 mentionner de cette courte analyse technique de l&rsquo;\u00e9volution du sondage est sa publicit\u00e9 n\u00e9cessaire, qui ach\u00e8ve de faire sortir le sondage de la sph\u00e8re scientifique pour le faire entrer dans la sph\u00e8re politique,  et, plus encore pour aujourd&rsquo;hui: dans la sph\u00e8re m\u00e9diatique et virtualiste, qui est la principale sph\u00e8re d&rsquo;activit\u00e9 de la politique dans notre temps historique. La publicit\u00e9 des sondages est n\u00e9cessaire, en effet, parce que c&rsquo;est la fonction m\u00eame du processus envisag\u00e9 ici (manipulation), pour effectuer le travail d&rsquo;influence qu&rsquo;on attend de lui. Ce faisant, on expose ce processus \u00e0 l&rsquo;autre face de sa publicit\u00e9: la critique, voire l&rsquo;auto-critique des esprits qu&rsquo;elle pr\u00e9tend influencer, voire conduire. (Comment? C&rsquo;est nous qui pensons cela, qui voulons voter dans ce sens? Mais nous ne le voulons pas! Etc.) Le risque de l&rsquo;inattendu et de l&rsquo;impr\u00e9vu se dresse soudain, \u00e0 c\u00f4t\u00e9 de l&rsquo;habilet\u00e9 de la manoeuvre d&rsquo;influence.<\/p>\n<\/p>\n<p><p>\tNous avons assist\u00e9 \u00e0 cette op\u00e9ration r\u00e9volutionnaire qui consiste \u00e0 extraire les sondages de la sph\u00e8re scientifique pr\u00e9tendument objective pour les faire entrer, comme acteur \u00e0 part enti\u00e8re, dans la bataille politique et \u00e9lectorale.<\/p>\n<\/p>\n<p><\/p>\n<h3>Comment l&rsquo;esprit se rebelle avec habilet\u00e9 devant la m\u00e9canisation du monde, lorsque cette m\u00e9canisation conduit in\u00e9luctablement \u00e0 nier l&rsquo;existence m\u00eame de l&rsquo;esprit<\/h3>\n<\/p>\n<p><p>\tNous envisageons ici un autre aspect des sondages, en les pla\u00e7ant, d&rsquo;un point de vue \u00e0 la fois plus psychologique et plus politiquement fondamental, comme une op\u00e9ration qui fait partie de la m\u00e9canisation du monde et de la recherche de l&rsquo;uniformisation de la pens\u00e9e qui font partie <em>in fine<\/em> du processus d\u00e9mocratique. C&rsquo;est une constatation qui d\u00e9coule de fa\u00e7on assez naturelle de l&rsquo;observation que la d\u00e9mocratie est per\u00e7ue, dans la conception que s&rsquo;en fait l&rsquo;\u00e8re moderne, non comme un r\u00e9gime naturel (d\u00e9coulant de la nature) mais comme un arrangement humain, par cons\u00e9quent artificiel, tendant \u00e0 installer un r\u00e9gime tendant lui-m\u00eame \u00e0 l&rsquo;id\u00e9al politique. L&rsquo;un des outils fondamentaux pour cette d\u00e9marche est \u00e9videmment le recours g\u00e9n\u00e9ral du syst\u00e8me \u00e0 la m\u00e9canique (\u00e0 partir de la machine), qui est elle-m\u00eame une rupture radicale avec la nature.<\/p>\n<\/p>\n<p><p>\tAu niveau de la pratique politique, il y a une recherche de la conformation des esprits pour atteindre \u00e0 un stade o\u00f9 tous les citoyens en viendraient naturellement (!) \u00e0 adh\u00e9rer au m\u00eame r\u00e9gime, aux m\u00eames normes, etc. C&rsquo;est le grand ph\u00e9nom\u00e8ne du conformisme de pens\u00e9e, qui a largement infect\u00e9 toutes les \u00e9lites occidentales et en grande partie la population am\u00e9ricaine (beaucoup moins pour les populations de certains pays europ\u00e9ens). Il s&rsquo;agit d&rsquo;uniformiser ce qui serait per\u00e7u comme \u00e9tant \u00e9videmment l&rsquo;attitude raisonnable par excellence.<\/p>\n<\/p>\n<p><p>\tConsid\u00e9r\u00e9s de ce point de vue, les sondages deviennent un cycle constant de m\u00e9canisation de l&rsquo;opinion, les opinions populaires \u00e9tant remises dans les mains des analystes et statisticiens des instituts de sondage, et l&rsquo;objet \u00e9ventuel de stimuli, de manoeuvres, \u00e9ventuellement de manipulations, qui sont elles-m\u00eames pour une bonne partie des processus  m\u00e9caniques. Nous observons d&rsquo;ores et d\u00e9j\u00e0 cette id\u00e9e, sur laquelle nous revenons un peu plus loin, que ces processus sont effectivement m\u00e9caniques, dans un processus g\u00e9n\u00e9ral qui l&rsquo;est lui-m\u00eame compl\u00e8tement, ce qui alimente l&rsquo;hypoth\u00e8se qu&rsquo;il n&rsquo;y a pas de r\u00e9elle conscience des manipulations dans la mesure o\u00f9 de telles attitudes pourraient \u00eatre jug\u00e9es ill\u00e9gales ou anti- d\u00e9mocratiques.<\/p>\n<\/p>\n<p><p>\tNous observons \u00e9galement que ces diff\u00e9rentes situations rel\u00e8vent de ce que nous d\u00e9signons comme du virtualisme. Il s&rsquo;agit de cr\u00e9er un univers fictif o\u00f9, d&rsquo;une part, le conformisme qui est cr\u00e9\u00e9 doit appara\u00eetre comme cette attitude naturelle qu&rsquo;il n&rsquo;est pas, o\u00f9, d&rsquo;autre part, une action doit \u00eatre entreprise pour convaincre le sond\u00e9 (l&rsquo;\u00e9lecteur virtuel) que son attitude et son choix sont \u00e0 la fois les bons et \u00e0 la fois la marque d&rsquo;une d\u00e9marche marqu\u00e9e par le libre arbitre et la libert\u00e9 de l&rsquo;esprit.<\/p>\n<\/p>\n<p><p>\tCe dernier point doit \u00eatre comment\u00e9 plus avant. Nous revenons au constat du besoin de publicit\u00e9 des sondages, et d&rsquo;une publicit\u00e9 \u00e0 la fois explicative et avantageuse. Il s&rsquo;agit de convaincre le sond\u00e9\/l&rsquo;\u00e9lecteur virtuel qu&rsquo;il fait, comme dirait l&rsquo;autre, le bon choix qui est l&rsquo;attitude raisonnable qui importe, et qu&rsquo;il montre une remarquable maturit\u00e9 en le faisant puisqu&rsquo;il le fait en toute ind\u00e9pendance d&rsquo;esprit.<\/p>\n<\/p>\n<p><p>\tCertains ont remarqu\u00e9 que les sondages provoquent dans le public un processus de d\u00e9doublement. Le public regarde les r\u00e9sultats des sondages comme s&rsquo;ils concernaient autre chose que lui-m\u00eame, alors qu&rsquo;il est par n\u00e9cessit\u00e9 statistique englob\u00e9 dans le r\u00e9sultat du sondage. Cette probabilit\u00e9 pose un probl\u00e8me en risquant de d\u00e9tacher le citoyen de l&rsquo;\u00e9lecteur qu&rsquo;il devra \u00eatre lors du scrutin r\u00e9el. La pression virtualiste importe par cons\u00e9quent d&rsquo;autant plus: refaire constamment l&rsquo;identification entre le citoyen et le sond\u00e9, et la refaire \u00e9videmment toujours par le m\u00eame proc\u00e9d\u00e9 de promotion des qualit\u00e9s du sond\u00e9 dont le citoyen est r\u00e9compens\u00e9 comme d&rsquo;autant de lauriers lorsque la r\u00e9-identification s&rsquo;effectue. C&rsquo;est le r\u00e9cit glorieux du comportement citoyen, de la responsabilit\u00e9 politique, etc.<\/p>\n<\/p>\n<p><p>\tL&rsquo;efficacit\u00e9 de la m\u00e9thode est av\u00e9r\u00e9e. Elle n&rsquo;en pr\u00e9sente pas moins des effets qui peuvent s&rsquo;av\u00e9rer pervers par rapport aux buts recherch\u00e9s par le syst\u00e8me, et qui s&rsquo;av\u00e8rent effectivement pervers comme l&rsquo;a montr\u00e9 la campagne du r\u00e9f\u00e9rendum. A vouloir convaincre le citoyen qu&rsquo;il est un sond\u00e9 et un futur \u00e9lecteur dot\u00e9 de grandes qualit\u00e9s morales et civiques, on finit par le convaincre du fait en plus de le convaincre de suivre une conduite civique exemplaire. Il peut alors \u00eatre amen\u00e9 \u00e0 faire preuve d&rsquo;ind\u00e9pendance d&rsquo;esprit et de libre arbitre pour autre chose que pour accepter la voie raisonnable qui lui est sugg\u00e9r\u00e9e. Il est finalement convaincu de se penser assez m\u00fbr du point de vue politique pour penser de lui-m\u00eame.<\/p>\n<\/p>\n<p><p>\tLa voie devient alors redoutable pour le syst\u00e8me. L&rsquo;esprit qui pense par lui-m\u00eame et exp\u00e9rimente la libert\u00e9 comme le bien le plus pr\u00e9cieux en vient rapidement \u00e0 mettre en cause ce qui menace le plus directement sa libert\u00e9. Dans notre univers r\u00e9gi absolument par la m\u00e9canisation, il n&rsquo;est pas de pression plus r\u00e9ductrice et plus oppressante que la m\u00e9canisation. Ce jugement presque de bon sens se renforce d&rsquo;une dimension quasiment \u00e9thique, en opposant les attributs puissants, lib\u00e9rateurs et esth\u00e9tiquement grandioses de la nature \u00e0 la fonction r\u00e9ductrice et artificielle de la m\u00e9canisation. Investi de la libert\u00e9 dans la sph\u00e8re m\u00e9canis\u00e9e du syst\u00e8me (et du sondage pour ce qui nous pr\u00e9occupe) dont il d\u00e9couvre rapidement qu&rsquo;il pr\u00e9tendait faire de lui un simple instrument de la manipulation, l&rsquo;esprit qui pense par lui-m\u00eame finit par avoir la tentation d&rsquo;user de cette libert\u00e9 pour un comportement devenu alors \u00e9vident: s&rsquo;y opposer.<\/p>\n<\/p>\n<p><p>\tObservons que ces processus divers que nous tentons de d\u00e9crire ne sont pas n\u00e9cessairement conscients au niveau individuel, bien au contraire. La campagne du r\u00e9f\u00e9rendum a montr\u00e9 qu&rsquo;il s&rsquo;agit de r\u00e9actions collectives et communautaires plus qu&rsquo;individuelles. La manipulation n&rsquo;est pas ressentie consciemment, de m\u00eame qu&rsquo;elle n&rsquo;est pas faite consciemment par ceux qui la font. Nous privil\u00e9gions l&rsquo;hypoth\u00e8se qu&rsquo;il y a dans la m\u00e9canisation et la manipulation des apprentis-\u00e9lecteurs une agression elle-m\u00eame ressentie inconsciemment, contre laquelle l&rsquo;esprit riposte \u00e9galement d&rsquo;une fa\u00e7on inconsciente. La manipulation m\u00e9canique engendre une r\u00e9volte, exprim\u00e9e naturellement par la contestation du syst\u00e8me, d&rsquo;autant plus forte qu&rsquo;elle est inconsciente dans ses motifs r\u00e9els et qu&rsquo;elle est ressentie comme une lib\u00e9ration: la confrontation avec le syst\u00e8me est une lib\u00e9ration.<\/p>\n<\/p>\n<p><\/p>\n<h3>Comment la m\u00e9canisation de la connaissance des intentions collectives, en \u00e9tant mise en cause par ceux-l\u00e0 m\u00eame qu&rsquo;elle pr\u00e9tend manipuler, finit par leur donner une psychologie collective<\/h3>\n<\/p>\n<p><p>\tAuparavant (les XIX\u00e8me et XX\u00e8me si\u00e8cles), la lib\u00e9ration se faisait par l&rsquo;acte brutal du d\u00e9sordre. La rue \u00e9tait le cadre privil\u00e9gi\u00e9 d&rsquo;une lib\u00e9ration qui passait n\u00e9cessairement par la r\u00e9volte violente. Ce faisant, tous les motifs de d\u00e9voiement, donc de manipulation politique et d&rsquo;appr\u00e9ciations fausses, existaient. La violence poussait \u00e0 cela, dans la mesure o\u00f9 son caract\u00e8re d&rsquo;urgence et son caract\u00e8re de pression insupportables, invitaient sinon for\u00e7aient \u00e0 des accommodements imm\u00e9diats. On trouvait \u00e9videmment dans ces accommodements le d\u00e9voiement, la manipulation politique et l&rsquo;appr\u00e9ciation fausse. La r\u00e9volte naturelle de f\u00e9vrier 1917 \u00e0 Petersbourg d\u00e9bouchait aussit\u00f4t (octobre 1917) sur la dictature et la violence d&rsquo;\u00c9tat affirm\u00e9es, affich\u00e9es et m\u00eame justifi\u00e9es.<\/p>\n<\/p>\n<p><p>\tCes d\u00e9bordements ne sont plus possibles parce que la m\u00e9canisation et la publicit\u00e9 des proc\u00e9dures (l&rsquo;accompagnement statistique de la d\u00e9mocratie et les communications entourant et commentant en permanence la vertu du syst\u00e8me) les interdisent en condamnant et en ridiculisant la violence <em>de facto<\/em> (l&rsquo;esprit lui-m\u00eame de l&rsquo;individu potentiellement r\u00e9volt\u00e9 en vient \u00e0 cette conclusion). Mais cette m\u00e9canisation et cette publicit\u00e9 des proc\u00e9dures ont atteint un tel degr\u00e9 de perfection m\u00e9canique qu&rsquo;elles induisent massivement les effets pervers dont elles sont charg\u00e9es. Dans le cas du r\u00e9f\u00e9rendum, la puissance de ces proc\u00e9dures (et aussi leur caract\u00e8re automatique autant qu&rsquo;\u00e9conomiquement n\u00e9cessaire: qui songerait \u00e0 respirer aujourd&rsquo;hui sans ses trois sondages hebdomadaires qui justifient les instituts statistiques veillant sur notre vertu d\u00e9mocratique?) a \u00e9veill\u00e9 l&rsquo;esprit public \u00e0 une possibilit\u00e9 que l&rsquo;habitude, le verrouillage du syst\u00e8me, la perception de la perfection de la m\u00e9canisation lui avaient sembl\u00e9 interdire: la possibilit\u00e9 de se r\u00e9volter contre le syst\u00e8me en disant, dans ce cas, non \u00e0 la Constitution. Point n&rsquo;est besoin pour cela de lire le texte de la Constitution (dans lequel tel ou tel opposant trouverait, \u00e0 c\u00f4t\u00e9 d&rsquo;articles qui doivent \u00eatre d\u00e9nonc\u00e9s selon son point de vue, des articles qui constituent un r\u00e9el apport,  puisque chacun sait que dans le salmigondis de ce texte soumis aux r\u00e9f\u00e9rendums europ\u00e9ens effectivement, on trouve \u00e0 peu pr\u00e8s tout).<\/p>\n<\/p>\n<p><p>\tJustement, l&rsquo;un des caract\u00e8res bruyamment d\u00e9nonc\u00e9 par les partisans du oui fut, dans cette bataille, le plus int\u00e9ressant et le plus enrichissant. Le non a regroup\u00e9 des oppositions marqu\u00e9es par l&rsquo;absence de coh\u00e9sion, voire par des oppositions fondamentales entre elles. Les souverainistes et les altermondialistes s&rsquo;opposaient \u00e0 la Constitution, autant que, un apport britannique de plus au d\u00e9bat, <em>The Economist<\/em> de Londres. C&rsquo;est justement ce d\u00e9sordre qui fait toute la vertu du non qui n&rsquo;aurait jamais exist\u00e9 sans les sondages de la m\u00e9canisation du syst\u00e8me, puisque personne ne s&rsquo;en serait avis\u00e9. Ce d\u00e9sordre de l&rsquo;opposition remplace le d\u00e9sordre des rues des XIX\u00e8me et XX\u00e8me si\u00e8cles qui ne peut plus \u00eatre. L&rsquo;avantage est que, loin de la pression de la violence, on ne se fait aucune illusion. Chacun sait ce qu&rsquo;il pense et qu&rsquo;il pense diff\u00e9remment de son alli\u00e9 de circonstance. Cette claire conscience des choses dans les circonstances apais\u00e9es de la m\u00e9canisation des processus fait que nul ne doit abroger ses convictions et que le d\u00e9sordre cr\u00e9ateur subsiste sans interf\u00e9rences de pressions manipulatrices (celles des r\u00e9volutionnaires professionnels type L\u00e9nine). Les partisans du syst\u00e8me hurlent que c&rsquo;est un travers \u00e9pouvantable, mais dans le cas du r\u00e9f\u00e9rendum ils n&rsquo;ont gu\u00e8re eu de chance d&rsquo;\u00eatre entendus puisque le r\u00e9sultat de l&rsquo;aventure n&rsquo;imposait aucune remise en ordre directe (nouvelle politique, nouveau gouvernement, etc). Cela fait que, jusqu&rsquo;au bout, chacun a jou\u00e9 son jeu et aucune confiscation n&rsquo;a pu \u00eatre r\u00e9alis\u00e9e par l&rsquo;une ou l&rsquo;autre faction de l&rsquo;opposition (comme L\u00e9nine \u00e9tait finalement parvenu \u00e0 faire en instituant son parti bolchevique comme seul garant  de la libert\u00e9 et du bonheur du monde [les lendemains qui chantent]).<\/p>\n<\/p>\n<p><p>\tAinsi, c&rsquo;est, au contraire, ce d\u00e9sordre du non sans violence ni exc\u00e8s dommageables qui fonde toute la puissance et l&rsquo;int\u00e9r\u00eat de la m\u00e9thode. C&rsquo;est ce d\u00e9sordre qui est lib\u00e9rateur dans la mesure o\u00f9 son objectif n&rsquo;est pas de casser des vitrines et de d\u00e9paver les rues mais de d\u00e9busquer les vices fondamentaux du syst\u00e8me. Ce faisant, il met \u00e0 jour que le syst\u00e8me de m\u00e9canisation du monde, derri\u00e8re son apparence et le commentaire que les communications lui permettent de se faire \u00e0 lui-m\u00eame, n&rsquo;est en fait que d\u00e9sordre. Le d\u00e9sordre du non retrouve la vertu premi\u00e8re du contre-feu: comme la meilleure arme contre le feu est le contre-feu, la meilleure arme contre le d\u00e9sordre du syst\u00e8me est le d\u00e9sordre du non au r\u00e9f\u00e9rendum (en attendant la suite). <\/p>\n<\/p>\n<p><p>\tIl y a l\u00e0 un constat r\u00e9volutionnaire \u00e0 faire. Au contraire d&rsquo;hier o\u00f9 seuls les actes brutaux de rupture (violence) offraient une possibilit\u00e9 d&rsquo;exprimer les grands courants historiques contre le syst\u00e8me et ses manifestations contr\u00f4l\u00e9es et manipul\u00e9es, aujourd&rsquo;hui des processus extr\u00eamement subtils, incontr\u00f4lables et inattendus ont pris le relais,  comme le montre la campagne r\u00e9f\u00e9rendaire. Il y a un changement d\u00e9cisif: hier, les actes brutaux de rupture \u00e9taient eux-m\u00eames aussit\u00f4t manipul\u00e9s et r\u00e9cup\u00e9r\u00e9s au nom du volontarisme historique; c&rsquo;\u00e9tait un effet de Charybde en Scylla, passant de la bureaucratie capitaliste \u00e0 la bureaucratie marxiste-l\u00e9niniste. Rien de semblable aujourd&rsquo;hui, o\u00f9 l&rsquo;inattendu et le caract\u00e8re incontr\u00f4lable emp\u00eachent les manipulations et les r\u00e9cup\u00e9rations. La campagne du non fut exemplaire \u00e0 cet \u00e9gard, son principal d\u00e9faut selon ses accusateurs \u00e9tant sa principale vertu: son absence de coh\u00e9sion et son absence de dirigeants ont rendu d&rsquo;autant plus efficace son travail de destruction du d\u00e9sordre cach\u00e9 du syst\u00e8me par son propre d\u00e9sordre. La mission du non n&rsquo;\u00e9tait certes pas de proposer une alternative, un nouveau syst\u00e8me (sous une forme embryonnaire) \u00e0 la place du syst\u00e8me, mais bien de contribuer un peu plus \u00e0 la d\u00e9stabilisation du syst\u00e8me. La panique extraordinaire de ceux qui se jugeaient comme les gardiens du syst\u00e8me au nom de la raison montre \u00e0 suffisance que la mission a \u00e9t\u00e9 parfaitement remplie. Ce fut donc un \u00e9v\u00e9nement parfait et il laissera une trace profonde.<\/p>\n<\/p>\n<p><\/p>\n<h3>Faut-il en revenir \u00e0 une sorte de providentialisme pour comprendre notre temps? Ou comment les grands courants de l&rsquo;Histoire trouvent aujourd&rsquo;hui des opportunit\u00e9s exceptionnelles de s&rsquo;exprimer, contre la volont\u00e9 des \u00e9lites dont le but est de servir de verrou moral,  car le verrou a saut\u00e9<\/h3>\n<\/p>\n<p><p>\tL&rsquo;extraordinaire caract\u00e9ristique de l&rsquo;\u00e9v\u00e9nement du r\u00e9f\u00e9rendum tient \u00e0 ce qu&rsquo;il s&rsquo;av\u00e8re au bout du compte une attaque mortelle contre le syst\u00e8me alors qu&rsquo;il est n\u00e9 enti\u00e8rement du syst\u00e8me lui-m\u00eame. La m\u00e9canisation du syst\u00e8me, par sa perfection (sondages n\u00e9cessaires) a invent\u00e9 litt\u00e9ralement un d\u00e9bat qui n&rsquo;aurait pas d\u00fb avoir lieu si l&rsquo;on s&rsquo;en tient aux capacit\u00e9s de la dissidence (inexistantes) et aux esp\u00e9rances de l&rsquo;opposition au syst\u00e8me (le oui gagnant d&rsquo;avance, selon cette m\u00e9canisation). En concr\u00e9tisant la possibilit\u00e9 du non, le syst\u00e8me a cr\u00e9\u00e9 de toutes pi\u00e8ces un d\u00e9bat qui n&rsquo;avait aucune raison d&rsquo;\u00eatre. La situation d\u00e9plac\u00e9e soudain vers cette opportunit\u00e9, le d\u00e9bat s&rsquo;\u00e9tant impos\u00e9 dans la r\u00e9alit\u00e9 d&rsquo;une fa\u00e7on compl\u00e8tement naturelle et, dirions-nous, autoris\u00e9e, sa potentialit\u00e9 explosive est apparue. On peut m\u00eame estimer que l&rsquo;explosion a eu lieu.<\/p>\n<\/p>\n<p><p>\tQuelle explication donner? Celle du hasard n&rsquo;est pas satisfaisante, parce que ce qui est survenu \u00e9tait la chose la moins possible, la moins envisageable, dans les circonstances et par les moyens o\u00f9 elle est apparue. On ajoutera que ce n&rsquo;est pas la premi\u00e8re fois que le syst\u00e8me, avec toute sa formidable puissance, se conduit lui-m\u00eame \u00e0 cr\u00e9er des armes redoutables pour ses adversaires (l&rsquo;exemple d&rsquo;Internet, premier diffuseur mondial des informations dissidentes et anti-syst\u00e8mes). L\u00e0 aussi, le hasard semble devoir laisser la place \u00e0 des explications plus historiques, ayant \u00e0 voir avec une fatalit\u00e9 anti-syst\u00e8me. Cela laisse beaucoup d&rsquo;espace de r\u00e9flexion pour d&rsquo;autres hypoth\u00e8ses, beaucoup plus \u00e9lev\u00e9es, voire spirituelles. Il est possible qu&rsquo;on soit conduit \u00e0 consid\u00e9rer dans ces \u00e9v\u00e9nements la manifestation d&rsquo;une adaptation postmoderne de la vieille th\u00e9orie du providentialisme.<\/p>\n<\/p>\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Une trag\u00e9die postmoderne D\u00e9but de cette r\u00e9flexion sur un constat extra-ordinaire: s&rsquo;il n&rsquo;y avait eu les sondages, nous n&rsquo;aurions rien eu de cet \u00e9branlement extra-ordinaire qu&rsquo;est le r\u00e9f\u00e9rendum fran\u00e7ais. Aujourd&rsquo;hui, la R\u00e9volution passe par les outils qui ont servi \u00e0 liquider la R\u00e9volution. Imaginons ce qu&rsquo;auraient \u00e9t\u00e9 ces mois exaltants et stup\u00e9fiants de la campagne&hellip;&nbsp;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","footnotes":"","jetpack_post_was_ever_published":false},"categories":[5],"tags":[],"class_list":["post-66526","post","type-post","status-publish","format-standard","hentry","category-de-defensa"],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/66526","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/comments?post=66526"}],"version-history":[{"count":0,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/66526\/revisions"}],"wp:attachment":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/media?parent=66526"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/categories?post=66526"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/tags?post=66526"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}