{"id":66559,"date":"2005-07-04T00:00:00","date_gmt":"2005-07-04T00:00:00","guid":{"rendered":"https:\/\/new.dedefensa.org\/index.php\/2005\/07\/04\/le-modele-italien-champ-de-manuvre-favori-de-la-cia\/"},"modified":"2005-07-04T00:00:00","modified_gmt":"2005-07-04T00:00:00","slug":"le-modele-italien-champ-de-manuvre-favori-de-la-cia","status":"publish","type":"post","link":"https:\/\/new.dedefensa.org\/index.php\/2005\/07\/04\/le-modele-italien-champ-de-manuvre-favori-de-la-cia\/","title":{"rendered":"<strong><em>Le \u201cmod\u00e8le italien\u201d, champ de man\u0153uvre favori de la CIA <\/em><\/strong>"},"content":{"rendered":"<p><h2 class=\"common-article\">Le mod\u00e8le italien, champ de manuvre favori de la CIA   <\/h2>\n<\/p>\n<p><\/p>\n<p><p>\t4 juillet 2005  Depuis 1943 et le d\u00e9barquement en Sicile, les Am\u00e9ricains sont en Italie comme chez eux. Ils l&rsquo;\u00e9taient en 1943 parce qu&rsquo;ils amenaient dans leurs bagages les recommandations de Charley <em>Lucky<\/em> Luciano, le <em>capo di tutti capi<\/em> de l&rsquo;organisation du crime organis\u00e9 italo-am\u00e9ricain <em>Cosa Nostra<\/em>. Luciano, alors en prison \u00e0 New York, n\u00e9gocia sa lib\u00e9ration anticip\u00e9e et son exil en Italie (en 1945), contre le soutien de la <em>Mafia<\/em> italienne aux forces am\u00e9ricaines qu&rsquo;il obtint en 1943, \u00e0 partir du d\u00e9barquement en Sicile. Les Am\u00e9ricains s&rsquo;install\u00e8rent en Italie, avec la chute du fascisme, comme dans une province reconquise. En 1944, James Jesus Angleton, de l&rsquo;OSS et futur chef du contre-espionnage de la CIA, arriva \u00e0 Rome pour organiser une Italie anticommuniste totalement align\u00e9e sur les USA. Les d\u00e9mocrates-chr\u00e9tiens, aiguillonn\u00e9s par le Vatican lanc\u00e9 dans la bataille anticommuniste, s&rsquo;align\u00e8rent d\u00e9votement sur la ligne US, main dans la main avec la <em>Mafia<\/em>. La victoire d\u00e9mocrate-chr\u00e9tienne aux l\u00e9gislatives de 1948 fut aussi bien celle de la CIA et diverses organisations-relais (le syndicat US AFL-CIO, notamment). C&rsquo;est \u00e0 partir de l&rsquo;Italie que fut organis\u00e9 le gros du r\u00e9seau <em>Gladio<\/em>, l&rsquo;organisation clandestine am\u00e9ricano-otanienne qui contr\u00f4la l&rsquo;essentiel des situations int\u00e9rieures en Europe occidentale pendant la Guerre froide, jusqu&rsquo;\u00e0 des aventures particuli\u00e8rement suspectes <a href=\"http:\/\/www.dedefensa.org\/article.php?art_id=1341\" class=\"gen\">\u00e0 partir de 1965-70<\/a>.<\/p>\n<\/p>\n<p><p>\tVoil\u00e0 quelques traits du tableau historique des rapports de l&rsquo;Italie avec les USA. On notera que nombre d&rsquo;Italiens sont conscients de cette situation et en souffrent mais ils la justifient par la dette qu&rsquo;ils doivent aux Am\u00e9ricains d&rsquo;avoir emp\u00each\u00e9 l&rsquo;investissement de l&rsquo;Italie par les communistes, lors des \u00e9lections de 1948. (Reste \u00e0 voir ce qu&rsquo;aurait \u00e9t\u00e9 cet investissement sans l&rsquo;intervention US, s&rsquo;il aurait eu lieu, etc.)<\/p>\n<\/p>\n<p><p>\tCela explique peut-\u00eatre, en partie, l&rsquo;aisance extraordinaire avec laquelle les Am\u00e9ricains se comportent en Italie selon les traditions les plus solides de l&rsquo;am\u00e9ricanisme. L&rsquo;intensit\u00e9 de leur m\u00e9pris pour la souverainet\u00e9 nationale de l&rsquo;Italie n&rsquo;a d&rsquo;\u00e9gale que <a href=\"http:\/\/www.dedefensa.org\/article.php?art_id=1405\" class=\"gen\">le comique r\u00e9p\u00e9titif<\/a> involontaire <a href=\"http:\/\/www.dedefensa.org\/article.php?art_id=1406\" class=\"gen\">d&rsquo;un Berlusconi<\/a> se plaignant r\u00e9guli\u00e8rement du viol \u00e9galement r\u00e9p\u00e9titif de cette souverainet\u00e9, pour aussit\u00f4t rappeler qu&rsquo;il y a tant de choses (des valeurs communes, on dit) qui unissent l&rsquo;Am\u00e9rique et l&rsquo;Italie. (Selon le <a href=\"http:\/\/www.lefigaro.fr\/europe\/20050702.FIG0128.html?215926\" class=\"gen\">Le Figaro du 2 juillet<\/a>, \u00ab <em>Berlusconi a exig\u00e9 des Etats-Unis le plein respect de la souverainet\u00e9 italienne. L&rsquo;ambassadeur Mel Sembler s&rsquo;est senti oblig\u00e9 de r\u00e9pondre que ce respect \u00e9tait total et continuerait de l&rsquo;\u00eatre \u00e0 l&rsquo;avenir. Pour conclure, et sur un ton plus am\u00e8ne, le pr\u00e9sident du Conseil a r\u00e9affirm\u00e9 que les deux pays \u00e9taient li\u00e9s par une amiti\u00e9 profonde, \u00e9troite et durable, sur la base du respect r\u00e9ciproque.<\/em> \u00bb)<\/p>\n<\/p>\n<p><p>\tDepuis le 11 septembre 2001, l&rsquo;activit\u00e9 US en Italie, et avec les Italiens comme dans le cas de <a href=\"http:\/\/www.dailykos.com\/story\/2005\/3\/5\/9747\/20502\" class=\"gen\">l&rsquo;otage Giuliana Sgrena<\/a>, est compl\u00e8tement extraordinaire, d\u00e9passant m\u00eame les \u00e9v\u00e9nements de l&rsquo;\u00e9poque <em>Gladio<\/em> et des manipulations autour du terrorisme des ann\u00e9es 1970. La derni\u00e8re op\u00e9ration (CIA) r\u00e9v\u00e9l\u00e9e par les Italiens, apr\u00e8s une enqu\u00eate de deux ann\u00e9es, est une \u00e9pure dans le domaine de l&rsquo;action am\u00e9ricaine.<\/p>\n<\/p>\n<p><p>\tL&rsquo;enqu\u00eate a \u00e9t\u00e9 extr\u00eamement minutieuse et de nombreux d\u00e9tails ont \u00e9t\u00e9 rendus publics, officiellement ou non. Manifestement, la justice italienne, qui d\u00e9teste Berlusconi, entend mettre en \u00e9vidence le cas extraordinaire de cette affaire, et embarrasser d&rsquo;autant l&rsquo;actuel Premier ministre. C&rsquo;est une r\u00e9ussite.<\/p>\n<\/p>\n<p><p>\t<a href=\"http:\/\/www.guardian.co.uk\/italy\/story\/0,12576,1519576,00.html\" class=\"gen\">The Guardian du 2 juillet<\/a> nous donne quelques pr\u00e9cieuses indications sur l&rsquo;action am\u00e9ricaine en Italie.<\/p>\n<\/p>\n<p><\/p>\n<p><p>\t\u00ab <em>Washington says it obtains guarantees that suspects grabbed in this way will not be tortured. But, in a call to his wife last year after he was released and before he disappeared again, Abu Omar said he had almost died under torture in an Egyptian jail. His current whereabouts is unknown, though associates say he was rearrested last year.<\/em> <\/p>\n<\/p>\n<p><p>\t\u00bb <em>By ploughing through hundreds of thousands of mobile phone records, tracing hotel registrations and bugging phone conversations, the Italian police have built up a picture of the CIA&rsquo;s operation that offers several surprises.<\/em> <\/p>\n<\/p>\n<p><p>\t\u00bb <em>According to the police version of events, the CIA&rsquo;s special removal unit (SRU) can whistle up private jets to fly its captives unseen across international frontiers.<\/em> <\/p>\n<\/p>\n<p><p>\t\u00bb <em>A Learjet allegedly took Abu Omar from the joint US base at Aviano in Italy to another US base at Ramstein, Germany, then a chartered Gulfstream V whisked him to Cairo. Yet barely a dollar was spent on making the team&rsquo;s communications secure.<\/em> <\/p>\n<\/p>\n<p><p>\t\u00bb <em>The secret agents used ordinary mobile phones. Italian investigators put names to the abductors by matching their calls to the phone contracts they had signed. And they could be sure of the team&rsquo;s movements because they could see when the calls had been made and from which mobile phone.<\/em> <\/p>\n<\/p>\n<p><p>\t\u00bb <em>In at least one case, calls were traced to a phone that was apparently returned to a US diplomatic pool. After a silence it was reactivated by an American citizen using the antenna 100 metres from the US embassy in Rome.<\/em> \u00bb<\/p>\n<\/p>\n<p><\/p>\n<p><p>\t&bull; Nous apprenons que l&rsquo;unit\u00e9 de la CIA charg\u00e9e de l&rsquo;enl\u00e8vement des suspects et de leur acheminement vers les unit\u00e9s de torture en sous-traitance, dans quelque pays-Zoulou de la p\u00e9riph\u00e9rie, se nomme Special Removal Unit (SRU). D&rsquo;autre part, selon <a href=\"http:\/\/www.washingtonpost.com\/wp-dyn\/content\/article\/2005\/06\/29\/AR2005062902971_pf.html\" class=\"gen\">The Washington Post du 30 juin<\/a>, l&rsquo;intervention est le fait d&rsquo;une autre unit\u00e9 de la CIA, \u00ab <em>the CIA&rsquo;s paramilitary branch, the Special Activities Division<\/em>. (Ou bien SRU est dans SAD mais pas inversement?)<\/p>\n<\/p>\n<p><p>\t&bull; Nous apprenons que les bases US de l&rsquo;OTAN (Aviano en Italie, Ramstein en Allemagne) servent de relais pour l&rsquo;enl\u00e8vement ill\u00e9gal de personnes et leur convoiement vers les sous-traitants pour une torture efficace. Autant pour le statut moral de la plus grande alliance de l&rsquo;Histoire.<\/p>\n<\/p>\n<p><p>\t&bull; Tout cela se passe \u00e0 d\u00e9couvert, sans m\u00eame de pr\u00e9caution de brouillage des communications entre agents de la CIA.<\/p>\n<\/p>\n<p><p>\t&bull; Des indications du Washington <em>Post<\/em> d\u00e9j\u00e0 cit\u00e9 nous disent que des instructions seraient venues (en 2002) du plus haut niveau (NSC). (<a href=\"http:\/\/www.washingtonpost.com\/wp-dyn\/content\/article\/2005\/06\/29\/AR2005062902971_pf.html\" class=\"gen\">Pr\u00e9cis\u00e9ment<\/a>: \u00ab <em>Officials involved in the Milan operation at the time said it was conceived by the Rome CIA station chief, organized by the CIA&rsquo;s Counterterrorism Center, and approved by the CIA leadership and by at least one person at the National Security Council. The station chief has since retired but remains undercover.<\/em> \u00bb) D&rsquo;autres indications parlent d&rsquo;initiatives \u00e0 des niveaux interm\u00e9diaires, d&rsquo;autres parlent d&rsquo;un conflit entre le r\u00e9sident de la CIA et sa hi\u00e9rarchie, ce r\u00e9sidant \u00e9tant oppos\u00e9 \u00e0 l&rsquo;op\u00e9ration.<\/p>\n<\/p>\n<p><p>\tEtc, etc. (On parle beaucoup.)<\/p>\n<\/p>\n<p><p>\tCas d&rsquo;\u00e9pure, effectivement, pour une raison pr\u00e9cise : la situation de l&rsquo;Italie, en compl\u00e8te soumission aux USA dans ce domaine, est un spectacle particuli\u00e8rement instructif du d\u00e9sordre qui caract\u00e9rise l&rsquo;action des services de renseignement US dans la guerre contre le terrorisme, notamment leur action dans la plus compl\u00e8te ill\u00e9galit\u00e9, leur acharnement dans des tactiques ineptes, etc. D\u00e9sormais, l&rsquo;action des services US est document\u00e9e de fa\u00e7on extr\u00eamement ouverte, notamment en raison des tensions internes en Italie, r\u00e9sultant notamment de cette abdication compl\u00e8te de la souverainet\u00e9 nationale dont Berlusconi s&rsquo;est fait une r\u00e8gle d&rsquo;or. Tout se tient: l&rsquo;attaque contre la souverainet\u00e9 nationale engendre le d\u00e9sordre dans le pays ainsi touch\u00e9, mais aussi elle r\u00e9v\u00e8le le d\u00e9sordre chez ceux-l\u00e0 m\u00eame qui traitent aussi bassement ce principe de la souverainet\u00e9 nationale. <\/p>\n<\/p>\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Le mod\u00e8le italien, champ de manuvre favori de la CIA 4 juillet 2005 Depuis 1943 et le d\u00e9barquement en Sicile, les Am\u00e9ricains sont en Italie comme chez eux. Ils l&rsquo;\u00e9taient en 1943 parce qu&rsquo;ils amenaient dans leurs bagages les recommandations de Charley Lucky Luciano, le capo di tutti capi de l&rsquo;organisation du crime organis\u00e9 italo-am\u00e9ricain&hellip;&nbsp;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[],"class_list":["post-66559","post","type-post","status-publish","format-standard","hentry","category-faits-et-commentaires"],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/66559","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/comments?post=66559"}],"version-history":[{"count":0,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/66559\/revisions"}],"wp:attachment":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/media?parent=66559"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/categories?post=66559"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/tags?post=66559"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}