{"id":66565,"date":"2005-07-05T00:00:00","date_gmt":"2005-07-05T00:00:00","guid":{"rendered":"https:\/\/new.dedefensa.org\/index.php\/2005\/07\/05\/chirac-aux-fourneaux-les-hamburgers-volent-bas\/"},"modified":"2005-07-05T00:00:00","modified_gmt":"2005-07-05T00:00:00","slug":"chirac-aux-fourneaux-les-hamburgers-volent-bas","status":"publish","type":"post","link":"https:\/\/new.dedefensa.org\/index.php\/2005\/07\/05\/chirac-aux-fourneaux-les-hamburgers-volent-bas\/","title":{"rendered":"Chirac aux fourneaux: les hamburgers volent bas"},"content":{"rendered":"<p><p>La presse <em>british<\/em> oscille entre l&rsquo;indignation, la condescendance m\u00e9prisante, l&rsquo;inqui\u00e9tude effar\u00e9e, la stup\u00e9faction \u00e9trangl\u00e9e et l&rsquo;on en passe. Tony Blair, en mission JO \u00e0 Singapour, a \u00e9t\u00e9 absolument furieux mais il restera digne au sommet du G8 car, <a href=\"http:\/\/www.telegraph.co.uk\/news\/main.jhtml?xml=\/news\/2005\/07\/05\/wchir05.xml&#038;sSheet=\/portal\/2005\/07\/05\/ixportaltop.html\" class=\"gen\">nous assure-t-on<\/a>, il est \u00ab <em>determined to retain the moral high ground<\/em> \u00bb. (L\u00e8vres pinc\u00e9es mais l\u00e9g\u00e8rement m\u00e9prisantes, son porte-parole officiel a laiss\u00e9 tomber : \u00ab <em>There are some things that are just not responded to<\/em> \u00bb ; <em>and<\/em> toc.)<\/p>\n<\/p>\n<p><p>\tQue se passe-t-il, que se passe-t-il? Personne d&rsquo;entre vous n&rsquo;ignore plus les appr\u00e9ciations du pr\u00e9sident fran\u00e7ais en secret, \u00e0 Kaliningrad, avec les amis Schr\u00f6der et Poutine, micros branch\u00e9s pour permettre aux journalistes d&rsquo;entendre. Cela fut imprim\u00e9 le 4 juillet <a href=\"http:\/\/www.liberation.fr\/page.php?Article=308723\" class=\"gen\">dans Lib\u00e9ration<\/a>, qui <a href=\"http:\/\/www.liberation.fr\/page.php?Article=308723\" class=\"gen\">maintient h\u00e9ro\u00efquement ses informations<\/a> malgr\u00e9 un d\u00e9menti mi-figue mi-raison, entre poire et fromage et style propos de table, de l&rsquo;entourage du pr\u00e9sident fran\u00e7ais.<\/p>\n<\/p>\n<p><p>\tPour rappel, un extrait de <em>Lib\u00e9ration<\/em> du 3 juillet:<\/p>\n<\/p>\n<p><p>\t\u00ab <em> Chirac s&rsquo;est lanc\u00e9 hier dans une s\u00e9rie de blagues sur le dos des Anglais, faisant bien rire Poutine et Schr\u00f6der. La seule chose qu&rsquo;ils ont faite pour l&rsquo;agriculture europ\u00e9enne, c&rsquo;est la vache folle, a ainsi balanc\u00e9 Chirac, pr\u00e9venant ses deux comp\u00e8res que, de toute fa\u00e7on, on ne peut pas faire confiance \u00e0 des gens qui ont une cuisine aussi mauvaise: Apr\u00e8s la Finlande, c&rsquo;est le pays o\u00f9 on mange le plus mal. Et les hamburgers?, a tent\u00e9 Poutine, qui cultive un reste de rivalit\u00e9 avec les Etats-Unis. Non, non, les hamburgers, ce n&rsquo;est rien encore, a r\u00e9pondu Chirac. Et le pr\u00e9sident fran\u00e7ais de raconter encore comment l&rsquo;Ecossais lord Robertson, ancien secr\u00e9taire g\u00e9n\u00e9ral de l&rsquo;Otan, lui avait fait go\u00fbter une sp\u00e9cialit\u00e9 peu rago\u00fbtante de son pays: De l\u00e0, nos difficult\u00e9s avec l&rsquo;Otan&#8230;<\/em> \u00bb<\/p>\n<\/p>\n<p><\/p>\n<p><p>\tNotre premi\u00e8re remarque, c&rsquo;est : que fait la Finlande? Qui s&rsquo;occupe de panser ses plaies? (Apr\u00e8s tout, on y mange encore plus mal qu&rsquo;en Angleterre, c&rsquo;est dire.)<\/p>\n<\/p>\n<p><p>\tNotre seconde remarque, c&rsquo;est le rappel assez banal mais toujours rafra\u00eechissant, \u00e0 l&rsquo;occasion de ces fuites organis\u00e9es (on le jurerait), que tous ces hommes politiques postmodernes, pompeux et ennuyeux lorsqu&rsquo;ils sont en activit\u00e9 conformiste, restent des \u00eatres humains comme vous et moi. C&rsquo;est une bonne chose car cela permet le d\u00e9foulement n\u00e9cessaire \u00e0 leur bon \u00e9quilibre psychologique, et cela nous confirme que nous ne sommes pas encore compl\u00e8tement dans le <em>1984<\/em> d&rsquo;Orwell.  <\/p>\n<\/p>\n<p><p>\tNotre troisi\u00e8me remarque est qu&rsquo;il y a entre les Anglais et les Fran\u00e7ais quelque chose qui est comme un lien qui les retient. Si l&rsquo;un ou l&rsquo;autre n&rsquo;existait pas, il faudrait l&rsquo;inventer pour que le solitaire ne devienne pas neurasth\u00e9nique. Dans cette affaire, personne n&rsquo;incrimine le Russe et l&rsquo;Allemand et nul ne s&rsquo;occupe de la Finlande. C&rsquo;est comme si, \u00e0 part la France et l&rsquo;Angleterre et leur mise en bo\u00eete respective, le <em>rest of the world<\/em> n&rsquo;existait pas (<em>sorry<\/em>, GW).<\/p>\n<\/p>\n<p><p>\tNotre quatri\u00e8me remarque, c&rsquo;est qu&rsquo;il est vrai que ce Robertson, secr\u00e9taire g\u00e9n\u00e9ral de l&rsquo;OTAN et ancien voyou des rues, avait un go\u00fbt \u00e9pouvantable, \u00e0 vous d\u00e9go\u00fbter d&rsquo;\u00eatre dans l&rsquo;OTAN. Voil\u00e0 qui confirme le bien-fond\u00e9 de la d\u00e9cision de 1964 du g\u00e9n\u00e9ral.<\/p>\n<\/p>\n<p><p>\tDans la presse britannique, <a href=\"http:\/\/news.independent.co.uk\/europe\/article296896.ece\" class=\"gen\">The Independent<\/a> a tenu \u00e0 contribuer \u00e0 r\u00e9duire la tension entre les deux pays, au moins dans les populations respectives, autant que faire se peut. M\u00eame si \u00ab <em>the newspaper Le Parisien said that a nation which eats boiled beef with mint had no right to comment on anything to do with food<\/em> \u00bb, il y a tout de m\u00eame la nouvelle que \u00ab <em>French farmers have adopted a more positive approach, greeting British tourists arriving at Channel ports with free cheese, fruit and tomatoes.<\/em> \u00bb<\/p>\n<\/p>\n<p><\/p>\n<p><p>\tMis en ligne le 5 juillet 2005 \u00e0 14H35<\/p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>La presse british oscille entre l&rsquo;indignation, la condescendance m\u00e9prisante, l&rsquo;inqui\u00e9tude effar\u00e9e, la stup\u00e9faction \u00e9trangl\u00e9e et l&rsquo;on en passe. Tony Blair, en mission JO \u00e0 Singapour, a \u00e9t\u00e9 absolument furieux mais il restera digne au sommet du G8 car, nous assure-t-on, il est \u00ab determined to retain the moral high ground \u00bb. (L\u00e8vres pinc\u00e9es mais l\u00e9g\u00e8rement&hellip;&nbsp;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","footnotes":"","jetpack_post_was_ever_published":false},"categories":[2],"tags":[705,4632],"class_list":["post-66565","post","type-post","status-publish","format-standard","hentry","category-bloc-notes","tag-blair","tag-kaliningrad"],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/66565","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/comments?post=66565"}],"version-history":[{"count":0,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/66565\/revisions"}],"wp:attachment":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/media?parent=66565"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/categories?post=66565"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/tags?post=66565"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}