{"id":66581,"date":"2005-07-10T00:00:00","date_gmt":"2005-07-10T00:00:00","guid":{"rendered":"https:\/\/new.dedefensa.org\/index.php\/2005\/07\/10\/les-chiffres-impressionnants-du-commerce-des-armes-disrael-vers-la-chine\/"},"modified":"2005-07-10T00:00:00","modified_gmt":"2005-07-10T00:00:00","slug":"les-chiffres-impressionnants-du-commerce-des-armes-disrael-vers-la-chine","status":"publish","type":"post","link":"https:\/\/new.dedefensa.org\/index.php\/2005\/07\/10\/les-chiffres-impressionnants-du-commerce-des-armes-disrael-vers-la-chine\/","title":{"rendered":"Les chiffres impressionnants du commerce des armes d&rsquo;Isra\u00ebl vers la Chine"},"content":{"rendered":"<p><p>Une r\u00e9cente estimation a \u00e9t\u00e9 donn\u00e9e sur le volume des transactions de syst\u00e8mes d&rsquo;armes isra\u00e9liens vers la Chine. Ce volume d\u00e9passerait d\u00e9sormais, pour la premi\u00e8re fois depuis 2004, le volume des autres transactions commerciales. En 2004, les exportations normales d&rsquo;Isra\u00ebl vers la Chine auraient atteint $2,4 milliards et le volume des exportations de syst\u00e8mes d&rsquo;armes et de technologies satellitaires (assimil\u00e9es au m\u00eame domaine strat\u00e9gique que les armes) aurait atteint $2,5 milliards. Ces chiffres ont notamment \u00e9t\u00e9 r\u00e9percut\u00e9s par la t\u00e9l\u00e9vision isra\u00e9lienne <em>Channel Two<\/em>.<\/p>\n<\/p>\n<p><p>\tIl s&rsquo;agit d&rsquo;un volume consid\u00e9rable, et qui ne serait nullement exceptionnel. Le tr\u00e8s fort volume d&rsquo;exportation de syst\u00e8mes d&rsquo;arme de 2004 n&rsquo;a fait que confirmer une tendance r\u00e9guli\u00e8re \u00e0 la hausse depuis 1990-91. Ce volume place Isra\u00ebl, selon les ann\u00e9es, \u00e9pisodiquement comme premier fournisseur d&rsquo;armes de la Chine en concurrence pour cette place avec la Russie.<\/p>\n<\/p>\n<p><p>\tL&rsquo;importance de ces \u00e9changes est telle, et la satisfaction des partenaires si grande, qu&rsquo;il existe tout un courant d&rsquo;analystes \u00e0 Washington pour penser que, malgr\u00e9 toutes les pressions US et les affirmations publiques d&rsquo;Isra\u00ebl de cessation de ces transferts vers la Chine, ceux-ci devraient pourtant continuer. Il se confirme ainsi qu&rsquo;il y a l\u00e0 une crise potentielle grave entre les USA et Isra\u00ebl.<\/p>\n<\/p>\n<p><\/p>\n<p><p>\tMis en ligne le 10 juillet 2005 \u00e0 09H20<\/p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Une r\u00e9cente estimation a \u00e9t\u00e9 donn\u00e9e sur le volume des transactions de syst\u00e8mes d&rsquo;armes isra\u00e9liens vers la Chine. Ce volume d\u00e9passerait d\u00e9sormais, pour la premi\u00e8re fois depuis 2004, le volume des autres transactions commerciales. En 2004, les exportations normales d&rsquo;Isra\u00ebl vers la Chine auraient atteint $2,4 milliards et le volume des exportations de syst\u00e8mes d&rsquo;armes&hellip;&nbsp;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","footnotes":"","jetpack_post_was_ever_published":false},"categories":[2],"tags":[],"class_list":["post-66581","post","type-post","status-publish","format-standard","hentry","category-bloc-notes"],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/66581","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/comments?post=66581"}],"version-history":[{"count":0,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/66581\/revisions"}],"wp:attachment":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/media?parent=66581"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/categories?post=66581"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/tags?post=66581"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}