{"id":66637,"date":"2005-07-27T00:00:00","date_gmt":"2005-07-27T00:00:00","guid":{"rendered":"https:\/\/new.dedefensa.org\/index.php\/2005\/07\/27\/usa-israel-la-crise-saggrave\/"},"modified":"2005-07-27T00:00:00","modified_gmt":"2005-07-27T00:00:00","slug":"usa-israel-la-crise-saggrave","status":"publish","type":"post","link":"https:\/\/new.dedefensa.org\/index.php\/2005\/07\/27\/usa-israel-la-crise-saggrave\/","title":{"rendered":"USA-Isra\u00ebl: la crise s&rsquo;aggrave"},"content":{"rendered":"<p><h2 class=\"common-article\">USA-Isra\u00ebl: la crise s&rsquo;aggrave<\/h2>\n<\/p>\n<p><p>\t27 juillet 2005  La crise entre Isra\u00ebl et les USA s&rsquo;est brusquement aggrav\u00e9e avec l&rsquo;annonce de l&rsquo;annulation d&rsquo;un voyage du ministre de la d\u00e9fense isra\u00e9lien \u00e0 Washington. C&rsquo;est le journal <a href=\"http:\/\/www.haaretz.com\/hasen\/spages\/605342.html\" class=\"gen\">Haaretz qui l&rsquo;annonce aujourd&rsquo;hui<\/a>, avec des pr\u00e9cisions particuli\u00e8rement impressionnantes sur la position am\u00e9ricaine.<\/p>\n<\/p>\n<p><p>\t\u00ab <em>Defense Minister Shaul Mofaz, who was about to leave for Washington for talks on the matter, canceled the trip following the increased U.S. demands. The crisis erupted over Israel&rsquo;s sale to China of replacement parts for Harpy attack drones.<\/em><\/p>\n<\/p>\n<p><p>\t\u00bb <em>The U.S. wants to see Knesset legislation enacted within 18 months tightening oversight of military exports, and is demanding a memorandum of understanding be signed. The U.S. also wants a written apology from Israel and Mofaz.<\/em><\/p>\n<\/p>\n<p><p>\t\u00bb <em>Opposition in Israel is mounting against the signing of such a memorandum. In any case, the agreement is not intended to end the crisis, but rather to stop it from gathering steam, by allowing for the gradual lifting of sanctions.<\/em><\/p>\n<\/p>\n<p><p>\t\u00bb <em>The sanctions were imposed as the result of a bill passed last month by the U.S. House of Representatives, which placed a five-year ban on the purchase of defense items from any country that sells arms to China.<\/em> \u00bb<\/p>\n<\/p>\n<p><p>\tLes exigences am\u00e9ricaines sont impressionnantes et confirment les pr\u00e9visions, tant sur <a href=\"http:\/\/www.dedefensa.org\/article.php?art_id=1474\" class=\"gen\">la chasse aux sorci\u00e8res<\/a> que sur <a href=\"http:\/\/www.dedefensa.org\/article.php?art_id=1759\" class=\"gen\">le maccarthysme transatlantique<\/a>, dans ce cas pour les Europ\u00e9ens (ils ne perdent rien pour attendre un tout petit peu) et dont les Isra\u00e9liens sont les premiers \u00e0 go\u00fbter les fruits amers.<\/p>\n<\/p>\n<p><p>\tLa partie de phrase la plus int\u00e9ressante de l&rsquo;article de <MI>Haaretz est certainement celle-ci: \u00ab <em>Opposition in Israel is mounting against<\/em> \u00bb,  signe que les Isra\u00e9liens commencent vraiment \u00e0 en avoir assez. Le probl\u00e8me, pour Isra\u00ebl est bien celui de la souverainet\u00e9 nationale, tel que nous commencions \u00e0 le pr\u00e9ciser <a href=\"http:\/\/www.dedefensa.org\/article.php?art_id=1582\" class=\"gen\">le 24 mai dernier<\/a>, avec d&rsquo;autres pr\u00e9cisions <a href=\"http:\/\/www.dedefensa.org\/article.php?art_id=1663\" class=\"gen\">depuis<\/a>.<\/p>\n<\/p>\n<p><p>\tC&rsquo;est une partie impressionnante qui est engag\u00e9e entre Isra\u00ebl et les USA, avec la partie am\u00e9ricaniste totalement obs\u00e9d\u00e9e par cette question des transferts d&rsquo;armements vers la Chine, sans le moindre souci pour la souverainet\u00e9 d&rsquo;autrui, f\u00fbt-ce l&rsquo;alli\u00e9 isra\u00e9lien.<\/p>\n<\/p>\n<p><p>\tPour l&rsquo;instant, sur cette question, nous proposons en commentaire un extrait de la rubrique <em>de defensa<\/em> du num\u00e9ro 20, Volume 20, de la livraison du 10 juillet 2005 de notre Lettre d&rsquo;Analyse <em>de defensa<\/em>. Nous y traitions bri\u00e8vement du cas d&rsquo;Isra\u00ebl plac\u00e9 face \u00e0 la perspective de l&rsquo;alli\u00e9 d\u00e9vorant que sont devenus les USA, notamment dans cette affaire des transferts de technologies vers la Chine. Nous y faisions preuve de pessimisme quant aux circonstances \u00e0 court terme (capitulation probable d&rsquo;Isra\u00ebl) et de r\u00e9alisme \u00e0 plus long terme (la crise USA-Isra\u00ebl ne pourra que s&rsquo;aggraver). Le long terme pourrait s&rsquo;av\u00e9rer beaucoup plus proche que nous n&rsquo;avions pr\u00e9vu.<\/p>\n<h3>Le cas d&rsquo;Isra\u00ebl<\/h3>\n<\/p>\n<p><p>\tSans doute le cas isra\u00e9lien est-il la meilleure illustration de l&rsquo;incapacit\u00e9 o\u00f9 nous nous trouvons de distinguer les v\u00e9ritables dimensions, voire les v\u00e9ritables constituants d&rsquo;un ph\u00e9nom\u00e8ne d\u00e9crit comme dramatique [NDLR : le ph\u00e9nom\u00e8ne de la perte d&rsquo;identit\u00e9 et de souverainet\u00e9]. La question est, en effet, pour Isra\u00ebl, de savoir quelle est la principale menace contre son existence. La r\u00e9ponse habituelle, unanime, imp\u00e9rative est le terrorisme. Mais tout le monde ne dit pas cela. Certains souvenirs restent, qui m\u00e9ritent d&rsquo;\u00eatre rappel\u00e9s.<\/p>\n<\/p>\n<p><p>\tDurant la guerre d&rsquo;octobre 1973, Kissinger joua avec les d\u00e9lais  divers pour retarder l&rsquo;ouverture d&rsquo;un pont a\u00e9rien d&rsquo;armements vers Isra\u00ebl alors en grandes difficult\u00e9s face aux Syriens (Kissinger exigeait certaines concessions politiques d&rsquo;Isra\u00ebl pour ordonner la livraison d&rsquo;armes). Certains Isra\u00e9liens purent alors se demander d&rsquo;o\u00f9 venait la v\u00e9ritable menace contre l&rsquo;existence d&rsquo;Isra\u00ebl. La main-mise du syst\u00e8me am\u00e9ricaniste (essentiellement le complexe militaro-industriel) sur Isra\u00ebl s&rsquo;est acc\u00e9l\u00e9r\u00e9e avec l&rsquo;\u00e9limination du projet d&rsquo;avion de combat national <em>Lavi<\/em> sous la pression du Pentagone, en 1986. Moshe Arens estimait qu&rsquo;il s&rsquo;agissait d&rsquo;un revers  dramatique pour la souverainet\u00e9 nationale isra\u00e9lienne. Le m\u00eame Moshe Arens, alors qu&rsquo;il \u00e9tait ministre de la d\u00e9fense dans le gouvernement Shamir, eut un entretien orageux avec Bush-p\u00e8re \u00e0 propos du r\u00f4le des missiles sol-air <em>Patriot<\/em> que les Am\u00e9ricains avaient d\u00e9ploy\u00e9s en Isra\u00ebl contre les <em>Scud<\/em> irakiens durant la guerre du Golfe. Bush-p\u00e8re sermonna violemment Arens parce que celui-ci avait d\u00e9clar\u00e9 que l&rsquo;efficacit\u00e9 des <em>Patriot<\/em> avait \u00e9t\u00e9 nulle (aucun <em>Scud<\/em> d\u00e9truit par les <em>Patriot<\/em>, selon lui). Raytheon, fabriquant des <em>Patriot<\/em> et bailleur de fonds des Bush, avait r\u00e9clam\u00e9 un s\u00e9v\u00e8re rappel \u00e0 l&rsquo;ordre, voire la t\u00eate du ministre isra\u00e9lien de la d\u00e9fense pour ses d\u00e9clarations.<\/p>\n<\/p>\n<p><p>\tOn observe, dans cette perspective, que la guerre contre la terreur n&rsquo;a gu\u00e8re modifi\u00e9 la tradition,  car il s&rsquo;agit bien d&rsquo;une tradition,  et, des pressions de Douglas Feith (du DoD) jusqu&rsquo;\u00e0 l&rsquo;intervention de Rice pour que les Isra\u00e9liens cessent leurs livraisons de syst\u00e8mes de technologies avanc\u00e9es aux Chinois, les \u00e9v\u00e9nements ne sont pas accidentels. Ces pressions ont abouti \u00e0 la capitulation annonc\u00e9e d&rsquo;Isra\u00ebl, qui pourrait envisager de cesser ses relations avec la Chine. Il y aura des compensations, certes, mais le coup port\u00e9 \u00e0 la souverainet\u00e9 nationale est de la sorte qui ne se r\u00e9pare pas avec des $milliards.<\/p>\n<\/p>\n<p><p>\tL&rsquo;exemple isra\u00e9lien doit \u00eatre appr\u00e9ci\u00e9 comme \u00e9difiant. Une perspective tr\u00e8s concevable, et que nous jugeons probable, est que la difficult\u00e9 grandissante (d\u00e9vorante, pourrait-on dire) des relations avec les USA va prendre le pas sur la question du terrorisme, jusqu&rsquo;\u00e0 devenir l&rsquo;hypoth\u00e8que centrale pesant sur la souverainet\u00e9 de l&rsquo;\u00c9tat juif. La question r\u00e9elle \u00e0 laquelle Isra\u00ebl va faire face n&rsquo;est pas celle de son existence au sens habituel qui est envisag\u00e9, parce que cette existence-l\u00e0 est \u00e9videmment assur\u00e9e par sa puissance, mais bien celle de sa souverainet\u00e9 et de son identit\u00e9,  qui est une autre forme d&rsquo;existence, peut-\u00eatre plus essentielle \u00e0 terme. Avec un alli\u00e9 comme les USA, c&rsquo;est une question tout simplement fondamentale.<\/p>\n<\/p>\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>USA-Isra\u00ebl: la crise s&rsquo;aggrave 27 juillet 2005 La crise entre Isra\u00ebl et les USA s&rsquo;est brusquement aggrav\u00e9e avec l&rsquo;annonce de l&rsquo;annulation d&rsquo;un voyage du ministre de la d\u00e9fense isra\u00e9lien \u00e0 Washington. C&rsquo;est le journal Haaretz qui l&rsquo;annonce aujourd&rsquo;hui, avec des pr\u00e9cisions particuli\u00e8rement impressionnantes sur la position am\u00e9ricaine. \u00ab Defense Minister Shaul Mofaz, who was about&hellip;&nbsp;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[3992,3977,2774,4096,3157],"class_list":["post-66637","post","type-post","status-publish","format-standard","hentry","category-faits-et-commentaires","tag-armes","tag-chine","tag-israel","tag-technologies","tag-transfert"],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/66637","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/comments?post=66637"}],"version-history":[{"count":0,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/66637\/revisions"}],"wp:attachment":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/media?parent=66637"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/categories?post=66637"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/tags?post=66637"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}