{"id":66645,"date":"2005-07-30T00:00:00","date_gmt":"2005-07-30T00:00:00","guid":{"rendered":"https:\/\/new.dedefensa.org\/index.php\/2005\/07\/30\/urgent-on-demande-un-bouche-a-bouche-pour-le-jsf\/"},"modified":"2005-07-30T00:00:00","modified_gmt":"2005-07-30T00:00:00","slug":"urgent-on-demande-un-bouche-a-bouche-pour-le-jsf","status":"publish","type":"post","link":"https:\/\/new.dedefensa.org\/index.php\/2005\/07\/30\/urgent-on-demande-un-bouche-a-bouche-pour-le-jsf\/","title":{"rendered":"<strong><em>Urgent: on demande un bouche-\u00e0-bouche pour le JSF<\/em><\/strong>"},"content":{"rendered":"<p><h2 class=\"common-article\">Urgent: on demande un bouche-\u00e0-bouche pour le JSF<\/h2>\n<\/p>\n<p><\/p>\n<p><p>\t30 juillet 2005  En 2000, le TGE (Tr\u00e8s-Grand Expert) de l&rsquo;industrie a\u00e9rospatiale du monde (c&rsquo;est-\u00e0-dire l&rsquo;industrie a\u00e9rospatiale am\u00e9ricaniste), Richard Aboulafia, avait \u00e9crit (dans <em>Aviation Week &#038; Space Technology<\/em>, 2 janvier 2000) l&rsquo;une et l&rsquo;autre de ces quelques phrases qui vous exp\u00e9dient <em>groggy<\/em>: \u00ab <em>It could be said that JSF is as much a national industrial strategy as it is a fighter program. The JSF could simply do to the European military industry what the F-16 almost did: destroy it.<\/em> \u00bb Au reste, dans un rapport publi\u00e9 il y a peu et vendu au prix qu&rsquo;il faut, le TGE <a href=\"http:\/\/www.dedefensa.org\/article.php?art_id=1643\" class=\"gen\">fit un copier-coller<\/a> et reprit les phrases telles quelles, tant l&rsquo;ensemble est de belle facture litt\u00e9raire et conceptuelle,  non sauf ceci: F-35 et plus JSF,  et puis ceci aussi, que nous n&rsquo;avions pas not\u00e9 sur l&rsquo;instant et qui vaut pourtant son pesant de pellicule: <em>kill it<\/em> (version 2005) au lieu de <em>destroy it<\/em> (version 2000); cela fait quand m\u00eame plus John Wayne dans <em>Les diables de Guadalcanal<\/em>.<\/p>\n<\/p>\n<p><p>\tLe JSF est la premi\u00e8re merveille du monde du domaine, et il le reste selon le TGE, dans tous les cas en f\u00e9vrier 2005, date de son plus r\u00e9cent rapport s\u00e9rieux sur la chose. La question annexe, pas envisag\u00e9e par le TGE, est: le JSF respire-t-il encore?<\/p>\n<\/p>\n<p><p>\tAujourd&rsquo;hui (c&rsquo;est-\u00e0-dire hier et m\u00eame avant-hier, 28 et 29 juillet), un journal dont on se demande s&rsquo;il faut le qualifier de grand quotidien \u00e9conomique bien inform\u00e9 ou <a href=\"http:\/\/www.dedefensa.org\/article.php?art_id=1788\" class=\"gen\">de comics pour galopin<\/a>, le <em>Financial Times<\/em>, publie une information (?) sur le sort du JSF am\u00e9ricain,  \u00e0 faire fr\u00e9mir, l&rsquo;information. Nous fr\u00e9missons. Le TGE, sans doute en vacances \u00e0 Malibu, n&rsquo;a pas le loisir de fr\u00e9mir.<\/p>\n<\/p>\n<p><p>\tEn gros, cela donne ceci, d&rsquo;apr\u00e8s <a href=\"http:\/\/www.defensenews.com\/story.php?F=1003310&#038;C=americas\" class=\"gen\">Defense News (Reuters) du 29 juillet<\/a>, qui en rapporte la substance, sans trop de commentaires tant la chose laisse sans voix (<em>speechless<\/em>):<\/p>\n<\/p>\n<p><\/p>\n<p><p>\t\u00ab <em>The U.S. Defense Department is considering proposals to cut the $200 billion-plus Joint Strike Fighter program by up to 70 per cent, Britain&rsquo;s Financial Times newspaper reported on July 29.<\/em> <\/p>\n<\/p>\n<p><p>\t\u00bb <em>The Pentagon has looked at several proposals to cut the project as part of a department-wide review of all weapons systems, the FT said, citing people briefed on internal Pentagon discussions. The report said one proposal includes scrapping the version of the JSF being built for the U.S. Air Force, which would see the 2,400-fighter project cut by 1,700 aircraft. A second proposal would see the U.S. Navy&rsquo;s version cut, the paper said.<\/em> <\/p>\n<\/p>\n<p><p>\t\u00bb <em>The Pentagon denied that senior decision-makers were considering cutting parts of the JSF, the FT reported. Speculation about individual programs by people who themselves will not be involved in the decisions is irresponsible, uninformed and unhelpful, it quoted Pentagon spokesman Larry Di Rita as saying. I have no doubt that somewhere in the beancounting end of the department people are laying out all kinds of possible scenarios, but if they are doing that, it is on the basis of incomplete slivers of info.<\/em> \u00bb<\/p>\n<\/p>\n<p><\/p>\n<\/p>\n<p><p>\tPour finir, le tr\u00e8s court articulet cit\u00e9 ici nous pr\u00e9cise: \u00ab <em>The Joint Strike Fighter is a U.S.-led effort to develop a relatively affordable family of radar-evading, supersonic multi-role warplanes with co-financing from eight other countries.<\/em> \u00bb Cela pour nous rappeler la chose de la coop\u00e9ration et nous faire supposer que les huit autres pays coop\u00e9rants sont soumis au choix draconien de mettre l&rsquo;\u00e9dition du FT \u00e0 la poubelle ou d&rsquo;envisager un m\u00e9mo interne pour se poser quelques questions sur le sort de leur coop\u00e9ration dans le programme JSF.<\/p>\n<\/p>\n<p><p>\tIl faut en effet pr\u00e9ciser, comme le FT lui-m\u00eame le fait, que personne parmi les huit pays coop\u00e9rants dont certains se targuent d&rsquo;\u00eatre grands et habiles, n&rsquo;est au courant. Pas parce que la chose n&rsquo;a pas eu lieu (maintenant, soyons s\u00e9rieux: le FT n&rsquo;a pas l&rsquo;habitude de publier des billeves\u00e9es) mais parce que, <a href=\"http:\/\/news.ft.com\/cms\/s\/bc2b1888-ff9c-11d9-86df-00000e2511c8.html\" class=\"gen\">selon le m\u00eame FT<\/a>, \u00ab <em>In spite of the size of the changes being considered, those who have been briefed say none of the eight international partners on the JSF programme, including the UK, has been consulted<\/em> \u00bb.<\/p>\n<\/p>\n<p><p>\tLe quotidien britannique, pudique et flegmatique comme il sait \u00eatre, ajoute ce commentaire sans fioritures: \u00ab <em>The British Ministry of Defence declined to comment.<\/em> \u00bb Cela signifie qu&rsquo;en tendant un peu l&rsquo;oreille du c\u00f4t\u00e9 de Whitehall, en choisissant un jour sans attentats \u00e0 Londres, on pourrait entendre les exclamations de fureur et insultes diverses (<em>You Sanavabitches, Bloody Yanks<\/em>, par exemple) (voir note ci-dessous) r\u00e9sonner d&rsquo;un mur \u00e0 l&rsquo;autre dans les divers services du MoD concern\u00e9s. Les <em>Britts<\/em> auront, dans le cas du JSF comme dans les autres cas de leur relation privil\u00e9gi\u00e9e, bu le calice jusqu&rsquo;\u00e0 la lie, avec la surprise de d\u00e9couvrir qu&rsquo;il reste toujours un peu de lie \u00e0 boire apr\u00e8s qu&rsquo;on ait cru avoir effectivement bu le calice jusqu&rsquo;\u00e0 la lie.<\/p>\n<\/p>\n<p><p>\tLe FT note encore, plut\u00f4t acide derri\u00e8re le flegme, \u00e0 l&rsquo;image de ses inspirateurs \u00e0 Whitehall ou \u00e0 Downing Street:<\/p>\n<\/p>\n<p><\/p>\n<p><p>\t\u00ab <em>Any decision to cut the number of aircraft produced would drive up the costs of the remaining fighters, since development costs, which have risen from $25bn when the programme was launched in 1996 to $45bn today, would be spread out over a smaller number of aircraft.<\/em><\/p>\n<\/p>\n<p><p>\t\u00bb <em>Analysts said such a price rise would put the entire JSF programme in jeopardy, since remaining customers might no longer be able to afford the fighter.<\/em> \u00bb <\/p>\n<\/p>\n<p><\/p>\n<p><p>\tLe commentaire sur le fond demande un peu plus de temps. On y reviendra. L&rsquo;information du FT, en effet, a pour premier effet de nous laisser <em>speechless<\/em>, comme le MoD lui-m\u00eame,  mais pas tant sur le sort du JSF que sur le comportement des Am\u00e9ricains, qui font toujours mieux que le pire qu&rsquo;on attend d&rsquo;eux. Enfin, il faut raison garder: tout cela ne concerne que des sc\u00e9narios, envisag\u00e9s, nous dit notre petit doigt, dans le cadre de la QDR-2005, <a href=\"http:\/\/www.dedefensa.org\/article.php?art_id=1635\" class=\"gen\">mod\u00e8le de mesure et de rigueur<\/a> comme chacun sait.<\/p>\n<\/p>\n<p><\/p>\n<p><p>\t@NOTES = <em>Sanavabitches<\/em> est la transcription litt\u00e9rale du fameux <em>son of a bitch<\/em> (traduit qui veut, mais fils de chienne ou, mieux, fils de pute pourrait faire l&rsquo;affaire), \u00e9ruct\u00e9 par Georges S. Patton quand il jugeait que ses <em>Sherman<\/em> n&rsquo;allaient pas assez vite, aux trousses des <em>panzers<\/em> en d\u00e9route.<\/p>\n<\/p>\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Urgent: on demande un bouche-\u00e0-bouche pour le JSF 30 juillet 2005 En 2000, le TGE (Tr\u00e8s-Grand Expert) de l&rsquo;industrie a\u00e9rospatiale du monde (c&rsquo;est-\u00e0-dire l&rsquo;industrie a\u00e9rospatiale am\u00e9ricaniste), Richard Aboulafia, avait \u00e9crit (dans Aviation Week &#038; Space Technology, 2 janvier 2000) l&rsquo;une et l&rsquo;autre de ces quelques phrases qui vous exp\u00e9dient groggy: \u00ab It could be said&hellip;&nbsp;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[4520,2851,4482,2852],"class_list":["post-66645","post","type-post","status-publish","format-standard","hentry","category-faits-et-commentaires","tag-4520","tag-financial","tag-qdr","tag-times"],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/66645","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/comments?post=66645"}],"version-history":[{"count":0,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/66645\/revisions"}],"wp:attachment":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/media?parent=66645"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/categories?post=66645"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/tags?post=66645"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}