{"id":66656,"date":"2005-08-01T00:00:00","date_gmt":"2005-08-01T00:00:00","guid":{"rendered":"https:\/\/new.dedefensa.org\/index.php\/2005\/08\/01\/entre-israel-et-washington-une-crise-de-confiance\/"},"modified":"2005-08-01T00:00:00","modified_gmt":"2005-08-01T00:00:00","slug":"entre-israel-et-washington-une-crise-de-confiance","status":"publish","type":"post","link":"https:\/\/new.dedefensa.org\/index.php\/2005\/08\/01\/entre-israel-et-washington-une-crise-de-confiance\/","title":{"rendered":"<strong><em>Entre Isra\u00ebl et Washington, une \u201ccrise de confiance\u201d\u2026<\/em><\/strong>"},"content":{"rendered":"<p><h2 class=\"common-article\">Entre Isra\u00ebl et Washington, une crise de confiance<\/h2>\n<\/p>\n<p><\/p>\n<p><p>\t1er ao\u00fbt 2005  Il ne faut pas craindre de poser et de poser encore son regard sur cette question des rapports entre les USA et Isra\u00ebl, qu&rsquo;on a <a href=\"http:\/\/www.dedefensa.org\/article.php?art_id=1779\" class=\"gen\">d\u00e9j\u00e0 largement abord\u00e9e<\/a>, jusqu&rsquo;\u00e0 indirectement (<a href=\"http:\/\/www.dedefensa.org\/article.php?art_id=1781\" class=\"gen\">en y ajoutant le facteur fran\u00e7ais<\/a>) le 28 juillet encore.<\/p>\n<\/p>\n<p><p>\tLes \u00e9chos divers de cette crise, notamment imprim\u00e9s, sont extraordinairement prudents et circonspects, en m\u00eame temps qu&rsquo;ils restent assez rares. Les rapports entre les deux pays sont fondamentaux, \u00e0 la fois tr\u00e8s d\u00e9licats et d&rsquo;une complexit\u00e9 inou\u00efe. Un changement significatif dans ces rapports signifierait un bouleversement formidable,  et nous parlons certes d&rsquo;un bouleversement politique et strat\u00e9gique, mais, plus encore, d&rsquo;un bouleversement psychologique.<\/p>\n<\/p>\n<p><p>\tAu Pentagone, o\u00f9 les journalistes posaient le vendredi 29 juillet des questions \u00e0 propos de l&rsquo;aspect de la vente d&rsquo;armes isra\u00e9liennes \u00e0 la Chine de cette crise (puisqu&rsquo;il ne s&rsquo;agit effectivement que d&rsquo;un aspect de la crise), la langue de bois est compl\u00e8te, verrouill\u00e9e, sans une seule interstice qui puisse laisser passer une raie de lumi\u00e8re. A entendre le porte-parole du DoD Lawrence Di Rita (dans <a href=\"http:\/\/www.haaretz.com\/hasen\/objects\/pages\/PrintArticleEn.jhtml?itemNo=606741\" class=\"gen\">Haaretz du 31 juillet<\/a>), on croirait l&rsquo;entendre parler de <a href=\"http:\/\/www.dedefensa.org\/article.php?art_id=1787\" class=\"gen\">l&rsquo;article du FT sur le JSF<\/a>. Par exemple :<\/p>\n<\/p>\n<p><\/p>\n<p><p>\t\u00ab <em>Tough issues remain in a dispute between Israel and the United States over Israeli arms sales to China, but talks to resolve them are not stalemated, a Pentagon official said on Friday. Pentagon spokesperson Lawrence Di Rita cited good progress in the talks but refused to put a timetable on the negotiations, which were delayed last week when Defense Minister Shaul Mofaz canceled a planned trip to Washington to take part in ongoing talks.<\/em><\/p>\n<\/p>\n<p><p>\t(&#8230;)<\/p>\n<\/p>\n<p><p>\t\u00bb <em>I have talked to people who are involved, who think this is going to be resolved, in the time-honored phrase, sooner rather than later. They don&rsquo;t think this is something that is going to take forever, Di Rita told reporters in response to questions at the Pentagon on Friday.<\/em><\/p>\n<\/p>\n<p><p>\t\u00bb <em>That was an assessment by people involved as of the last day or two &#8230; There still is a general sense that they will probably get something done, he said.<\/em> \u00bb<\/p>\n<\/p>\n<p><\/p>\n<p><p>\tAlors, comment en juger?<\/p>\n<\/p>\n<p><p>\tL&rsquo;article de commentaire du journaliste de <em>Haaretz<\/em>, Ze&rsquo;ev Schiff, en date du 29 juillet est int\u00e9ressant. (Nous le publions <a href=\"http:\/\/www.dedefensa.org\/choix.php?link_id=5726&#038;comm=1\" class=\"gen\">aujourd&rsquo;hui dans Nos choix comment\u00e9s<\/a>.) Il est prudentissime, il est \u00e9crit comme si l&rsquo;auteur marchait sur des ufs,  mais il nous dit certaines choses tr\u00e8s int\u00e9ressantes, notamment par leur nouveaut\u00e9. (L&rsquo;on peut \u00eatre s\u00fbr que les esquisses d&rsquo;analyse que Ze&rsquo;ev Schiff pr\u00e9sente sont proches de celles du gouvernement isra\u00e9lien, et qu&rsquo;elles repr\u00e9sentent \u00e9galement, dans la formulation o\u00f9 elles sont faites, l&rsquo;appr\u00e9ciation la plus conciliante pour les vues de Washington qu&rsquo;on puisse en donner du c\u00f4t\u00e9 isra\u00e9lien.) Cela permet de compl\u00e9ter le tableau et de voir que la perception pessimiste qu&rsquo;on a d\u00e9j\u00e0 signal\u00e9e, de la situation g\u00e9n\u00e9rale des rapports isra\u00e9lo-am\u00e9ricains, n&rsquo;est pas exag\u00e9r\u00e9e.<\/p>\n<\/p>\n<p><p>\tOn trouvera ci-dessous quelques citations extraites de l&rsquo;article, avec quelques rapides commentaires tentant d&rsquo;en d\u00e9gager la signification.<\/p>\n<\/p>\n<p><p>\t&bull; Comment faut-il appr\u00e9cier cette crise? \u00ab <em>It is a serious crisis, which has spilled over into political and economic spheres&#8230;<\/em> \u00bb La phrase est significative. Elle nous montre que la crise ne peut \u00eatre r\u00e9duite \u00e0 la seule question des ventes d&rsquo;armes \u00e0 la Chine, quelque importance qu&rsquo;ait ce domaine. D&rsquo;une certaine fa\u00e7on, il s&rsquo;agit d&rsquo;une surprise (pour nous, mais aussi, chemin faisant, pour les Isra\u00e9liens et les Am\u00e9ricains eux-m\u00eames).<\/p>\n<\/p>\n<p><p>\t&bull; &#8230; A preuve, cette remarque, qui n&rsquo;est pas rien: \u00ab <em> One of the conclusions is that no comprehensive strategic dialogue is currently taking place<\/em> [&#8230;] <em>The strategic dialogue between the countries has slowly evaporated over the past two years&#8230;<\/em> \u00bb Ze&rsquo;ev Schiff donne un exemple de cette absence de dialogue entre Isra\u00e9liens et Am\u00e9ricains: \u00ab <em>An example of the shallowness of the strategic contacts is the absence of a fundamental discussion between the United States and Israel regarding the U.S. administration&rsquo;s plan to expand the democratic process in the Middle East.<\/em> \u00bb Il s&rsquo;agit d&rsquo;une critique indirectement dite, mais ferme, des Isra\u00e9liens \u00e0 l&rsquo;encontre des Am\u00e9ricains. Le probl\u00e8me est sans doute que les Isra\u00e9liens ignorent que cette absence de consultation des Am\u00e9ricains sur les plans de l&rsquo;administration US dans le domaine de la d\u00e9mocratisation du Moyen-Orient repose d&rsquo;abord sur le fait que ces plans n&rsquo;existent pas. Mais, bien s\u00fbr, les Isra\u00e9liens ne peuvent croire cela et il n&rsquo;est pas question que les Am\u00e9ricains le disent.<\/p>\n<\/p>\n<p><p>\t&bull; Les Isra\u00e9liens se sont tromp\u00e9s sur l&rsquo;ampleur de la crise sur la question des transferts d&rsquo;armements, notamment sur les intentions des Am\u00e9ricains, leur position tr\u00e8s dure dans cet affrontement. Cette remarque le dit : \u00ab <em>The assumption was that Washington would end the crisis before the disengagement. Instead, the Americans have presented more stringent demands.<\/em> \u00bb Alors, <em>mea culpa<\/em> de la part des Isra\u00e9liens? Peut-\u00eatre, mais qui tient \u00e0 la seule tactique: \u00ab <em>We must ask how it happened that almost all Israel&rsquo;s assessments regarding the conduct of negotiations with the Americans in the Chinese UAV affair have proved to be mistaken. Israel maneuvered itself into a situation where its friends in the administration and in Congress cannot, or do not wish to, help it in this matter.<\/em> \u00bb<\/p>\n<\/p>\n<p><p>\t&bull; &#8230;Il n&#8217;emp\u00eache, il y a des conditions que les Isra\u00e9liens n&rsquo;accepteront pas, malgr\u00e9 toute la bonne volont\u00e9 du monde. Isra\u00ebl ne veut pas \u00eatre trait\u00e9 comme une r\u00e9publique banani\u00e8re: \u00ab <em>Because <\/em>[the Americans] <em>feel affronted, they are not taking into account the political situation in Israel, and are trying to dictate to the Knesset, in an insulting manner, a timetable for its decisions. An agreement is meant to end a crisis, and not to force a friendly nation to agree to be punished in stages. Even a banana republic would not sign such an agreement.<\/em> \u00bb<\/p>\n<\/p>\n<p><p>\tIl est difficile, \u00e0 la lumi\u00e8re de ces diverses remarques, de ne pas conclure selon la proposition de d\u00e9part, que la crise entre les deux pays est effectivement grave. Ze&rsquo;ev Schiff nous en donne d&rsquo;ailleurs la mesure, par une phrase peut-\u00eatre imprudente, ou bien voulue mais avec un sens de gravit\u00e9 extr\u00eame m\u00eame si les termes restent prudents: \u00ab <em>Israel is making efforts to end the dispute but is not succeeding, apparently because it is a crisis of confidence.<\/em> \u00bb Une crise de confiance entre deux pays qu&rsquo;on nous pr\u00e9sente et qui se pr\u00e9sentent comme apparemment si compl\u00e8tement soud\u00e9s, si compl\u00e8tement unis sur des valeurs qui reposent justement sur une confiance commune et r\u00e9ciproque compl\u00e8te, c&rsquo;est une chose \u00e0 la fois surprenante et gravissime.<\/p>\n<\/p>\n<p><p>\tL&rsquo;article de Ze&rsquo;ev Schiff est donc prudentissime, pour nous d\u00e9crire une situation gravissime Il nous confirme que les contacts r\u00e9els entre Isra\u00ebl et Washington se perdent aujourd&rsquo;hui dans les quiproquos, l&rsquo;amertume et le soup\u00e7on, et surtout l&rsquo;incompr\u00e9hension qui est la m\u00e8re de toutes les tensions et la voie vers la possibilit\u00e9 d&rsquo;une perte de contr\u00f4le de l&rsquo;\u00e9volution des choses. La crise am\u00e9ricaine, la situation d\u00e9form\u00e9e par le virtualisme, la brutalit\u00e9 des rapports US avec l&rsquo;ext\u00e9rieur qui en d\u00e9coule, ne sont pas pour rien dans cette gravit\u00e9. Tout est en place, effectivement, pour une \u00e9volution de plus en plus chaotique, d&rsquo;autant que le chaos int\u00e9rieur washingtonien n&rsquo;est pas pr\u00eat de cesser. C&rsquo;est dire si nous maintenons <a href=\"http:\/\/www.dedefensa.org\/article.php?art_id=1781\" class=\"gen\">notre hypoth\u00e8se fondamentale<\/a> sur l&rsquo;arri\u00e8re-plan de la situation, portant sur la question de la souverainet\u00e9, avec la possibilit\u00e9 d&rsquo;\u00e9volutions spectaculaires et surprenantes (dans ce cas entre Isra\u00ebl et la France).<\/p>\n<\/p>\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Entre Isra\u00ebl et Washington, une crise de confiance 1er ao\u00fbt 2005 Il ne faut pas craindre de poser et de poser encore son regard sur cette question des rapports entre les USA et Isra\u00ebl, qu&rsquo;on a d\u00e9j\u00e0 largement abord\u00e9e, jusqu&rsquo;\u00e0 indirectement (en y ajoutant le facteur fran\u00e7ais) le 28 juillet encore. Les \u00e9chos divers de&hellip;&nbsp;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[4678,2746,3519,610],"class_list":["post-66656","post","type-post","status-publish","format-standard","hentry","category-faits-et-commentaires","tag-incomprehension","tag-souverainete","tag-technologie","tag-virtualisme"],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/66656","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/comments?post=66656"}],"version-history":[{"count":0,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/66656\/revisions"}],"wp:attachment":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/media?parent=66656"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/categories?post=66656"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/tags?post=66656"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}