{"id":66686,"date":"2005-08-09T00:00:00","date_gmt":"2005-08-09T00:00:00","guid":{"rendered":"https:\/\/new.dedefensa.org\/index.php\/2005\/08\/09\/bouvard-and-pecuchet-at-war-suite\/"},"modified":"2005-08-09T00:00:00","modified_gmt":"2005-08-09T00:00:00","slug":"bouvard-and-pecuchet-at-war-suite","status":"publish","type":"post","link":"https:\/\/new.dedefensa.org\/index.php\/2005\/08\/09\/bouvard-and-pecuchet-at-war-suite\/","title":{"rendered":"<strong><em>Bouvard and Pecuchet at war (suite*)<\/em><\/strong>"},"content":{"rendered":"<p><h2 class=\"common-article\">Bouvard and Pecuchet at war (suite*)<\/h2>\n<\/p>\n<p><\/p>\n<p><p>\t9 ao\u00fbt 2005  Jamais pris de court, le Pentagone s&rsquo;est aper\u00e7u qu&rsquo;il y a une nouvelle forme de guerre en cours en Irak, c&rsquo;est-\u00e0-dire une forme de guerre \u00e0 laquelle les forces am\u00e9ricaines ne sont pas adapt\u00e9es. La surprise est totale et cette trouvaille consid\u00e9rable m\u00e9riterait des mesures ad\u00e9quates, a conclu le Pentagone.<\/p>\n<\/p>\n<p><p>\tMontrant une souplesse consid\u00e9rable, le Pentagone prend donc des mesures pour s&rsquo;adapter. Il a form\u00e9 une unit\u00e9 sp\u00e9ciale, le Asymmetric Warfare Group (AWG), dont le r\u00f4le va \u00eatre de partir partout o\u00f9 l&rsquo;arm\u00e9e am\u00e9ricaine se bat, c&rsquo;est-\u00e0-dire partout o\u00f9 elle essuie des revers, pour comprendre, compiler, classer, analyser, soupeser, etc, les conditions de cette nouvelle guerre, avant de r\u00e9diger un rapport volumineux dont nombre d&rsquo;experts recevront un exemplaire, charge \u00e0 eux de faire les commentaires qui s&rsquo;imposent&#8230; On pourrait avoir les premi\u00e8res conclusions sur la nouvelle guerre en cours, disons en 2007-2008, peut-\u00eatre apr\u00e8s la d\u00e9faite en Irak. (Cela, ces pr\u00e9cisions de date, supposition rageuse ou moqueuse de notre part.)<\/p>\n<\/p>\n<p><p>\tUn texte de <a href=\"http:\/\/www.defensenews.com\/story.php?F=979727&#038;C=america\" class=\"gen\">Defense News du 1er ao\u00fbt 2005<\/a> rend compte de l&rsquo;\u00e9v\u00e9nement. <\/p>\n<\/p>\n<p><p>\tCe texte introduit indirectement, mais dans l&rsquo;encha\u00eenement naturel de son raisonnement et des informations qu&rsquo;il veut nous donner, d&rsquo;\u00e9tonnantes et significatives contradictions. S&rsquo;il est fait, et avec quel s\u00e9rieux, pour exposer la r\u00e9alit\u00e9 des difficult\u00e9s de la situation des forces arm\u00e9es am\u00e9ricaines et les solutions \u00e9ventuelles \u00e0 apporter, il aboutit, par inadvertance, \u00e0 \u00e9clairer la r\u00e9alit\u00e9 de l&rsquo;appr\u00e9ciation intellectuelle de cette situation. On peut ainsi mieux comprendre les sp\u00e9cificit\u00e9s \u00e9tranges de la psychologie am\u00e9ricaniste.<\/p>\n<\/p>\n<p><p>\t&bull; Premi\u00e8re d\u00e9monstration :<\/p>\n<\/p>\n<p><\/p>\n<p><p>\t\u00ab <em>The asymmetric warriors of tomorrow are learning their lessons today, and they&rsquo;re taking notes, said Col. Robert Shaw, commander of the AWG. We&rsquo;ve got to get out of reaction mode and into predicting, because what happens in Iraq, those same tactics, techniques and procedures pop up somewhere else in the world.<\/em> <\/p>\n<\/p>\n<p><p>\t\u00bb <em>What used to be labeled low-intensity conflict by the U.S. military is now called asymmetric warfare, where an enemy pursues unconventional tactics to nullify America&rsquo;s decidedly high-tech advantages. The military&rsquo;s high-tech revolution, the centerpiece of Defense Secretary Donald Rumsfeld&rsquo;s transformation efforts, has run into the reality of a less than revolutionary war in Iraq.<\/em> \u00bb<\/p>\n<\/p>\n<p><\/p>\n<p><p>\tLe premier paragraphe nous cite le brillant colonel Shaw, chef de l&rsquo;AWG, nous exposant certaines consid\u00e9rations concernant la nouvelle forme de guerre qu&rsquo;on qualifie, comme chacun sait, d&rsquo;asym\u00e9trique. Donc, une guerre compl\u00e8tement nouvelle, inattendue, extraordinaire, \u00e0 laquelle le Pentagone va devoir s&rsquo;adapter Patatras ! Le second paragraphe nous r\u00e9v\u00e8le le pot aux roses : \u00ab <em>What used to be labeled low-intensity conflict by the U.S. military is now called asymmetric warfare, where an enemy pursues unconventional tactics to nullify America&rsquo;s decidedly high-tech advantages.<\/em> \u00bb Autrement dit, la guerre asym\u00e9trique existait avant, on l&rsquo;appelait LIC (<em>Low Intensity Conflict<\/em>), terme utilis\u00e9 dans les ann\u00e9es 1960 jusqu&rsquo;\u00e0 la fin des ann\u00e9es 1980. Le changement d&rsquo;acronyme a \u00e9t\u00e9 fatal \u00e0 la r\u00e9alit\u00e9: le Pentagone a jet\u00e9 LIC aux oubliettes, conclu que la guerre de basse intensit\u00e9, future guerre asym\u00e9trique, n&rsquo;existait plus, pour d\u00e9couvrir qu&rsquo;elle existe toujours et se nomme d\u00e9sormais guerre asym\u00e9trique. Il ne faut jamais jeter un acronyme avant d&rsquo;avoir v\u00e9rifi\u00e9 s&rsquo;il a compl\u00e8tement servi.<\/p>\n<\/p>\n<p><p>\t&bull; Deuxi\u00e8me d\u00e9monstration, mais plut\u00f4t pour franchement sourire, tant les enfonceurs de portes ouvertes peuvent se montrer involontairement dr\u00f4les. Voici un de ces guerriers <em>high-tech<\/em> qui vous parle des voitures-suicides comme \u00e9tant the warfare of the future<D>,  un de ces esprits compartiment\u00e9s, \u00e9cartant un instant le F\/A-22 ou le JSF pour s&rsquo;exclamer devant le postmodernisme des voitures-suicides, non pardon des IED des terroristes : \u00ab <em>What we are seeing is the warfare of the future, Votel, commander of the Improvised Explosive Device (IED) Task Force, said last fall when describing the formation of the new AWG. The IED Task Force eventually will be part of the AWG.<\/em> \u00bb<\/p>\n<\/p>\n<p><p>\t&bull; Troisi\u00e8me d\u00e9monstration, qui est dans le mode encore plus intellectuel.<\/p>\n<\/p>\n<p><\/p>\n<p><p>\t\u00ab <em>We&rsquo;re in a new era of warfare, <\/em>[Shaw] <em>said. A lot of asymmetric warfare is understanding it first, understanding that an enemy will do what he can to seek out your weak spots. Every bad guy with a brain is thinking up a new way to kill us every day.<\/em> \u00bb<\/p>\n<\/p>\n<p><\/p>\n<p><p>\tCes remarques de Shaw sont pr\u00e9c\u00e9d\u00e9es de l&rsquo;appr\u00e9ciation g\u00e9n\u00e9rale de ce m\u00eame colonel Shaw, homme exp\u00e9riment\u00e9 en la mati\u00e8re, \u00ab <em>sees asymmetric warfare as a predominantly intellectual versus technological challenge<\/em> \u00bb. La principale trouvaille de cette recherche quasiment initiatique est qu&rsquo;il faut d&rsquo;abord bien comprendre, pour comprendre la guerre asym\u00e9trique, que l&rsquo;adversaire cherche vos points faibles pour vous frapper de fa\u00e7on plus efficace et d\u00e9vastatrice ; car, comble du comble de la trouvaille, chaque m\u00e9chant \u00e9quip\u00e9 de cette chose (actuellement non r\u00e9f\u00e9renc\u00e9e sous acronyme du Pentagone) qu&rsquo;on nomme cerveau cherche chaque jour, la crapule, une nouvelle fa\u00e7on de vous tuer, si possible in\u00e9dite, si possible efficace et ainsi de suite.<\/p>\n<\/p>\n<p><p>\tTout cela nousest ass\u00e9n\u00e9 sur un ton docte et avec le plus grand s\u00e9rieux du monde.<\/p>\n<\/p>\n<p><p>\t&bull; Quatri\u00e8me et derni\u00e8re d\u00e9monstration, de type g\u00e9ographique celle-l\u00e0. Il faut \u00eatre pr\u00eat \u00e0 affronter ce redoutable ennemi l\u00e0 o\u00f9 il se manifestera Mais o\u00f9? \u00ab <em>You&rsquo;ve got to look at the threat today and where it can go in the future, to study the insurgent groups, see what they&rsquo;re doing, Shaw said. We&rsquo;ve got to get out of reacting and into predicting, he said, and identify the area that will be the next Iraq or Afghanistan.<\/em> \u00bb<\/p>\n<\/p>\n<p><p>\tCette remarque, \u00e0 partir des exemples choisis, est remarquable d&rsquo;humour involontaire et bureaucratique. Nous voyons notre brave colonel Shaw se demandant o\u00f9 l&rsquo;ennemi va frapper, citant l&rsquo;Afghanistan et l&rsquo;Irak comme exemple de telles situations (\u00ab <em>identify the area that will be the next Iraq or Afghanistan.<\/em> \u00bb),  alors que ce sont pr\u00e9cis\u00e9ment les Am\u00e9ricains qui ont choisi de frapper en Afghanistan et en Irak, et de fa\u00e7on totalement arbitraire et erron\u00e9e quant \u00e0 la lutte contre le terrorisme en choisissant l&rsquo;Irak<\/p>\n<\/p>\n<p><p>\tPass\u00e9e cette revue de d\u00e9tails, proposons quelques conclusions :<\/p>\n<\/p>\n<p><p>\t&bull; Le Pentagone s&rsquo;est aper\u00e7u qu&rsquo;il se passe quelque chose en Irak.<\/p>\n<\/p>\n<p><p>\t&bull; Il a identifi\u00e9 une nouvelle sorte de guerre aussi vieille que le monde : la guerre du faible contre le fort, ou de David contre Goliath.<\/p>\n<\/p>\n<p><p>\t&bull; Il se doute de quelque chose et va entreprendre des recherches : il semblerait que David (le faible) ait vaincu Goliath (le fort).<\/p>\n<\/p>\n<p><p>\t&bull; Il va \u00e9tudier le probl\u00e8me et proposer des solutions qui n&rsquo;ont \u00e9videmment aucune chance de donner le moindre r\u00e9sultat sinon d&rsquo;aggraver les choses.<\/p>\n<\/p>\n<p><p>\t&bull; Il nous est ainsi confirm\u00e9 que la psychologie de la bureaucratie du Pentagone, et la psychologie am\u00e9ricaniste en g\u00e9n\u00e9ral, sont totalement coup\u00e9es du reste du monde, de la r\u00e9alit\u00e9, et de tout ce qui a le moindre rapport avec ce qu&rsquo;on nomme bon sens. Le cloisonnement est complet, les rapports de causes \u00e0 effets r\u00e9solument ignor\u00e9s et ainsi de suite.<\/p>\n<\/p>\n<p><p>\tDans le m\u00eame article et sans beaucoup d&rsquo;espoir d&rsquo;arriver \u00e0 quelque r\u00e9sultat que ce soit, le strat\u00e8ge William S. Lind, sp\u00e9cialiste de la guerre asym\u00e9trique, qui d\u00e9nonce depuis des ann\u00e9es la folle politique du Pentagone d&rsquo;acquisition syst\u00e9matique de hautes technologies, remarque :<\/p>\n<\/p>\n<p><\/p>\n<p><p>\t\u00ab <em>The problem isn&rsquo;t technology or equipment, the problem is we don&rsquo;t understand how to fight this kind of war, said Bill Lind, a leading voice of the group.<\/em> <\/p>\n<\/p>\n<p><p>\t\u00bb <em>As evidence, Lind points to the fighting in Iraq, where the guerrillas&rsquo; most lethal weapons are the omnipresent rocket-propelled grenade, a weapon developed in the 1960s, and often crudely constructed IEDs. The high-tech U.S. military, with all its computers, airborne sensors and spy satellites, has little counter against these low-tech weapons.<\/em> <\/p>\n<\/p>\n<p><p>\t()<\/p>\n<\/p>\n<p><p>\t\u00bb <em>Counterinsurgency warfare is often described as a clash between David and Goliath. The big, well-armed and heavily armored Goliath is ponderous and slow moving in the face of the small, agile David who brings Goliath to his knees with a stone.<\/em> <\/p>\n<\/p>\n<p><p>\t\u00bb <em> A belief in technological superiority is why Goliath always loses, Lind said. The more you make yourself look like Goliath, the more you say how superior you are, the more you guarantee your own defeat.<\/em> \u00bb<\/p>\n<\/p>\n<p><\/p>\n<p><p>\t(*) Nous l&rsquo;avouons platement, nous avons repris ce titre&#8230; \u00e0 nous-m\u00eames, \u00e0 un texte de la Lettre d&rsquo;Analyse <em>de defensa<\/em> du <a href=\"http:\/\/www.dedefensa.org\/article.php?art_id=36\" class=\"gen\">25 mars 2001<\/a>, offrant une r\u00e9flexion sur la guerre du Kosovo deux ans plus t\u00f4t. Nous pensons, gravement, en pesant nos mots, qu&rsquo;il y a une cha\u00eene humaine de la stupidit\u00e9, comme une magnifique continuit\u00e9 de la b\u00eatise entre ce conflit et celui que nous suivons aujourd&rsquo;hui, notamment dans l&rsquo;aspect virtualiste d&rsquo;invention d&rsquo;une r\u00e9alit\u00e9 artificielle \u00e0 la place de la r\u00e9alit\u00e9.<\/p>\n<\/p>\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Bouvard and Pecuchet at war (suite*) 9 ao\u00fbt 2005 Jamais pris de court, le Pentagone s&rsquo;est aper\u00e7u qu&rsquo;il y a une nouvelle forme de guerre en cours en Irak, c&rsquo;est-\u00e0-dire une forme de guerre \u00e0 laquelle les forces am\u00e9ricaines ne sont pas adapt\u00e9es. La surprise est totale et cette trouvaille consid\u00e9rable m\u00e9riterait des mesures ad\u00e9quates,&hellip;&nbsp;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[3745,1012],"class_list":["post-66686","post","type-post","status-publish","format-standard","hentry","category-faits-et-commentaires","tag-asymetrique","tag-lind"],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/66686","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/comments?post=66686"}],"version-history":[{"count":0,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/66686\/revisions"}],"wp:attachment":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/media?parent=66686"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/categories?post=66686"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/tags?post=66686"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}