{"id":66687,"date":"2005-08-09T00:00:00","date_gmt":"2005-08-09T00:00:00","guid":{"rendered":"https:\/\/new.dedefensa.org\/index.php\/2005\/08\/09\/reponse-de-ito-a-ito-et-a-un-ami-lecteur\/"},"modified":"2005-08-09T00:00:00","modified_gmt":"2005-08-09T00:00:00","slug":"reponse-de-ito-a-ito-et-a-un-ami-lecteur","status":"publish","type":"post","link":"https:\/\/new.dedefensa.org\/index.php\/2005\/08\/09\/reponse-de-ito-a-ito-et-a-un-ami-lecteur\/","title":{"rendered":"R\u00e9ponse de Ito \u00e0 Ito (et \u00e0 un ami lecteur)"},"content":{"rendered":"<p><p>Nous tentons de rassurer un ami lecteur (voir <a href=\"http:\/\/www.dedefensa.org\/forum.php?art_id=1824\" class=\"gen\">le message de Patrick Chapus<\/a> sur le <em>Forum<\/em> du <em>F&#038;C<\/em> du 8 ao\u00fbt) en relayant la r\u00e9ponse du maire de Nagasaki Iccho Ito, n\u00e9 deux semaines apr\u00e8s l&rsquo;atomisation de sa ville par les civilis\u00e9s, \u00e0 Joichi Ito, qui propose de <a href=\"http:\/\/www.dedefensa.org\/article.php?art_id=1824\" class=\"gen\">lobotomiser la m\u00e9moire de l&rsquo;atomisation de la dite villle<\/a>. (Quant \u00e0 la similitude des noms et compte tenu de nos connaissances tr\u00e8s limit\u00e9es en japonais, nous restons aussi interdits que Patrick Chapus.)<\/p>\n<\/p>\n<p><p>\tBref, Iccho Ito le maire est aussi d\u00e9cid\u00e9 \u00e0 conserver la m\u00e9moire de l&rsquo;atomisation de sa ville que Joichi Ito le publiciste-entrepreneur <em>high tech<\/em> est d\u00e9termin\u00e9 \u00e0 en obtenir la liquidation. Iccho Ito le maire s&rsquo;interroge justement sur la fa\u00e7on de proc\u00e9der pour y parvenir (selon une d\u00e9p\u00eache AFP du 8 ao\u00fbt <a href=\"http:\/\/www.spacewar.com\/2005\/050808011254.exbgsedp.html\" class=\"gen\">reprise sur le site Spacewar.com<\/a>).<\/p>\n<\/p>\n<p><p>\t\u00ab <em>With witnesses to the world&rsquo;s only nuclear attacks rapidly passing away, Japan faces the tough task of how to preserve memories of the unthinkable horror for a younger and often disinterested generation. Thousands of aged survivors are dying each year in both Hiroshima and Nagasaki, the southwestern city which on August 9, 1945 became the second and so far last place to endure nuclear attack.<\/em><\/p>\n<\/p>\n<p><p>\t\u00bb <em>It isn&rsquo;t easy, Nagasaki Mayor Iccho Ito, who was born just two weeks after the nuclear explosion that killed 70,000 people, said of handing down the legacy. As those who have direct experience are dying, we have to keep an anti-nuclear message alive, Ito told AFP. We hope young people will stand up and expand the network.<\/em> \u00bb<\/p>\n<\/p>\n<p><p>\tMis en ligne le 9 ao\u00fbt 2005 \u00e0 15H30<\/p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Nous tentons de rassurer un ami lecteur (voir le message de Patrick Chapus sur le Forum du F&#038;C du 8 ao\u00fbt) en relayant la r\u00e9ponse du maire de Nagasaki Iccho Ito, n\u00e9 deux semaines apr\u00e8s l&rsquo;atomisation de sa ville par les civilis\u00e9s, \u00e0 Joichi Ito, qui propose de lobotomiser la m\u00e9moire de l&rsquo;atomisation de la&hellip;&nbsp;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","footnotes":"","jetpack_post_was_ever_published":false},"categories":[2],"tags":[3782,3409,1325,4701],"class_list":["post-66687","post","type-post","status-publish","format-standard","hentry","category-bloc-notes","tag-ba","tag-bombe","tag-hiroshima","tag-nagasaki"],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/66687","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/comments?post=66687"}],"version-history":[{"count":0,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/66687\/revisions"}],"wp:attachment":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/media?parent=66687"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/categories?post=66687"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/tags?post=66687"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}