{"id":66757,"date":"2005-08-31T00:00:00","date_gmt":"2005-08-31T00:00:00","guid":{"rendered":"https:\/\/new.dedefensa.org\/index.php\/2005\/08\/31\/ou-est-passee-la-garde\/"},"modified":"2005-08-31T00:00:00","modified_gmt":"2005-08-31T00:00:00","slug":"ou-est-passee-la-garde","status":"publish","type":"post","link":"https:\/\/new.dedefensa.org\/index.php\/2005\/08\/31\/ou-est-passee-la-garde\/","title":{"rendered":"O\u00f9 est pass\u00e9e la Garde?"},"content":{"rendered":"<p><p>Les secours et les mesures de protection dans les \u00c9tats du Mississipi et de Louisiane pour l&rsquo;ouragan Katrina ont beaucoup souffert et souffrent des effectifs r\u00e9duits de la Garde Nationale dans ces deux \u00c9tats. La raison de cette situation est simple et elle a un nom : l&rsquo;Irak, o\u00f9 les forces am\u00e9ricaines s&rsquo;appuient de fa\u00e7on importante sur les r\u00e9serves et la Garde Nationale.<\/p>\n<\/p>\n<p><p>\tL&rsquo;agence <a href=\"http:\/\/www.armytimes.com\/story.php?f=1-292925-1066780.php\" class=\"gen\">Associated Press<\/a> analyse rapidement la question, observant notamment : \u00ab <em>Some 6,000 National Guard personnel in Louisiana and Mississippi who would be available to help deal with the aftermath of Hurricane Katrina are in Iraq, highlighting the changing role of America&rsquo;s part-time soldiers.<\/em><\/p>\n<\/p>\n<p><p>\t\u00bb <em>The juxtaposition of the mission to Iraq and the response to Katrina really demonstrates the new and changing character of the National Guard, Daniel Goure, a military analyst at the private Lexington Institute, said Monday.<\/em> \u00bb<\/p>\n<\/p>\n<p><p>\tCet \u00e9l\u00e9ment va ajouter un facteur pol\u00e9mique de plus autour de la catastrophe de l&rsquo;ouragan Katrina. Il s&rsquo;agit d&rsquo;un facteur pol\u00e9mique hautement politique, qui concerne les rapports entre les \u00c9tats de l&rsquo;Union et le centre washingtonien, d\u00e9j\u00e0 tendus sur la question <a href=\"http:\/\/www.dedefensa.org\/article.php?art_id=1882\" class=\"gen\">du global warming<\/a>. En bref, la question est : \u00e0 quoi sert la Garde? Aux aventures ext\u00e9rieures lanc\u00e9es par les bureaucrates de Washington ou \u00e0 la s\u00e9curit\u00e9 des \u00c9tats dont elle est issue?<\/p>\n<\/p>\n<p><\/p>\n<p><p>\tMis en ligne le 31 ao\u00fbt 2005 \u00e0 09H35<\/p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Les secours et les mesures de protection dans les \u00c9tats du Mississipi et de Louisiane pour l&rsquo;ouragan Katrina ont beaucoup souffert et souffrent des effectifs r\u00e9duits de la Garde Nationale dans ces deux \u00c9tats. La raison de cette situation est simple et elle a un nom : l&rsquo;Irak, o\u00f9 les forces am\u00e9ricaines s&rsquo;appuient de fa\u00e7on&hellip;&nbsp;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","footnotes":"","jetpack_post_was_ever_published":false},"categories":[2],"tags":[1368],"class_list":["post-66757","post","type-post","status-publish","format-standard","hentry","category-bloc-notes","tag-katrina"],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/66757","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/comments?post=66757"}],"version-history":[{"count":0,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/66757\/revisions"}],"wp:attachment":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/media?parent=66757"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/categories?post=66757"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/tags?post=66757"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}