{"id":66768,"date":"2005-09-03T00:00:00","date_gmt":"2005-09-03T00:00:00","guid":{"rendered":"https:\/\/new.dedefensa.org\/index.php\/2005\/09\/03\/comme-si-row-sy-attendait\/"},"modified":"2005-09-03T00:00:00","modified_gmt":"2005-09-03T00:00:00","slug":"comme-si-row-sy-attendait","status":"publish","type":"post","link":"https:\/\/new.dedefensa.org\/index.php\/2005\/09\/03\/comme-si-row-sy-attendait\/","title":{"rendered":"<strong><em>Comme si ROW s&rsquo;y attendait\u2026<\/em><\/strong>"},"content":{"rendered":"<p><h2 class=\"common-article\">Comme si ROW s&rsquo;y attendait<\/h2>\n<\/p>\n<p><\/p>\n<p><p>\t3 septembre 2005  Parmi d&rsquo;autres sans doute auxquels nous n&rsquo;avons pas encore eu le temps d&rsquo;avoir acc\u00e8s, le texte de Reuters (disponible sur <a href=\"http:\/\/www.commondreams.org\/headlines05\/0902-04.htm\" class=\"gen\">CommonDreams.org<\/a>) reprenant diverses r\u00e9actions dans le monde aux \u00e9v\u00e9nements am\u00e9ricains est tr\u00e8s caract\u00e9ristique. M\u00e9thode habituelle des agences : on collecte dans un certain nombre de pays des avis du type non autoris\u00e9  des citoyens interrog\u00e9s de fa\u00e7on impromptue  pour tenter de donner l&rsquo;impression g\u00e9n\u00e9rale du reste du monde (<em>the Rest Of the World<\/em>, ou ROW) sur les \u00e9v\u00e9nements. L&rsquo;impression ressortie de ce texte est \u00e9tonnante, elle parle \u00e0 notre intuition en confirmant notre raison. Elle va \u00e0 l&rsquo;essentiel (soulign\u00e9 par nous en gras) : \u00ab <em>The world has watched amazed as the planet&rsquo;s only superpower struggles with the aftermath of Hurricane Katrina, with some saying<\/em> <strong><em>the chaos has exposed flaws and deep divisions in American society.<\/em><\/strong> \u00bb<\/p>\n<\/p>\n<p><p>\tReuters a m\u00eame trouv\u00e9 des officiels disant des choses int\u00e9ressantes, \u00e0 c\u00f4t\u00e9 des incroyables palinodies de la plupart d&rsquo;entre eux, incapables en ces heures si graves d&rsquo;exposer enfin un jugement honn\u00eate sur ces \u00e9v\u00e9nements. C&rsquo;est le cas du Luxembourgeois Jean Asselborn, ministre des affaires \u00e9trang\u00e8res,  ce petit pays \u00e0 la r\u00e9putation d&rsquo;ennui bien surfaite, le Luxembourg, est une p\u00e9pini\u00e8re d&rsquo;hommes solides et lucides \u00e0 l&rsquo;image de son Premier ministre Jean-Claude Juncker, n&rsquo;h\u00e9sitant jamais \u00e0 dire les choses que les gouvernements voisins osent \u00e0 peine penser tout bas, s&rsquo;il est confirm\u00e9 qu&rsquo;ils pensent tout bas. A une r\u00e9union de l&rsquo;Union europ\u00e9enne, \u00e0 Newport, au Pays de Galles, Jean Asselborn a d\u00e9clar\u00e9: \u00ab <em>You see in this example that even in the 21st century you need the state, a good functioning state, and I hope that for all these people, these poor people, that the Americans will do their best.<\/em> \u00bb.<\/p>\n<\/p>\n<p><p>\tComme cinglante critique diplomatique de l&rsquo;administration GW, on ne fait pas mieux. Il faut croire que la trag\u00e9die de Katrina est la plus formidable affirmation de la n\u00e9cessit\u00e9 d&rsquo;un gouvernement de bien public pour la soci\u00e9t\u00e9, fond\u00e9 sur une perception r\u00e9galienne de la direction de la soci\u00e9t\u00e9 ; la n\u00e9cessit\u00e9 d&rsquo;un gouvernement qui assure la coh\u00e9sion sociale et donne le sens de l&rsquo;unit\u00e9 et de la solidarit\u00e9 en m\u00eame temps qu&rsquo;il tente d&rsquo;assurer l&rsquo;efficacit\u00e9 de l&rsquo;action collective. Ce sont des d\u00e9cennies et des tonnes de propagande virtualiste en faveur de l&rsquo;individualisme irresponsable qui sont balay\u00e9es par les flots d\u00e9cha\u00een\u00e9s du Golfe du Mexique. La nature fait bien son travail.<\/p>\n<\/p>\n<p><p>\tC&rsquo;est effectivement dans ce sens que nombre des r\u00e9actions vont \u00e0 l&rsquo;essentiel dans les le\u00e7ons \u00e0 tirer presque dans l&rsquo;imm\u00e9diat, sans trop s&#8217;embarrasser des consid\u00e9rations humanitaires et de solidarit\u00e9 qui vont de soi : Katrina expose la monstruosit\u00e9 du syst\u00e8me am\u00e9ricaniste, et la profondeur exceptionnelle de sa crise. Ce sont des paroles de dignit\u00e9 et d&rsquo;humanit\u00e9 qui r\u00e9sonnent de cette fa\u00e7on. Nous en donnons trois exemples extraits de l&rsquo;article, dont deux nous viennent, heureuse circonstance, de ce monde ext\u00e9rieur auquel la civilisation du syst\u00e8me monstrueux entend imposer sa loi en l&rsquo;assortissant de le\u00e7ons de vertu,  et le troisi\u00e8me, non moins heureuse circonstance, du pays qui s&rsquo;est aveugl\u00e9ment soumis au syst\u00e8me.<\/p>\n<\/p>\n<p><p>\t&bull; \u00ab <em>I am absolutely disgusted. After the tsunami our people, even the ones who lost everything, wanted to help the others who were suffering, Sajeewa Chinthaka, 36, <\/em>[said] <em>as he watched a cricket match in Colombo, Sri Lanka. Not a single tourist caught in the tsunami was mugged. Now with all this happening in the U.S. we can easily see where the civilized part of the world&rsquo;s population is.<\/em> \u00bb<\/p>\n<\/p>\n<p><p>\t&bull; Une employ\u00e9e sud-cor\u00e9enne du si\u00e8ge sud-cor\u00e9en d&rsquo;une firme multinationale dirig\u00e9e par un Am\u00e9ricain nous dit simplement que Katrina n&rsquo;est, apr\u00e8s tout, peut-\u00eatre pas un accident (On notera la pr\u00e9caution du t\u00e9moin, voulant garder l&rsquo;anonymat parce que son patron est Am\u00e9ricain, et l&rsquo;on comprendra quelle sorte d&rsquo;humanit\u00e9 nous est impos\u00e9e aujourd&rsquo;hui.) \u00ab <em>Maybe it was punishment for what it did to Iraq, which has a man-made disaster, not a natural disaster, said the woman, who did not want to be named as she has an American manager. A lot of the people I work with think this way. We spoke about it just the other day, she said.<\/em> \u00bb<\/p>\n<\/p>\n<p><p>\t&bull;  David Fordham, 33 ans, est un anesth\u00e9siste d&rsquo;un h\u00f4pital londonien et nous dit qu&rsquo;il a v\u00e9cu en Am\u00e9rique, et qu&rsquo;il n&rsquo;est pas vraiment \u00e9tonn\u00e9: \u00ab <em>Maybe they just thought they could sit it out and everything would be okay.<\/em> \u00bb Effectivement, c&rsquo;est leur m\u00e9thode nihiliste puisque c&rsquo;est celle qu&rsquo;ils employ\u00e8rent en Irak: conqu\u00e9rir le pays, s&rsquo;asseoir et attendre que tout se mette en place dans l&rsquo;ordre am\u00e9ricaniste. Le march\u00e9 libre fera le reste.<\/p>\n<\/p>\n<p><p>\tObservons encore que m\u00eame un journal fran\u00e7ais, parisien comme on ne peut plus puisqu&rsquo;il s&rsquo;agit de <em>Lib\u00e9ration<\/em>, ose une remarque ironique qui, une semaine plus t\u00f4t, e\u00fbt \u00e9t\u00e9 un sacril\u00e8ge puisqu&rsquo;elle implique que Ben Laden est un \u00eatre humain comme vous et moi : \u00ab <em>A modern metropolis sinking in water and into anarchy  it is a really cruel spectacle for a champion of security like Bush, France&rsquo;s left-leaning Liberation newspaper said. (Al Qaeda leader Osama) bin Laden, nice and dry in his hideaway, must be killing himself laughing.<\/em> \u00bb<\/p>\n<\/p>\n<p><p>\tIl y a effectivement une \u00e9trange atmosph\u00e8re dans ces remarques, une atmosph\u00e8re qui marque la transmutation imm\u00e9diate de la perception de la trag\u00e9die vers le contexte qui importe,  une \u00e9preuve de v\u00e9rit\u00e9 pour le syst\u00e8me, dans laquelle le syst\u00e8me sombre aussit\u00f4t, plus s\u00fbrement que La Nouvelle Orl\u00e9ans, dans l&rsquo;incomp\u00e9tence criminelle et le ridicule ; et une \u00e9preuve de v\u00e9rit\u00e9 impos\u00e9e par quelque chose au-del\u00e0 de la raison et des lois m\u00e9caniques de la nature, par la puissance et la logique d&rsquo;une Histoire r\u00e9pondant \u00e0 des impulsions transcendantales bien plus qu&rsquo;\u00e0 la volont\u00e9 des hommes.<\/p>\n<\/p>\n<p><p>\tDe l\u00e0, la sensation universelle que le syst\u00e8me est aujourd&rsquo;hui face \u00e0 son heure de v\u00e9rit\u00e9. Katrina expose la profondeur presque mal\u00e9fique (voir ce que nous dit la Sud-Cor\u00e9enne) des travers du syst\u00e8me, qui semble avoir \u00e9t\u00e9 fabriqu\u00e9 pour le malheur de l&rsquo;humanit\u00e9 et pour la destruction de la civilisation, avec l&rsquo;habituelle ruse (le ruse supr\u00eame du Mal est de se faire passer pour le Bien). La remarque du tr\u00e8s grand \u00e9crivain am\u00e9ricain Gore Vidal, pr\u00e9monitoire dans <a href=\"http:\/\/www.lemonde.fr\/web\/article\/0,1-0,36-684157,0.html\" class=\"gen\">son interview du Monde<\/a> publi\u00e9e le 1er septembre (mais r\u00e9alis\u00e9e bien entendu avant Katrina), alors qu&rsquo;il prend la pr\u00e9caution ironique de se d\u00e9clarer ath\u00e9e pour ne pas se trouver dans la m\u00eame gal\u00e8re que GW (\u00ab <em> Oh oui ! un pur ath\u00e9e. Un ath\u00e9e born again&#8230;<\/em> \u00bb). Vidal r\u00e9pond \u00e0 propos de la religion en Am\u00e9rique mais il est entendu, pour nous, que, dans le cas am\u00e9ricaniste, la religion n&rsquo;est qu&rsquo;un instrument hyst\u00e9rique du syst\u00e8me et vraiment rien d&rsquo;autre: <\/p>\n<\/p>\n<p><p>\t\u00ab <em>C&rsquo;est l&rsquo;uvre du diable. Il n&rsquo;y a peut-\u00eatre pas de bon Dieu, mais il y a s\u00fbrement un diable et sa passion dominante, c&rsquo;est la religion des fondamentalistes protestants. Je crois que mon pays commence, \u00e0 de nombreux \u00e9gards, \u00e0 ressembler \u00e0 une th\u00e9ocratie. Par le biais de la t\u00e9l\u00e9vision, les \u00e9vang\u00e9listes l\u00e8vent des fonds consid\u00e9rables qu&rsquo;ils investissent ensuite pour faire \u00e9lire des obscurantistes attard\u00e9s. Comme il n&rsquo;y a pas de syst\u00e8me d&rsquo;\u00e9ducation publique, la grande majorit\u00e9 de mes concitoyens est d&rsquo;une ignorance \u00e0 faire peur. Ils ne savent pas o\u00f9 est l&rsquo;Irak. Ils prennent tout ce que le gouvernement leur dit pour parole d&rsquo;Evangile. Bon sang, n&rsquo;importe quel pays normal se serait r\u00e9volt\u00e9 contre cette guerre ! Mais nous sommes un pays anormal, gouvern\u00e9 par des experts en publicit\u00e9 mensong\u00e8re.<\/em> \u00bb<\/p>\n<\/p>\n<p><p>\tConclusion : s&rsquo;il fallait Katrina pour changer cela, eh bien Katrina pourrait \u00eatre ce bien pour un mal qu&rsquo;on doit esp\u00e9rer.<\/p>\n<\/p>\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Comme si ROW s&rsquo;y attendait 3 septembre 2005 Parmi d&rsquo;autres sans doute auxquels nous n&rsquo;avons pas encore eu le temps d&rsquo;avoir acc\u00e8s, le texte de Reuters (disponible sur CommonDreams.org) reprenant diverses r\u00e9actions dans le monde aux \u00e9v\u00e9nements am\u00e9ricains est tr\u00e8s caract\u00e9ristique. M\u00e9thode habituelle des agences : on collecte dans un certain nombre de pays des&hellip;&nbsp;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[1375],"class_list":["post-66768","post","type-post","status-publish","format-standard","hentry","category-faits-et-commentaires","tag-vidal"],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/66768","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/comments?post=66768"}],"version-history":[{"count":0,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/66768\/revisions"}],"wp:attachment":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/media?parent=66768"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/categories?post=66768"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/tags?post=66768"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}