{"id":66772,"date":"2005-09-03T00:00:00","date_gmt":"2005-09-03T00:00:00","guid":{"rendered":"https:\/\/new.dedefensa.org\/index.php\/2005\/09\/03\/le-systeme-lirak-et-la-defaite\/"},"modified":"2005-09-03T00:00:00","modified_gmt":"2005-09-03T00:00:00","slug":"le-systeme-lirak-et-la-defaite","status":"publish","type":"post","link":"https:\/\/new.dedefensa.org\/index.php\/2005\/09\/03\/le-systeme-lirak-et-la-defaite\/","title":{"rendered":"<strong><em>Le syst\u00e8me, l&rsquo;Irak et la d\u00e9faite<\/em><\/strong>"},"content":{"rendered":"<p><h2 class=\"common-article\">Le syst\u00e8me, l&rsquo;Irak et la d\u00e9faite<\/h2>\n<\/p>\n<p><p>\t3 septembre 2005  L&rsquo;am\u00e9ricaniste, surtout s&rsquo;il est militaire et membre de la bureaucratie de la s\u00e9curit\u00e9 nationale, ne peut vivre sans planifier. Il pr\u00e9pare les \u00e9v\u00e9nements du futur, avec tant d&rsquo;entrain qu&rsquo;il lui arrive le plus souvent d&rsquo;ignorer, voire de sacrifier ceux du pr\u00e9sent. Du moins nous semble-t-il que r\u00e9agit ainsi le processus psychologique. On d\u00e9couvre vite qu&rsquo;il s&rsquo;agit non d&rsquo;une r\u00e9action mais d&rsquo;une conception : par essence, le pr\u00e9sent n&rsquo;existe pas et le pass\u00e9 n&rsquo;a d&rsquo;int\u00e9r\u00eat qu&rsquo;en ce qu&rsquo;il est la preuve irr\u00e9futable que le futur sera meilleur. Par cons\u00e9quent, seul le futur compte : il ne tient aucun compte du pr\u00e9sent et il sera la preuve irr\u00e9futable que le pass\u00e9 n&rsquo;a aucun int\u00e9r\u00eat. Cette m\u00e9canique psychologique ne se fixant jamais et l&rsquo;int\u00e9r\u00eat se portant par cons\u00e9quent toujours sur le futur qui ne cesse de toujours rester aussi distant \u00e0 mesure qu&rsquo;on avance, on pourrait aussi bien argumenter que le futur n&rsquo;existera jamais et qu&rsquo;on se trouve devant une branche particuli\u00e8re du virtualisme.<\/p>\n<\/p>\n<p><p>\tAinsi en est-il avec l&rsquo;Irak. La guerre continue (le pr\u00e9sent) et le planificateur bureaucratique s&rsquo;affaire \u00e0 en tirer les le\u00e7ons qui lui conviennent pour pr\u00e9parer la prochaine (le futur) comme si cette guerre d&rsquo;Irak n&rsquo;avait pas eu vraiment lieu et ne se poursuivait pas entre-temps. Il s&rsquo;av\u00e8re finalement que cette guerre (le pr\u00e9sent) est vite consid\u00e9r\u00e9e dans le travail du planificateur comme d\u00e9pass\u00e9e et ne pr\u00e9sentant gu\u00e8re d&rsquo;int\u00e9r\u00eat (le pass\u00e9), sinon comme repoussoir pour confirmer <em>a contrario<\/em> la justesse de la planification du futur. C&rsquo;est dire si les le\u00e7ons qui sont tir\u00e9es par la bureaucratie de la guerre en Irak ne concernent pas le monde r\u00e9el.<\/p>\n<\/p>\n<p><p>\tN\u00e9anmoins, nous sommes dans un moment particulier. L&rsquo;effet catastrophique de la guerre d&rsquo;Irak est \u00e0 son sommet. On ne peut pas ne pas en tenir compte,  temporairement, c&rsquo;est-\u00e0-dire <strong>sembler<\/strong> en tenir compte, pour simples raisons de relations publiques.<\/p>\n<\/p>\n<p><p>\tL&rsquo;attitude bureaucratique et am\u00e9ricaniste d\u00e9crite plus haut n&rsquo;est pas le cas des hommes (les soldats am\u00e9ricains) qui, sur le terrain, subissent les horreurs de la guerre m\u00eame s&rsquo;ils en sont initialement la cause, conform\u00e9ment \u00e0 la politique des dirigeants du syst\u00e8me. \u00ab <em>Officers Return With Changed View of Future Needs<\/em> \u00bb, \u00e9crit le 29 mai <em>Defense News<\/em>. Cette phrase est le sous-titre <a href=\"http:\/\/www.defensenews.com\/story.php?F=1026888&#038;C=thisweek\" class=\"gen\">d&rsquo;un article consacr\u00e9 aux le\u00e7ons de la guerre en Irak<\/a>. L&rsquo;article d\u00e9crit \u00e0 la fois l&rsquo;\u00e9tat d&rsquo;esprit de ceux qui ont \u00e9t\u00e9 en Irak et celui de ceux qui n&rsquo;y ont pas \u00e9t\u00e9, ou pas assez. Plus encore : l&rsquo;article permet de bien p\u00e9n\u00e9trer la mentalit\u00e9 am\u00e9ricaniste, et celle de la bureaucratie de s\u00e9curit\u00e9 nationale.<\/p>\n<\/p>\n<p><p>\t&bull; D&rsquo;abord ce constat, qui est aussi un aveu extraordinairement significatif de la fa\u00e7on dont fonctionne le syst\u00e8me,  cette fa\u00e7on dont, au d\u00e9part, la guerre qui va \u00eatre conduite devra \u00eatre conforme \u00e0 la planification pr\u00e9vue, et qui sera m\u00eame l&rsquo;application dans le r\u00e9el de cette planification. Au d\u00e9part, la guerre \u00e0 entreprendre (le pr\u00e9sent) n&rsquo;est consid\u00e9r\u00e9e que dans la mesure o\u00f9 elle doit confirmer la planification (le futur, ou virtualisme) ; d&rsquo;o\u00f9 les avatars dus aux heurts avec le pr\u00e9sent: \u00ab <em>Operation Iraqi Freedom was supposed to be the proving ground for the Army&rsquo;s new network-centric doctrine: Find the enemy with state-of-the-art sensors, prepare the battlefield with precision standoff fire, and maneuver networked forces to destroy survivors.<\/em> <\/p>\n<\/p>\n<p><p>\t\u00bb <em>Yet American troops often discover their enemies only when they see the smoke trail of a rocket-propelled grenade or feel the concussion of an improvised roadside bomb.<\/em> \u00bb<\/p>\n<\/p>\n<p><p>\t&bull; L&rsquo;accueil que fait la bureaucratie planificatrice aux r\u00e9criminations et aux exp\u00e9riences des soldats qui ont connu le combat en Irak est \u00e0 la fois r\u00e9v\u00e9lateur et syst\u00e9matique. C&rsquo;est tout juste si elle prend des gants dans la formulation de sa r\u00e9action parce que la guerre est toujours en cours et que les organes de communication s&rsquo;\u00e9meuvent des pertes subies et des d\u00e9g\u00e2ts caus\u00e9s, et qu&rsquo;il serait malvenu, du point de vue des relations publiques, d&rsquo;\u00e9carter cela avec trop de d\u00e9sinvolture. Il n&#8217;emp\u00eache, on sent bien qu&rsquo;il y a quelque chose de malsain, de tr\u00e8s faible, dans le fait que tous ces hommes soient <em>very influenced<\/em> par ce qu&rsquo;ils ont connu et subi en Irak : \u00ab <em>Officers are very influenced by the experiences they&rsquo;ve had, but you have to be careful not to be driven solely by current events, said <\/em>[Brig. Gen.. David] <em>Fastabend, whose center maps out and coordinates the evolution of Army capabilities for the service&rsquo;s Training and Doctrine Command. We work very hard to try to balance change you want for the future and the change for the present.<\/em> \u00bb En r\u00e9alit\u00e9, la pens\u00e9e est plus nette encore. L&rsquo;\u00e9cole bureaucratique et planificatrice, c&rsquo;est-\u00e0-dire les tenants du syst\u00e8me, estime que l&rsquo;Irak \u00ab <em>is not broadly representative of future warfare. Its proponents concede a growing need for special operations units, but say the Army must remain configured to fight the big battle. They push high-tech modernization as exemplified by FCS.<\/em> \u00bb<\/p>\n<\/p>\n<p><p>\tOn continuera donc \u00e0 d\u00e9velopper les gros syst\u00e8mes ultra-sophistiqu\u00e9s, tr\u00e8s chers, bard\u00e9s de hautes technologies. Le FCS (Future Combat Systems), est pr\u00e9sent\u00e9 par <em>Defense News<\/em> comme \u00ab <em>the Army&rsquo;s highly networked, multibillion-dollar, next-generation armored vehicle program<\/em> \u00bb.<\/p>\n<\/p>\n<p><p>\t&bull; Les adversaires de cette attitude se recrutent parmi les francs-tireurs habituels, m\u00eame s&rsquo;il s&rsquo;agit de gens li\u00e9s \u00e0 l&rsquo;<em>establishment<\/em>. Plus que repr\u00e9sentant une \u00e9cole de pens\u00e9e, ils figurent comme des dissidents temporaires, \u00e9gar\u00e9s par l&rsquo;influence de ce qu&rsquo;on pourrait d\u00e9signer par exemple comme du bon sens, et qui est l&rsquo;exp\u00e9rience de la r\u00e9alit\u00e9 en train de se faire. L&rsquo;ancien officier de l&rsquo;U.S. Army Andrew Krepinevich devenu expert, dit \u00e0 propos de ces pr\u00e9visions de la bureaucratie pour se pr\u00e9parer aux futures grandes batailles qui sont le contraire de l&rsquo;Irak : \u00ab <em>Krepinevich said that the weakness of <\/em>[the bureaucratic] <em>argument is that you really have to search long and hard to find another military that&rsquo;s building another Republican Guard or major tank army to take on the American Army. <\/em>[He] <em>believes that large state-on-state conflicts are a thing of the past, and that irregular fighting in Iraq is the future of warfare.<\/em> \u00bb<\/p>\n<\/p>\n<p><p>\tKrepinevich en vient m\u00eame, dans la chaleur de l&rsquo;argument, \u00e0 verser dans l&rsquo;id\u00e9alisme, voire dans l&rsquo;utopie pure et simple. Il pr\u00e9voit ceci, qui montre chez lui une grande m\u00e9connaissance de la puissance du syst\u00e8me et de sa capacit\u00e9 de transformer m\u00eame ceux qui se sont form\u00e9s des id\u00e9es fortes au contact du r\u00e9el: \u00ab <em>Krepinevich believes a transformation will hit the U.S. Army as a generation of officers that is over in Iraq two tours, three tours, come back and look around and see a world in which the Army&rsquo;s past has been Haiti, Somalia, Afghanistan and Iraq.<\/em> \u00bb<\/p>\n<\/p>\n<p><p>\t&bull; Temporairement, les \u00e9v\u00e9nements d&rsquo;Irak, leurs \u00e9chos d&rsquo;une tr\u00e8s grande puissance peuvent sembler favoriser les tenants d&rsquo;une r\u00e9forme radicale. (Il faut toujours garder, dans le jugement qu&rsquo;on fait, ce terme \u00e0 l&rsquo;esprit : temporairement. Il est utile car il r\u00e8gle tout, sur la dur\u00e9e o\u00f9 le syst\u00e8me triomphe.)<\/p>\n<\/p>\n<p><p>\t\u00ab <em>Fastabend said the war has shifted the flow of lessons, which now come from the younger generation of officers, from the field, rather than from doctrinal manuals issued by the Army leaders. When a new unit deploys, they&rsquo;re much more interested in recent enemy tactics coming out in the previous few weeks than any doctrine, the general said.<\/em> <\/p>\n<\/p>\n<p><p>\t\u00bb <em>Before Iraq, officers would visit the Army&rsquo;s National Training Center, Fort Irwin, Calif., and watch maneuvers on the training ground to learn the latest approaches to war fighting. Now, officers go to Iraq to learn the latest tactics, what works and what doesn&rsquo;t in a real-world combat environment, the general said.<\/em> <\/p>\n<\/p>\n<p><p>\t\u00bb <em>But at Fastabend&rsquo;s Futures Center, at Fort Monroe, Va., the one-star admits he&rsquo;s fighting what often seems an uphill battle to keep at least one element of the Army focused on the future and what types of forces it might need 10, 20 or 30 years down the road. The general argues that the future Army must be able to fight and win in any type of conflict, from irregular wars up to large-scale conventional tank battles.<\/em> \u00bb<\/p>\n<\/p>\n<p><p>\t&bull; Alors, tout espoir est perdu que le Pentagone puisse tirer des le\u00e7ons de bon sens de l&rsquo;Irak? Non, il y en a un, selon un argument d\u00e9velopp\u00e9 dans l&rsquo;article par un ancien militaire devenu consultant et auteur, le colonel de l&rsquo;U.S. Army Ken Allard  et l&rsquo;on reconna\u00eetra l&rsquo;univers du paradoxe surr\u00e9aliste o\u00f9 nous nous d\u00e9pla\u00e7ons : si les Am\u00e9ricains perdent, tout est possible  \u00ab <em>Allard argues that the Army&rsquo;s embrace of all things technological resulted from the intellectual malaise that followed the 1991 Gulf War.<\/em> <\/p>\n<\/p>\n<p><p>\t\u00bb <em>After Desert Storm, we had a disabling, paralytic problem that we had won, and victory can paralyze critical thought for a generation, Allard said.<\/em> <\/p>\n<\/p>\n<p><p>\t\u00bb <em>He said Iraq&rsquo;s influence on the current generation of officers would mirror the Vietnam War&rsquo;s effect on current Army leaders. How the Army adapts and changes itself after the war largely depends on whether we win or lose.<\/em> \u00bb<\/p>\n<h3>La psychologie am\u00e9ricaniste ignore le concept de d\u00e9faite<\/h3>\n<\/p>\n<p><p>\tD&rsquo;accord : mais est-ce possible? Les Am\u00e9ricains peuvent-ils perdre? Nous comprenons bien Allard, lib\u00e9r\u00e9 des contraintes bureaucratiques et conduit \u00e0 penser de mani\u00e8re ind\u00e9pendante. Il a l&rsquo;air de consid\u00e9rer que le Vi\u00eat-nam fut une d\u00e9faite militaire, ce qui est le cas si on accorde au qualificatif militaire la sophistication et la complexit\u00e9 qui conviennent ; mais est-ce le cas au sein du syst\u00e8me, dans la bureaucratie, chez les allum\u00e9s des batailles sans fin qui forment d\u00e9sormais le <em>corpus<\/em> de la pens\u00e9e strat\u00e9gique et conceptuelle am\u00e9ricaniste, saupoudr\u00e9e d&rsquo;un zeste consid\u00e9rable de manich\u00e9isme religieux? Leur argument est au contraire que l&rsquo;on obligea les militaires am\u00e9ricains \u00e0 se battre avec des moyens insuffisants (!) et des restrictions d&rsquo;action significatives (re-!). Ils ne perdirent pas, tout au plus peut-on dire qu&rsquo;ils furent emp\u00each\u00e9s de gagner \u00e0 Washington. <\/p>\n<\/p>\n<p><p>\t(Au contraire, ce que Allard qualifie de victoire et qui a si compl\u00e8tement d\u00e9prim\u00e9 les planificateurs am\u00e9ricanistes, la premi\u00e8re guerre du Golfe, n&rsquo;en est pas une selon le sens commun qui lit l&rsquo;histoire comme elle se passe puisqu&rsquo;on fut oblig\u00e9 de s&rsquo;y remettre treize ans plus tard, <em>to finish the job<\/em>. D&rsquo;autre part, ce que Allard consid\u00e8re comme un enseignement fructueux du Vi\u00eat-nam puisque, selon lui, les Am\u00e9ricains perdirent au Vi\u00eat-nam, n&rsquo;en est pas un puisqu&rsquo;il mena \u00e0 la guerre du Golfe-1990 qui ne peut \u00eatre consid\u00e9r\u00e9e comme une victoire puisqu&rsquo;elle dut \u00eatre compl\u00e9t\u00e9e par la guerre du Golfe-2003 Toutes ces notions sont tributaires d&rsquo;une relativit\u00e9 virtualiste particuli\u00e8rement remarquable.)<\/p>\n<\/p>\n<p><p>\tCertes, la question revient bel et bien \u00e0 savoir si la notion de d\u00e9faite existe pour une psychologie am\u00e9ricaniste. Voici l&rsquo;int\u00e9ressante r\u00e9ponse de James William Gibson dans son livre <em>Warrior Dreams<\/em>, qui date de 1994. Gibson analyse la question du point de vue de la mythologie am\u00e9ricaniste, notamment exprim\u00e9e par les standards hollywoodiens.<\/p>\n<\/p>\n<p><p>\t\u00ab <em>At first, then, the trauma of the prolonged war in Vietnam, followed as i twas by ignominious defeat, seemed to spell the end of the traditional war mythology. Both the Western and war-movies genres faded away in the 1960s et 1970s. John Wayne&rsquo;s death in 1979 seemed to bring a symnolic closure to this cultural history. But paradoxically, the old mythology of American prowess and moral virtue instead assumed an even greater hold on the popular imagination. Why it did has much to say about the American way of looking at the world: defeat was incompregensible, bith morally and scientifically.&rsquo;<\/em><\/p>\n<\/p>\n<p><p>\t\u00bb <em>Ever since World War II, it had been an article of faith of U.S. military policy that a country&rsquo;s technological sophistication and the sheer quantity of its war supplies were the decisive factors that would lead to victory. In this new model of warfare (which I call techno-war, war wa\ts conceptualized as a kid of high-technology production process in which the officer corps were managers, the  elisted men were workers, and the final product was death: whoever had the biggest, most sophisticated apparatus was sure to produce the highest ennemy body counts and thus win. The soft varianles of war, such as the history, the culture, and motivations of a people, were not seen as important because they had none of the hard reality of the weapons.<\/em> \u00bb<\/p>\n<\/p>\n<p><p>\tEn d&rsquo;autres termes: la d\u00e9faite est impossible, <em>unthinkable<\/em>, quelque chose qui n&rsquo;a aucune r\u00e9alit\u00e9 pour l&rsquo;esprit am\u00e9ricaniste. Allard n&rsquo;aura pas sa r\u00e9forme. La seule chose que nous devions attendre est que le syst\u00e8me (le Pentagone) s&rsquo;\u00e9croule de lui-m\u00eame, par l&rsquo;int\u00e9rieur, sous le poids de ses propres travers. Cela est moins, beaucoup moins impossible qu&rsquo;on croit, \u00e0 moins de consid\u00e9rer ce syst\u00e8me d&rsquo;un il am\u00e9ricaniste qui ne croit qu&rsquo;\u00e0 la quantit\u00e9 et \u00e0 la technologie. (Qui s&rsquo;en \u00e9tonnera? Ce n&rsquo;est pas notre cas.)<\/p>\n<\/p>\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Le syst\u00e8me, l&rsquo;Irak et la d\u00e9faite 3 septembre 2005 L&rsquo;am\u00e9ricaniste, surtout s&rsquo;il est militaire et membre de la bureaucratie de la s\u00e9curit\u00e9 nationale, ne peut vivre sans planifier. Il pr\u00e9pare les \u00e9v\u00e9nements du futur, avec tant d&rsquo;entrain qu&rsquo;il lui arrive le plus souvent d&rsquo;ignorer, voire de sacrifier ceux du pr\u00e9sent. Du moins nous semble-t-il que&hellip;&nbsp;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[3066,4255,4734,4735,857,3099,3014],"class_list":["post-66772","post","type-post","status-publish","format-standard","hentry","category-faits-et-commentaires","tag-americaniste","tag-defaite","tag-impossible","tag-indefectibilite","tag-irak","tag-psychologie","tag-systeme"],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/66772","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/comments?post=66772"}],"version-history":[{"count":0,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/66772\/revisions"}],"wp:attachment":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/media?parent=66772"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/categories?post=66772"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/tags?post=66772"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}