{"id":66781,"date":"2005-09-05T00:00:00","date_gmt":"2005-09-05T00:00:00","guid":{"rendered":"https:\/\/new.dedefensa.org\/index.php\/2005\/09\/05\/en-dire-trop-ou-pas-assez-cest-reculer-devant-la-question-essentielle\/"},"modified":"2005-09-05T00:00:00","modified_gmt":"2005-09-05T00:00:00","slug":"en-dire-trop-ou-pas-assez-cest-reculer-devant-la-question-essentielle","status":"publish","type":"post","link":"https:\/\/new.dedefensa.org\/index.php\/2005\/09\/05\/en-dire-trop-ou-pas-assez-cest-reculer-devant-la-question-essentielle\/","title":{"rendered":"En dire trop ou pas assez, c&rsquo;est reculer devant la question essentielle"},"content":{"rendered":"<p><p>L&rsquo;article de Jonathan Freedland dans <a href=\"http:\/\/www.guardian.co.uk\/katrina\/story\/0,16441,1562901,00.html\" class=\"gen\">le Guardian de ce matin<\/a> est peut-\u00eatre tr\u00e8s exemplaire des blocages du jugement des Europ\u00e9ens sur la situation am\u00e9ricaine. Il est d&rsquo;autant plus exemplaire qu&rsquo;il vient d&rsquo;un commentateur britannique qui, d&rsquo;habitude, n&rsquo;a pas froid aux yeux lorsqu&rsquo;il s&rsquo;agit de juger l&rsquo;Am\u00e9rique.<\/p>\n<\/p>\n<p><p>\tEffectivement, Freedland n&rsquo;a pas froid aux yeux lorsqu&rsquo;il d\u00e9taille l&rsquo;\u00e9tat de l&rsquo;Am\u00e9rique. Par ailleurs, si la chose \u00e9tait audacieuse il y a trois ans elle est commune aujourd&rsquo;hui : tout le monde commence \u00e0 comprendre ou \u00e0 envisager, m\u00eame si avec r\u00e9ticence et \u00e0 contrecoeur, que l&rsquo;Am\u00e9rique n&rsquo;est qu&rsquo;une hyperpuissance de carton-p\u00e2te, qu&rsquo;elle est caract\u00e9ris\u00e9e par des faiblesses et des travers d&rsquo;un poids consid\u00e9rable, qui l&#8217;emporte de plus en plus.<\/p>\n<\/p>\n<p><p>\tCe qui nous importe d\u00e9sormais, c&rsquo;est la conclusion \u00e0 en tirer. De ce point de vue, Freedland est bien court. Comparant la d\u00e9stabilisation actuelle \u00e0 celle des ann\u00e9es 1970 (Vi\u00eat-nam, Watergate, Carter), il rappelle la tendance habituelle des Etats-Unis \u00e0 se replier lorsqu&rsquo;ils connaissent de tels troubles (isolationnisme) pour en repousser aussit\u00f4t la possibilit\u00e9. Ne peut-il envisager rien d&rsquo;autre ? Curieusement, il aurait pu le faire, avec une autre analogie historique qu&rsquo;il avance en comparant, pour l&rsquo;\u00e9volution politique plus que pour l&rsquo;\u00e9conomie, cette p\u00e9riode avec celle qui conduit \u00e0 la Grande D\u00e9pression am\u00e9ricaine. Cette fois, la cons\u00e9quence fut bien plus la possibilit\u00e9 r\u00e9elle de l&rsquo;effondrement des Etats-Unis qu&rsquo;un choix de politique (isolationnisme ou pas). Aujourd&rsquo;hui, l&rsquo;enjeu v\u00e9ritable est exactement celui-l\u00e0.<\/p>\n<\/p>\n<p><p>\tCi-dessous, les trois paragraphes de conclusion de Freedland.<\/p>\n<\/p>\n<p><p>\t\u00ab <em>That belief had already taken a few blows. The vulnerability exposed on 9\/11 was one. The struggle in Iraq  where America has become a Gulliver, tied down  was another. But now the giant has been hit again, its weak spot exposed. When corpses float in the streets for five days, the indispensable nation looks like a society that cannot take care of its own. When Sri Lanka offers to send emergency aid, the humiliation is complete.<\/em><\/p>\n<\/p>\n<p><p>\t\u00bb <em>That could lead to a shift in priorities, a sense that too many energies were diverted to Iraq and Afghanistan and away from the home front. It could even see the US retreating from the world and hunkering down.<\/em><\/p>\n<\/p>\n<p><p>\t\u00bb <em>But don&rsquo;t count on it. At the end of the 1970s, American confidence was also shaken  by defeat in Vietnam, by the serial failure (and worse) of government institutions. What followed, after the interval of the Carter presidency, was a period of gung-ho bullishness that became the Reagan era. It may look battered  but only a fool would count America out.<\/em> \u00bb<\/p>\n<\/p>\n<p><\/p>\n<p><p>\tMis en ligne le 5 septembre 2005 \u00e0 08H15<\/p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>L&rsquo;article de Jonathan Freedland dans le Guardian de ce matin est peut-\u00eatre tr\u00e8s exemplaire des blocages du jugement des Europ\u00e9ens sur la situation am\u00e9ricaine. Il est d&rsquo;autant plus exemplaire qu&rsquo;il vient d&rsquo;un commentateur britannique qui, d&rsquo;habitude, n&rsquo;a pas froid aux yeux lorsqu&rsquo;il s&rsquo;agit de juger l&rsquo;Am\u00e9rique. Effectivement, Freedland n&rsquo;a pas froid aux yeux lorsqu&rsquo;il d\u00e9taille&hellip;&nbsp;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","footnotes":"","jetpack_post_was_ever_published":false},"categories":[2],"tags":[1382],"class_list":["post-66781","post","type-post","status-publish","format-standard","hentry","category-bloc-notes","tag-freedland"],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/66781","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/comments?post=66781"}],"version-history":[{"count":0,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/66781\/revisions"}],"wp:attachment":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/media?parent=66781"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/categories?post=66781"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/tags?post=66781"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}