{"id":66814,"date":"2005-09-12T00:00:00","date_gmt":"2005-09-12T00:00:00","guid":{"rendered":"https:\/\/new.dedefensa.org\/index.php\/2005\/09\/12\/la-barbarie-jubilante-du-darwinisme-postmoderne\/"},"modified":"2005-09-12T00:00:00","modified_gmt":"2005-09-12T00:00:00","slug":"la-barbarie-jubilante-du-darwinisme-postmoderne","status":"publish","type":"post","link":"https:\/\/new.dedefensa.org\/index.php\/2005\/09\/12\/la-barbarie-jubilante-du-darwinisme-postmoderne\/","title":{"rendered":"La \u201cbarbarie jubilante\u201d du darwinisme postmoderne"},"content":{"rendered":"<p><h2 class=\"common-article\">La barbarie jubilante du darwinisme postmoderne<\/h2>\n<\/p>\n<p><p>\tLorsqu&rsquo;il a \u00e9t\u00e9 r\u00e9v\u00e9l\u00e9 (le <a href=\"http:\/\/www.dedefensa.org\/article.php?art_id=1956\" class=\"gen\">11 septembre<\/a>, sur <a href=\"http:\/\/antiwar.com\/orig\/scahill.php?articleid=7217\" class=\"gen\">Antiwar.com<\/a>) que des mercenaires de Blackwater Inc. se trouvaient \u00e0 New Orleans, la question s&rsquo;est aussit\u00f4t pos\u00e9e de savoir pourquoi. La r\u00e9ponse est qu&rsquo;il y a d&rsquo;une part la tendance naturelle de la bureaucratie de proc\u00e9der selon ses normes, d&rsquo;autant plus que les effectifs des forces arm\u00e9es US sont r\u00e9duits par rapport aux normes am\u00e9ricaines d&#8217;emploi: en Irak, il y a des mercenaires, il y en aura aussi \u00e0 New Orleans. (L&rsquo;\u00e9quivalence stup\u00e9fiante New Orleans-Bagdad est, l\u00e0 aussi, compl\u00e8tement fond\u00e9e.)<\/p>\n<\/p>\n<p><p>\tDepuis, avec <a href=\"http:\/\/www.guardian.co.uk\/katrina\/story\/0,16441,1567656,00.html\" class=\"gen\">un article du Guardian ce matin<\/a>, il y a, d&rsquo;autre part, une deuxi\u00e8me r\u00e9ponse : les mercenaires sont l\u00e0 aussi (<strong>surtout<\/strong>?) pour prot\u00e9ger les biens des riches de New Orleans.<\/p>\n<h3>New Orleans, c&rsquo;est beaucoup plus que Bagdad<\/h3>\n<\/p>\n<p><p>\tC&rsquo;est l&rsquo;illustration d&rsquo;un fait quasiment philosophique qui s&rsquo;est impos\u00e9e avec cette crise. Dans ce cas, l&rsquo;\u00e9quivalence New Orleans-Bagdad est d\u00e9pass\u00e9e : New Orleans est <strong>beaucoup plus<\/strong> significatif que Bagdad. Selon le professeur Cornel West, qui publie un article (\u00ab <em>Exiles from a city and from a nation<\/em> \u00bb) hier dans  <a href=\"http:\/\/www.guardian.co.uk\/katrina\/story\/0,16441,1567249,00.html\" class=\"gen\">The Guardian<\/a>, ce n&rsquo;est rien de moins que \u00ab [the] <em>Darwinism in action  the survival of the fittest<\/em> \u00bb. Il s&rsquo;agit d&rsquo;une exacte description du processus de s\u00e9lection naturelle (extraordinaire ironie grin\u00e7ante du qualificatif) qui a \u00e9t\u00e9 mis en action dans l&rsquo;op\u00e9ration de sauvetage de New Orleans, et l&rsquo;explication conceptuelle  quoique partielle  de la militarisation de cette op\u00e9ration. Effectivement, il s&rsquo;agit d&rsquo;une tendance \u00e0 l&rsquo;\u00e9limination des plus faibles, selon les conceptions de l&rsquo;am\u00e9ricanisme,  en gros, les plus pauvres, les plus marginaux, les plus ind\u00e9sir\u00e9s de la tendance dominante de la soci\u00e9t\u00e9 am\u00e9ricaniste,  ceux que le processus de distribution in\u00e9galitaire de la richesse met n\u00e9cessairement dans cette position, quels que soient leurs m\u00e9rites.<\/p>\n<\/p>\n<p><p>\t(Il reste \u00e0 d\u00e9montrer qu&rsquo;une autre tendance est possible dans la soci\u00e9t\u00e9 am\u00e9ricaniste, ce que tentent de faire les lib\u00e9raux du syst\u00e8me. On en appelle alors aux m\u00e2nes du Roosevelt de 1933, du Kennedy de la l\u00e9gende fabriqu\u00e9e, du Johnson de la Grande Soci\u00e9t\u00e9 de 1965. Il reste \u00e0 d\u00e9montrer que cette p\u00e9riode n&rsquo;est pas un accident destin\u00e9 \u00e0 sauver le syst\u00e8me menac\u00e9 d&rsquo;implosion par la Grande D\u00e9pression, ou encore, plus tard, \u00e0 ne pas pr\u00eater le flanc \u00e0 la propagande sovi\u00e9tique (voir plus loin, en fin de texte). Nous souhaitons bien du plaisir aux d\u00e9monstrateurs, tant le contraire,  l&rsquo;accident temporaire avant le retour au naturel d&rsquo;avant 1933, entrepris \u00e0 partir <a href=\"http:\/\/www.dedefensa.org\/article.php?art_id=353\" class=\"gen\">de 1971-72<\/a> et surtout de 1980 [Reagan],  repr\u00e9sente \u00e0 qui entreprend une \u00e9tude objective l&rsquo;\u00e9vidence de l&rsquo;histoire am\u00e9ricaniste.)<\/p>\n<h3>La Nouvelle Orl\u00e9ans \u00e9tait le Tiers-Monde bien avant Katrina<\/h3>\n<\/p>\n<p><p>\tVoici ce qu&rsquo;en dit Cornel West (il n&rsquo;est pas difficile de deviner que le professeur est noir : \u00ab <em>Dr Cornel West is professor of African American studies and religion at Princeton University. His great grandfather was a slave. He is a rap artist and appeared as Counsellor West in Matrix Reloaded and Matrix Revolutions.<\/em> \u00bb):<\/p>\n<\/p>\n<p><p>\t\u00ab <em>What we saw unfold in the days after the hurricane was the most naked manifestation of conservative social policy towards the poor, where the message for decades has been: You are on your own. Well, they really were on their own for five days in that Superdome, and it was Darwinism in action  the survival of the fittest. People said: It looks like something out of the Third World. Well, New Orleans was Third World long before the hurricane.<\/em><\/p>\n<\/p>\n<p><p>\t\u00bb <em>It&rsquo;s not just Katrina, it&rsquo;s povertina. People were quick to call them refugees because they looked as if they were from another country. They are. Exiles in America. Their humanity had been rendered invisible so they were never given high priority when the well-to-do got out and the helicopters came for the few. Almost everyone stuck on rooftops, in the shelters, and dying by the side of the road was poor black.<\/em><\/p>\n<\/p>\n<p><p>\t\u00bb <em>In the end George Bush has to take responsibility. When [the rapper] Kanye West said the President does not care about black people, he was right, although the effects of his policies are different from what goes on in his soul. You have to distinguish between a racist intent and the racist consequences of his policies. Bush is still a frat boy&rsquo;, making jokes and trying to please everyone while the Neanderthals behind him push him more to the right.<\/em><\/p>\n<\/p>\n<p><p>\t\u00bb <em>Poverty has increased for the last four or five years. A million more Americans became poor last year, even as the super-wealthy became much richer. So where is the trickle-down, the equality of opportunity? Healthcare and education and the social safety net being ripped away  and that flawed structure was nowhere more evident than in a place such as New Orleans, 68 per cent black. The average adult income in some parishes of the city is under $8,000 (\u00a34,350) a year. The average national income is $33,000, though for African-Americans it is about $24,000. It has one of the highest city murder rates in the US. From slave ships to the Superdome was not that big a journey.<\/em><\/p>\n<\/p>\n<p><p>\t\u00bb <em>New Orleans has always been a city that lived on the edge. The white blues man himself, Tennessee Williams, had it down in A Streetcar Named Desire  with Elysian Fields and cemeteries and the quest for paradise. When you live so close to death, behind the levees, you live more intensely, sexually, gastronomically, psychologically. Louis Armstrong came out of that unbelievable cultural breakthrough unprecedented in the history of American civilisation. The rural blues, the urban jazz. It is the tragi-comic lyricism that gives you the courage to get through the darkest storm. Charlie Parker would have killed somebody if he had not blown his horn. The history of black people in America is one of unbelievable resilience in the face of crushing white supremacist powers.<\/em> <\/p>\n<\/p>\n<p><p>\t\u00bb <em>This kind of dignity in your struggle cuts both ways, though, because it does not mobilise a collective uprising against the elites. That was the Black Panther movement. You probably need both. There would have been no Panthers without jazz. If I had been of Martin Luther King&rsquo;s generation I would never have gone to Harvard or Princeton.<\/em> \u00bb<\/p>\n<h3>L&rsquo;Am\u00e9rique est un univers supr\u00e9matiste<\/h3>\n<\/p>\n<p><p>\tCe que West nous d\u00e9crit, c&rsquo;est moins un univers raciste qu&rsquo;un univers supr\u00e9matiste, et ce n&rsquo;est pas du tout la m\u00eame chose. L&rsquo;univers supr\u00e9matiste est une rupture de la civilisation conduisant \u00e0 la n\u00e9gation de la diff\u00e9rence, qui rend n\u00e9cessaire l&rsquo;\u00e9limination des \u00eatres diff\u00e9rents, notamment et singuli\u00e8rement l&rsquo;\u00eatre soi-disant inf\u00e9rieur, ou plut\u00f4t rendu inf\u00e9rieur dans le cas am\u00e9ricaniste par la distribution fondamentalement in\u00e9galitaire et surtout fondamentalement <strong>corrompue<\/strong> de la richesse jusqu&rsquo;\u00e0 rendre n\u00e9cessaire son \u00e9limination. (Distribution corrompue dans le sens o\u00f9 l&rsquo;in\u00e9galit\u00e9 ne favorise pas, dans ce cas, quelque attitude qu&rsquo;on pourrait juger vertueuse, mais des attitudes syst\u00e9matiquement mafieuses, escroqueuses, trompeuses et indignes.) L&rsquo;univers supr\u00e9matiste, loin de cr\u00e9er une \u00e9lite dans le sens noble et historique du terme, cr\u00e9e une classe unique et clon\u00e9e (des GW Bush \u00e0 r\u00e9p\u00e9tition) distingu\u00e9e dans le cas am\u00e9ricaniste par l&rsquo;argent, l&rsquo;ignorance de tout ce qui ne procure pas l&rsquo;argent, l&rsquo;absence de go\u00fbt, de politesse et de respect, l&rsquo;inculture, le m\u00e9pris des valeurs altruistes comme l&rsquo;honneur, et, enfin, le conformisme si absolu de la pens\u00e9e qu&rsquo;il d\u00e9bouche n\u00e9cessairement sur la n\u00e9gation de la pens\u00e9e par uniformisation de cette activit\u00e9. Cas de GW.<\/p>\n<\/p>\n<p><p>\tL&rsquo;univers raciste est, par contraste, une d\u00e9rive malheureuse, condamnable et \u00e9ventuellement r\u00e9parable d&rsquo;une civilisation n\u00e9cessairement fond\u00e9e sur l&rsquo;identification de la diff\u00e9rence: s&rsquo;il para\u00eet \u00e0 l&rsquo;origine employer des r\u00e9f\u00e9rences semblables, l&rsquo;univers raciste n&rsquo;a, dans son fondement, rien de commun avec l&rsquo;univers supr\u00e9matiste puisqu&rsquo;il aboutit \u00e0 son inverse,  l&rsquo;univers supr\u00e9matiste aboutissant, lui, \u00e0 l&rsquo;\u00e9limination de la diff\u00e9rence par s\u00e9lection naturelle revue \u00e0 la sauce humaine, am\u00e9ricaniste dans ce cas.<\/p>\n<\/p>\n<p><p>\tLe supr\u00e9matisme am\u00e9ricaniste s&rsquo;exerce \u00e9videmment contre les Noirs, qui ont perdu leur int\u00e9r\u00eat \u00e9conomique depuis la fin de l&rsquo;esclavage ; mais il s&rsquo;est exerc\u00e9 aussi bien contre les Indiens comme il s&rsquo;exerce contre les petits blancs,  on s&rsquo;en est aper\u00e7u lors de la Grande D\u00e9pression,  et contre d&rsquo;autres marginaux, y compris les traditionalistes du syst\u00e8me de d\u00e9mocratie localiste \u00e0 la Jefferson, y compris contre les \u00e9crivains am\u00e9ricains dont la tendance g\u00e9n\u00e9rale est une mise en cause radicale du syst\u00e8me. Relire \u00e0 ce propos le texte du barbare jubilant, le colonel Ralph Peters, supr\u00e9matiste s&rsquo;il en est : dans son texte qu&rsquo;on retrouve <a href=\"http:\/\/www.dedefensa.org\/article.php?art_id=662\" class=\"gen\">sur ce site<\/a>, on voit bien qu&rsquo;une partie de la population [blanche] US est promise \u00e0 l&rsquo;\u00e9limination : \u00ab <em>These noncompetitive cultures, such as that of Arabo-Persian Islam or the rejectionist segment of our own population, are enraged. Their cultures are under assault; their cherished values have proven dysfunctional, and the successful move on without them. The laid-off blue-collar worker in America and the Taliban militiaman in Afghanistan are brothers in suffering&#8230;<\/em> \u00bb<\/p>\n<h3>L&rsquo;art de bricoler Darwin<\/h3>\n<\/p>\n<p><p>\tUn univers supr\u00e9matiste est un univers darwinien o\u00f9 le darwinisme est devenu une philosophie alors qu&rsquo;il ne pr\u00e9tend \u00eatre et n&rsquo;est au d\u00e9part, et ne devrait rester qu&rsquo;une description de type finalement anthropologiste d&rsquo;un m\u00e9canisme naturel n\u00e9cessairement partiel. (Darwin ne s&rsquo;est pas du tout arr\u00eat\u00e9 \u00e0 la psychologie animale dans la description de l&rsquo;\u00e9volution des esp\u00e8ces. Il faudrait au moins lui ajouter Konrad Lorenz pour compl\u00e9ter sa description ; encore n&rsquo;en resterions-nous qu&rsquo;\u00e0 une description compl\u00e9t\u00e9e, toujours pas une philosophie.)<\/p>\n<\/p>\n<p><p>\tC&rsquo;est une tendance fondamentale de l&rsquo;am\u00e9ricanisme : bricoler les d\u00e9marches intellectuelles des autres, transformer le comment en pourquoi. L&rsquo;am\u00e9ricanisme a fait cela avec Descartes, comme il l&rsquo;a fait plus tard avec Darwin. La M\u00e9thode de Descartes est un moyen de d\u00e9cha\u00eener l&rsquo;esprit, et nullement un sens donn\u00e9 \u00e0 l&rsquo;esprit. L&rsquo;am\u00e9ricanisme en a fait un sens, une philosophie ; c&rsquo;est le \u00ab <em>Descartes descendu dans la rue<\/em> \u00bb de Arnaud Dandieu et Robert Aron (<em>D\u00e9cadence de la nation fran\u00e7aise<\/em>, 1931) ; c&rsquo;est Descartes + Ford et la M\u00e9thode devenue sens en se transformant en fordisme (m\u00e9thode de production \u00e0 la cha\u00eene), et aboutissant \u00e0 une \u00ab <em>\u00e9conomie de force<\/em> \u00bb. L\u00e0 o\u00f9 il n&rsquo;y avait que moyen pour l&rsquo;esprit, on fait une philosophie asservissant l&rsquo;esprit au moyen, et la soci\u00e9t\u00e9 devenue prisonni\u00e8re de l&rsquo;\u00e9conomie de production au lieu que l&rsquo;\u00e9conomie de production ait \u00e9t\u00e9 donn\u00e9e comme moyen \u00e0 la soci\u00e9t\u00e9 de l&rsquo;esprit,  avec t\u00e2che pour celle-l\u00e0 et celui-ci d&rsquo;en civiliser l&rsquo;orientation, le rythme, le but, la n\u00e9cessit\u00e9 en un mot.<\/p>\n<h3>Justice doit \u00eatre faite du sot argument de l&rsquo;antiracisme officiel<\/h3>\n<\/p>\n<p><p>\tQuant \u00e0 l&rsquo;argument des stupides intellectuels fran\u00e7ais qui d\u00e9fendront l&rsquo;Am\u00e9rique au-del\u00e0 s&rsquo;il le faut de l&rsquo;infamie de l&rsquo;am\u00e9ricanisme, confondant tout aussi stupidement Am\u00e9rique et am\u00e9ricanisme,  l&rsquo;argument du mais regardez Condi Rice! Mais regardez Colin Powell! O\u00f9 voyez-vous du racisme l\u00e0-dedans? ; la r\u00e9ponse est dans l&rsquo;ab\u00eeme de l&rsquo;\u00e2me humaine et ses fourberies sans fin. Harry Belafonte l&rsquo;avait d\u00e9j\u00e0 faite en assimilant Colin Powell \u00e0 ces <em>house niggers<\/em>, ces esclaves noirs qui jouaient un r\u00f4le de favori, et de <em>kapos<\/em> pour leurs fr\u00e8res, aupr\u00e8s des planteurs blancs. (Powell n&rsquo;avait pas appr\u00e9ci\u00e9, se doutant de quelque chose lorsque ses oreilles sonnaient des \u00e9chos des insultes des <em>neocons<\/em> \u00e0 son encontre, on se doute dans quel sens et de quelle couleur ces insultes&#8230;)<\/p>\n<\/p>\n<p><p>\tR\u00e9ponse de Cornel West, dans le m\u00eame sens: \u00ab <em>But Oprah <\/em>[Winfrey] <em>the billionaire and the black judges and chief executives and movie stars do not mean equality, or even equality of opportunity yet. Black faces in high places does not mean racism is over. Condoleezza Rice has sold her soul.<\/em> \u00bb<\/p>\n<\/p>\n<p><p>\tD&rsquo;une fa\u00e7on g\u00e9n\u00e9rale, l&rsquo;histoire fait, par simple \u00e9vidence de la chronologie et des circonstances, justice de l&rsquo;aspect <strong>moral<\/strong> de l&rsquo;argument de l&rsquo;antiracisme officiel. Le soutien officiel \u00e0 la promotion des droits civiques des Noirs apparut en 1947-48, sur recommandation du d\u00e9partement d&rsquo;\u00c9tat (rien \u00e0 voir avec les questions int\u00e9rieures). L&rsquo;argument unique des diplomates \u00e9tait l&rsquo;\u00e9vidence que le sort fait aux Noirs aux USA nourrissait puissamment la propagande anti-am\u00e9ricaine des communistes et de l&rsquo;URSS en particulier. Il fallait r\u00e9agir contre cela : pure r\u00e9action de relations publiques.<\/p>\n<\/p>\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>La barbarie jubilante du darwinisme postmoderne Lorsqu&rsquo;il a \u00e9t\u00e9 r\u00e9v\u00e9l\u00e9 (le 11 septembre, sur Antiwar.com) que des mercenaires de Blackwater Inc. se trouvaient \u00e0 New Orleans, la question s&rsquo;est aussit\u00f4t pos\u00e9e de savoir pourquoi. La r\u00e9ponse est qu&rsquo;il y a d&rsquo;une part la tendance naturelle de la bureaucratie de proc\u00e9der selon ses normes, d&rsquo;autant plus&hellip;&nbsp;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","footnotes":"","jetpack_post_was_ever_published":false},"categories":[3],"tags":[3251,4042,4745,4743,4244,4744,3250,1391,4746],"class_list":["post-66814","post","type-post","status-publish","format-standard","hentry","category-analyse","tag-barbarie","tag-dandieu","tag-darwinisme","tag-descartes","tag-ford","tag-jubilante","tag-peters","tag-powell","tag-social"],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/66814","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/comments?post=66814"}],"version-history":[{"count":0,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/66814\/revisions"}],"wp:attachment":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/media?parent=66814"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/categories?post=66814"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/tags?post=66814"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}