{"id":66820,"date":"2005-09-14T00:00:00","date_gmt":"2005-09-14T00:00:00","guid":{"rendered":"https:\/\/new.dedefensa.org\/index.php\/2005\/09\/14\/villepin-a-lonu-ou-le-regard-de-la-france-vers-lexterieur\/"},"modified":"2005-09-14T00:00:00","modified_gmt":"2005-09-14T00:00:00","slug":"villepin-a-lonu-ou-le-regard-de-la-france-vers-lexterieur","status":"publish","type":"post","link":"https:\/\/new.dedefensa.org\/index.php\/2005\/09\/14\/villepin-a-lonu-ou-le-regard-de-la-france-vers-lexterieur\/","title":{"rendered":"<strong><em>Villepin \u00e0 l&rsquo;ONU, ou le regard de la France vers l&rsquo;ext\u00e9rieur<\/em><\/strong>"},"content":{"rendered":"<p><h2 class=\"common-article\">Villepin \u00e0 l&rsquo;ONU, ou le regard de la France vers l&rsquo;ext\u00e9rieur<\/h2>\n<\/p>\n<p><\/p>\n<p><p>\t14 septembre 2005  Si le destin a le go\u00fbt de l&rsquo;ironie et le sens du politique, il doit consid\u00e9rer avec une satisfaction discr\u00e8te l&rsquo;\u00e9pisode de l&rsquo;hospitalisation du pr\u00e9sident fran\u00e7ais. Un directeur de communication machiav\u00e9lique n&rsquo;aurait pas imagin\u00e9 mieux. Cela dit, tous nos vux de repos et de prompt r\u00e9tablissement au chef de l&rsquo;\u00c9tat.<\/p>\n<\/p>\n<p><p>\tOn dit et r\u00e9p\u00e8te que Jacques Chirac n&rsquo;a plus aucune chance dans l&rsquo;\u00e9lection pr\u00e9sidentielle pour 2007, m\u00eame d&rsquo;y figurer,  dans tous les cas s&rsquo;il en a ou en avait le projet. Son alerte de sant\u00e9 rend cet effacement \u00e0 la fois plus naturel et plus glorieux, comme un simple acquiescement devant la force des choses,  attitude profond\u00e9ment gaulliste, s&rsquo;il en est. Politiquement, elle permet, en toute innocence, une manuvre qui comble les vux suppos\u00e9s du m\u00eame chef de l&rsquo;\u00c9tat. Voil\u00e0 pour la politique dont on conna\u00eet la conclusion: l&rsquo;incident de sant\u00e9 de Chirac est une circonstance qui conduit \u00e0 mettre le Premier ministre Dominique de Villepin en \u00e9vidence, et cela doit \u00eatre appr\u00e9ci\u00e9 en termes \u00e9lectoraux. L\u00e0 o\u00f9 Villepin affirme sa position, Sarkozy enrage un peu plus et le Pr\u00e9sident de la R\u00e9publique en est ragaillardi. Paradoxe, si l&rsquo;on veut: l&rsquo;incident de sant\u00e9 de Chirac doit permettre au m\u00eame Chirac de s&rsquo;en remettre encore bien plus ragaillardi.<\/p>\n<\/p>\n<p><p>\tTous les commentateurs ont not\u00e9 ce ph\u00e9nom\u00e8ne en devenir dans notre soci\u00e9t\u00e9 de communication, avec un Villepin partant \u00e0 New York nimb\u00e9 dans le drapeau fran\u00e7ais, pour affirmer sa stature de pr\u00e9sidentiable,  question d&rsquo;image, disent-ils. \u00ab <em>A travers cette pr\u00e9sence \u00e0 l&rsquo;ONU, M. de Villepin pourrait asseoir la stature pr\u00e9sidentielle dont les Fran\u00e7ais le cr\u00e9ditent d\u00e9sormais dans les sondages et qui attise sa rivalit\u00e9 avec le ministre de l&rsquo;int\u00e9rieur, Nicolas Sarkozy. Le premier ministre pourrait trouver \u00e0 New York l&rsquo;opportunit\u00e9 de creuser l&rsquo;\u00e9cart.<\/em> \u00bb (selon Christophe Jakubyszyn et Corine Lesnes, dans <a href=\"http:\/\/www.lemonde.fr\/web\/article\/0,1-0@2-3224,36-687772@51-685440,0.html\" class=\"gen\">Le Monde du 11 septembre<\/a>).<\/p>\n<\/p>\n<p><p>\tLaissons l\u00e0 le fardeau de notre temps historique. Il y a plus qu&rsquo;une question \u00e9lectorale et bien plus, infiniment plus qu&rsquo;une question d&rsquo;image.<\/p>\n<\/p>\n<p><p>\tLe voyage de Villepin \u00e0 New York, avec lui \u00e0 la place de Jacques Chirac, a un sens important \u00e0 ce moment de la situation fran\u00e7aise. Le Premier ministre fran\u00e7ais y va entour\u00e9 d&rsquo;une certaine faveur des commentateurs. Il semble qu&rsquo;on puisse dire qu&rsquo;il aurait plut\u00f4t r\u00e9ussi \u00e0 s&rsquo;imposer apr\u00e8s ses trois premiers mois \u00e0 la t\u00eate du gouvernement, et \u00e0 appara\u00eetre comme un candidat tr\u00e8s acceptable face \u00e0 Sarkozy, pour les pr\u00e9sidentielles de 2007. D&rsquo;autre part, et ceci expliquant cela en bonne partie, Sarkozy, qui s&rsquo;agite consid\u00e9rablement, commence \u00e0 provoquer une certaine lassitude, voire de l&rsquo;agacement ou du sarcasme chez ces m\u00eames commentateurs. Le premier moment d&rsquo;enthousiasme est pass\u00e9. Tout cela est normal.<\/p>\n<\/p>\n<p><p>\tOn peut alors mieux pr\u00eater attention \u00e0 plusieurs faits que le voyage de Villepin \u00e0 l&rsquo;ONU pourrait contribuer \u00e0 mettre en \u00e9vidence. Plusieurs remarques, pour illustrer ces faits, peuvent \u00eatre propos\u00e9es.<\/p>\n<\/p>\n<p><p>\t&bull; Le m\u00eame mouvement que celui qu&rsquo;on constate en France se fait jour \u00e0 l&rsquo;\u00e9tranger, et ce voyage \u00e0 l&rsquo;ONU vient le conforter d&rsquo;une fa\u00e7on tr\u00e8s affirm\u00e9e. En m\u00eame temps qu&rsquo;on d\u00e9couvre que Villepin fait un Premier ministre acceptable, on observe aussit\u00f4t qu&rsquo;il peut parfaitement tenir le r\u00f4le du dirigeant fran\u00e7ais supr\u00eame sur la sc\u00e8ne internationale. C&rsquo;est une impression qui existe aujourd&rsquo;hui \u00e0 Bruxelles, dans les milieux europ\u00e9ens, et \u00e9galement dans les milieux anglo-saxons. La remarque (le 11 septembre) de John Keegan, de l&rsquo;<em>Observer<\/em>, qu&rsquo;on a <a href=\"http:\/\/www.dedefensa.org\/article.php?art_id=1955\" class=\"gen\">d\u00e9j\u00e0 not\u00e9e dans ces colonnes<\/a> et qui vient des milieux financiers anglo-saxons, concerne directement Villepin \u00e0 cause du r\u00f4le qu&rsquo;il a jou\u00e9 \u00e0 l&rsquo;ONU:  \u00ab <em>Disapproval of the French for being cheese-eating surrender monkeys over the Iraq war has given way, in certain circles, to recognition that they were right. The irony that flood prevention and rescue work in New Orleans suffered from a diversion of resources to Iraq has been noted.<\/em> \u00bb<\/p>\n<\/p>\n<p><p>\t&bull; A l&rsquo;ONU, Villepin reviendra pratiquement en terrain conquis \u00e0 la grande tribune internationale. Les observateurs le placeront instinctivement, en raison de ses positions naturelles et fran\u00e7aises, et sans qu&rsquo;il ait besoin de les affirmer outre mesure, contre John Bolton ; il b\u00e9n\u00e9ficiera par cons\u00e9quent, de fa\u00e7on indirecte et non exprim\u00e9e mais assur\u00e9e, de la d\u00e9testation unanime que suscite Bolton. Une rencontre pr\u00e9vue en marge de sa visite \u00e0 New York avec Colin Powell renforcerait ce cr\u00e9dit. Quoi qu&rsquo;il en soit, la position de Villepin est d&rsquo;ores et d\u00e9j\u00e0 fortement renforc\u00e9e \u00e0 cet \u00e9gard par le constat public de Powell selon lequel lui-m\u00eame avait \u00e9t\u00e9 tromp\u00e9 (par sa propre administration) et qu&rsquo;il s&rsquo;\u00e9tait tromp\u00e9 \u00e0 l&rsquo;ONU, en 2003, en plaidant pour la guerre face \u00e0 Villepin.<\/p>\n<\/p>\n<p><p>\t&bull; Ce sommet de l&rsquo;ONU est \u00e0 la fois capital et dramatique. Des d\u00e9cisions importantes devraient y \u00eatre prises mais l&rsquo;obstruction de Bolton, le repr\u00e9sentant US, est massive. On y trouvera r\u00e9sum\u00e9s \u00e0 la fois les formidables dangers qui p\u00e8sent sur notre \u00e9poque et le r\u00f4le d\u00e9stabilisateur profond et d\u00e9vastateur, proche du nihilisme, que les Am\u00e9ricains y jouent,  ce qui est un <em>remake<\/em>, en beaucoup plus confortable et moins dramatique pour les Fran\u00e7ais, de la situation de 2003 o\u00f9 ils (par la voix de Villepin) eurent raison contre les Am\u00e9ricains.<\/p>\n<\/p>\n<p><p>\t&bull; Par cons\u00e9quent, les Fran\u00e7ais auront l&rsquo;occasion de d\u00e9couvrir que leur pessimisme actuel, largement document\u00e9 par les enqu\u00eates d&rsquo;opinion, ne tient pas seulement \u00e0 la situation fran\u00e7aise, qu&rsquo;il refl\u00e8te simplement, pour le compte de la France, une situation mondiale g\u00e9n\u00e9rale extr\u00eamement pr\u00e9occupante. Dans cette mesure, le pessimisme fran\u00e7ais (de l&rsquo;opinion publique fran\u00e7aise) n&rsquo;est que du r\u00e9alisme et une intuition nette du sens des choses. Il est bon que les Fran\u00e7ais, surtout ceux qui parlent des r\u00e9formes n\u00e9cessaires pour remettre la France au niveau des autres, commencent \u00e0 s&rsquo;int\u00e9resser \u00e0 l&rsquo;ext\u00e9rieur pour d\u00e9couvrir que les probl\u00e8mes int\u00e9rieurs fran\u00e7ais sont en tr\u00e8s grande partie la cons\u00e9quence d&rsquo;une situation g\u00e9n\u00e9rale inextricable, et qu&rsquo;\u00e0 cet \u00e9gard les autres, y compris les glorieux Anglo-Saxons, ne sont pas mieux lotis. Il n&rsquo;est pas assur\u00e9 que le syst\u00e8me fran\u00e7ais soit dans un \u00e9tat aussi lamentable que le syst\u00e8me am\u00e9ricain, au vu de la d\u00e9b\u00e2cle qu&rsquo;a constitu\u00e9 l&rsquo;\u00e9pisode tragique de l&rsquo;ouragan Katrina et ses suites. Les conseils pressants et parfois hyst\u00e9riques des r\u00e9formateurs radicaux parisiens d&rsquo;imiter \u00e0 toute force le syst\u00e8me anglo-saxon (am\u00e9ricain) devraient au moins \u00eatre reconsid\u00e9r\u00e9s \u00e0 cette lumi\u00e8re.<\/p>\n<\/p>\n<p><p>\t&bull; Face \u00e0 ces constats, Villepin a non seulement une stature nouvelle de pr\u00e9sidentiable mais \u00e9galement une image nouvelle de gaulliste,  ou de n\u00e9o-gaulliste, disons, et c&rsquo;est bien plus qu&rsquo;une image. Ce qui para\u00eet <em>ringard<\/em> ou d\u00e9mago aux yeux des commentateurs parisiens,  <a href=\"http:\/\/www.dedefensa.org\/article.php?art_id=1885\" class=\"gen\">une politique \u00e9nerg\u00e9tique nationale<\/a>, un plan de protection des industries strat\u00e9giques fran\u00e7aises,  appara\u00eet de plus en plus, au vu des \u00e9v\u00e9nements mondiaux, comme une n\u00e9cessit\u00e9 vitale sugg\u00e9r\u00e9e par le bon sens autant que par le sens de l&rsquo;int\u00e9r\u00eat national. M\u00eame les Britanniques,  autre r\u00e9f\u00e9rence f\u00e9tiche, sinon f\u00e9tichiste, des r\u00e9formateurs radicaux fran\u00e7ais,  commencent \u00e0 paniquer devant l&rsquo;\u00e9tat de d\u00e9pendance ext\u00e9rieure et de d\u00e9cr\u00e9pitude technologique o\u00f9 se trouve leur industrie a\u00e9ronautique.<\/p>\n<\/p>\n<p><p>\tOn arr\u00eate l\u00e0 les constats possibles du voyage de Villepin, en observant que cette liste n&rsquo;est pas exhaustive. En d&rsquo;autres termes et pour en revenir \u00e0 la comptabilit\u00e9 \u00e9lectorale, Villepin a, comme on dit, une belle et bonne carte \u00e0 jouer \u00e0 New York, \u00e0 la tribune de l&rsquo;ONU, pour lui-m\u00eame et pour la France ; sans vraiment devoir s&rsquo;y d\u00e9penser d&rsquo;ailleurs, simplement en y \u00e9tant, \u00e0 ce moment pr\u00e9cis.<\/p>\n<\/p>\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Villepin \u00e0 l&rsquo;ONU, ou le regard de la France vers l&rsquo;ext\u00e9rieur 14 septembre 2005 Si le destin a le go\u00fbt de l&rsquo;ironie et le sens du politique, il doit consid\u00e9rer avec une satisfaction discr\u00e8te l&rsquo;\u00e9pisode de l&rsquo;hospitalisation du pr\u00e9sident fran\u00e7ais. Un directeur de communication machiav\u00e9lique n&rsquo;aurait pas imagin\u00e9 mieux. Cela dit, tous nos vux de&hellip;&nbsp;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[1092,1391],"class_list":["post-66820","post","type-post","status-publish","format-standard","hentry","category-faits-et-commentaires","tag-bolton","tag-powell"],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/66820","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/comments?post=66820"}],"version-history":[{"count":0,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/66820\/revisions"}],"wp:attachment":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/media?parent=66820"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/categories?post=66820"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/tags?post=66820"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}