{"id":66876,"date":"2005-09-30T00:00:00","date_gmt":"2005-09-30T00:00:00","guid":{"rendered":"https:\/\/new.dedefensa.org\/index.php\/2005\/09\/30\/vous-avez-dit-missile-contre-le-pentagone-comme-cest-bizarre\/"},"modified":"2005-09-30T00:00:00","modified_gmt":"2005-09-30T00:00:00","slug":"vous-avez-dit-missile-contre-le-pentagone-comme-cest-bizarre","status":"publish","type":"post","link":"https:\/\/new.dedefensa.org\/index.php\/2005\/09\/30\/vous-avez-dit-missile-contre-le-pentagone-comme-cest-bizarre\/","title":{"rendered":"Vous avez dit \u201cmissile\u201d (contre le Pentagone)? Comme c&rsquo;est bizarre\u2026"},"content":{"rendered":"<p><p>Gr\u00e2ce soit rendue \u00e0 l&rsquo;un de nos lecteurs,  que nous d\u00e9signerons par prudence et par ses initiales GCF, ignorant s&rsquo;il veut \u00eatre identifi\u00e9 Bref, GCF nous indique la transcription d&rsquo;une interview du secr\u00e9taire \u00e0 la d\u00e9fense Rumsfeld en date du 12 septembre 2001, donn\u00e9e \u00e0 <em>Parade Magazine<\/em>. Tout cela est compl\u00e8tement officiel, il n&rsquo;y a pas de trace de dissident ou de terroriste l\u00e0-dedans, puisque nous parlons d&rsquo;un machin <a href=\"http:\/\/www.defenselink.mil\/transcripts\/2001\/t11182001_t1012pm.html\" class=\"gen\">pr\u00e9sent sur le site du Pentagone<\/a> (dans tous les cas jusqu&rsquo;au fameux \u00e0 l&rsquo;heure o\u00f9 j&rsquo;\u00e9cris ces lignes et jusqu&rsquo;\u00e0 d\u00e9sormais,  pourvu qu&rsquo;ils n&rsquo;aient pas la mauvaise id\u00e9e d&rsquo;enlever ce texte apr\u00e8s lecture de <em>dedefensa.org<\/em>).<\/p>\n<\/p>\n<p><p>\tBien. Nous parcourons l&rsquo;interview, en diagonales, plus en d\u00e9tails, etc., jusqu&rsquo;\u00e0 \u00eatre arr\u00eat\u00e9s par ce d\u00e9tail-l\u00e0 (mot soulign\u00e9 en gras par nous, uniquement <strong>par nous<\/strong>). (Pour rappel : le 11 septembre 2001, un mois avant l&rsquo;interview, un gros avion bien reconnaissable  nous disons bien un avion, un 757 consid\u00e9rable de 60 tonnes et d&rsquo;American Airlines  a percut\u00e9 le Pentagone peu apr\u00e8s l&rsquo;attaque contre le World Trade Center. Ceux qui ont avanc\u00e9 qu&rsquo;il y avait manigance et que ce n&rsquo;\u00e9tait pas un avion mais, par exemple, un missile, ceux-l\u00e0 ont \u00e9t\u00e9 trait\u00e9s de fous, d&rsquo;escrocs, d&rsquo;agents du KGB et j&rsquo;en passe, jusqu&rsquo;\u00e0 la menace de l&rsquo;internement pour folie obsessionnelle et confirm\u00e9e.)<\/p>\n<\/p>\n<p><p>\tVoici le passage tel que copi\u00e9-coll\u00e9, dans la bouche officielle du secr\u00e9taire \u00e0 la d\u00e9fense des Etats-Unis Donald Rumsfeld, parlant dans son bureau du Pentagone (\u00ab <em> this building<\/em> \u00bb): \u00ab <em>They [find a lot] and any number of terrorist efforts have been dissuaded, deterred or stopped by good intelligence gathering and good preventive work. It is a truth that a terrorist can attack any time, any place, using any technique and it&rsquo;s physically impossible to defend at every time and every place against every conceivable technique. Here we&rsquo;re talking about plastic knives and using an American Airlines flight filed with our citizens, and the<\/em> <strong><em>missile<\/em><\/strong> <em>to damage this building and similar (inaudible) that damaged the World Trade Center. The only way to deal with this problem is by taking the battle to the terrorists, wherever they are, and dealing with them.<\/em> \u00bb<\/p>\n<\/p>\n<p><\/p>\n<p><p>\tQu&rsquo;a-t-il voulu dire? Qu&rsquo;est-ce donc que cette langue qui a fourch\u00e9? Ce lapsus est-il vraiment un lapsus et est-il r\u00e9v\u00e9lateur? Un missile d&rsquo;American Airlines baptis\u00e9 Vol 77, avec des passagers et des terroristes \u00e0 son bord? <em>Porque no, Oll\u00e9<\/em>! Merci, GCF Et \u00e0 Donald Rumsfeld, pour sa collaboration, merci \u00e9galement.<\/p>\n<\/p>\n<p><p>\t(Ah oui On oubliait : beaucoup de choses circulent sur le <em>Web<\/em> actuellement concernant une vision r\u00e9visionniste de l&rsquo;attaque du 11 septembre. Voyez un film \u00e0 ce sujet, qui nous a \u00e9t\u00e9 signal\u00e9 par quelques lecteurs et amis, sur <a href=\"\/www.jp-petit.com\" class=\"gen\">le site de Jean-Pierre Petit<\/a>, provenant du  <a href=\"http:\/\/at.moh.online.fr\/ReOpen911\/PainfulDeceptions_french.htm\" class=\"gen\">site PainFul Deceptions<\/a>, avec notamment une analyse de l&rsquo;attaque contre le Pentagone. L&rsquo;identification du Boeing 757 du Vol77 comme machine attaquant le Pentagone est contest\u00e9e, et l&rsquo;hypoth\u00e8se d&rsquo;un UAV sans pilote <em>Global Hawk<\/em> propos\u00e9e,  UAV, pour Unmanned Aerial Vehicle, un <em>drone<\/em> qu&rsquo;on peut \u00e9galement qualifier en passant de missile. Tout cela nous \u00e9loigne bien de Ben Laden et sa bande, non encore \u00e9quip\u00e9s en <em>Global Hawk<\/em> ou en missiles. <em>So what<\/em>?)<\/p>\n<\/p>\n<p><\/p>\n<p><p>\tMis en ligne le 30 septembre 2005 \u00e0 10H25<\/p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Gr\u00e2ce soit rendue \u00e0 l&rsquo;un de nos lecteurs, que nous d\u00e9signerons par prudence et par ses initiales GCF, ignorant s&rsquo;il veut \u00eatre identifi\u00e9 Bref, GCF nous indique la transcription d&rsquo;une interview du secr\u00e9taire \u00e0 la d\u00e9fense Rumsfeld en date du 12 septembre 2001, donn\u00e9e \u00e0 Parade Magazine. Tout cela est compl\u00e8tement officiel, il n&rsquo;y a&hellip;&nbsp;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","footnotes":"","jetpack_post_was_ever_published":false},"categories":[2],"tags":[354,370,3265,3266,569,3640,3639],"class_list":["post-66876","post","type-post","status-publish","format-standard","hentry","category-bloc-notes","tag-354","tag-370","tag-ben","tag-laden","tag-rumsfeld","tag-towers","tag-twin"],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/66876","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/comments?post=66876"}],"version-history":[{"count":0,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/66876\/revisions"}],"wp:attachment":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/media?parent=66876"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/categories?post=66876"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/tags?post=66876"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}