{"id":66935,"date":"2005-10-19T00:00:00","date_gmt":"2005-10-19T00:00:00","guid":{"rendered":"https:\/\/new.dedefensa.org\/index.php\/2005\/10\/19\/une-attaque-de-diversion\/"},"modified":"2005-10-19T00:00:00","modified_gmt":"2005-10-19T00:00:00","slug":"une-attaque-de-diversion","status":"publish","type":"post","link":"https:\/\/new.dedefensa.org\/index.php\/2005\/10\/19\/une-attaque-de-diversion\/","title":{"rendered":"Une attaque  de diversion?"},"content":{"rendered":"<p><p>Le site <em>WSWS.org<\/em> analyse la r\u00e9cente (6 octobre) alerte d&rsquo;attaque terroriste dans le m\u00e9tro new-yorkais. L&rsquo;accent est mis sur la possibilit\u00e9 tr\u00e8s forte que cette alerte <a href=\"http:\/\/www.wsws.org\/articles\/2005\/oct2005\/nyc-o19.shtml\" class=\"gen\">soit un montage<\/a>. Les diff\u00e9rentes circonstances montrant que des initiatives de pr\u00e9caution et de pr\u00e9vention aupr\u00e8s de groupes sp\u00e9cifiques proches du pouvoir avant l&rsquo;alerte sont mises en \u00e9vidence. Les divergences entre des services de s\u00e9curit\u00e9 sont \u00e9galement mises en \u00e9vidence.<\/p>\n<\/p>\n<p><p>\tIl semble que la logique de cet incident soit envisag\u00e9e selon la th\u00e8se implicite qu&rsquo;il s&rsquo;agit d&rsquo;une sorte de r\u00e9p\u00e9tition, dans tous les cas d&rsquo;un exercice calcul\u00e9 fonctionnant comme une mise en garde et un encouragement pour les groupes proches du pouvoir \u00e0 prendre certaines pr\u00e9cautions. La conclusion du site est qu&rsquo;il faudrait envisager de voir dans cet ensemble de fait les signes d&rsquo;une possible attaque provoqu\u00e9e, voire d&rsquo;une attaque v\u00e9ridique qui serait facilit\u00e9e. La cause en est \u00e9vidente : d\u00e9tourner l&rsquo;attention des difficult\u00e9s actuelles de l&rsquo;administration.<\/p>\n<\/p>\n<p><p>\t\u00ab <em>Under these circumstances, the public downplaying of the alert as non-credible and a hoax by the Department of Homeland Security may have ominous implications. Vice President Dick Cheney and other senior administration officials, it should be recalled, were similarly warned prior to 9\/11 not to fly on commercial airplanes based on government foreknowledge of an imminent terrorist attacka warning that was withheld from the public as the attacks were allowed to take plae.<\/em><\/p>\n<\/p>\n<p><p>\t\u00bb <em>With the Bush administration increasingly beset with reversalsthe quagmire in Iraq, the exposure of its gross incompetence in responding to Hurricane Katrina, the potential indictment of top advisors in the Valerie Plame affair, the indictment of House Majority leader Tom DeLay for campaign finance violationsthe potential that another real terror attack may be allowed to go forward should be taken very seriously.<\/em> \u00bb<\/p>\n<\/p>\n<p><\/p>\n<p><p>\tMis en ligne le 19 octobre 2005 \u00e0 13H22<\/p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Le site WSWS.org analyse la r\u00e9cente (6 octobre) alerte d&rsquo;attaque terroriste dans le m\u00e9tro new-yorkais. L&rsquo;accent est mis sur la possibilit\u00e9 tr\u00e8s forte que cette alerte soit un montage. Les diff\u00e9rentes circonstances montrant que des initiatives de pr\u00e9caution et de pr\u00e9vention aupr\u00e8s de groupes sp\u00e9cifiques proches du pouvoir avant l&rsquo;alerte sont mises en \u00e9vidence. Les&hellip;&nbsp;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","footnotes":"","jetpack_post_was_ever_published":false},"categories":[2],"tags":[],"class_list":["post-66935","post","type-post","status-publish","format-standard","hentry","category-bloc-notes"],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/66935","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/comments?post=66935"}],"version-history":[{"count":0,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/66935\/revisions"}],"wp:attachment":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/media?parent=66935"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/categories?post=66935"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/tags?post=66935"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}