{"id":66943,"date":"2005-10-21T00:00:00","date_gmt":"2005-10-21T00:00:00","guid":{"rendered":"https:\/\/new.dedefensa.org\/index.php\/2005\/10\/21\/retour-au-plan-b\/"},"modified":"2005-10-21T00:00:00","modified_gmt":"2005-10-21T00:00:00","slug":"retour-au-plan-b","status":"publish","type":"post","link":"https:\/\/new.dedefensa.org\/index.php\/2005\/10\/21\/retour-au-plan-b\/","title":{"rendered":"<strong><em>Retour au \u201cplan B\u201d<\/em><\/strong>"},"content":{"rendered":"<p><h2 class=\"common-article\">Retour au plan B<\/h2>\n<\/p>\n<p><\/p>\n<p><p>\t21 octobre 2005  L&rsquo;intervention, le 19 octobre devant la Chambre des d\u00e9put\u00e9s, du Premier ministre belge (lib\u00e9ral flamand) Guy Verhofstadt, constitue un rappel, ou un retour au premier plan de l&rsquo;actualit\u00e9, de la formule europ\u00e9enne que nous avions nous-m\u00eames d\u00e9sign\u00e9e comme <a href=\"http:\/\/www.dedefensa.org\/article.php?art_id=1552\" class=\"gen\">un vrai plan B<\/a>. C&rsquo;\u00e9tait alors l&rsquo;expression en vogue d&rsquo;une formule europ\u00e9enne alternative devant le naufrage du r\u00e9f\u00e9rendum fran\u00e7ais du 29 mai condamnant la marche vers l&rsquo;int\u00e9gration des 25.<\/p>\n<\/p>\n<p><p>\tD&rsquo;abord, voici un compte-rendu interne de l&rsquo;intervention de Verhofstadt :<\/p>\n<\/p>\n<p><p>\t\u00ab <em>Le Premier ministre belge Guy Verhofstadt a appel\u00e9 mercredi la tenue en 2006 d&rsquo;un sommet des chefs d&rsquo;Etat et de gouvernement des pays de l&rsquo;eurozone pour discuter de l&rsquo;avenir de l&rsquo;Europe, et la faire red\u00e9marrer dans sa strat\u00e9gie sociale. J&rsquo;ai la volont\u00e9 d&rsquo;appeler la tenue en 2006 d&rsquo;un sommet des chefs d&rsquo;Etat des pays de l&rsquo;eurozone pour voir comment approfondir l&rsquo;Union europ\u00e9enne. <\/em>[&#8230;] <em>Ce sommet servirait \u00e0 faire red\u00e9marrer l&rsquo;Union europ\u00e9enne dans sa strat\u00e9gie sociale, a confi\u00e9 mercredi le chef du gouvernement lors d&rsquo;un d\u00e9bat \u00e0 la Chambre sur l&rsquo;UE. Pour le Premier ministre, la seule r\u00e9ponse \u00e0 la grave crise de confiance que traverse actuellement l&rsquo;Europe, c&rsquo;est de poser les choix qui n&rsquo;ont pas \u00e9t\u00e9 faits ces 15 derni\u00e8res ann\u00e9es, \u00e0 savoir poursuivre l&rsquo;int\u00e9gration europ\u00e9enne, notamment en mati\u00e8re de politique \u00e9trang\u00e8re et de d\u00e9fense, de s\u00e9curit\u00e9 et de justice, mais aussi en mati\u00e8re socio-\u00e9conomique. Dans l&rsquo;id\u00e9al, cela devrait se faire avec les vingt-cinq Etats membres, mais si ce n&rsquo;est pas possible, nous devons le faire avec ceux qui veulent aller de l&rsquo;avant.<\/em> \u00bb<\/p>\n<\/p>\n<p><p>\tDeux points sont importants dans cette intervention :<\/p>\n<\/p>\n<p><p>\t&bull; La proposition de la poursuite de l&rsquo;int\u00e9gration europ\u00e9enne au moins dans deux domaines en mati\u00e8re de s\u00e9curit\u00e9 (essentiellement d\u00e9fense) et la mati\u00e8re socio-\u00e9conomique qui implique la protection du soi-disant mod\u00e8le europ\u00e9en.<\/p>\n<\/p>\n<p><p>\t&bull; L&rsquo;appel \u00e0 un travail europ\u00e9en sur un noyau dur (\u00ab <em>Dans l&rsquo;id\u00e9al, cela devrait se faire avec les vingt-cinq Etats membres, mais si ce n&rsquo;est pas possible, nous devons le faire avec ceux qui veulent aller de l&rsquo;avant<\/em> \u00bb). Nous aurions tendance \u00e0 commenter que la restriction (si ce n&rsquo;est pas possible \u00e0 25) est de pure forme : tout le monde sait, Verhofstadt le premier, que rien de s\u00e9rieux n&rsquo;est possible \u00e0 25 et qu&rsquo;il faut songer \u00e0 un noyau dur r\u00e9duit \u00e0 cinq, six ou sept.<\/p>\n<\/p>\n<p><p>\tCette intervention fait partie d&rsquo;un dispositif plus ou moins spontan\u00e9 qui se met en place du c\u00f4t\u00e9 belge pour relancer une dynamique europ\u00e9enne resserr\u00e9e \u00e0 quelques pays. Dans l&rsquo;histoire tr\u00e8s r\u00e9cente, les Belges ont \u00e9t\u00e9 actifs (avec les Fran\u00e7ais et les Allemands) en 2002-2003, dans une position pro-europ\u00e9enne mais surtout anti-am\u00e9ricaine marqu\u00e9e qui leur est tr\u00e8s inhabituelle. (Les Belges n&rsquo;aiment pas prendre cette sorte de risque.) A suivi une p\u00e9riode de repli, suscit\u00e9e notamment par de fortes pressions US, selon l&rsquo;habituelle politique de l&rsquo;administration GW de punir les alli\u00e9s les plus faibles qui ne montrent pas un alignement impeccable. Les Belges en reviennent ici \u00e0 leur position favorite: <em>honest brockers<\/em> en mati\u00e8re europ\u00e9enne,  et, en apparence, dans cette seule mati\u00e8re vertueuse de l&rsquo;Europe (pas de soup\u00e7on d&rsquo;anti-am\u00e9ricanisme, s&rsquo;il vous pla\u00eet). Leur but est de tenter une relance de l&rsquo;id\u00e9e du noyau dur, ce que nous avions appel\u00e9 le plan B apr\u00e8s le 29 mai.<\/p>\n<\/p>\n<p><p>\t(L&rsquo;intervention de Verhofstadt avait \u00e9t\u00e9 pr\u00e9c\u00e9d\u00e9e, samedi dernier, par le passage \u00e0 la t\u00eate du parti socialiste flamand de l&rsquo;ancien vice-Premier ministre Van Delanotte. Le nouveau pr\u00e9sident socialiste flamand entend relancer son parti dans les affaires internationales en pr\u00f4nant \u00e9galement une Europe ind\u00e9pendante avec mod\u00e8le social <em>ad hoc<\/em>, repli\u00e9e sur le noyau dur s&rsquo;il le faut. C&rsquo;est un deuxi\u00e8me signal officiel de l&rsquo;int\u00e9r\u00eat belge pour une relance europ\u00e9enne. Un point \u00e0 signaler est que les deux signaux mentionn\u00e9s ici viennent de la partie flamande du pays alors que l&rsquo;initiative belge a n\u00e9cessairement une orientation d&rsquo;abord vers la France, qui serait n\u00e9cessairement le pilier d&rsquo;une telle initiative. Cela implique une position belge tr\u00e8s proche de l&rsquo;unanimit\u00e9, les francophones du pays \u00e9tant en g\u00e9n\u00e9ral acquis \u00e0 toute initiative europ\u00e9enne qui implique la France.)<\/p>\n<\/p>\n<p><p>\tLe morceau de choix, pour le s\u00e9rieux de la chose, c&rsquo;est la proposition d&rsquo;une Europe ind\u00e9pendante en mati\u00e8re de s\u00e9curit\u00e9. C&rsquo;est l\u00e0 qu&rsquo;on se comptera et qu&rsquo;on comptera. (Le mod\u00e8le social europ\u00e9en c&rsquo;est bien mais c&rsquo;est vague, et cela ne fait pas une Europe, m\u00eame r\u00e9duite. Si vous n&rsquo;avez pas d&rsquo;autonomie europ\u00e9enne vis-\u00e0-vis des USA,  et l&rsquo;on parle d&rsquo;autonomie au niveau de la s\u00e9curit\u00e9 et de la d\u00e9fense,  vous pouvez dire adieu \u00e0 votre mod\u00e8le social. L&rsquo;\u00e9quation est simple.)<\/p>\n<\/p>\n<p><p>\tL&rsquo;id\u00e9e qui court \u00e0 Bruxelles, c&rsquo;est d&rsquo;abord une Europe de la d\u00e9fense plus int\u00e9gr\u00e9e que l&rsquo;actuelle et, surtout, d\u00e9clarant son ind\u00e9pendance de mani\u00e8re formelle. Le sch\u00e9ma recherch\u00e9 pour les participants, puisqu&rsquo;il faut un point de d\u00e9part, serait inspir\u00e9 de celui des participants \u00e0 l&rsquo;Eurocorps : Allemagne, Belgique, France, Luxembourg, Espagne. Des contacts informels sont en cours d&rsquo;\u00e9tablissement entre Belges et Fran\u00e7ais. Il y aurait eu aussi des signaux d&rsquo;int\u00e9r\u00eat venus de l&rsquo;Allemagne. (En Allemagne, il faudra un certain temps pour d\u00e9canter la situation: mais l&rsquo;on sait que, m\u00eame du c\u00f4t\u00e9 de la CDU\/CSU, <a href=\"http:\/\/www.dedefensa.org\/article.php?art_id=1951\" class=\"gen\">on n&rsquo;est pas hostile \u00e0 l&rsquo;id\u00e9e<\/a>. Pour le SPD, l&rsquo;id\u00e9e devrait aller de soi.).<\/p>\n<\/p>\n<p><p>\tPour l&rsquo;instant, il s&rsquo;agit de contacts au niveau des experts, par exemple pour l&rsquo;organisation de s\u00e9minaires significatifs qui permettraient de renforcer et de d\u00e9tailler l&rsquo;initiative. Mais les autorit\u00e9s concern\u00e9es suivent la chose, et l&rsquo;on irait m\u00eame jusqu&rsquo;\u00e0 \u00e9crire qu&rsquo;elles pourraient tr\u00e8s bien appara\u00eetre comme parrainant la chose officieusement si les circonstances sont favorables.<\/p>\n<\/p>\n<p><p>\tUn point int\u00e9ressant est de voir quelle attitude prendraient les institutions europ\u00e9ennes \u00e0 l&rsquo;\u00e9gard d&rsquo;une telle initiative. Une source \u00e0 la Commission observe : \u00ab <em>A premi\u00e8re vue, on doit penser que la Commission n&rsquo;est pas favorable \u00e0 une initiative qui ne concerne pas les 25 pays. C&rsquo;est un r\u00e9flexe quasiment ontologique. Cela dit, vu les circonstances, avec le processus europ\u00e9en si mal en point, et d&rsquo;autre part si l&rsquo;affaire est men\u00e9e avec habilet\u00e9, il n&rsquo;est pas dit qu&rsquo;il n&rsquo;y ait pas quelque int\u00e9r\u00eat qui puisse se manifester de fa\u00e7on concr\u00e8te<\/em> \u00bb<\/p>\n<\/p>\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Retour au plan B 21 octobre 2005 L&rsquo;intervention, le 19 octobre devant la Chambre des d\u00e9put\u00e9s, du Premier ministre belge (lib\u00e9ral flamand) Guy Verhofstadt, constitue un rappel, ou un retour au premier plan de l&rsquo;actualit\u00e9, de la formule europ\u00e9enne que nous avions nous-m\u00eames d\u00e9sign\u00e9e comme un vrai plan B. C&rsquo;\u00e9tait alors l&rsquo;expression en vogue d&rsquo;une&hellip;&nbsp;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[1465],"class_list":["post-66943","post","type-post","status-publish","format-standard","hentry","category-faits-et-commentaires","tag-verhofstadt"],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/66943","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/comments?post=66943"}],"version-history":[{"count":0,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/66943\/revisions"}],"wp:attachment":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/media?parent=66943"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/categories?post=66943"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/tags?post=66943"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}