{"id":66950,"date":"2005-10-24T00:00:00","date_gmt":"2005-10-24T00:00:00","guid":{"rendered":"https:\/\/new.dedefensa.org\/index.php\/2005\/10\/24\/selon-quon-est-financial-times-ou-the-independent\/"},"modified":"2005-10-24T00:00:00","modified_gmt":"2005-10-24T00:00:00","slug":"selon-quon-est-financial-times-ou-the-independent","status":"publish","type":"post","link":"https:\/\/new.dedefensa.org\/index.php\/2005\/10\/24\/selon-quon-est-financial-times-ou-the-independent\/","title":{"rendered":"Selon qu&rsquo;on est <em>Financial Times<\/em> ou <em>The Independent<\/em>"},"content":{"rendered":"<p><p>Int\u00e9ressante diff\u00e9rence d&rsquo;orientation et de pr\u00e9sentation des r\u00e9sultats publi\u00e9s de l&rsquo;\u00e9volution des d\u00e9penses R&#038;D des entreprises priv\u00e9es dans le monde, et par cons\u00e9quent au Royaume-Uni, dans deux journaux londoniens.<\/p>\n<\/p>\n<p><p>\t&bull; Le <a href=\"http:\/\/news.ft.com\/cms\/s\/2083c070-4406-11da-b752-00000e2511c8,ft_acl=,s01=1.html\" class=\"gen\">Financial Times<\/a> de ce matin insiste emphatiquement sur la position mauvaise de l&rsquo;Europe de l&rsquo;UE dans le domaine des R&#038;D dans les entreprises priv\u00e9es (\u00ab <em>corporate investments<\/em> \u00bb). L&rsquo;Europe n&rsquo;augmente ses R&#038;D que de 2% contre 7% pour l&rsquo;Asie et les USA, selon International R&#038;D Scoreboard. La question des investissements europ\u00e9ens en R&#038;D sera, selon notre journal londonien de r\u00e9f\u00e9rence, \u00ab <em>a key theme of this Thursday&rsquo;s EU summit at Hampton Court, near London<\/em> \u00bb Bien entendu, TB y sera en position centrale, en  pr\u00e9sident-h\u00f4te et en donneur de le\u00e7on : \u00ab <em>Tony Blair, the British prime minister and host of the summit, wants to get Europe back on track in the direction of modernisation.<\/em> \u00bb<\/p>\n<\/p>\n<p><p>\t&bull; Peut-\u00eatre est-ce parce qu&rsquo;il est un quotidien aussi pro-europ\u00e9en que le FT est nationaliste-financier? <a href=\"http:\/\/news.independent.co.uk\/business\/news\/article321700.ece\" class=\"gen\">The Independent de ce matin<\/a> se concentre, lui, sur les r\u00e9sultats britanniques, pour nous informer implicitement et indirectement que, si l&rsquo;UE a des r\u00e9sultats si pr\u00e9occupants pour Blair, c&rsquo;est en bonne partie aux Britanniques qu&rsquo;elle le doit: \u00ab <em>Spending by UK companies on research and development is continuing to decline despite generous tax breaks from the Government aimed at stimulating more investment in innovation. Figures published today by the Department for Trade and Industry show that R&#038;D spending by British industry fell 1 per cent last year to \u00a317bn. By contrast, overseas rivals increased spending, with R&#038;D investment by the world&rsquo;s top 1,000 companies up by 5 per cent to \u00a3220bn.<\/em><\/p>\n<\/p>\n<p><p>\t\u00bb <em>This is the second year running that R&#038;D spending by UK companies has slipped, even though new tax incentives introduced in 2000 and 2002 enable firms to offset more than 100 per cent of their investment against tax. The DTI&rsquo;s 2005 R&#038;D Scoreboard also shows that UK companies still lag a long way behind the international average in terms of the relative amount spent on innovation. Internationally, spending on R&#038;D was equivalent to 3.8 per cent of turnover but in the UK the figure was only 2 per cent.<\/em> \u00bb<\/p>\n<\/p>\n<p><\/p>\n<p><p>\tMis en ligne le 24 octobre 2005 \u00e0 14H11<\/p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Int\u00e9ressante diff\u00e9rence d&rsquo;orientation et de pr\u00e9sentation des r\u00e9sultats publi\u00e9s de l&rsquo;\u00e9volution des d\u00e9penses R&#038;D des entreprises priv\u00e9es dans le monde, et par cons\u00e9quent au Royaume-Uni, dans deux journaux londoniens. &bull; Le Financial Times de ce matin insiste emphatiquement sur la position mauvaise de l&rsquo;Europe de l&rsquo;UE dans le domaine des R&#038;D dans les entreprises priv\u00e9es&hellip;&nbsp;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","footnotes":"","jetpack_post_was_ever_published":false},"categories":[2],"tags":[],"class_list":["post-66950","post","type-post","status-publish","format-standard","hentry","category-bloc-notes"],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/66950","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/comments?post=66950"}],"version-history":[{"count":0,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/66950\/revisions"}],"wp:attachment":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/media?parent=66950"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/categories?post=66950"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/tags?post=66950"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}